{"id":1400,"date":"2016-01-07T04:00:18","date_gmt":"2016-01-07T02:00:18","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=1400"},"modified":"2017-09-28T11:37:46","modified_gmt":"2017-09-28T08:37:46","slug":"03-07-04","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/03-07-04\/","title":{"rendered":"04. El valor de la bendici\u00f3n por la Tor\u00e1."},"content":{"rendered":"<p>Luego que la tierra de Israel fuera destruida y el pueblo jud\u00edo exiliado, surgi\u00f3 la pregunta (Irmiahu 9:11): \u00ab\u00bfPor qu\u00e9 motivo se ha perdido la tierra?\u00bb Por cierto, que todos ten\u00edan claro que a causa de nuestros pecados fuimos exiliados de nuestra tierra, sin embargo la pregunta era: \u00bfCu\u00e1l es el pecado central que origin\u00f3 el derrumbe espiritual que llev\u00f3 a la destrucci\u00f3n? Esta pregunta le fue formulada a nuestros sabios de bendita memoria, a los profetas y a los \u00e1ngeles ministeriales sin que nadie haya sabido qu\u00e9 responder. Hasta que el mism\u00edsimo Santo Bendito Sea lo explic\u00f3: \u00abPorque han abandonado Mi Ley que Yo establec\u00ed para ellos\u00bb (\u00eddem 9:12), esto es, porque no bendijeron por la Tor\u00e1 antes de estudiarla (Talmud Babilonio Tratado de <em>Nedarim<\/em> 81: (A)).<\/p>\n<p>Si bien en la pr\u00e1ctica estudiaban Tor\u00e1, del momento en que no se vinculaban con ella como una ense\u00f1anza Divina de origen celestial, esto se les consideraba como si la hubiesen abandonado. Esto se debe a que todo aquel que estudia Tor\u00e1 como una disciplina m\u00e1s de investigaci\u00f3n humana, no se considera que la estudie. Empero, si se recita previamente la bendici\u00f3n por la Tor\u00e1, se puede luego acceder al estudio desde la perspectiva de la fe e imbuidos de un intenso deseo de conexi\u00f3n con Quien la entreg\u00f3.<\/p>\n<p>Nuestros sabios tambi\u00e9n se preguntaron (Nedarim \u00eddem) \u00bfpor qu\u00e9 ocurre que no todos los hijos de los grandes eruditos de la Tor\u00e1 siguen el camino de sus padres y no se convierten en estudiosos, a pesar, de que sin duda sus padres hubiesen deseado que dediquen toda su vida al estudio de la Tor\u00e1? \u00bfA causa de qu\u00e9 los eruditos de la Tor\u00e1 no tienen \u00e9xito en la educaci\u00f3n de todos sus hijos?\u00a0 M\u00e1s a\u00fan, en esos d\u00edas se acostumbraba que cada hijo continuara con el oficio de su padre, los hijos del carpintero se convert\u00edan en carpinteros, los hijos de los agricultores se convert\u00edan en agricultores y as\u00ed todos.<\/p>\n<p>La pregunta entonces es \u00bfpor qu\u00e9 un alto porcentaje de hijos de estudiosos de la Tor\u00e1 no se convierten en estudiosos como sus padres? El Talmud trae varias explicaciones a este asunto; la \u00faltima pertenece a Rabina quien dijo que la causa de la discontinuidad intergeneracional en el estudio radica en que no bendijeron por la Tor\u00e1 antes de estudiarla. Esto es, muchas veces los hijos de los eruditos de la Tor\u00e1 la estudian por haber visto a sus padres hacerlo, y as\u00ed como a todos los hijos les gusta imitar a sus progenitores, as\u00ed tambi\u00e9n ellos intentan estudiar Tor\u00e1. Empero la Tor\u00e1 solo se puede adquirir si se estudia con pureza de intenci\u00f3n o por amor a D\u00b4s (\u00ab<em>leshem shamaim<\/em>\u00ab), mediante una conexi\u00f3n personal con quien la entreg\u00f3 y por eso los hijos que estudiaron por imitaci\u00f3n a sus padres o por costumbre no vislumbran una bendici\u00f3n ni resultados en su estudio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego que la tierra de Israel fuera destruida y el pueblo jud\u00edo exiliado, surgi\u00f3 la pregunta (Irmiahu 9:11): \u00ab\u00bfPor qu\u00e9 motivo se ha perdido la tierra?\u00bb Por cierto, que todos ten\u00edan claro que a causa de nuestros pecados fuimos exiliados de nuestra tierra, sin embargo la pregunta era: \u00bfCu\u00e1l es el pecado central que origin\u00f3 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-1400","post","type-post","status-publish","format-standard","hentry","category-03-07"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>04. El valor de la bendici\u00f3n por la Tor\u00e1. - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/03-07-04\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"04. El valor de la bendici\u00f3n por la Tor\u00e1. - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Luego que la tierra de Israel fuera destruida y el pueblo jud\u00edo exiliado, surgi\u00f3 la pregunta (Irmiahu 9:11): \u00ab\u00bfPor qu\u00e9 motivo se ha perdido la tierra?\u00bb Por cierto, que todos ten\u00edan claro que a causa de nuestros pecados fuimos exiliados de nuestra tierra, sin embargo la pregunta era: \u00bfCu\u00e1l es el pecado central que origin\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/03-07-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-07T02:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-28T08:37:46+00:00\" \/>\n<meta name=\"author\" content=\"orah765768\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"orah765768\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-07-04\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-07-04\\\/\"},\"author\":{\"name\":\"orah765768\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/0996d17962bfd8ffd1c8ef7117a4204b\"},\"headline\":\"04. El valor de la bendici\u00f3n por la Tor\u00e1.\",\"datePublished\":\"2016-01-07T02:00:18+00:00\",\"dateModified\":\"2017-09-28T08:37:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-07-04\\\/\"},\"wordCount\":510,\"commentCount\":0,\"articleSection\":[\"07. Las Bendiciones por la Tor\u00e1.\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-07-04\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-07-04\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-07-04\\\/\",\"name\":\"04. El valor de la bendici\u00f3n por la Tor\u00e1. - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2016-01-07T02:00:18+00:00\",\"dateModified\":\"2017-09-28T08:37:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/0996d17962bfd8ffd1c8ef7117a4204b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-07-04\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-07-04\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-07-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"04. El valor de la bendici\u00f3n por la Tor\u00e1.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/0996d17962bfd8ffd1c8ef7117a4204b\",\"name\":\"orah765768\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g\",\"caption\":\"orah765768\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/orah765768\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"04. El valor de la bendici\u00f3n por la Tor\u00e1. - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/03-07-04\/","og_locale":"es_ES","og_type":"article","og_title":"04. El valor de la bendici\u00f3n por la Tor\u00e1. - Pninei Halaj\u00e1","og_description":"Luego que la tierra de Israel fuera destruida y el pueblo jud\u00edo exiliado, surgi\u00f3 la pregunta (Irmiahu 9:11): \u00ab\u00bfPor qu\u00e9 motivo se ha perdido la tierra?\u00bb Por cierto, que todos ten\u00edan claro que a causa de nuestros pecados fuimos exiliados de nuestra tierra, sin embargo la pregunta era: \u00bfCu\u00e1l es el pecado central que origin\u00f3 [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/03-07-04\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2016-01-07T02:00:18+00:00","article_modified_time":"2017-09-28T08:37:46+00:00","author":"orah765768","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"orah765768","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/03-07-04\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/03-07-04\/"},"author":{"name":"orah765768","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/0996d17962bfd8ffd1c8ef7117a4204b"},"headline":"04. El valor de la bendici\u00f3n por la Tor\u00e1.","datePublished":"2016-01-07T02:00:18+00:00","dateModified":"2017-09-28T08:37:46+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/03-07-04\/"},"wordCount":510,"commentCount":0,"articleSection":["07. Las Bendiciones por la Tor\u00e1."],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/03-07-04\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/03-07-04\/","url":"https:\/\/ph.yhb.org.il\/es\/03-07-04\/","name":"04. El valor de la bendici\u00f3n por la Tor\u00e1. - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2016-01-07T02:00:18+00:00","dateModified":"2017-09-28T08:37:46+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/0996d17962bfd8ffd1c8ef7117a4204b"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/03-07-04\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/03-07-04\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/03-07-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"04. El valor de la bendici\u00f3n por la Tor\u00e1."}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/0996d17962bfd8ffd1c8ef7117a4204b","name":"orah765768","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g","caption":"orah765768"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/orah765768\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/1400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=1400"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/1400\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=1400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=1400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=1400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}