{"id":1425,"date":"2016-01-08T09:00:55","date_gmt":"2016-01-08T07:00:55","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=1425"},"modified":"2017-09-28T11:36:24","modified_gmt":"2017-09-28T08:36:24","slug":"03-08-09","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/03-08-09\/","title":{"rendered":"09. El caso de alumnas que comen en su casa y rezan en el colegio."},"content":{"rendered":"<p>Muchachas que acostumbran a rezar Shajarit en el colegio y si no comen primero en sus casas van a pasar hambre despu\u00e9s lo cual es nocivo para su salud y perjudicial para su concentraci\u00f3n en el rezo y los estudios, tienen permitido hacerlo. Si les alcanza con comer un bocadillo ligero que no incluye pan es mejor que as\u00ed lo hagan y luego en el primer recreo que hagan abluci\u00f3n de manos y coman pan. En este caso no se debe argumentar que es mejor que recen Shajarit en la casa, ya que el rezo en el colegio a un horario fijo educa a las j\u00f3venes y realza el status de la plegaria. Empero es correcto que primero reciten las bendiciones matinales y de la Tor\u00e1 antes de comer y beber.<\/p>\n<p>En el caso de ni\u00f1os que a\u00fan no llegaron a la mayor\u00eda de edad (doce para las ni\u00f1as y trece para los varones), pueden comer antes de rezar ya que en este caso se los educa a abstenerse de alimentos \u00fanicamente cuando \u00e9stos no son kasher. Nuestros sabios decretaron que no se ingieran alimentos antes de rezar o antes del Kidush, empero como estos alimentos en cuesti\u00f3n son aptos, el decreto no aplica a los menores de edad. Si bien a priori es bueno que no coman antes de rezar, en caso de ser necesario pueden hacerlo (<em>Mishn\u00e1 Berur\u00e1<\/em> 106:5, <em>Iab\u00eda Omer<\/em> IV 12:15 y ver <em>Kaf HaJaim<\/em> 106:11).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muchachas que acostumbran a rezar Shajarit en el colegio y si no comen primero en sus casas van a pasar hambre despu\u00e9s lo cual es nocivo para su salud y perjudicial para su concentraci\u00f3n en el rezo y los estudios, tienen permitido hacerlo. Si les alcanza con comer un bocadillo ligero que no incluye pan [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72],"tags":[],"class_list":["post-1425","post","type-post","status-publish","format-standard","hentry","category-03-08"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>09. El caso de alumnas que comen en su casa y rezan en el colegio. - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/03-08-09\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"09. El caso de alumnas que comen en su casa y rezan en el colegio. - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Muchachas que acostumbran a rezar Shajarit en el colegio y si no comen primero en sus casas van a pasar hambre despu\u00e9s lo cual es nocivo para su salud y perjudicial para su concentraci\u00f3n en el rezo y los estudios, tienen permitido hacerlo. Si les alcanza con comer un bocadillo ligero que no incluye pan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/03-08-09\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-08T07:00:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-28T08:36:24+00:00\" \/>\n<meta name=\"author\" content=\"orah765768\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"orah765768\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-08-09\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-08-09\\\/\"},\"author\":{\"name\":\"orah765768\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/0996d17962bfd8ffd1c8ef7117a4204b\"},\"headline\":\"09. El caso de alumnas que comen en su casa y rezan en el colegio.\",\"datePublished\":\"2016-01-08T07:00:55+00:00\",\"dateModified\":\"2017-09-28T08:36:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-08-09\\\/\"},\"wordCount\":261,\"commentCount\":0,\"articleSection\":[\"08. El rezo de Shajarit y\u00a0 reglas previo a su recitado.\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-08-09\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-08-09\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-08-09\\\/\",\"name\":\"09. El caso de alumnas que comen en su casa y rezan en el colegio. - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2016-01-08T07:00:55+00:00\",\"dateModified\":\"2017-09-28T08:36:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/0996d17962bfd8ffd1c8ef7117a4204b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-08-09\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-08-09\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-08-09\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"09. El caso de alumnas que comen en su casa y rezan en el colegio.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/0996d17962bfd8ffd1c8ef7117a4204b\",\"name\":\"orah765768\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g\",\"caption\":\"orah765768\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/orah765768\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"09. El caso de alumnas que comen en su casa y rezan en el colegio. - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/03-08-09\/","og_locale":"es_ES","og_type":"article","og_title":"09. El caso de alumnas que comen en su casa y rezan en el colegio. - Pninei Halaj\u00e1","og_description":"Muchachas que acostumbran a rezar Shajarit en el colegio y si no comen primero en sus casas van a pasar hambre despu\u00e9s lo cual es nocivo para su salud y perjudicial para su concentraci\u00f3n en el rezo y los estudios, tienen permitido hacerlo. Si les alcanza con comer un bocadillo ligero que no incluye pan [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/03-08-09\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2016-01-08T07:00:55+00:00","article_modified_time":"2017-09-28T08:36:24+00:00","author":"orah765768","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"orah765768","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/03-08-09\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/03-08-09\/"},"author":{"name":"orah765768","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/0996d17962bfd8ffd1c8ef7117a4204b"},"headline":"09. El caso de alumnas que comen en su casa y rezan en el colegio.","datePublished":"2016-01-08T07:00:55+00:00","dateModified":"2017-09-28T08:36:24+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/03-08-09\/"},"wordCount":261,"commentCount":0,"articleSection":["08. El rezo de Shajarit y\u00a0 reglas previo a su recitado."],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/03-08-09\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/03-08-09\/","url":"https:\/\/ph.yhb.org.il\/es\/03-08-09\/","name":"09. El caso de alumnas que comen en su casa y rezan en el colegio. - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2016-01-08T07:00:55+00:00","dateModified":"2017-09-28T08:36:24+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/0996d17962bfd8ffd1c8ef7117a4204b"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/03-08-09\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/03-08-09\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/03-08-09\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"09. El caso de alumnas que comen en su casa y rezan en el colegio."}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/0996d17962bfd8ffd1c8ef7117a4204b","name":"orah765768","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g","caption":"orah765768"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/orah765768\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/1425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=1425"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/1425\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=1425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=1425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=1425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}