{"id":1622,"date":"2016-01-20T01:00:22","date_gmt":"2016-01-19T23:00:22","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=1622"},"modified":"2017-09-28T11:25:36","modified_gmt":"2017-09-28T08:25:36","slug":"03-20-01","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/03-20-01\/","title":{"rendered":"01. Los hombres tienen el deber de rezar con \u00abMini\u00e1n\u00bb en la sinagoga."},"content":{"rendered":"<p>Los sabios establecieron que los hombres deben rezar con \u00abMini\u00e1n\u00bb en la sinagoga. Asimismo dijeron que cuando diez jud\u00edos se ocupan de cuestiones relativas a la santidad, la Divina Presencia reposa sobre ellos tal como est\u00e1 escrito (Salmos 82:1): \u00abD\u00b4s se hace presente en la congregaci\u00f3n de sus fieles\u00bb y diez israelitas conforman una congregaci\u00f3n. Y si bien cuando una sola persona reza o estudia la Presencia Divina tambi\u00e9n reposa sobre \u00e9l, existiendo diferentes niveles siendo el m\u00e1s elevado de los mismos cuando diez jud\u00edos se dedican a algo relativo a la santidad (\u00ab<em>davar shebakdush\u00e1<\/em>\u00ab) y es cuando \u00e9sta se revela en el mundo (ver Talmud Babilonio Tratado de <em>Berajot<\/em> 6(A)). Seg\u00fan esta idea nuestros sabios instituyeron que todas las cuestiones relativas a la santidad se reciten en un qu\u00f3rum de diez. Entre ellas se encuentran: la repetici\u00f3n de la \u00abAmid\u00e1\u00bb por parte del oficiante, la bendici\u00f3n sacerdotal, \u00abbarej\u00fa\u00bb, el recitado del \u00abkadish\u00bb y la lectura de la Tor\u00e1 (Talmud Babilonio Tratado de <em>Meguil\u00e1<\/em> 23(B)).<\/p>\n<p>Nuestros sabios afirmaron que la plegaria que una persona ora en p\u00fablico es aceptada, y aunque no hayan puesto la debida intenci\u00f3n durante el rezo, El Santo Bendito Sea nunca desecha la plegaria p\u00fablica (Talmud Babilonio Tratado de <em>Berajot <\/em>8(A)).<\/p>\n<p>Vemos pues que el \u00abMini\u00e1n\u00bb posee dos virtudes, la primera es que la Divina Presencia reposa en la congregaci\u00f3n y por lo tanto la plegaria es bien recibida, la segunda radica en que con este qu\u00f3rum se pueden recitar aquellas cuestiones referidas a la santidad (\u00ab<em>dvarim shebakdush\u00e1<\/em>\u00ab) que nuestros sabios dispusieron se reciten con qu\u00f3rum (ver <em>Peninei Halaj\u00e1 Tefil\u00e1<\/em> 2:1-3).<\/p>\n<p>Dado que en virtud del \u00abMini\u00e1n\u00bb reposa la Divina Presencia, es apropiado que cada persona procure ser de los primeros diez en conformar el qu\u00f3rum.<\/p>\n<p>Cuando el \u00abMini\u00e1n\u00bb tiene lugar en la sinagoga posee dos virtudes especiales, la primera es que la persona se halla en un sitio especial destinado a cuestiones relativas a la santidad (Talmud Babilonio Tratado de <em>Berajot<\/em> 6(A) y 8(A)). La sinagoga recibe el nombre de \u00abpeque\u00f1o santuario\u00bb o \u00absantuario en miniatura\u00bb (\u00ab<em>Mikdash Me\u00b4at<\/em>\u00ab) ya que posee una\u00a0 santidad relacionada o que rememora la del Templo de Jerusalem, tal como est\u00e1 escrito (Ezequiel 11:16): \u00abhe sido para ellos como un peque\u00f1o santuario\u00bb lo cual fue explicado por Rab\u00ed Itzjak como referido \u00aba las sinagogas y casas de estudio\u00bb (Talmud Babilonio Tratado de <em>Meguil\u00e1 <\/em>29(A)).<\/p>\n<p>Vemos entonces que el rezo p\u00fablico en la sinagoga funge, en cierta forma,\u00a0 como sustituto de la labor sacra del Templo de Jerusalem. All\u00ed donde se encuentran diez jud\u00edos reposa la Divina Presencia y entonces la santidad de la sinagoga rememora en cierta forma a la del sagrado Templo, y los rezos fueron establecidos en concordancia con las ofrendas p\u00fablicas.<\/p>\n<p>Dijo Reish Lakish: todo aqu\u00e9l que tiene una sinagoga en su ciudad y no entra a rezar en ella es llamado \u00abmal vecino\u00bb. Adem\u00e1s causa el exilio para s\u00ed y sus hijos. En cambio, quienes llegan temprano a la sinagoga al servicio de Shajarit y demoran en salir de \u00e9sta tras el servicio de Arvit son recompensados con longevidad (Talmud Babilonio Tratado de <em>Berajot<\/em> 8(A), <em>Shulj\u00e1n Aruj<\/em> 90:11).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los sabios establecieron que los hombres deben rezar con \u00abMini\u00e1n\u00bb en la sinagoga. Asimismo dijeron que cuando diez jud\u00edos se ocupan de cuestiones relativas a la santidad, la Divina Presencia reposa sobre ellos tal como est\u00e1 escrito (Salmos 82:1): \u00abD\u00b4s se hace presente en la congregaci\u00f3n de sus fieles\u00bb y diez israelitas conforman una congregaci\u00f3n. [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-1622","post","type-post","status-publish","format-standard","hentry","category-03-20"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>01. Los hombres tienen el deber de rezar con &quot;Mini\u00e1n&quot; en la sinagoga. - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/03-20-01\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"01. Los hombres tienen el deber de rezar con &quot;Mini\u00e1n&quot; en la sinagoga. - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Los sabios establecieron que los hombres deben rezar con \u00abMini\u00e1n\u00bb en la sinagoga. Asimismo dijeron que cuando diez jud\u00edos se ocupan de cuestiones relativas a la santidad, la Divina Presencia reposa sobre ellos tal como est\u00e1 escrito (Salmos 82:1): \u00abD\u00b4s se hace presente en la congregaci\u00f3n de sus fieles\u00bb y diez israelitas conforman una congregaci\u00f3n. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/03-20-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-19T23:00:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-28T08:25:36+00:00\" \/>\n<meta name=\"author\" content=\"orah765768\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"orah765768\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-20-01\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-20-01\\\/\"},\"author\":{\"name\":\"orah765768\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/0996d17962bfd8ffd1c8ef7117a4204b\"},\"headline\":\"01. Los hombres tienen el deber de rezar con \u00abMini\u00e1n\u00bb en la sinagoga.\",\"datePublished\":\"2016-01-19T23:00:22+00:00\",\"dateModified\":\"2017-09-28T08:25:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-20-01\\\/\"},\"wordCount\":562,\"commentCount\":0,\"articleSection\":[\"20. Leyes referentes al rezo con \\\"Mini\u00e1n\\\"\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-20-01\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-20-01\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-20-01\\\/\",\"name\":\"01. Los hombres tienen el deber de rezar con \\\"Mini\u00e1n\\\" en la sinagoga. - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2016-01-19T23:00:22+00:00\",\"dateModified\":\"2017-09-28T08:25:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/0996d17962bfd8ffd1c8ef7117a4204b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-20-01\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-20-01\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/03-20-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"01. Los hombres tienen el deber de rezar con \u00abMini\u00e1n\u00bb en la sinagoga.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/0996d17962bfd8ffd1c8ef7117a4204b\",\"name\":\"orah765768\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g\",\"caption\":\"orah765768\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/orah765768\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"01. Los hombres tienen el deber de rezar con \"Mini\u00e1n\" en la sinagoga. - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/03-20-01\/","og_locale":"es_ES","og_type":"article","og_title":"01. Los hombres tienen el deber de rezar con \"Mini\u00e1n\" en la sinagoga. - Pninei Halaj\u00e1","og_description":"Los sabios establecieron que los hombres deben rezar con \u00abMini\u00e1n\u00bb en la sinagoga. Asimismo dijeron que cuando diez jud\u00edos se ocupan de cuestiones relativas a la santidad, la Divina Presencia reposa sobre ellos tal como est\u00e1 escrito (Salmos 82:1): \u00abD\u00b4s se hace presente en la congregaci\u00f3n de sus fieles\u00bb y diez israelitas conforman una congregaci\u00f3n. [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/03-20-01\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2016-01-19T23:00:22+00:00","article_modified_time":"2017-09-28T08:25:36+00:00","author":"orah765768","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"orah765768","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/03-20-01\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/03-20-01\/"},"author":{"name":"orah765768","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/0996d17962bfd8ffd1c8ef7117a4204b"},"headline":"01. Los hombres tienen el deber de rezar con \u00abMini\u00e1n\u00bb en la sinagoga.","datePublished":"2016-01-19T23:00:22+00:00","dateModified":"2017-09-28T08:25:36+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/03-20-01\/"},"wordCount":562,"commentCount":0,"articleSection":["20. Leyes referentes al rezo con \"Mini\u00e1n\""],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/03-20-01\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/03-20-01\/","url":"https:\/\/ph.yhb.org.il\/es\/03-20-01\/","name":"01. Los hombres tienen el deber de rezar con \"Mini\u00e1n\" en la sinagoga. - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2016-01-19T23:00:22+00:00","dateModified":"2017-09-28T08:25:36+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/0996d17962bfd8ffd1c8ef7117a4204b"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/03-20-01\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/03-20-01\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/03-20-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"01. Los hombres tienen el deber de rezar con \u00abMini\u00e1n\u00bb en la sinagoga."}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/0996d17962bfd8ffd1c8ef7117a4204b","name":"orah765768","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0fdb49d8a411a6adc7129873884ffe72812892b9141dc21fe63bbadcaf2d84f6?s=96&d=mm&r=g","caption":"orah765768"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/orah765768\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/1622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=1622"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/1622\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=1622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=1622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=1622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}