{"id":251,"date":"2000-05-06T04:00:31","date_gmt":"2000-05-06T01:00:31","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=251"},"modified":"2015-05-13T10:31:25","modified_gmt":"2015-05-13T07:31:25","slug":"05-06-04","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/05-06-04\/","title":{"rendered":"4 &#8211; Nueve de Av."},"content":{"rendered":"<p>Dijeron nuestros sabios (Tratado de Ta\u00b4anit 25(B)): \u00abCinco eventos funestos acaecieron a nuestros ancestros el nueve de Av: se decret\u00f3 sobre nuestros ancestros (la \u2018Generaci\u00f3n del Desierto\u2019) que no habr\u00edan de ingresar a la Tierra de Israel, fueron destruidos el Primero y Segundo Templo, cay\u00f3 la ciudad de Betar y fue arada la ciudad (de Jerusal\u00e9m)\u00bb.<\/p>\n<p>El primer evento ocurri\u00f3 en d\u00edas de la salida de Egipto. Mosh\u00e9 acept\u00f3 la propuesta del pueblo de enviar doce esp\u00edas para que reconozcan la tierra de Cana\u00e1n y a su regreso diez de ellos difamaron al pa\u00eds desmoralizando al p\u00fablico, al sostener que no podr\u00edan conquistar la tierra en virtud del poder\u00edo de sus habitantes. \u00abEntonces levant\u00f3se la congregaci\u00f3n y alz\u00f3 sus voces de angustia. La gente llor\u00f3 esa noche. Y todos los hijos de Israel murmuraron  contra Mosh\u00e9 y Ahar\u00f3n y les dijeron: \u00ab\u00a1Ojal\u00e1 hubi\u00e9semos muerto en la tierra de Egipto o en este desierto! \u00bfPara qu\u00e9 nos trajo el Eterno a esta tierra? \u00bfPara que perezcamos por la espada y nuestras mujeres y nuestros hijos se conviertan en presa? \u00bfNo ser\u00eda mejor para nosotros volver a la tierra de Egipto?\u00bb(N\u00fameros 14:1-4)<\/p>\n<p>Iehosh\u00faa hijo de Nun y Caleb hijo de Iefun\u00e9 contradijeron el testimonio mayoritario de los esp\u00edas sosteniendo que, \u00abEl pa\u00eds por el que hemos pasado es muy buena tierra. Si el Eterno se complace en nosotros nos dar\u00e1 la tierra que mana leche y miel, pero no os rebel\u00e9is contra el  Eterno ni tem\u00e1is a los pobladores de esa tierra porque son pan (comido) para nosotros ya que el Eterno se ha apartado de ellos para favorecernos. No los tem\u00e1is\u00bb (N\u00fameros 14:7-9). Empero sus palabras no fueron aceptadas por la muchedumbre enardecida que \u00abtrat\u00f3 de apedrearlos\u00bb (\u00eddem 10).<\/p>\n<p>En ciertos aspectos el pecado de los esp\u00edas es m\u00e1s grave que el del becerro de oro, ya que en el segundo el pueblo no reneg\u00f3 de D\u00b4s y de Mosh\u00e9 por completo, sino que se equivocaron. El error consisti\u00f3 en que pensaron que Mosh\u00e9 hab\u00eda fallecido y por lo tanto D\u00b4s ya no se les revelar\u00eda de modo directo, y era entonces necesario encontrar un \u00eddolo que haga de intermediario entre ellos y el Creador. Por esta raz\u00f3n una vez concluido el episodio del pecado del becerro de oro, D\u00b4s perdona a la comunidad. Sin embargo en el episodio del pecado de los esp\u00edas, la grey neg\u00f3 la capacidad de D\u00b4s de actuar en el mundo y de ayudarles a conquistar el pa\u00eds. M\u00e1s a\u00fan, fallaron en la misi\u00f3n fundamental que es la causa de la creaci\u00f3n del mundo y elecci\u00f3n del Pueblo Jud\u00edo, revelar la Presencia Divina a trav\u00e9s de la  Tierra de Israel. Por esta raz\u00f3n el pecado de los esp\u00edas nunca fue perdonado, los participantes en \u00e9l fueron castigados, neg\u00e1ndoseles la posibilidad de ingresar a la Tierra de Israel, mientras que Iehosh\u00faa Bin Nun y Caleb Ben Iefun\u00e9 por no ser parte de la trasgresi\u00f3n, tuvieron el m\u00e9rito de poder ingresar.<\/p>\n<p>Esa noche en la que el pueblo llor\u00f3 y despreciaron a la tierra de Israel era un nueve de Av. En vistas de lo ocurrido D\u00b4s dijo: vosotros hab\u00e9is llorado un llanto vano y yo os establezco un llanto por todas las generaciones (Tratado de Sanhedr\u00edn 104(B)). En ese momento se decret\u00f3 que el Templo de Jerusal\u00e9m habr\u00eda de ser destruido (Tanjuma Shelaj).<\/p>\n<p>Por efecto del pecado del becerro de oro se resquebraj\u00f3 la muralla de la fe, en virtud de esta fisura se abri\u00f3 posteriormente un boquete en los muros de Jerusal\u00e9m y al final se derribaron el prestigio de la Tor\u00e1 y el servicio en el Templo. En virtud del pecado de los esp\u00edas, se destruy\u00f3 la convicci\u00f3n b\u00e1sica respecto de la misi\u00f3n del pueblo Jud\u00edo de consagrar el Nombre Divino en el mundo y todas las desgracias que se desencadenaron posteriormente, implican la anulaci\u00f3n o la destrucci\u00f3n de nuestra capacidad de revelar Santidad en el mundo material de manera constante. En un inicio, se decret\u00f3 ese mismo nueve de Av, que la generaci\u00f3n del desierto no ingresar\u00eda a la Tierra de Israel y como no logramos reparar el pecado de los esp\u00edas, sus efectos se extendieron en el tiempo causando la destrucci\u00f3n de ambos Santuarios. Posteriormente tampoco  logramos reparar el pecado de los esp\u00edas, por lo que fue destruida la ciudad de Betar que fue el basti\u00f3n de la rebeli\u00f3n de Bar Kojba y la ciudad de Jerusal\u00e9m fue arada, esto es, destruida por completo y arrasada hasta los cimientos. Todos estos eventos tr\u00e1gicos impidieron la manifestaci\u00f3n de la Divina Presencia en el mundo, siendo esta la causa de nuestro pesar y por la cual ayunamos el nueve de Av.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dijeron nuestros sabios (Tratado de Ta\u00b4anit 25(B)): \u00abCinco eventos funestos acaecieron a nuestros ancestros el nueve de Av: se decret\u00f3 sobre nuestros ancestros (la \u2018Generaci\u00f3n del Desierto\u2019) que no habr\u00edan de ingresar a la Tierra de Israel, fueron destruidos el Primero y Segundo Templo, cay\u00f3 la ciudad de Betar y fue arada la ciudad (de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-251","post","type-post","status-publish","format-standard","hentry","category-05-06"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4 - Nueve de Av. - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/05-06-04\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 - Nueve de Av. - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Dijeron nuestros sabios (Tratado de Ta\u00b4anit 25(B)): \u00abCinco eventos funestos acaecieron a nuestros ancestros el nueve de Av: se decret\u00f3 sobre nuestros ancestros (la \u2018Generaci\u00f3n del Desierto\u2019) que no habr\u00edan de ingresar a la Tierra de Israel, fueron destruidos el Primero y Segundo Templo, cay\u00f3 la ciudad de Betar y fue arada la ciudad (de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/05-06-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-05-06T01:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-13T07:31:25+00:00\" \/>\n<meta name=\"author\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-06-04\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-06-04\\\/\"},\"author\":{\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"headline\":\"4 &#8211; Nueve de Av.\",\"datePublished\":\"2000-05-06T01:00:31+00:00\",\"dateModified\":\"2015-05-13T07:31:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-06-04\\\/\"},\"wordCount\":851,\"articleSection\":[\"06- Los cuatro ayunos por la destrucci\u00f3n del Templo.\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-06-04\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-06-04\\\/\",\"name\":\"4 - Nueve de Av. - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-05-06T01:00:31+00:00\",\"dateModified\":\"2015-05-13T07:31:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-06-04\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-06-04\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-06-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 &#8211; Nueve de Av.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\",\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"caption\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/thfvhacvcss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 - Nueve de Av. - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/05-06-04\/","og_locale":"es_ES","og_type":"article","og_title":"4 - Nueve de Av. - Pninei Halaj\u00e1","og_description":"Dijeron nuestros sabios (Tratado de Ta\u00b4anit 25(B)): \u00abCinco eventos funestos acaecieron a nuestros ancestros el nueve de Av: se decret\u00f3 sobre nuestros ancestros (la \u2018Generaci\u00f3n del Desierto\u2019) que no habr\u00edan de ingresar a la Tierra de Israel, fueron destruidos el Primero y Segundo Templo, cay\u00f3 la ciudad de Betar y fue arada la ciudad (de [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/05-06-04\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-05-06T01:00:31+00:00","article_modified_time":"2015-05-13T07:31:25+00:00","author":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/05-06-04\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-06-04\/"},"author":{"name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"headline":"4 &#8211; Nueve de Av.","datePublished":"2000-05-06T01:00:31+00:00","dateModified":"2015-05-13T07:31:25+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-06-04\/"},"wordCount":851,"articleSection":["06- Los cuatro ayunos por la destrucci\u00f3n del Templo."],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/05-06-04\/","url":"https:\/\/ph.yhb.org.il\/es\/05-06-04\/","name":"4 - Nueve de Av. - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-05-06T01:00:31+00:00","dateModified":"2015-05-13T07:31:25+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-06-04\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/05-06-04\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/05-06-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"4 &#8211; Nueve de Av."}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178","name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","caption":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/thfvhacvcss\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=251"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/251\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}