{"id":2740,"date":"2000-01-21T00:07:09","date_gmt":"2000-01-20T22:07:09","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=2740"},"modified":"2017-10-31T10:26:35","modified_gmt":"2017-10-31T08:26:35","slug":"01-21-07","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/01-21-07\/","title":{"rendered":"07 &#8211; El permiso de cargar en una \u00abzona exenta\u00bb (\u00abmakom patur\u00bb)."},"content":{"rendered":"<p>Tal como ya aprendimos (halaj\u00e1 3), la \u00abzona exenta\u00bb se encuentra en el \u00abdominio p\u00fablico\u00bb, como es el caso de una roca cuya altura es inferior a tres palmos (23 cm.) y su ancho inferior a cuatro (30 cm.). Dado que la \u00abzona exenta\u00bb no es considerada un sitio importante, se permite tomar un objeto del \u00abdominio p\u00fablico\u00bb o del \u00abprivado\u00bb y depositarlo sobre una \u00abzona exenta\u00bb y al rev\u00e9s, tomar un objeto del \u00e1rea \u00abexenta\u00bb y depositarlo en el \u00abdominio p\u00fablico\u00bb o \u00abprivado\u00bb.<\/p>\n<p>Seg\u00fan la Tor\u00e1, de esta forma se permite pasar un objeto del \u00abdominio privado\u00bb al \u00abp\u00fablico\u00bb, o sea, en un principio se extrae el objeto del \u00abdominio privado\u00bb y se lo deposita sobre la \u00abzona exenta\u00bb o \u00abmakom patur\u00bb. Luego, se tomar\u00e1 el objeto de esta \u00faltima \u00a0y se lo depositar\u00e1 en el \u00abdominio p\u00fablico\u00bb. Sin embargo, los sabios prohibieron hacer esto para prevenir que las personas tomen a la ligera la prohibici\u00f3n de la Tor\u00e1 de \u00abtransportar\u00bb.<\/p>\n<p>Sin embargo, los juristas debatieron respecto de si se puede hacer uso de la \u00abzona exenta\u00bb a los efectos de pasar objetos del \u00abdominio privado\u00bb al \u00abcarmelit\u00bb y viceversa. Hay juristas que opinan que los sabios tambi\u00e9n prohibieron pasar objetos al \u00abcarmelit\u00bb por medio de la \u00abzona exenta\u00bb o \u00abmakom patur\u00bb, y si bien la prohibici\u00f3n de cargar objetos en el \u00abcarmelit\u00bb es una prohibici\u00f3n rab\u00ednica, los sabios no establecieron una diferenciaci\u00f3n entre ambas \u00e1reas (Rab\u00ed Zeraji\u00e1 Halev\u00ed, Rabad y Rosh). Otros juristas sostienen que los sabios prohibieron pasar objetos por medio de la \u00abzona exenta\u00bb solamente en caso de que se tema que las personas pueden trasgredir la prohibici\u00f3n de la Tor\u00e1\u00a0 de cargar del \u00abdominio privado\u00bb al \u00abdominio p\u00fablico\u00bb y viceversa, empero se permite pasar objetos del \u00abdominio privado\u00bb al \u00abcarmelit\u00bb\u00a0 v\u00eda una \u00abzona exenta\u00bb (Rif, Ramb\u00e1m).<\/p>\n<p>En la pr\u00e1ctica, en caso de necesidad se permite confiar en la opini\u00f3n m\u00e1s flexible y cargar objetos del \u00abdominio privado\u00bb al \u00abcarmelit\u00bb y viceversa, pasando por la \u00abzona exenta\u00bb o \u00abmakom patur\u00bb. Esta opci\u00f3n es relevante para los soldados que pasan Shabat en un sitio que carece de \u00abEruv\u00bb. Si desean llevar un objeto desde su tienda que es \u00abdominio privado\u00bb al patio del campamento militar que es \u00abcarmelit\u00bb, habr\u00e1n de caminar con el objeto y no se habr\u00e1n de detener hasta depositarlo sobre una \u00abzona exenta\u00bb o \u00abmakom patur\u00bb, para luego extraerlo de all\u00ed y depositarlo en el patio. Asimismo, si quieren llevar algo del patio a la tienda de campa\u00f1a, es menester depositarlo primeramente en una \u00abzona exenta\u00bb para luego cargarlo hasta la carpa. Otro tanto se debe hacer si se quiere llevar un objeto de una tienda de campa\u00f1a a otra pasando por el patio. Primeramente se debe extraer el objeto de la tienda\u00a0 y se lo deposita en una \u00abzona exenta\u00bb en el patio y luego se puede \u00a0tomar y llevar hasta la otra tienda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tal como ya aprendimos (halaj\u00e1 3), la \u00abzona exenta\u00bb se encuentra en el \u00abdominio p\u00fablico\u00bb, como es el caso de una roca cuya altura es inferior a tres palmos (23 cm.) y su ancho inferior a cuatro (30 cm.). Dado que la \u00abzona exenta\u00bb no es considerada un sitio importante, se permite tomar un objeto [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111],"tags":[],"class_list":["post-2740","post","type-post","status-publish","format-standard","hentry","category-01-21"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>07 - El permiso de cargar en una &quot;zona exenta&quot; (&quot;makom patur&quot;). - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/01-21-07\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"07 - El permiso de cargar en una &quot;zona exenta&quot; (&quot;makom patur&quot;). - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Tal como ya aprendimos (halaj\u00e1 3), la \u00abzona exenta\u00bb se encuentra en el \u00abdominio p\u00fablico\u00bb, como es el caso de una roca cuya altura es inferior a tres palmos (23 cm.) y su ancho inferior a cuatro (30 cm.). Dado que la \u00abzona exenta\u00bb no es considerada un sitio importante, se permite tomar un objeto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/01-21-07\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-01-20T22:07:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-31T08:26:35+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-07\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-07\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"07 &#8211; El permiso de cargar en una \u00abzona exenta\u00bb (\u00abmakom patur\u00bb).\",\"datePublished\":\"2000-01-20T22:07:09+00:00\",\"dateModified\":\"2017-10-31T08:26:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-07\\\/\"},\"wordCount\":514,\"commentCount\":0,\"articleSection\":[\"21. \\\"Transportar\\\" (\\\"Hotza\u00e1\\\")\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-07\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-07\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-07\\\/\",\"name\":\"07 - El permiso de cargar en una \\\"zona exenta\\\" (\\\"makom patur\\\"). - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-01-20T22:07:09+00:00\",\"dateModified\":\"2017-10-31T08:26:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-07\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-07\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-07\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"07 &#8211; El permiso de cargar en una \u00abzona exenta\u00bb (\u00abmakom patur\u00bb).\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"07 - El permiso de cargar en una \"zona exenta\" (\"makom patur\"). - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/01-21-07\/","og_locale":"es_ES","og_type":"article","og_title":"07 - El permiso de cargar en una \"zona exenta\" (\"makom patur\"). - Pninei Halaj\u00e1","og_description":"Tal como ya aprendimos (halaj\u00e1 3), la \u00abzona exenta\u00bb se encuentra en el \u00abdominio p\u00fablico\u00bb, como es el caso de una roca cuya altura es inferior a tres palmos (23 cm.) y su ancho inferior a cuatro (30 cm.). Dado que la \u00abzona exenta\u00bb no es considerada un sitio importante, se permite tomar un objeto [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/01-21-07\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-01-20T22:07:09+00:00","article_modified_time":"2017-10-31T08:26:35+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/01-21-07\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/01-21-07\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"07 &#8211; El permiso de cargar en una \u00abzona exenta\u00bb (\u00abmakom patur\u00bb).","datePublished":"2000-01-20T22:07:09+00:00","dateModified":"2017-10-31T08:26:35+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/01-21-07\/"},"wordCount":514,"commentCount":0,"articleSection":["21. \"Transportar\" (\"Hotza\u00e1\")"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/01-21-07\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/01-21-07\/","url":"https:\/\/ph.yhb.org.il\/es\/01-21-07\/","name":"07 - El permiso de cargar en una \"zona exenta\" (\"makom patur\"). - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-01-20T22:07:09+00:00","dateModified":"2017-10-31T08:26:35+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/01-21-07\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/01-21-07\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/01-21-07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"07 &#8211; El permiso de cargar en una \u00abzona exenta\u00bb (\u00abmakom patur\u00bb)."}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/2740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=2740"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/2740\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=2740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=2740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=2740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}