{"id":2746,"date":"2000-01-21T00:10:57","date_gmt":"2000-01-20T22:10:57","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=2746"},"modified":"2017-10-31T10:28:21","modified_gmt":"2017-10-31T08:28:21","slug":"01-21-10","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/01-21-10\/","title":{"rendered":"10 &#8211; Vestir una prenda no se considera \u00abtransportar\u00bb."},"content":{"rendered":"<p>Est\u00e1 permitido vestir ropa, calzar zapatos, portar sombreros y salir con estos al \u00abdominio p\u00fablico\u00bb. Esto obedece a que la ropa es secundaria respecto de la persona y mientras se la viste es considerada parte de su cuerpo, por lo que al llevarla puesta no se trasgrede la prohibici\u00f3n de \u00abcargar\u00bb.<\/p>\n<p>Asimismo, las ropas destinadas a circunstancias especiales son secundarias al cuerpo. Por lo tanto se permite vestir sobre un abrigo una cobertura especial de nylon a prueba de agua, pues hay quienes acostumbran a vestirlo en d\u00edas de lluvia. Adem\u00e1s, se permite llevar galochas sobre los zapatos o ponerse dos pares de medias pues en invierno hay quienes acostumbran a hacerlo. Igualmente, se permite vestir dos camisas, una encima de la otra, pues hay quienes acostumbran a hacerlo as\u00ed. Por lo tanto, si una persona quiere llevarle a su amigo una camisa atravesando el \u00abdominio p\u00fablico\u00bb, podr\u00e1 vestirla sobre la suya y as\u00ed alcanz\u00e1rsela incluso durante el verano. Empero, si tom\u00f3 la prenda con sus manos o se la puso al hombro y sali\u00f3 al \u00abdominio p\u00fablico\u00bb &#8211; trasgredi\u00f3 una prohibici\u00f3n de la Tor\u00e1.<\/p>\n<p>Tambi\u00e9n en el caso de algo que no se considera vestimenta, quien se envuelve con ello tal como se acostumbra a hacer con ropa, podr\u00e1 salir con ello al \u00abdominio p\u00fablico\u00bb. Por ejemplo, una mujer que quiere llevar por el \u00abdominio p\u00fablico\u00bb una frazada o un mantel podr\u00e1 envolverse en estos y as\u00ed pasarlos a otro dominio; una mujer que va a la \u00abmikve\u00bb podr\u00e1 envolverse en la toalla y llevarla as\u00ed por el \u00abdominio p\u00fablico\u00bb. La regla general indica que todo aquello que se puede llevar puesto como prenda se lo puede cargar (<em>Shulj\u00e1n Aruj<\/em> 301:35-36).<\/p>\n<p>Los sabios decretaron, como prevenci\u00f3n que no se salga al \u00abdominio p\u00fablico\u00bb con ropa que se puede caer. Sin embargo, se permite salir con kip\u00e1 puesta a pesar de que no est\u00e9 firmemente fijada, pues si se cae no se teme que alguien la cargue cuatro codos ya que la halaj\u00e1 indica que no se puede caminar esta distancia\u00a0 con la cabeza descubierta. Por lo tanto, ni bien la persona recoge su kip\u00e1, la devuelve a su cabeza de inmediato y no se teme que la \u00abcargue\u00bb cuatro codos (<em>Shulj\u00e1n Aruj<\/em> 301:7, <em>Mishn\u00e1 Berur\u00e1<\/em> 153).<\/p>\n<p>Respecto de los guantes hay quienes dicen que no se debe salir con ellos en un sitio que no est\u00e1 rodeado por un \u00abEruv\u00bb, para prevenir que si a la persona le da calor se los quite, los coloque en el bolsillo y los cargue cuatro codos en el \u00abdominio p\u00fablico\u00bb &#8211; trasgrediendo as\u00ed la prohibici\u00f3n de la Tor\u00e1. A priori, corresponde adoptar la actitud m\u00e1s estricta y la costumbre extendida es de acuerdo a la opini\u00f3n m\u00e1s flexible (<em>Shulj\u00e1n Aruj<\/em> 301:37, ver <em>Beur Halaj\u00e1<\/em> all\u00ed).<\/p>\n<p>Los juristas debatieron respecto de la cobertura especial de nylon que se\u00a0 coloca sobre los sombreros como protecci\u00f3n para los d\u00edas de lluvia. Hay quienes lo proh\u00edben pues no se trata de una prenda sino de un protector de la misma, mientras que otros lo permiten pues consideran que, efectivamente se trata de una prenda. Quien quiera adoptar la opini\u00f3n m\u00e1s flexible puede hacerlo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 permitido vestir ropa, calzar zapatos, portar sombreros y salir con estos al \u00abdominio p\u00fablico\u00bb. Esto obedece a que la ropa es secundaria respecto de la persona y mientras se la viste es considerada parte de su cuerpo, por lo que al llevarla puesta no se trasgrede la prohibici\u00f3n de \u00abcargar\u00bb. Asimismo, las ropas destinadas [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111],"tags":[],"class_list":["post-2746","post","type-post","status-publish","format-standard","hentry","category-01-21"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 - Vestir una prenda no se considera &quot;transportar&quot;. - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/01-21-10\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 - Vestir una prenda no se considera &quot;transportar&quot;. - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Est\u00e1 permitido vestir ropa, calzar zapatos, portar sombreros y salir con estos al \u00abdominio p\u00fablico\u00bb. Esto obedece a que la ropa es secundaria respecto de la persona y mientras se la viste es considerada parte de su cuerpo, por lo que al llevarla puesta no se trasgrede la prohibici\u00f3n de \u00abcargar\u00bb. Asimismo, las ropas destinadas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/01-21-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-01-20T22:10:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-31T08:28:21+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-10\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"10 &#8211; Vestir una prenda no se considera \u00abtransportar\u00bb.\",\"datePublished\":\"2000-01-20T22:10:57+00:00\",\"dateModified\":\"2017-10-31T08:28:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-10\\\/\"},\"wordCount\":559,\"commentCount\":0,\"articleSection\":[\"21. \\\"Transportar\\\" (\\\"Hotza\u00e1\\\")\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-10\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-10\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-10\\\/\",\"name\":\"10 - Vestir una prenda no se considera \\\"transportar\\\". - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-01-20T22:10:57+00:00\",\"dateModified\":\"2017-10-31T08:28:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-10\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-10\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 &#8211; Vestir una prenda no se considera \u00abtransportar\u00bb.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 - Vestir una prenda no se considera \"transportar\". - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/01-21-10\/","og_locale":"es_ES","og_type":"article","og_title":"10 - Vestir una prenda no se considera \"transportar\". - Pninei Halaj\u00e1","og_description":"Est\u00e1 permitido vestir ropa, calzar zapatos, portar sombreros y salir con estos al \u00abdominio p\u00fablico\u00bb. Esto obedece a que la ropa es secundaria respecto de la persona y mientras se la viste es considerada parte de su cuerpo, por lo que al llevarla puesta no se trasgrede la prohibici\u00f3n de \u00abcargar\u00bb. Asimismo, las ropas destinadas [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/01-21-10\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-01-20T22:10:57+00:00","article_modified_time":"2017-10-31T08:28:21+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/01-21-10\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/01-21-10\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"10 &#8211; Vestir una prenda no se considera \u00abtransportar\u00bb.","datePublished":"2000-01-20T22:10:57+00:00","dateModified":"2017-10-31T08:28:21+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/01-21-10\/"},"wordCount":559,"commentCount":0,"articleSection":["21. \"Transportar\" (\"Hotza\u00e1\")"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/01-21-10\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/01-21-10\/","url":"https:\/\/ph.yhb.org.il\/es\/01-21-10\/","name":"10 - Vestir una prenda no se considera \"transportar\". - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-01-20T22:10:57+00:00","dateModified":"2017-10-31T08:28:21+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/01-21-10\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/01-21-10\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/01-21-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"10 &#8211; Vestir una prenda no se considera \u00abtransportar\u00bb."}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/2746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=2746"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/2746\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=2746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=2746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=2746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}