{"id":2756,"date":"2000-01-21T00:15:00","date_gmt":"2000-01-20T22:15:00","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=2756"},"modified":"2017-10-31T10:31:23","modified_gmt":"2017-10-31T08:31:23","slug":"01-21-15","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/01-21-15\/","title":{"rendered":"15 &#8211; El reloj, la llave, el documento de identidad y las medicinas."},"content":{"rendered":"<p>Los juristas debatieron respecto del reloj de mano. Algunos opinan que se puede llevar puesto en el \u00abdominio p\u00fablico\u00bb \u00fanicamente si funge como joya, y la prueba de cu\u00e1l es su status se presenta cuando este deja de funcionar. Si en este caso se acostumbra a quitarlo es se\u00f1al de que no tiene el car\u00e1cter de joya y se usa \u00fanicamente para saber la hora. Entonces, por cuanto que no cubre una necesidad del cuerpo, est\u00e1 prohibido llevarlo por el \u00abdominio p\u00fablico\u00bb en Shabat.<\/p>\n<p>Sin embargo, si por ejemplo se trata de un reloj de oro y cuando\u00a0 deja de funcionar se lo sigue portando por ser bonito, queda claro que se trata de una joya y se permite llevarlo puesto por el \u00abdominio p\u00fablico\u00bb.<\/p>\n<p>Muchos juristas consideran que debe ser considerado ropa dado que el reloj va adjunto al cuerpo como si fuera una prenda de vestir, y cuando no se lo porta la persona siente que algo en su indumentaria falta. Adem\u00e1s, la manera de usarlo es mir\u00e1ndolo mientras permanece junto al cuerpo por lo que se lo considera secundario a este, y se lo ha de considerar como una prenda o una joya; siendo as\u00ed se permite salir con este al \u00abdominio p\u00fablico\u00bb. La opini\u00f3n principal es la flexible, y quien adopte la estricta ser\u00e1 bendecido.<\/p>\n<p>A quien vive o se aloja en un sitio que carece de \u00abEruv\u00bb se le presenta un grave problema al salir de su casa pues no sabe qu\u00e9 hacer con la llave. La soluci\u00f3n es usarla como hebilla del cintur\u00f3n. Esto es, tomando un cord\u00f3n por el cual habr\u00e1 de pasar la llave, at\u00e1ndolo con un nudo de corbata y us\u00e1ndolo como cinto en el cual la llave cumple la funci\u00f3n de hebilla; de este modo podr\u00e1 salir libremente al \u00abdominio p\u00fablico\u00bb (<em>Shmirat Shabat Kehiljat\u00e1<\/em> 18:49-50).<\/p>\n<p>Hay pa\u00edses en los cuales est\u00e1 prohibido andar por la calle sin documento de identidad y cuando una persona precisa hacerlo en Shabat en virtud de una gran necesidad o a los efectos de cumplir un precepto, que lo transporte de un modo diferente al habitual, por ejemplo, llev\u00e1ndolo bajo el sombrero o dentro de su camisa de modo tal que el documento en cuesti\u00f3n no se caiga a causa del cintur\u00f3n y de esta forma se transporta mediante \u00abShvut Deshvut\u00bb. Este m\u00e9todo est\u00e1 autorizado por los sabios en caso de gran necesidad o a los efectos de cumplir con un precepto (arriba 9:11).<\/p>\n<p>En el caso de un enfermo a quien el m\u00e9dico le prescribi\u00f3 no salir de su casa sin una medicina determinada, podr\u00e1 hacerlo en caso de gran necesidad o a los efectos de cumplir un precepto siempre y cuando cargue el remedio de un modo diferente al habitual. En este caso, es correcto que quien se pliega a esta actitud flexible no se pare en el \u00abdominio p\u00fablico\u00bb sino que camine por este sin pausa hasta llegar al \u00abdominio privado\u00bb deseado (<em>Shmirat Shabat Kehiljat\u00e1<\/em> 40:7).<\/p>\n<p>En el caso de un \u00e1rea que no est\u00e1 rodeada por un \u00abEruv\u00bb y existe un imperativo de seguridad y salvaguarda de la vida (\u00abpikuaj nefesh\u00bb) que requiere que personas carguen armas y tel\u00e9fonos celulares, podr\u00e1n salir port\u00e1ndolos a todos los sitios que se acostumbra a\u00a0 ir en Shabat. El tel\u00e9fono se habr\u00e1 de cargar de un modo diferente al habitual, mas el arma se habr\u00e1 de portar del modo habitual ya que hacerlo de un modo diferente implica riesgos. Se proh\u00edbe salir en Shabat con arma y medios de comunicaci\u00f3n si se trata de un paseo. Esta norma se explicar\u00e1 en detalle m\u00e1s adelante (27:17).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los juristas debatieron respecto del reloj de mano. Algunos opinan que se puede llevar puesto en el \u00abdominio p\u00fablico\u00bb \u00fanicamente si funge como joya, y la prueba de cu\u00e1l es su status se presenta cuando este deja de funcionar. Si en este caso se acostumbra a quitarlo es se\u00f1al de que no tiene el car\u00e1cter [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111],"tags":[],"class_list":["post-2756","post","type-post","status-publish","format-standard","hentry","category-01-21"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>15 - El reloj, la llave, el documento de identidad y las medicinas. - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/01-21-15\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15 - El reloj, la llave, el documento de identidad y las medicinas. - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Los juristas debatieron respecto del reloj de mano. Algunos opinan que se puede llevar puesto en el \u00abdominio p\u00fablico\u00bb \u00fanicamente si funge como joya, y la prueba de cu\u00e1l es su status se presenta cuando este deja de funcionar. Si en este caso se acostumbra a quitarlo es se\u00f1al de que no tiene el car\u00e1cter [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/01-21-15\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-01-20T22:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-31T08:31:23+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-15\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-15\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"15 &#8211; El reloj, la llave, el documento de identidad y las medicinas.\",\"datePublished\":\"2000-01-20T22:15:00+00:00\",\"dateModified\":\"2017-10-31T08:31:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-15\\\/\"},\"wordCount\":640,\"commentCount\":0,\"articleSection\":[\"21. \\\"Transportar\\\" (\\\"Hotza\u00e1\\\")\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-15\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-15\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-15\\\/\",\"name\":\"15 - El reloj, la llave, el documento de identidad y las medicinas. - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-01-20T22:15:00+00:00\",\"dateModified\":\"2017-10-31T08:31:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-15\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-15\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/01-21-15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"15 &#8211; El reloj, la llave, el documento de identidad y las medicinas.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15 - El reloj, la llave, el documento de identidad y las medicinas. - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/01-21-15\/","og_locale":"es_ES","og_type":"article","og_title":"15 - El reloj, la llave, el documento de identidad y las medicinas. - Pninei Halaj\u00e1","og_description":"Los juristas debatieron respecto del reloj de mano. Algunos opinan que se puede llevar puesto en el \u00abdominio p\u00fablico\u00bb \u00fanicamente si funge como joya, y la prueba de cu\u00e1l es su status se presenta cuando este deja de funcionar. Si en este caso se acostumbra a quitarlo es se\u00f1al de que no tiene el car\u00e1cter [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/01-21-15\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-01-20T22:15:00+00:00","article_modified_time":"2017-10-31T08:31:23+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/01-21-15\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/01-21-15\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"15 &#8211; El reloj, la llave, el documento de identidad y las medicinas.","datePublished":"2000-01-20T22:15:00+00:00","dateModified":"2017-10-31T08:31:23+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/01-21-15\/"},"wordCount":640,"commentCount":0,"articleSection":["21. \"Transportar\" (\"Hotza\u00e1\")"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/01-21-15\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/01-21-15\/","url":"https:\/\/ph.yhb.org.il\/es\/01-21-15\/","name":"15 - El reloj, la llave, el documento de identidad y las medicinas. - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-01-20T22:15:00+00:00","dateModified":"2017-10-31T08:31:23+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/01-21-15\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/01-21-15\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/01-21-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"15 &#8211; El reloj, la llave, el documento de identidad y las medicinas."}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/2756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=2756"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/2756\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=2756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=2756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=2756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}