{"id":276,"date":"2000-05-08T01:00:08","date_gmt":"2000-05-07T22:00:08","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=276"},"modified":"2015-05-13T12:44:52","modified_gmt":"2015-05-13T09:44:52","slug":"05-08-01","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/05-08-01\/","title":{"rendered":"1 &#8211; Los d\u00edas de \u00abBein Hameitzarim\u00bb (\u201cEntre las estrecheces\u201d)"},"content":{"rendered":"<p>Las tres semanas que se inician en la noche del diecisiete del mes de Tamuz y se contin\u00faan hasta el nueve del mes de Av son d\u00edas de dolor, sobre los cuales est\u00e1 escrito en las Lamentaciones de Jerem\u00edas (Meguilat Eij\u00e1 1:3) \u00ab\u2026 (Iehud\u00e1) no hall\u00f3 descanso, todos  sus perseguidores la alcanzaron entre las estrecheces\u00bb. Por esta raz\u00f3n los sabios recomendaron conducirse en estos d\u00edas que tienden a ser dif\u00edciles con suma cautela, y  a modo de ejemplo, quienes van de paseo o a tomar un ba\u00f1o de mar si bien siempre deben ser cuidadosos, en estos d\u00edas deben extremar precauciones (Ver Eij\u00e1 Rab\u00e1 1:29) <\/p>\n<p>A los efectos de destacar el car\u00e1cter de estos d\u00edas nuestros sabios establecieron la lectura de haftarot especiales durante los tres s\u00e1bados de este per\u00edodo. Estas haftarot versan sobre profec\u00edas que anuncian desgracias sobre el Pueblo de Israel. Asimismo, determinaron que en cada uno de los siete s\u00e1bados posteriores al 9 de Av se lean haftarot de consuelo a causa de la destrucci\u00f3n del Templo. (Shulj\u00e1n Aruj 428:8 de acuerdo a la Pesikta)<\/p>\n<p>Y si bien nuestros sabios \u2013de bendita memoria- no dispusieron medidas especiales a fin de destacar la tristeza y el duelo en estas tres semanas, el Pueblo de Israel acostumbr\u00f3 en ese tiempo a abstenerse de danzas y bailes as\u00ed como de recitar la bendici\u00f3n de \u00abShehejeianu\u00bb. <\/p>\n<p>Asimismo, en algunas comunidades se acostumbr\u00f3 a conducirse con algunas normas de duelo. Los ashkenazim y algunos sefaradim y entre estos \u00faltimos los oriundos de Marruecos y de Djerba acostumbran a no cortarse el cabello durante las \u201cTres Semanas\u201d mientras que el resto de los sefarad\u00edes se abstienen \u00fanicamente a partir del inicio de la semana en que acaece el 9 de Av. <\/p>\n<p>Asimismo, en lo que respecta a la celebraci\u00f3n de bodas, los ashkenazim y los yemenitas as\u00ed como la mayor\u00eda de los sefarad\u00edes no contraen enlaces nupciales a lo largo de las \u201cTres Semanas\u201d mientras que los dem\u00e1s sefarad\u00edes son m\u00e1s flexibles al respecto y no realizan bodas solamente a partir del primer d\u00eda del mes de Av. (\u00eddem halaj\u00e1 7)<\/p>\n<p>A continuaci\u00f3n especificaremos y ampliaremos las costumbres de las \u201cTres Semanas\u201d que van del 17 de Tamuz al 9 de Av: las de  los primeros nueve d\u00edas de Av y las de la semana en la que cae el ayuno del 9 de Av.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las tres semanas que se inician en la noche del diecisiete del mes de Tamuz y se contin\u00faan hasta el nueve del mes de Av son d\u00edas de dolor, sobre los cuales est\u00e1 escrito en las Lamentaciones de Jerem\u00edas (Meguilat Eij\u00e1 1:3) \u00ab\u2026 (Iehud\u00e1) no hall\u00f3 descanso, todos sus perseguidores la alcanzaron entre las estrecheces\u00bb. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-276","post","type-post","status-publish","format-standard","hentry","category-05-08"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1 - Los d\u00edas de &quot;Bein Hameitzarim&quot; (\u201cEntre las estrecheces\u201d) - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/05-08-01\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1 - Los d\u00edas de &quot;Bein Hameitzarim&quot; (\u201cEntre las estrecheces\u201d) - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Las tres semanas que se inician en la noche del diecisiete del mes de Tamuz y se contin\u00faan hasta el nueve del mes de Av son d\u00edas de dolor, sobre los cuales est\u00e1 escrito en las Lamentaciones de Jerem\u00edas (Meguilat Eij\u00e1 1:3) \u00ab\u2026 (Iehud\u00e1) no hall\u00f3 descanso, todos sus perseguidores la alcanzaron entre las estrecheces\u00bb. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/05-08-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-05-07T22:00:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-13T09:44:52+00:00\" \/>\n<meta name=\"author\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-01\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-01\\\/\"},\"author\":{\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"headline\":\"1 &#8211; Los d\u00edas de \u00abBein Hameitzarim\u00bb (\u201cEntre las estrecheces\u201d)\",\"datePublished\":\"2000-05-07T22:00:08+00:00\",\"dateModified\":\"2015-05-13T09:44:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-01\\\/\"},\"wordCount\":419,\"articleSection\":[\"08 \u2013 Las costumbres de las \\\"Tres Semanas\\\"\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-01\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-01\\\/\",\"name\":\"1 - Los d\u00edas de \\\"Bein Hameitzarim\\\" (\u201cEntre las estrecheces\u201d) - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-05-07T22:00:08+00:00\",\"dateModified\":\"2015-05-13T09:44:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-01\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-01\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1 &#8211; Los d\u00edas de \u00abBein Hameitzarim\u00bb (\u201cEntre las estrecheces\u201d)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\",\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"caption\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/thfvhacvcss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1 - Los d\u00edas de \"Bein Hameitzarim\" (\u201cEntre las estrecheces\u201d) - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/05-08-01\/","og_locale":"es_ES","og_type":"article","og_title":"1 - Los d\u00edas de \"Bein Hameitzarim\" (\u201cEntre las estrecheces\u201d) - Pninei Halaj\u00e1","og_description":"Las tres semanas que se inician en la noche del diecisiete del mes de Tamuz y se contin\u00faan hasta el nueve del mes de Av son d\u00edas de dolor, sobre los cuales est\u00e1 escrito en las Lamentaciones de Jerem\u00edas (Meguilat Eij\u00e1 1:3) \u00ab\u2026 (Iehud\u00e1) no hall\u00f3 descanso, todos sus perseguidores la alcanzaron entre las estrecheces\u00bb. [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/05-08-01\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-05-07T22:00:08+00:00","article_modified_time":"2015-05-13T09:44:52+00:00","author":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/05-08-01\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-08-01\/"},"author":{"name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"headline":"1 &#8211; Los d\u00edas de \u00abBein Hameitzarim\u00bb (\u201cEntre las estrecheces\u201d)","datePublished":"2000-05-07T22:00:08+00:00","dateModified":"2015-05-13T09:44:52+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-08-01\/"},"wordCount":419,"articleSection":["08 \u2013 Las costumbres de las \"Tres Semanas\""],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/05-08-01\/","url":"https:\/\/ph.yhb.org.il\/es\/05-08-01\/","name":"1 - Los d\u00edas de \"Bein Hameitzarim\" (\u201cEntre las estrecheces\u201d) - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-05-07T22:00:08+00:00","dateModified":"2015-05-13T09:44:52+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-08-01\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/05-08-01\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/05-08-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"1 &#8211; Los d\u00edas de \u00abBein Hameitzarim\u00bb (\u201cEntre las estrecheces\u201d)"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178","name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","caption":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/thfvhacvcss\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=276"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/276\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}