{"id":306,"date":"2000-05-08T12:00:31","date_gmt":"2000-05-08T09:00:31","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=306"},"modified":"2015-05-13T12:46:20","modified_gmt":"2015-05-13T09:46:20","slug":"05-08-12","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/05-08-12\/","title":{"rendered":"12 &#8211; \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d."},"content":{"rendered":"<p>Dijeron nuestros sabios en la Mishn\u00e1 (Taanit 26:2): \u00abCuando comienza el mes de Av disminuye la alegr\u00eda\u00bb ya que son d\u00edas de luto por la destrucci\u00f3n del Templo de Jerusal\u00e9m. Por lo tanto no se deben llevar a cabo actividades que implican alegr\u00eda como lo son paseos, vacaciones en un hotel o encuentros de camarader\u00eda. Solamente eventos que tiene un objetivo primordialmente educativo o p\u00fablico est\u00e1n permitidos. Asimismo, quien est\u00e9 necesitado de un descanso por razones de salud puede salir en estos d\u00edas de vacaciones a un hotel o a alg\u00fan lugar de descanso (ver inciso 6).<\/p>\n<p>Se acostumbr\u00f3 a no preparar el telar para tejer en los nueve primeros d\u00edas de Av. Esta costumbre se fundament\u00f3 en el hecho de que con la destrucci\u00f3n del Templo fue profanada la piedra fundacional o \u00abEven Hashti\u00e1\u00bb que es el asiento del Santo Sanct\u00f3rum o Kodesh Kodashim, el sitio m\u00e1s sagrado del recinto templario donde reposaba el Arca del Pacto. (Esta piedra es en la tradici\u00f3n jud\u00eda el sitio donde se empez\u00f3 a crear el mundo, suerte de primer nudo del telar siendo en esta met\u00e1fora todo el universo una especie de gran tapiz N. de T.).<\/p>\n<p>Asimismo est\u00e1 prohibido coser ropas nuevas en los \u201cNueve D\u00edas\u201d as\u00ed como no se tejen vestimentas o kipot (solideos) (Shulj\u00e1n Aruj 551:7-8). Sin embargo est\u00e1 permitido reparar vestimentas usadas y quien se gana el sustento de la confecci\u00f3n de ropa o tejido de telas y le urge trabajar en estos nueve d\u00edas debe consultar una autoridad rab\u00ednica.<\/p>\n<p>Es preferible suspender un curso de costura en los nueve d\u00edas y en caso de necesidad se puede continuar en el mismo a condici\u00f3n de que no se confeccionen prendas nuevas sino que \u00fanicamente se reparen prendas usadas o se realicen ejercicios de costura sobre telas que ya no est\u00e1n en uso.<\/p>\n<p>Nuestros sabios dijeron que en estos d\u00edas se disminuyen los preparativos para  eventos alegres y es bueno reducir todas las actividades comerciales o profesionales. Nos abstenemos de construir y de plantar \u00e1rboles  si estas actividades tienen un car\u00e1cter alegre y las reglas espec\u00edficas las veremos en el inciso 18. <\/p>\n<p>Dado que en estos d\u00edas disminuimos la alegr\u00eda se acostumbra a no comer carne ni beber vino ya que la ingesti\u00f3n de estos productos causan alegr\u00eda.<\/p>\n<p>Por cuanto se trata de d\u00edas propensos a desgracias, nuestros sabios recomendaron  que quien tenga un pleito judicial con un no jud\u00edo busque la forma de no tener que comparecer ante los tribunales, ya que en estos d\u00edas la suerte del jud\u00edo es mala y se arriesga a perder el litigio (Shulj\u00e1n Aruj 551:1).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dijeron nuestros sabios en la Mishn\u00e1 (Taanit 26:2): \u00abCuando comienza el mes de Av disminuye la alegr\u00eda\u00bb ya que son d\u00edas de luto por la destrucci\u00f3n del Templo de Jerusal\u00e9m. Por lo tanto no se deben llevar a cabo actividades que implican alegr\u00eda como lo son paseos, vacaciones en un hotel o encuentros de camarader\u00eda. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-306","post","type-post","status-publish","format-standard","hentry","category-05-08"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12 - \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d. - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/05-08-12\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12 - \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d. - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Dijeron nuestros sabios en la Mishn\u00e1 (Taanit 26:2): \u00abCuando comienza el mes de Av disminuye la alegr\u00eda\u00bb ya que son d\u00edas de luto por la destrucci\u00f3n del Templo de Jerusal\u00e9m. Por lo tanto no se deben llevar a cabo actividades que implican alegr\u00eda como lo son paseos, vacaciones en un hotel o encuentros de camarader\u00eda. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/05-08-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-05-08T09:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-13T09:46:20+00:00\" \/>\n<meta name=\"author\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-12\\\/\"},\"author\":{\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"headline\":\"12 &#8211; \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d.\",\"datePublished\":\"2000-05-08T09:00:31+00:00\",\"dateModified\":\"2015-05-13T09:46:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-12\\\/\"},\"wordCount\":478,\"articleSection\":[\"08 \u2013 Las costumbres de las \\\"Tres Semanas\\\"\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-12\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-12\\\/\",\"name\":\"12 - \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d. - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-05-08T09:00:31+00:00\",\"dateModified\":\"2015-05-13T09:46:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-12\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-12\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-08-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12 &#8211; \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\",\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"caption\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/thfvhacvcss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12 - \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d. - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/05-08-12\/","og_locale":"es_ES","og_type":"article","og_title":"12 - \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d. - Pninei Halaj\u00e1","og_description":"Dijeron nuestros sabios en la Mishn\u00e1 (Taanit 26:2): \u00abCuando comienza el mes de Av disminuye la alegr\u00eda\u00bb ya que son d\u00edas de luto por la destrucci\u00f3n del Templo de Jerusal\u00e9m. Por lo tanto no se deben llevar a cabo actividades que implican alegr\u00eda como lo son paseos, vacaciones en un hotel o encuentros de camarader\u00eda. [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/05-08-12\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-05-08T09:00:31+00:00","article_modified_time":"2015-05-13T09:46:20+00:00","author":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/05-08-12\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-08-12\/"},"author":{"name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"headline":"12 &#8211; \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d.","datePublished":"2000-05-08T09:00:31+00:00","dateModified":"2015-05-13T09:46:20+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-08-12\/"},"wordCount":478,"articleSection":["08 \u2013 Las costumbres de las \"Tres Semanas\""],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/05-08-12\/","url":"https:\/\/ph.yhb.org.il\/es\/05-08-12\/","name":"12 - \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d. - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-05-08T09:00:31+00:00","dateModified":"2015-05-13T09:46:20+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-08-12\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/05-08-12\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/05-08-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"12 &#8211; \u201cAl iniciarse el mes de Av se disminuye la alegr\u00eda\u201d."}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178","name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","caption":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/thfvhacvcss\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=306"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/306\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}