{"id":3363,"date":"2014-04-01T00:01:44","date_gmt":"2014-03-31T21:01:44","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=3363"},"modified":"2019-01-14T13:13:51","modified_gmt":"2019-01-14T11:13:51","slug":"14-00-01","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/14-00-01\/","title":{"rendered":"Pr\u00f3logo del Rabino Eliezer Melamed"},"content":{"rendered":"<p><strong>1<\/strong><\/p>\n<p>Siguiendo el consejo de buenos amigos, este libro es publicado en una edici\u00f3n interna en virtud del delicado tenor de las cuestiones que se tratan en sus primeros cuatro cap\u00edtulos, temas que, por cuestiones vinculadas al recato, no se suelen estudiar p\u00fablicamente e incluso es posible que haya rabinos que se opongan a que a este libro se le de publicidad. Por esta raz\u00f3n esta obra no se publica en el marco de la serie \u00abPninei Halaj\u00e1\u00bb. Lo titul\u00e9 <strong>\u00abLa alegr\u00eda del hogar y su bendici\u00f3n\u00bb<\/strong> pues en \u00e9l se detallan las reglas del cumplimiento del precepto de On\u00e1 cuyo tema central es el de la alegr\u00eda tal como la denominaron nuestros sabios (Talmud Babilonio Tratado de <em>Pesajim<\/em> 72(B), <em>Avod\u00e1 Zar\u00e1<\/em> 5(A)): \u00abla alegr\u00eda de la On\u00e1\u00bb. \u00abEl hogar\u00bb es la familia y \u00absu bendici\u00f3n\u00bb el precepto de la procreaci\u00f3n que se analiza detalladamente en este libro y el cual se deriva del de On\u00e1.<\/p>\n<p>En un principio pens\u00e9 que si D\u00b4s quiere y tendr\u00e9 el m\u00e9rito alg\u00fan d\u00eda de explicar por escrito estas cuestiones lo har\u00e9 siendo ya un anciano, con la esperanza de que entonces me averg\u00fcence menos en publicarlo. Sin embargo, en los \u00faltimos a\u00f1os junto con mi esposa nos vimos expuestos a las carencias y los errores que a veces afectan a los cursos preparatorios para novios y novias, falencias que pueden llegar a causar problemas y dolor all\u00ed donde deben de reinar la alegr\u00eda y el amor. Generalmente estos cursos se extienden en los detalles referidos a las leyes de Nid\u00e1 y separaci\u00f3n durante el periodo menstrual y abrevian en cuanto a las reglas del precepto de On\u00e1. Mi se\u00f1ora compara esto a una muchacha joven que acude a lo de una se\u00f1ora mayor para que esta le ense\u00f1e a cocinar comida apropiada para el Shabat. La se\u00f1ora mayor le ense\u00f1a c\u00f3mo tamizar la harina y revisar que las verduras y las legumbres est\u00e9n libres de insectos, c\u00f3mo verificar que los huevos no tengan manchas de sangre, c\u00f3mo separar los utensilios de carne de los de leche as\u00ed como tambi\u00e9n los diferentes cuchillos y entre ellos el de la cebolla, c\u00f3mo evitar la cocci\u00f3n de alimentos por parte de no jud\u00edos, c\u00f3mo evitar los productos que contienen leche no supervisada o gelatina y tambi\u00e9n c\u00f3mo adquirir \u00fanicamente ingredientes con el m\u00e1ximo grado de certificaci\u00f3n de kashrut. Y no s\u00f3lo no le ense\u00f1a a cocinar alimentos sabrosos para deleitar con estos el Shabat, sino que adem\u00e1s la lleva a pensar err\u00f3neamente de que basta con que los alimentos sean kasher para que entonces el Shabat sea placentero; y que el hecho de que los ingredientes no est\u00e9n suficientemente cocidos y que los platillos no sepan bien no es problema ya que nuestro rol en el mundo es sufrir y santificar as\u00ed el Nombre de D\u00b4s. Hay gu\u00edas del curso para novias que ense\u00f1an que basta con cuidar las reglas de Nid\u00e1 y distanciamiento durante el per\u00edodo menstrual para que la casa se vea bendecida por la santidad, en lugar de comprender que la alegr\u00eda de la uni\u00f3n de la pareja mediante el precepto de On\u00e1 es la manifestaci\u00f3n de la santidad en la vida, mientras que las reglas de distanciamiento durante el per\u00edodo son la condici\u00f3n necesaria para el cumplimiento del precepto en s\u00ed.<\/p>\n<p>A ra\u00edz de este error surge una separaci\u00f3n terrible entre la santidad y la vida, la verdad y el bien, el deber y la alegr\u00eda, distanciamiento que debe ser reparado por medio del precepto de \u00abamar\u00e1s a tu pr\u00f3jimo como a ti mismo\u00bb en general y el de On\u00e1 en particular. Por ello, en el invierno de 5774 reun\u00ed las fuerzas y el valor necesarios para escribir las halajot o reglas as\u00ed como tambi\u00e9n el racional del precepto de On\u00e1, y a partir de estas continu\u00e9 aclarando y elaborando las reglas del precepto de procrear.<\/p>\n<p>No habr\u00e9 de ocultarles que muchos de mis maestros y amigos me aconsejaron abstenerme de escribir la presente obra o al menos de atenuar su significado. En su mayor\u00eda, el m\u00f3vil del consejo era una sincera preocupaci\u00f3n por mi persona, y en otros, por considerar que no corresponde comentar y explicar cuestiones que es mejor mantener en discreci\u00f3n. Empero, dado que en el seno del p\u00fablico circulan ideas equivocadas y rumores falsos que afectan el buen nombre de nuestra sagrada Tor\u00e1 al insinuar que esta promueve la reducci\u00f3n de la alegr\u00eda que resulta del cumplimiento del precepto de On\u00e1; me vi en la obligaci\u00f3n de presentar de un modo claro la postura de nuestra Tor\u00e1 y evitar las maledicencias de las que es v\u00edctima, salvando as\u00ed a las queridas parejas, hombres y mujeres, del dolor y las carencias que las posturas equivocadas provocan. Es oportuno se\u00f1alar que la mala fama que se le ha hecho a nuestra Tor\u00e1 se deriva de una mala comprensi\u00f3n de las ense\u00f1anzas de nuestros sabios de bendita memoria, de los pasajes del Zohar y las ense\u00f1anzas de los maestros kabalistas, la cual muchas veces se debe a una cierta influencia de la religi\u00f3n cristiana que ensalza a quien por apego religioso decide no casarse.<\/p>\n<p>A los efectos de desmentir esta mala fama deber\u00eda haber publicado este libro de manera abierta y para todo p\u00fablico empero me abstuve de hacerlo ante el temor de que los conceptos aqu\u00ed vertidos sean entendidos \u00fanicamente en su sentido exterior y de modo parcial por parte de quienes son ajenos al mundo del estudio de la Tor\u00e1 mientras que la intenci\u00f3n principal de la elaboraci\u00f3n de la presente obra es que sea le\u00edda en las casas de estudio (\u00abBatei Midrash\u00bb) por un p\u00fablico sagrado y recatado para que, por medio de la luz redentora que ingrese en sus hogares al seguir las directivas maritales de la Tor\u00e1, la santidad general del pueblo de Israel irrumpa cual aurora y su claridad se expanda paulatinamente resultando en un remedio y una salvaci\u00f3n para el mundo entero.<\/p>\n<p>Este libro est\u00e1 destinado en primer lugar para rabinos y gu\u00edas de novios y novias, mas tambi\u00e9n lo est\u00e1 para parejas que deseen que su vida familiar se vea iluminada por las directivas y la luz de la Tor\u00e1. De todas maneras, la distribuci\u00f3n del presente libro ser\u00e1 interna y se destinar\u00e1 principalmente a los miembros de la comunidad de Har Beraj\u00e1, a los alumnos de la Yeshiv\u00e1 y para las personas allegadas a nuestra localidad y nuestra casa de estudio. Si D\u00b4s quiere el contenido de este libro aparecer\u00e1 y se expandir\u00e1 poco a poco tal como lo hace la redenci\u00f3n del pueblo de Israel.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>2<\/strong><\/p>\n<p>Este es el lugar apropiado para agradecer al Rabino Maor Kayam Sheli\u00bbta, docente (\u00abRosh Metivta\u00bb) de la Yeshiv\u00e1 de Har Beraj\u00e1 quien me acompa\u00f1\u00f3 y apoy\u00f3 a lo largo de todo el proceso de elaboraci\u00f3n de la presente obra, y por medio de su laboriosidad y habilidad ampli\u00f3 de gran manera el espectro de las fuentes citadas. Esto ayud\u00f3 al an\u00e1lisis de los diferentes temas as\u00ed como tambi\u00e9n permiti\u00f3 sustentar con mayor solidez las explicaciones y las ideas principales. En el marco de su invaluable ayuda se ocup\u00f3 de compilar el libro de las ampliaciones que tiene por objetivo agregar fuentes y reflexiones a los contenidos expuestos en esta obra. Asimismo, he de agradecer al Rabino Barel Shevaj Sheli\u00bbta por haber ayudado tambi\u00e9n en la organizaci\u00f3n tem\u00e1tica de los temas de an\u00e1lisis.<\/p>\n<p>Debo agradecer tambi\u00e9n a los rabinos que tuvieron la gentileza de leer los primeros cap\u00edtulos y me obsequiaron sus observaciones: al Rabino Ioel Kat\u00e1n Sheli\u00bbta, mi mentor desde la temprana juventud quien junto a su mujer que es Rabanit y Ginec\u00f3loga se especializaron en la tem\u00e1tica del presente libro y aportaron su parte al mismo; al Rabino Iehosh\u00faa Shapira Sheli\u00bbta, Decano de la Yeshiv\u00e1 de Ramat Gan quien junto a su esposa orientan y preparan parejas para que transiten por la senda de la santidad y la alegr\u00eda superando diferentes dificultades que se presentan en la relaci\u00f3n marital; al Rabino Iehud\u00e1 Brandes Sheli\u00bbta, quien realiz\u00f3 observaciones tanto \u00fatiles como iluminadoras a los primeros cap\u00edtulos, am\u00e9n de impulsarme a escribir la presente obra sin esperar a la vejez trayendo como ejemplo al Rey Salom\u00f3n quien escribiera el Cantar de los Cantares de joven, Los Proverbios siendo ya adulto y El Eclesiast\u00e9s en su ancianidad (Shir Hashirim Rab\u00e1 1:10), haci\u00e9ndome entender que cada edad tiene su aporte \u00fanico y especial que no debe dejar de expresarse. Asimismo debo agradecer enormemente a mi hermano el Rabino Israel Melamed Sheli\u00bbta quien adem\u00e1s de su labor educativa se especializ\u00f3 en el \u00e1rea de asesor\u00eda de parejas con dificultades vinculadas al cumplimiento del precepto de On\u00e1, por lo que sus profundas y fundamentales observaciones fueron m\u00e1s que \u00fatiles en los primeros cuatro cap\u00edtulos.<\/p>\n<p>Debo agradecer tambi\u00e9n a los rabinos que ense\u00f1an en la Yeshiv\u00e1, quienes adem\u00e1s de repasar los cap\u00edtulos y hacer sus oportunas observaciones durante muchos a\u00f1os han estado preparando a los alumnos y a los egresados previo a su casamiento, por lo que tuvimos la oportunidad de analizar concienzudamente toda la tem\u00e1tica presentada en la presente obra. Agradezco al Rabino Id\u00f3 Alba Sheli\u00bbta por sus observaciones a los cap\u00edtulos que se enfocan en el precepto de la procreaci\u00f3n as\u00ed como tambi\u00e9n al Rabino Shmuel Ariel Sheli\u00bbta.<\/p>\n<p>Un especial agradecimiento al Rabino Ionadav Zar Sheli\u00bbta que ahond\u00f3 en la investigaci\u00f3n de las halajot y revis\u00f3 la totalidad del libro. Agradezco al Rabino Maor Horowitz Sheli\u00bbta que particip\u00f3 del an\u00e1lisis de los temas y se ocup\u00f3 de la revisi\u00f3n final del texto y su preparaci\u00f3n para la impresi\u00f3n. Al Rabino Netanel Rozenstein por escribir el \u00edndice onom\u00e1stico, al Rabino Yaakov Wainberger director general de la Yeshiv\u00e1 y a quienes le antecedieron en el ejercicio del cargo, a los Rabinos Yaakov Katz y Dudu Saada, a los responsables de la edici\u00f3n, la impresi\u00f3n y la distribuci\u00f3n Keren Fogel y Iojan\u00e1n Lisha.<\/p>\n<p>Finalmente quisiera agradecer a los queridos residentes de Har Beraj\u00e1 y a los egresados de la Yeshiv\u00e1 quienes me guiaron en la elaboraci\u00f3n de la presente obra por medio de sus consultas y el estudio conjunto de los hombres conmigo y las mujeres con mi se\u00f1ora. Respecto del contenido de este libro puede citarse la m\u00e1xima: \u00abMucho aprend\u00ed de mis maestros, de mis compa\u00f1eros m\u00e1s que de mis maestros y de mis alumnos m\u00e1s que de nadie\u00bb (Talmud Babilonio Tratado de <em>Ta\u00b4anit<\/em> 7(A)).<\/p>\n<p><strong>3<\/strong><\/p>\n<p>La relaci\u00f3n entre el Kadosh Bar\u00faj H\u00fa y el pueblo de Israel es ejemplificada por medio de la relaci\u00f3n entre un novio y una novia (adelante 1:5-6) y el pesar por la destrucci\u00f3n del Templo opac\u00f3 la alegr\u00eda en el interior de los hogares jud\u00edos (adelante 3:15). Conjuntamente con el proceso de reuni\u00f3n de\u00a0 las di\u00e1sporas y construcci\u00f3n de la tierra de Israel, se han abierto p\u00f3rticos de paz, alegr\u00eda y bendici\u00f3n ante las parejas que erigen su hogar sobre la base de la santidad.<\/p>\n<p>Quiera D\u00b4s que se cumplan en nosotros las palabras del profeta (Ishaiahu-Isa\u00edas 62:1-5): \u00ab<em>Por Si\u00f3n no guardar\u00e9 silencio, y por Jerusal\u00e9m no descansar\u00e9, hasta que salga su triunfo como resplandor y su salvaci\u00f3n como una antorcha que quema. Y las naciones ver\u00e1n tu triunfo y todos los reyes tu gloria. Y ser\u00e1s llamado por un nombre nuevo que pronunciar\u00e1 la boca del Eterno. Ser\u00e1 tambi\u00e9n una corona de belleza en la mano del Eterno y una diadema real en la mano abierta de tu D\u00b4s. No te reputar\u00e1n m\u00e1s abandonada, y a tu tierra no la considerar\u00e1n m\u00e1s desolada, sino que te llamar\u00e1n \u00abJeftz\u00ed Ba\u00bb (Mi deleite en ella) y a tu tierra \u00abBeul\u00e1\u00bb (casada, pose\u00edda) porque el Eterno se deleita en ti, y tu tierra ser\u00e1 pose\u00edda. Porque as\u00ed como un mancebo se desposa con una doncella, as\u00ed tu Constructor se desposar\u00e1 contigo, y como el novio se regocija sobre la novia, as\u00ed se regocijar\u00e1 tu D\u00b4s sobre ti<\/em>\u00ab. Entonces el precepto de On\u00e1 se cumplir\u00e1 de un modo \u00edntegro. <em>\u00abY te desposar\u00e9 conmigo por siempre. Si, te desposar\u00e9 en justicia y en rectitud, y en misericordia y en compasi\u00f3n. Y te desposar\u00e9 conmigo en fidelidad, y conocer\u00e1s al Eterno. Y suceder\u00e1 en aquel que Yo <strong>responder\u00e9<\/strong> <\/em>(\u00abE\u00b4en\u00e9\u00bb vocablo similar al de \u00abOn\u00e1\u00bb n. de t.)<em> dice el Eterno, <strong>responder\u00e9<\/strong> a los cielos, y ellos <strong>responder\u00e1n<\/strong> a la tierra, y la tierra <strong>responder\u00e1<\/strong> al trigo, y al vino, y al aceite, y ellos <strong>responder\u00e1n<\/strong> a Izre\u00b4el. Y la sembrar\u00e9 para m\u00ed en la tierra, y tendr\u00e9 compasi\u00f3n de ella, que hab\u00eda sido compadecida, y les dir\u00e9 a los que no hab\u00edan sido Mi pueblo: \u00b4Eres Mi pueblo\u00b4, y ellos contestar\u00e1n: \u00b4T\u00fa eres mi D\u00b4s<\/em>\u00b4\u00bb (Oshea-Oseas 2:18-25). Ojal\u00e1 que este peque\u00f1o libro pueda incrementar la alegr\u00eda y la bendici\u00f3n entre marido y mujer, de modo tal que no nos avergoncemos ni en este mundo ni en el venidero.<\/p>\n<p>Eliezer Melamed<\/p>\n<p>Siv\u00e1n 5774<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1 Siguiendo el consejo de buenos amigos, este libro es publicado en una edici\u00f3n interna en virtud del delicado tenor de las cuestiones que se tratan en sus primeros cuatro cap\u00edtulos, temas que, por cuestiones vinculadas al recato, no se suelen estudiar p\u00fablicamente e incluso es posible que haya rabinos que se opongan a que [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[132],"tags":[],"class_list":["post-3363","post","type-post","status-publish","format-standard","hentry","category-14-00"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00f3logo del Rabino Eliezer Melamed - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/14-00-01\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00f3logo del Rabino Eliezer Melamed - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"1 Siguiendo el consejo de buenos amigos, este libro es publicado en una edici\u00f3n interna en virtud del delicado tenor de las cuestiones que se tratan en sus primeros cuatro cap\u00edtulos, temas que, por cuestiones vinculadas al recato, no se suelen estudiar p\u00fablicamente e incluso es posible que haya rabinos que se opongan a que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/14-00-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-31T21:01:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-14T11:13:51+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/14-00-01\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/14-00-01\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"Pr\u00f3logo del Rabino Eliezer Melamed\",\"datePublished\":\"2014-03-31T21:01:44+00:00\",\"dateModified\":\"2019-01-14T11:13:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/14-00-01\\\/\"},\"wordCount\":2318,\"commentCount\":0,\"articleSection\":[\"Pr\u00f3logo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/14-00-01\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/14-00-01\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/14-00-01\\\/\",\"name\":\"Pr\u00f3logo del Rabino Eliezer Melamed - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2014-03-31T21:01:44+00:00\",\"dateModified\":\"2019-01-14T11:13:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/14-00-01\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/14-00-01\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/14-00-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00f3logo del Rabino Eliezer Melamed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00f3logo del Rabino Eliezer Melamed - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/14-00-01\/","og_locale":"es_ES","og_type":"article","og_title":"Pr\u00f3logo del Rabino Eliezer Melamed - Pninei Halaj\u00e1","og_description":"1 Siguiendo el consejo de buenos amigos, este libro es publicado en una edici\u00f3n interna en virtud del delicado tenor de las cuestiones que se tratan en sus primeros cuatro cap\u00edtulos, temas que, por cuestiones vinculadas al recato, no se suelen estudiar p\u00fablicamente e incluso es posible que haya rabinos que se opongan a que [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/14-00-01\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2014-03-31T21:01:44+00:00","article_modified_time":"2019-01-14T11:13:51+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/14-00-01\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/14-00-01\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"Pr\u00f3logo del Rabino Eliezer Melamed","datePublished":"2014-03-31T21:01:44+00:00","dateModified":"2019-01-14T11:13:51+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/14-00-01\/"},"wordCount":2318,"commentCount":0,"articleSection":["Pr\u00f3logo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/14-00-01\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/14-00-01\/","url":"https:\/\/ph.yhb.org.il\/es\/14-00-01\/","name":"Pr\u00f3logo del Rabino Eliezer Melamed - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2014-03-31T21:01:44+00:00","dateModified":"2019-01-14T11:13:51+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/14-00-01\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/14-00-01\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/14-00-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"Pr\u00f3logo del Rabino Eliezer Melamed"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/3363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=3363"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/3363\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=3363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=3363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=3363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}