{"id":3527,"date":"2000-04-04T00:04:37","date_gmt":"2000-04-03T22:04:37","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=3527"},"modified":"2019-02-10T11:57:13","modified_gmt":"2019-02-10T09:57:13","slug":"04-04-04","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/04-04-04\/","title":{"rendered":"04. Sitios que es necesario revisar"},"content":{"rendered":"<p>Deben ser revisados todos los dominios de un jud\u00edo en los que se tema pueda hallarse un \u201ckazait\u201d (29 gramos) de jametz. Por lo que se debe revisar tanto la cocina como el sal\u00f3n comedor. Lo mismo se har\u00e1 con las habitaciones, dep\u00f3sito o balc\u00f3n a los que se ingresa de vez en cuando portando jametz (<em>Shulj\u00e1n Aruj<\/em> 433:3-4).<\/p>\n<p>Los armarios de la ropa que no suelen ser utilizados durante las comidas no requieren ser revisados. Sin embargo, si hay ni\u00f1os peque\u00f1os en la casa los armarios deben ser revisados pues se teme que hayan jugado dentro de los armarios mientras sosten\u00edan jametz en sus manos o incluso pueden haber escondido all\u00ed jametz. En el caso de las partes altas de los armarios a las que los ni\u00f1os no alcanzan &#8211; no requieren ser revisados.<\/p>\n<p>Se deben revisar los autom\u00f3viles y tambi\u00e9n aquellos bolsos en los que a veces colocamos alimentos. En el caso de personas mayores que no suelen poner comida en sus bolsillos no precisan revisarlos. Sin embargo, es necesario revisar los bolsillos de los ni\u00f1os peque\u00f1os. Prendas que fueron lavadas antes de Pesaj y previo a su lavado sus bolsillos fueron vaciados &#8211; no requieren ser revisados en la noche del d\u00eda 14 de Nis\u00e1n (ver adelante halaj\u00e1 8). En el caso de quien carece de casa no debe recitar la bendici\u00f3n previa a la revisaci\u00f3n de su autom\u00f3vil o sus bolsillos pues nuestros sabios estipularon que se recite bendici\u00f3n \u00fanicamente por la revisaci\u00f3n de los hogares (<em>Kaf HaJa\u00edm<\/em> 433:91).<\/p>\n<p>En el caso de las escaleras de un edificio de apartamentos, estas son propiedad o est\u00e1n bajo la responsabilidad de todos los residentes y por lo tanto todos deben revisarlas, por lo que debe designar a alguien que lo haga. No es necesario revisar patios abiertos pues de haber all\u00ed jametz se puede asumir que los animales ya se lo comieron, pero si en este hay hoyos o espacios en los cuales pudo haber, debe ser revisado pues se teme que los animales no lo hayan encontrado y por lo tanto no se lo hayan comido. Asimismo, si se sabe que en el patio en cuesti\u00f3n hubo jametz en la noche del 14 es necesario revisarlo pues no se puede confiar en que los animales alcancen a comerlo hasta el mediod\u00eda (<em>Mishn\u00e1 Berur\u00e1<\/em> 433:27, seg\u00fan la opini\u00f3n de <em>Mekor Ja\u00edm<\/em>). Un balc\u00f3n que tiene cerca, aunque est\u00e9 abierto hacia el patio debe ser revisado. \u00c1reas abiertas a todo el p\u00fablico no necesitan ser revisadas ya que, aunque haya en estas jametz, no se incurre en prohibici\u00f3n alguna por cuanto que este no pertenece a un jud\u00edo espec\u00edfico y la prohibici\u00f3n de retener jametz aplica al dominio de un particular y no a los espacios p\u00fablicos (<em>Shulj\u00e1n Aruj<\/em> 445:3, <em>Mishn\u00e1 Berur\u00e1<\/em> 18, la regla referente a los botes de basura se explicar\u00e1 adelante 5:5).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deben ser revisados todos los dominios de un jud\u00edo en los que se tema pueda hallarse un \u201ckazait\u201d (29 gramos) de jametz. Por lo que se debe revisar tanto la cocina como el sal\u00f3n comedor. Lo mismo se har\u00e1 con las habitaciones, dep\u00f3sito o balc\u00f3n a los que se ingresa de vez en cuando portando [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[138],"tags":[],"class_list":["post-3527","post","type-post","status-publish","format-standard","hentry","category-04-04"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>04. Sitios que es necesario revisar - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/04-04-04\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"04. Sitios que es necesario revisar - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Deben ser revisados todos los dominios de un jud\u00edo en los que se tema pueda hallarse un \u201ckazait\u201d (29 gramos) de jametz. Por lo que se debe revisar tanto la cocina como el sal\u00f3n comedor. Lo mismo se har\u00e1 con las habitaciones, dep\u00f3sito o balc\u00f3n a los que se ingresa de vez en cuando portando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/04-04-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-04-03T22:04:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-10T09:57:13+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-04-04\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-04-04\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"04. Sitios que es necesario revisar\",\"datePublished\":\"2000-04-03T22:04:37+00:00\",\"dateModified\":\"2019-02-10T09:57:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-04-04\\\/\"},\"wordCount\":507,\"commentCount\":0,\"articleSection\":[\"04. La revisaci\u00f3n del jametz\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-04-04\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-04-04\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-04-04\\\/\",\"name\":\"04. Sitios que es necesario revisar - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-04-03T22:04:37+00:00\",\"dateModified\":\"2019-02-10T09:57:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-04-04\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-04-04\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-04-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"04. Sitios que es necesario revisar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"04. Sitios que es necesario revisar - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/04-04-04\/","og_locale":"es_ES","og_type":"article","og_title":"04. Sitios que es necesario revisar - Pninei Halaj\u00e1","og_description":"Deben ser revisados todos los dominios de un jud\u00edo en los que se tema pueda hallarse un \u201ckazait\u201d (29 gramos) de jametz. Por lo que se debe revisar tanto la cocina como el sal\u00f3n comedor. Lo mismo se har\u00e1 con las habitaciones, dep\u00f3sito o balc\u00f3n a los que se ingresa de vez en cuando portando [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/04-04-04\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-04-03T22:04:37+00:00","article_modified_time":"2019-02-10T09:57:13+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/04-04-04\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/04-04-04\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"04. Sitios que es necesario revisar","datePublished":"2000-04-03T22:04:37+00:00","dateModified":"2019-02-10T09:57:13+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/04-04-04\/"},"wordCount":507,"commentCount":0,"articleSection":["04. La revisaci\u00f3n del jametz"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/04-04-04\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/04-04-04\/","url":"https:\/\/ph.yhb.org.il\/es\/04-04-04\/","name":"04. Sitios que es necesario revisar - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-04-03T22:04:37+00:00","dateModified":"2019-02-10T09:57:13+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/04-04-04\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/04-04-04\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/04-04-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"04. Sitios que es necesario revisar"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/3527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=3527"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/3527\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=3527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=3527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=3527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}