{"id":3552,"date":"2000-04-05T00:01:23","date_gmt":"2000-04-04T22:01:23","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=3552"},"modified":"2019-02-10T12:07:54","modified_gmt":"2019-02-10T10:07:54","slug":"04-05-01","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/04-05-01\/","title":{"rendered":"01. La anulaci\u00f3n del jametz de noche y de d\u00eda"},"content":{"rendered":"<p>Tal como ya aprendimos (arriba 3:4) se cumple con el precepto de cesar el jametz de dos maneras: mediante la acci\u00f3n pr\u00e1ctica y mediante el pensamiento. El orden para la cesaci\u00f3n del jametz consiste en cuatro pasos: la revisaci\u00f3n del jametz y posteriormente su primera anulaci\u00f3n que se lleva a cabo en la noche del 14 de Nis\u00e1n, la eliminaci\u00f3n del jametz al d\u00eda siguiente y su posterior segunda anulaci\u00f3n. Habiendo ya estudiado las halajot de la revisaci\u00f3n del jametz pasemos a estudiar las correspondientes a su anulaci\u00f3n.<\/p>\n<p>Inmediatamente despu\u00e9s de la revisaci\u00f3n eliminamos el jametz de manera espiritual mediante la anulaci\u00f3n.\u00a0 A los efectos de simplificar esta labor se redact\u00f3 un formato de anulaci\u00f3n en idioma arameo pues fue compuesto en un tiempo en el cual las grandes masas jud\u00edas entend\u00edan \u00fanicamente esta lengua.<\/p>\n<p>Este es el formato de la anulaci\u00f3n (versi\u00f3n ashkenaz\u00ed): \u00abKol jamira Vejam\u00eda Deika Birshutei, Del\u00f3 Jazitei Udel\u00f3 Biartei, Livtil Ulehavei Hefker Keafra Deara\u00bb, que puede tambi\u00e9n ser recitado en hebreo: \u00abKol Jametz Useor Sheiesh Birshut\u00ed, Shel\u00f3 Reitiv Ushel\u00f3 Biartiv, Ibatel Vihi\u00e9 Keafar Haaretz\u00bb (\u00abTodo leudo o levadura que se encuentre en mi posesi\u00f3n y no lo haya visto y no lo haya eliminado que sea anulado y se transforme en polvo de la tierra\u00bb) \u00a0(En la versi\u00f3n sefarad\u00ed se recuerda solamente el jametz pues este incluye a la levadura. Asimismo, se recuerda solamente la cuesti\u00f3n de la anulaci\u00f3n pues esta incluye la renuncia a su propiedad, ver <em>Jaz\u00f3n Ovadi\u00e1<\/em> p. 32).<\/p>\n<p>Tras la eliminaci\u00f3n pr\u00e1ctica del jametz que tiene lugar en la ma\u00f1ana del d\u00eda 14 de Nis\u00e1n (tal como se vio en la halaj\u00e1 3) este vuelve a ser anulado. Si bien ya fue anulado el 14 por la noche tras la revisaci\u00f3n, esta primera anulaci\u00f3n se refiere a aquel jametz que pas\u00f3 desapercibido o que no se encontr\u00f3 al revisar, mientras que el jametz que se tiene la intenci\u00f3n de ingerir en la cena y en el desayuno no se puede anular pues es de importancia para nosotros. Adem\u00e1s, el jametz que encontramos tampoco es anulado porque tenemos la intenci\u00f3n de cesarlo a la ma\u00f1ana siguiente mediante su quemado. M\u00e1s aun, si tuvi\u00e9semos la intenci\u00f3n de anular por la noche el jametz que habremos de comer por la ma\u00f1ana esta ser\u00eda una demostraci\u00f3n de que en realidad se trat\u00f3 solamente de un formalismo y por lo tanto result\u00f3 in\u00fatil. Es as\u00ed como en la noche anulamos \u00fanicamente el jametz que no logramos encontrar en la revisaci\u00f3n y no aquel que guardamos para las comidas faltantes y para lo que ser\u00e1 quemado. Dado que es posible que hayamos pasado por alto u olvidado parte de este jametz, lo volvemos a anular por la ma\u00f1ana para no incurrir en las prohibiciones de haber pose\u00eddo y haber visto el jametz que poseemos. Es necesario tener el cuidado de anular el jametz hasta el final de la quinta hora, pues al entrar la sexta pasa a estar prohibido obtener beneficio de este y ya no es posible anularlo (<em>Shulj\u00e1n Aruj Oraj Ja\u00edm<\/em> 434:2).<\/p>\n<p>El formato de la anulaci\u00f3n de la ma\u00f1ana es levemente diferente al de la noche, pues en este \u00faltimo se anula solamente el jametz que no se encontr\u00f3 en la revisaci\u00f3n, mientras que en el matutino se anula todo el jametz por completo. Este es el texto de la anulaci\u00f3n de la ma\u00f1ana: \u00ab<em>Kol Jamir\u00e1 VaJami\u00e1 Deika Birshutei, Dejazitei Udel\u00f3 Jazitei, Debiartei Udel\u00f3 Biartei Libtil Ulehavei Hefker Keafra Deara<\/em>\u00ab. Su traducci\u00f3n al hebreo es: \u00ab<em>Kol Jametz Useor Sheiesh Birshut\u00ed, Shereitiv Ushelo Reitiv, Shebiartiv Ushel\u00f3 Biartiv, Ibatel Vihi\u00e9 Keafar Haaretz<\/em>\u00bb (\u00abTodo leudo o levadura que se encuentra en mi posesi\u00f3n, si lo vi o si no lo vi, si lo elimin\u00e9 o si no lo elimin\u00e9, que sea anulado y se transforme en polvo de la tierra\u00bb).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tal como ya aprendimos (arriba 3:4) se cumple con el precepto de cesar el jametz de dos maneras: mediante la acci\u00f3n pr\u00e1ctica y mediante el pensamiento. El orden para la cesaci\u00f3n del jametz consiste en cuatro pasos: la revisaci\u00f3n del jametz y posteriormente su primera anulaci\u00f3n que se lleva a cabo en la noche del [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[],"class_list":["post-3552","post","type-post","status-publish","format-standard","hentry","category-04-05"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>01. La anulaci\u00f3n del jametz de noche y de d\u00eda - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/04-05-01\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"01. La anulaci\u00f3n del jametz de noche y de d\u00eda - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Tal como ya aprendimos (arriba 3:4) se cumple con el precepto de cesar el jametz de dos maneras: mediante la acci\u00f3n pr\u00e1ctica y mediante el pensamiento. El orden para la cesaci\u00f3n del jametz consiste en cuatro pasos: la revisaci\u00f3n del jametz y posteriormente su primera anulaci\u00f3n que se lleva a cabo en la noche del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/04-05-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-04-04T22:01:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-10T10:07:54+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-05-01\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-05-01\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"01. La anulaci\u00f3n del jametz de noche y de d\u00eda\",\"datePublished\":\"2000-04-04T22:01:23+00:00\",\"dateModified\":\"2019-02-10T10:07:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-05-01\\\/\"},\"wordCount\":692,\"commentCount\":0,\"articleSection\":[\"05. La anulaci\u00f3n del jametz y su eliminaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-05-01\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-05-01\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-05-01\\\/\",\"name\":\"01. La anulaci\u00f3n del jametz de noche y de d\u00eda - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-04-04T22:01:23+00:00\",\"dateModified\":\"2019-02-10T10:07:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-05-01\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-05-01\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/04-05-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"01. La anulaci\u00f3n del jametz de noche y de d\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"01. La anulaci\u00f3n del jametz de noche y de d\u00eda - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/04-05-01\/","og_locale":"es_ES","og_type":"article","og_title":"01. La anulaci\u00f3n del jametz de noche y de d\u00eda - Pninei Halaj\u00e1","og_description":"Tal como ya aprendimos (arriba 3:4) se cumple con el precepto de cesar el jametz de dos maneras: mediante la acci\u00f3n pr\u00e1ctica y mediante el pensamiento. El orden para la cesaci\u00f3n del jametz consiste en cuatro pasos: la revisaci\u00f3n del jametz y posteriormente su primera anulaci\u00f3n que se lleva a cabo en la noche del [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/04-05-01\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-04-04T22:01:23+00:00","article_modified_time":"2019-02-10T10:07:54+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/04-05-01\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/04-05-01\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"01. La anulaci\u00f3n del jametz de noche y de d\u00eda","datePublished":"2000-04-04T22:01:23+00:00","dateModified":"2019-02-10T10:07:54+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/04-05-01\/"},"wordCount":692,"commentCount":0,"articleSection":["05. La anulaci\u00f3n del jametz y su eliminaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/04-05-01\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/04-05-01\/","url":"https:\/\/ph.yhb.org.il\/es\/04-05-01\/","name":"01. La anulaci\u00f3n del jametz de noche y de d\u00eda - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-04-04T22:01:23+00:00","dateModified":"2019-02-10T10:07:54+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/04-05-01\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/04-05-01\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/04-05-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"01. La anulaci\u00f3n del jametz de noche y de d\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/3552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=3552"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/3552\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=3552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=3552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=3552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}