{"id":3894,"date":"2000-10-02T02:00:43","date_gmt":"2000-10-01T23:00:43","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=3894"},"modified":"2020-01-16T13:26:11","modified_gmt":"2020-01-16T11:26:11","slug":"10-02-02","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/10-02-02\/","title":{"rendered":"02) La explicaci\u00f3n espiritual del precepto"},"content":{"rendered":"<p>Cuanto m\u00e1s esencial o indispensable es una acci\u00f3n para la persona, mayor es su influencia sobre ella tanto positiva como negativamente. Es por ello que en torno a la comida, un aspecto fundamental de la existencia humana, fueron legisladas numerosas halajot. Esto se debe a que la persona puede comer para obtener un placer moment\u00e1neo o para obtener las energ\u00edas necesarias para vivir una vida plena de contenido y significado. Todas las halajot que se dictaron sobre temas vinculados al comer apuntan a un solo objetivo: que el alimento potencie en nosotros buenas sensaciones y nos de fuerzas para elevarnos y dedicarnos a la reparaci\u00f3n del mundo, mas no nos haga caer en la baja pasi\u00f3n de la simple gula carente de todo contenido espiritual. Dado que el pan es el principal alimento humano nuestros sabios decretaron que lavemos nuestras manos antes de ingerirlo.<\/p>\n<p>La mayor parte de las acciones humanas se llevan a cabo por medio de las manos y de los dedos. Las manos tienen el poder de realizar acciones buenas y \u00fatiles, as\u00ed como tambi\u00e9n malas y perniciosas. Esto se manifiesta por su capacidad especial de movimiento, se las puede alzar por encima de la cabeza y tambi\u00e9n hacerlas descender. Las manos sostienen, tocan y palpan todo, y por ello pueden ensuciarse m\u00e1s que cualquier otro \u00f3rgano del cuerpo. Dado que el objetivo final de la comida es incrementar la fuerza y la vitalidad, abluimos nuestras manos de la impureza que se adhiri\u00f3 a estas por medio de las diferentes ocupaciones mundanas y las santificamos previo a comer, para poder extraer del alimento la vitalidad necesaria para una vida llena de valores.<\/p>\n<p>Sobre esto, nuestros sabios dijeron (Talmud Babilonio Tratado de <em>Sot\u00e1 <\/em>4(B)): \u00abTodo aquel que come pan sin abluir sus manos es como si copulase con una prostituta\u00bb. Tanto la comida como el amor entre un hombre y una mujer son esenciales para la existencia humana, y al igual que todo en esta vida, se lo puede realizar con santidad o, D\u00b4s no lo quiera, del modo inverso. As\u00ed como la Tor\u00e1 proh\u00edbe amar por medio de la prostituci\u00f3n y nos ordena hacerlo por medio del matrimonio (\u00abJup\u00e1 y Kidush\u00edn\u00bb), de igual manera nuestros sabios nos ordenaron que lavemos nuestras manos antes de comer para de esa forma purificar y santificar nuestra alimentaci\u00f3n. Empero quien come sin abluir sus manos se asemeja a quien come pan impuro, pues se remite \u00fanicamente al aspecto material del pan (Maharal de Praga, <em>Netiv HaAvod\u00e1<\/em> 16).<\/p>\n<p>El precepto de lavar las manos recae sobre todo aquel que come del pan, aunque no llegue a tocarlo con la mano y lo coma con cuchillo y tenedor o, aunque otra persona lo coloque directamente en su boca. Sin embargo, una persona que no se dispone a comer ella misma, aunque toque el pan para alimentar a otra persona- no precisa lavar sus manos. Esto se debe a que el decreto del lavado de manos est\u00e1 destinado a purificar y santificar a la persona previo a que esta coma y por ende debe abluir las manos \u00fanicamente aquel que se dispone a comer (<em>Shulj\u00e1n Aruj Oraj Ja\u00edm<\/em> 163:2).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuanto m\u00e1s esencial o indispensable es una acci\u00f3n para la persona, mayor es su influencia sobre ella tanto positiva como negativamente. Es por ello que en torno a la comida, un aspecto fundamental de la existencia humana, fueron legisladas numerosas halajot. Esto se debe a que la persona puede comer para obtener un placer moment\u00e1neo [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[],"class_list":["post-3894","post","type-post","status-publish","format-standard","hentry","category-10-02"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>02) La explicaci\u00f3n espiritual del precepto - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/10-02-02\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"02) La explicaci\u00f3n espiritual del precepto - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Cuanto m\u00e1s esencial o indispensable es una acci\u00f3n para la persona, mayor es su influencia sobre ella tanto positiva como negativamente. Es por ello que en torno a la comida, un aspecto fundamental de la existencia humana, fueron legisladas numerosas halajot. Esto se debe a que la persona puede comer para obtener un placer moment\u00e1neo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/10-02-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-10-01T23:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-16T11:26:11+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-02\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"02) La explicaci\u00f3n espiritual del precepto\",\"datePublished\":\"2000-10-01T23:00:43+00:00\",\"dateModified\":\"2020-01-16T11:26:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-02\\\/\"},\"wordCount\":545,\"commentCount\":0,\"articleSection\":[\"Cap\u00edtulo 02 - Lavado o abluci\u00f3n de manos previo a la comida\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-02\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-02\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-02\\\/\",\"name\":\"02) La explicaci\u00f3n espiritual del precepto - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-10-01T23:00:43+00:00\",\"dateModified\":\"2020-01-16T11:26:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-02\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-02\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"02) La explicaci\u00f3n espiritual del precepto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"02) La explicaci\u00f3n espiritual del precepto - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/10-02-02\/","og_locale":"es_ES","og_type":"article","og_title":"02) La explicaci\u00f3n espiritual del precepto - Pninei Halaj\u00e1","og_description":"Cuanto m\u00e1s esencial o indispensable es una acci\u00f3n para la persona, mayor es su influencia sobre ella tanto positiva como negativamente. Es por ello que en torno a la comida, un aspecto fundamental de la existencia humana, fueron legisladas numerosas halajot. Esto se debe a que la persona puede comer para obtener un placer moment\u00e1neo [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/10-02-02\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-10-01T23:00:43+00:00","article_modified_time":"2020-01-16T11:26:11+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/10-02-02\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/10-02-02\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"02) La explicaci\u00f3n espiritual del precepto","datePublished":"2000-10-01T23:00:43+00:00","dateModified":"2020-01-16T11:26:11+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/10-02-02\/"},"wordCount":545,"commentCount":0,"articleSection":["Cap\u00edtulo 02 - Lavado o abluci\u00f3n de manos previo a la comida"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/10-02-02\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/10-02-02\/","url":"https:\/\/ph.yhb.org.il\/es\/10-02-02\/","name":"02) La explicaci\u00f3n espiritual del precepto - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-10-01T23:00:43+00:00","dateModified":"2020-01-16T11:26:11+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/10-02-02\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/10-02-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/10-02-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"02) La explicaci\u00f3n espiritual del precepto"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/3894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=3894"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/3894\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=3894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=3894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=3894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}