{"id":3906,"date":"2000-10-02T08:00:29","date_gmt":"2000-10-02T05:00:29","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=3906"},"modified":"2020-01-16T13:32:55","modified_gmt":"2020-01-16T11:32:55","slug":"10-02-08","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/10-02-08\/","title":{"rendered":"08) El recipiente"},"content":{"rendered":"<p>El lavado que purifica las manos antes de la comida debe realizarse mediante un recipiente, emulando a los cohanim quienes santificaban sus manos y pies con agua proveniente del \u00abkior\u00bb que era un utensilio que conten\u00eda agua. De no mediar el uso de un recipiente, la abluci\u00f3n de manos no es v\u00e1lida. Por ejemplo, si una persona recoge agua en sus palmas y la vierte sobre las manos de su compa\u00f1ero este \u00faltimo no cumpli\u00f3 con su deber, por cuanto que en el lavado no medi\u00f3 un recipiente. Asimismo, quien llena una bolsa de nylon con agua y desde esta vierte agua sobre sus manos &#8211; no cumpli\u00f3 con su deber, por cuanto que la bolsa no es considerada un recipiente.<\/p>\n<p>El recipiente debe contener por lo menos un \u00abrevi\u00edt\u00bb (un huevo y medio que equivale a unos 75 ml.). Si el recipiente no posee esta capacidad no es apto para la acci\u00f3n de la abluci\u00f3n (<em>Shulj\u00e1n Aruj<\/em> 159:1).<\/p>\n<p>Un recipiente que est\u00e1 averiado o perforado, si al ser sumergido en l\u00edquido este puede ingresar a trav\u00e9s del orificio de la aver\u00eda (\u00abkon\u00e9s mashk\u00e9\u00bb) \u2013 no es apto para la acci\u00f3n de la abluci\u00f3n. Cuando el recipiente contiene en su interior agua y esta gotea de modo constante, sin dudas que esta aver\u00eda entra en la categor\u00eda de \u00abkon\u00e9s mashk\u00e9\u00bb, por lo que no es apto para ser usado en la abluci\u00f3n (<em>Shulj\u00e1n Aruj<\/em> 159:1, <em>Mishn\u00e1 Berur\u00e1<\/em> 7).<\/p>\n<p>Si el orificio de la aver\u00eda es m\u00e1s amplio y a trav\u00e9s de este sale agua en una cantidad que permite lavar las manos y hasta la altura del orificio el recipiente puede contener un volumen equivalente a un revi\u00edt, se podr\u00e1 realizar la abluci\u00f3n vertiendo el agua a trav\u00e9s del orificio (<em>Shulj\u00e1n Aruj<\/em> 159:2).<\/p>\n<p>De existir una quebradura en el borde del recipiente, este sigue siendo apto para realizar la abluci\u00f3n empero es necesario tener la precauci\u00f3n de verter el agua a trav\u00e9s del sitio donde el borde se quebr\u00f3, pues s\u00f3lo hasta la altura de la rotura el agua permanece dentro del recipiente sin fluir hacia afuera; lo que est\u00e1 por encima de la rotura, por cuanto que no puede retener el agua en su interior, no se lo considera recipiente y no es apto para la abluci\u00f3n. Asimismo, se permite lavar las manos vertiendo agua de una jarra que tiene una suerte de embudo o tubo estrecho de salida en su borde, empero si este tubo se encuentra en un sitio de la jarra m\u00e1s bajo que su borde habitual se debe verter el agua sobre las manos a trav\u00e9s del tubo. Asimismo, se permite verter agua sobre las manos desde una caldera o pava; sin embargo si el pico vertedor se encuentra m\u00e1s abajo que el resto del borde de la tapa, se deber\u00e1 necesariamente verter el agua sobre las manos desde el pico vertedor, pues la pava o caldera retiene agua solamente hasta esa altura (<em>Mishn\u00e1 Berur\u00e1<\/em> 159:24).<\/p>\n<p>Hay quienes dicen que, a priori, no se debe usar un vaso desechable de pl\u00e1stico o cart\u00f3n para abluir las manos, dado que no se lo considera como recipiente duradero ya que ser\u00e1 arrojado a la basura inmediatamente despu\u00e9s de ser utilizado. Sin embargo, en la pr\u00e1ctica, la opini\u00f3n mayoritaria de los juristas considera que no hace diferencia si se usa un recipiente una o varias veces, y dado que el vaso desechable es usado como recipiente pues se bebe de \u00e9l \u2013 se lo considera as\u00ed a los efectos de abluir las manos (<em>Tzitz Eliezer<\/em> 12:23). Sin embargo, a los efectos de cumplir el precepto con excelencia, es mejor usar siempre un mismo recipiente que no est\u00e9 destinado a ser arrojado a la basura (<em>Az Nidber\u00fa<\/em> 6:48, ver <em>Pninei Halaj\u00e1 Shabat<\/em> 5).<\/p>\n<p>Est\u00e1 permitido lavarse las manos vertiendo agua desde una botella y aunque esto lleve algo m\u00e1s de tiempo la demora no implica problema alguno. De ser posible, es mejor que el agua fluya de modo continuo hasta alcanzar a mojar la totalidad de la mano (<em>Mishn\u00e1 Berur\u00e1<\/em> 162:30, ver <em>Shaar Hatzi\u00fan<\/em> 27-28).<\/p>\n<p>De esta halaj\u00e1 se puede aprender que todo ideal, por encumbrado que sea requiere de un marco definido que permite su concreci\u00f3n. El agua representa el contenido y el recipiente el marco sin el cual el agua no puede purificar las manos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lavado que purifica las manos antes de la comida debe realizarse mediante un recipiente, emulando a los cohanim quienes santificaban sus manos y pies con agua proveniente del \u00abkior\u00bb que era un utensilio que conten\u00eda agua. De no mediar el uso de un recipiente, la abluci\u00f3n de manos no es v\u00e1lida. Por ejemplo, si [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[154],"tags":[],"class_list":["post-3906","post","type-post","status-publish","format-standard","hentry","category-10-02"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>08) El recipiente - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/10-02-08\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"08) El recipiente - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"El lavado que purifica las manos antes de la comida debe realizarse mediante un recipiente, emulando a los cohanim quienes santificaban sus manos y pies con agua proveniente del \u00abkior\u00bb que era un utensilio que conten\u00eda agua. De no mediar el uso de un recipiente, la abluci\u00f3n de manos no es v\u00e1lida. Por ejemplo, si [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/10-02-08\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-10-02T05:00:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-16T11:32:55+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-08\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-08\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"08) El recipiente\",\"datePublished\":\"2000-10-02T05:00:29+00:00\",\"dateModified\":\"2020-01-16T11:32:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-08\\\/\"},\"wordCount\":750,\"commentCount\":0,\"articleSection\":[\"Cap\u00edtulo 02 - Lavado o abluci\u00f3n de manos previo a la comida\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-08\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-08\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-08\\\/\",\"name\":\"08) El recipiente - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-10-02T05:00:29+00:00\",\"dateModified\":\"2020-01-16T11:32:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-08\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-08\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/10-02-08\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"08) El recipiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"08) El recipiente - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/10-02-08\/","og_locale":"es_ES","og_type":"article","og_title":"08) El recipiente - Pninei Halaj\u00e1","og_description":"El lavado que purifica las manos antes de la comida debe realizarse mediante un recipiente, emulando a los cohanim quienes santificaban sus manos y pies con agua proveniente del \u00abkior\u00bb que era un utensilio que conten\u00eda agua. De no mediar el uso de un recipiente, la abluci\u00f3n de manos no es v\u00e1lida. Por ejemplo, si [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/10-02-08\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-10-02T05:00:29+00:00","article_modified_time":"2020-01-16T11:32:55+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/10-02-08\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/10-02-08\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"08) El recipiente","datePublished":"2000-10-02T05:00:29+00:00","dateModified":"2020-01-16T11:32:55+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/10-02-08\/"},"wordCount":750,"commentCount":0,"articleSection":["Cap\u00edtulo 02 - Lavado o abluci\u00f3n de manos previo a la comida"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/10-02-08\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/10-02-08\/","url":"https:\/\/ph.yhb.org.il\/es\/10-02-08\/","name":"08) El recipiente - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-10-02T05:00:29+00:00","dateModified":"2020-01-16T11:32:55+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/10-02-08\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/10-02-08\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/10-02-08\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"08) El recipiente"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/3906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=3906"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/3906\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=3906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=3906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=3906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}