{"id":429,"date":"2000-05-12T02:00:11","date_gmt":"2000-05-11T23:00:11","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=429"},"modified":"2015-05-13T14:27:21","modified_gmt":"2015-05-13T11:27:21","slug":"05-12-02","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/05-12-02\/","title":{"rendered":"2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (\u00abmehadr\u00edn min hamehadr\u00edn\u00bb)."},"content":{"rendered":"<p>El precepto del encendido de velas de Januca, goza de un afecto popular especial. Normalmente existen dos niveles en el cumplimiento de mitzvot, el nivel b\u00e1sico y el cumplimiento con un nivel especial de excelencia (\u00ablemehadr\u00edn\u00bb). Sin embargo, en el encendido de las velas de Januca, existen tres niveles de cumplimiento: 1) el b\u00e1sico, 2) el nivel con un grado de excelencia y 3) con dos grados de excelencia. Aun as\u00ed, el Pueblo de Israel ha acostumbrado a cumplir el precepto en su nivel m\u00e1s alto.<\/p>\n<p>El deber b\u00e1sico es, que en cada hogar se encienda cada d\u00eda una vela para todos los miembros de la familia y mediante esta vela se recuerda y se publicita el milagro. Con un grado de excelencia (mehadr\u00edn) implica que se enciende en cada hogar cada d\u00eda una vela por cada miembro adulto de la familia. Si el n\u00facleo familiar cuenta con cuatro miembros adultos se encienden cada d\u00eda cuatro velas y de esta manera se expresa la participaci\u00f3n de todos y cada uno en el cumplimiento del precepto.<\/p>\n<p>El segundo grado de excelencia en el cumplimiento (\u00abmehadr\u00edn min hamehadr\u00edn\u00bb), implica que se encienden velas de acuerdo al n\u00famero de d\u00edas de la fiesta, suscit\u00e1ndose aqu\u00ed una discusi\u00f3n famosa entre los disc\u00edpulos de Hilel y los de Shamai. Los disc\u00edpulos de Shamai opinaban que el primer d\u00eda se deb\u00edan encender ocho velas, y de aqu\u00ed en adelante se reduc\u00eda el n\u00famero hasta que el \u00faltimo d\u00eda se encend\u00eda solamente una vela. De acuerdo a este m\u00e9todo, se encienden velas seg\u00fan el n\u00famero de d\u00edas de fiesta que restan por celebrar. Los disc\u00edpulos de Hilel opinaban que el primer d\u00eda hab\u00eda que encender una vela solamente y de ah\u00ed en m\u00e1s se iba agregando una cada d\u00eda, de acuerdo al n\u00famero de d\u00edas festivos que ya pasaron. De esta manera el primer d\u00eda se encend\u00eda una vela y el octavo ocho, expresando el aumento gradual de  la intensidad en el milagro, pues cada d\u00eda en que la menor\u00e1 era encendida de esa peque\u00f1a jarra inicial de aceite el milagro era m\u00e1s notorio. Adem\u00e1s, de esta manera se va aumentando en santidad de manera tal que el octavo d\u00eda, se llega al grado m\u00e1s elevado con el encendido de ocho velas (Tratado de Shabat 21(B)). El pueblo de Israel todo acostumbr\u00f3 a encender con dos niveles de excelencia, \u00abmehadr\u00edn min hamehadr\u00edn\u00bb seg\u00fan la opini\u00f3n de los disc\u00edpulos de Hilel (Shulj\u00e1n Aruj Oraj Ja\u00edm 671(2)). <\/p>\n<p>En la pr\u00e1ctica se enciende un total de treinta y seis velas en ocho d\u00edas. Adem\u00e1s, es costumbre encender todos los d\u00edas una vela extra, el \u00abshamash\u00bb o vela utilitaria, a los efectos de que si se necesita luz, se use esa vela, ya que est\u00e1 prohibido obtener provecho de las velas de Januca. Empero el \u00abshamash\u00bb est\u00e1 separado del resto de las velas, ya que la l\u00f3gica de cumplir el precepto con dos grados de excelencia, es que se note con claridad el n\u00famero exacto de candelas que corresponde al d\u00eda espec\u00edfico, pues as\u00ed se expresa el car\u00e1cter \u00abin crescendo\u00bb del milagro (se ver\u00e1 m\u00e1s detalladamente en los incisos 10 y 11).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El precepto del encendido de velas de Januca, goza de un afecto popular especial. Normalmente existen dos niveles en el cumplimiento de mitzvot, el nivel b\u00e1sico y el cumplimiento con un nivel especial de excelencia (\u00ablemehadr\u00edn\u00bb). Sin embargo, en el encendido de las velas de Januca, existen tres niveles de cumplimiento: 1) el b\u00e1sico, 2) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-429","post","type-post","status-publish","format-standard","hentry","category-05-12"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (&quot;mehadr\u00edn min hamehadr\u00edn&quot;). - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/05-12-02\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (&quot;mehadr\u00edn min hamehadr\u00edn&quot;). - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"El precepto del encendido de velas de Januca, goza de un afecto popular especial. Normalmente existen dos niveles en el cumplimiento de mitzvot, el nivel b\u00e1sico y el cumplimiento con un nivel especial de excelencia (\u00ablemehadr\u00edn\u00bb). Sin embargo, en el encendido de las velas de Januca, existen tres niveles de cumplimiento: 1) el b\u00e1sico, 2) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/05-12-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-05-11T23:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-05-13T11:27:21+00:00\" \/>\n<meta name=\"author\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-12-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-12-02\\\/\"},\"author\":{\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"headline\":\"2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (\u00abmehadr\u00edn min hamehadr\u00edn\u00bb).\",\"datePublished\":\"2000-05-11T23:00:11+00:00\",\"dateModified\":\"2015-05-13T11:27:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-12-02\\\/\"},\"wordCount\":597,\"articleSection\":[\"12 - El encendido de las velas de Januca.\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-12-02\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-12-02\\\/\",\"name\":\"2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (\\\"mehadr\u00edn min hamehadr\u00edn\\\"). - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-05-11T23:00:11+00:00\",\"dateModified\":\"2015-05-13T11:27:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-12-02\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-12-02\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/05-12-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (\u00abmehadr\u00edn min hamehadr\u00edn\u00bb).\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\",\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"caption\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/thfvhacvcss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (\"mehadr\u00edn min hamehadr\u00edn\"). - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/05-12-02\/","og_locale":"es_ES","og_type":"article","og_title":"2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (\"mehadr\u00edn min hamehadr\u00edn\"). - Pninei Halaj\u00e1","og_description":"El precepto del encendido de velas de Januca, goza de un afecto popular especial. Normalmente existen dos niveles en el cumplimiento de mitzvot, el nivel b\u00e1sico y el cumplimiento con un nivel especial de excelencia (\u00ablemehadr\u00edn\u00bb). Sin embargo, en el encendido de las velas de Januca, existen tres niveles de cumplimiento: 1) el b\u00e1sico, 2) [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/05-12-02\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-05-11T23:00:11+00:00","article_modified_time":"2015-05-13T11:27:21+00:00","author":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/05-12-02\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-12-02\/"},"author":{"name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"headline":"2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (\u00abmehadr\u00edn min hamehadr\u00edn\u00bb).","datePublished":"2000-05-11T23:00:11+00:00","dateModified":"2015-05-13T11:27:21+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-12-02\/"},"wordCount":597,"articleSection":["12 - El encendido de las velas de Januca."],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/05-12-02\/","url":"https:\/\/ph.yhb.org.il\/es\/05-12-02\/","name":"2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (\"mehadr\u00edn min hamehadr\u00edn\"). - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-05-11T23:00:11+00:00","dateModified":"2015-05-13T11:27:21+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/05-12-02\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/05-12-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/05-12-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"2- El n\u00famero de velas y la costumbre de cumplir con dos grados de excelencia (\u00abmehadr\u00edn min hamehadr\u00edn\u00bb)."}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178","name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","caption":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/thfvhacvcss\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=429"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/429\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}