{"id":4789,"date":"2000-12-03T00:04:28","date_gmt":"2000-12-02T22:04:28","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=4789"},"modified":"2021-04-19T11:01:13","modified_gmt":"2021-04-19T08:01:13","slug":"12-03-04","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/12-03-04\/","title":{"rendered":"04 &#8211; El permiso de realizar labores es s\u00f3lo para Yom Tov"},"content":{"rendered":"<p>Todas las labores que fueron autorizadas en Yom Tov, fueron permitidas para los menesteres festivos, pero seg\u00fan la Tor\u00e1 est\u00e1 prohibido realizar en Yom Tov labores para los menesteres de los d\u00edas comunes. Por lo tanto, quien cocina poco antes de que concluya el Yom Tov de modo tal que el platillo preparado no habr\u00e1 de estar listo para su ingesti\u00f3n durante la festividad \u2013 transgrede una prohibici\u00f3n de la Tor\u00e1, ya que cocin\u00f3 en Yom Tov para los d\u00edas de la semana. Si esa comida en cuesti\u00f3n estar\u00e1 lista para su ingesti\u00f3n antes de la conclusi\u00f3n de la festividad \u2013 no se habr\u00e1 transgredido la prohibici\u00f3n de la Tor\u00e1, ya que en caso de que llegaran invitados podr\u00edan comerlo en Yom Tov, por lo que no se tiene la certeza de que lo cocido sea para los d\u00edas de la semana. Sin embargo, dado que se ten\u00eda la intenci\u00f3n de que lo cocinado sea para la semana \u2013 se habr\u00e1 transgredido una prohibici\u00f3n rab\u00ednica (Talmud Babilonio Tratado de <em>Beitz\u00e1 <\/em>17(A), <em>Rab\u00e1 BePesajim<\/em> 46:2, <em>Shulj\u00e1n Aruj<\/em> 503:1).<\/p>\n<p>Est\u00e1 tambi\u00e9n prohibido cocinar en Yom Tov para Shabat, empero los sabios permitieron hacerlo por medio de un <em>Eruv Tavshil\u00edn<\/em> (lit. \u00abFusi\u00f3n de comidas o platillos\u00bb) tal como se explicar\u00e1 adelante (8:1).<\/p>\n<p>Est\u00e1 tambi\u00e9n prohibido realizar en Yom Tov acciones para la semana o para Shabat que conlleven esfuerzo, aunque no impliquen la realizaci\u00f3n de labores, tal como poner la mesa y lavar platos (tal como se explica en <em>Pninei Halaj\u00e1 Shabat<\/em> 22:15-16).<\/p>\n<p>Quien desee preparar milanesas o <em>schnitzel<\/em> para la comida festiva puede preparar de m\u00e1s para asegurarse que no falte y el sobrante podr\u00e1 ingerirse al d\u00eda siguiente. Sin embargo, est\u00e1 prohibido preparar a priori porciones para que queden para el d\u00eda siguiente.<\/p>\n<p>Quien desee calentar agua para beber un vaso, puede llenar una olla para que quede agua caliente para la noche. Asimismo, quien desee cocinar puede preparar una olla grande para que le sobre alimento para la noche, por cuanto que al colocarla sobre el fuego de una vez &#8211; no est\u00e1 prohibido agregar comida. En un caso as\u00ed deber\u00e1 cuidar de no decir que agrega alimentos para que quede para los d\u00edas de la semana. Una vez colocada la olla sobre el fuego estar\u00e1 prohibido agregar cualquier cosa para los d\u00edas de la semana (<em>Shulj\u00e1n Aruj<\/em> 503:2, <em>Mishn\u00e1 Berur\u00e1<\/em> 15).<\/p>\n<p>En el caso de un platillo que se sabe que agregarle m\u00e1s carne o pescado mejora su sabor, aunque ya haya sido puesto sobre el fuego &#8211; estar\u00e1 permitido hacerlo. Si bien la intenci\u00f3n central es la de ingerir estos trozos agregados durante la semana &#8211; se permite agregar porque en la pr\u00e1ctica se desea el mejoramiento del platillo para su ingesti\u00f3n en Yom Tov (<em>Shulj\u00e1n Aruj<\/em> 503:1, <em>Mishn\u00e1 Berur\u00e1<\/em> 6) (Ver adelante 8:5 respecto del caso de quien olvid\u00f3 colocar \u00abEruv Tavshil\u00edn\u00bb, qu\u00e9 alimento le est\u00e1 permitido agregar a la olla en Yom Tov).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todas las labores que fueron autorizadas en Yom Tov, fueron permitidas para los menesteres festivos, pero seg\u00fan la Tor\u00e1 est\u00e1 prohibido realizar en Yom Tov labores para los menesteres de los d\u00edas comunes. Por lo tanto, quien cocina poco antes de que concluya el Yom Tov de modo tal que el platillo preparado no habr\u00e1 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[195],"tags":[],"class_list":["post-4789","post","type-post","status-publish","format-standard","hentry","category-12-03"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>04 - El permiso de realizar labores es s\u00f3lo para Yom Tov - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/12-03-04\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"04 - El permiso de realizar labores es s\u00f3lo para Yom Tov - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Todas las labores que fueron autorizadas en Yom Tov, fueron permitidas para los menesteres festivos, pero seg\u00fan la Tor\u00e1 est\u00e1 prohibido realizar en Yom Tov labores para los menesteres de los d\u00edas comunes. Por lo tanto, quien cocina poco antes de que concluya el Yom Tov de modo tal que el platillo preparado no habr\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/12-03-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-12-02T22:04:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-19T08:01:13+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-04\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-04\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"04 &#8211; El permiso de realizar labores es s\u00f3lo para Yom Tov\",\"datePublished\":\"2000-12-02T22:04:28+00:00\",\"dateModified\":\"2021-04-19T08:01:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-04\\\/\"},\"wordCount\":521,\"commentCount\":0,\"articleSection\":[\"03 - Reglas relativas a las labores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-04\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-04\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-04\\\/\",\"name\":\"04 - El permiso de realizar labores es s\u00f3lo para Yom Tov - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-12-02T22:04:28+00:00\",\"dateModified\":\"2021-04-19T08:01:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-04\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-04\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"04 &#8211; El permiso de realizar labores es s\u00f3lo para Yom Tov\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"04 - El permiso de realizar labores es s\u00f3lo para Yom Tov - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/12-03-04\/","og_locale":"es_ES","og_type":"article","og_title":"04 - El permiso de realizar labores es s\u00f3lo para Yom Tov - Pninei Halaj\u00e1","og_description":"Todas las labores que fueron autorizadas en Yom Tov, fueron permitidas para los menesteres festivos, pero seg\u00fan la Tor\u00e1 est\u00e1 prohibido realizar en Yom Tov labores para los menesteres de los d\u00edas comunes. Por lo tanto, quien cocina poco antes de que concluya el Yom Tov de modo tal que el platillo preparado no habr\u00e1 [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/12-03-04\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-12-02T22:04:28+00:00","article_modified_time":"2021-04-19T08:01:13+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/12-03-04\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/12-03-04\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"04 &#8211; El permiso de realizar labores es s\u00f3lo para Yom Tov","datePublished":"2000-12-02T22:04:28+00:00","dateModified":"2021-04-19T08:01:13+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/12-03-04\/"},"wordCount":521,"commentCount":0,"articleSection":["03 - Reglas relativas a las labores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/12-03-04\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/12-03-04\/","url":"https:\/\/ph.yhb.org.il\/es\/12-03-04\/","name":"04 - El permiso de realizar labores es s\u00f3lo para Yom Tov - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-12-02T22:04:28+00:00","dateModified":"2021-04-19T08:01:13+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/12-03-04\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/12-03-04\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/12-03-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"04 &#8211; El permiso de realizar labores es s\u00f3lo para Yom Tov"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/4789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=4789"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/4789\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=4789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=4789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=4789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}