{"id":4797,"date":"2000-12-03T00:08:44","date_gmt":"2000-12-02T22:08:44","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=4797"},"modified":"2021-04-19T11:04:15","modified_gmt":"2021-04-19T08:04:15","slug":"12-03-08","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/12-03-08\/","title":{"rendered":"08 &#8211; Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov"},"content":{"rendered":"<p>El fundamento del permiso para realizar labores en Yom Tov radica en que estas tienen por cometido preparar alimentos sabrosos que alegren la fiesta. Esto se debe a que no es igual el sabor del pan que sale caliente del horno y el de aquel que fue horneado el d\u00eda anterior. No se asemeja el sabor de una milanesa o <em>schnitzel<\/em> frito o de papas al horno que se preparan en el d\u00eda con el de aquellos preparados el d\u00eda anterior. Tambi\u00e9n los guisos que fueron cocidos en el d\u00eda saben mejor que los cocidos el d\u00eda anterior. Dado que se permite preparar alimentos en Yom Tov para intensificar as\u00ed la alegr\u00eda festiva, no es necesario tratar de prepararlos en el d\u00eda de la v\u00edspera. Asimismo, se permite tambi\u00e9n cocinar en la noche de Yom Tov para la cena festiva a pesar de que si los alimentos hubiesen sido cocinados en la v\u00edspera poco antes de comenzar la festividad los platillos sabr\u00edan pr\u00e1cticamente igual de bien. Esto obedece a que no se diferencia entre las comidas, y todo alimento cuyo sabor es mejor si es preparado contiguamente a la festividad \u2013 est\u00e1 permitido cocinarlo en Yom Tov. Incluso hoy d\u00eda que poseemos refrigeradores que nos permiten mantener lo cocido u horneado en buen estado, el permiso de cocinar en Yom Tov se mantiene en pie ya que los alimentos mismos, de no mediar la influencia exterior de diversos aparatos o utensilios, saben mejor si son cocinados poco antes de la comida festiva.<\/p>\n<p>Todo esto se refiere a alimentos cuyo sabor se ve perjudicado en cierto grado si son cocinados el d\u00eda anterior, empero aquellos cuyo sabor no empeora con el pasar de un d\u00eda \u2013 deben ser preparados en la v\u00edspera de la festividad. Por ejemplo, quien desee comer helado o frutas cocidas (compota) en Yom Tov, dado que su sabor no se estropea en absoluto &#8211; deben ser preparados en la v\u00edspera de la festividad. En caso de no haber preparado estos platillos en la v\u00edspera de Yom Tov &#8211; podr\u00e1 hacerlo durante la festividad, empero mediando alguna modificaci\u00f3n (<em>shinui<\/em>). Este cambio no tiene que ser de magnitud, ya que su cometido es el de recordarnos que el d\u00eda es festivo y evitar que realicemos labores prohibidas (<em>Levush<\/em> 504:1). Por ejemplo, si alguien acostumbra preparar los alimentos sobre una determinada mesa, podr\u00e1 realizar un cambio extendiendo sobre esta un mantel o una bandeja y cocinar sobre ellos. Quien no pudo preparar estos alimentos en la v\u00edspera de Yom Tov por causas de fuerza mayor podr\u00e1 prepararlos en Yom Tov sin que medie cambio alguno (<em>Mishn\u00e1 Berur\u00e1<\/em> 495:10, <em>Shaar Hatzi\u00fan<\/em> 8).<\/p>\n<p>Esta es tambi\u00e9n la norma a aplicar respecto de la labor de seleccionar (<em>Borer<\/em>) o las otras labores permitidas con la finalidad de preparar alimentos para la comida festiva (<em>ojel nefesh<\/em>), todo aquello que se pueda realizar en la v\u00edspera de Yom Tov sin que implique afectar el alimento &#8211; debe ser hecho entonces. En caso de no haberse realizado la labor en cuesti\u00f3n en la v\u00edspera de Yom Tov &#8211; se permite realizarla en Yom Tov por medio de un cambio (<em>shinui<\/em>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fundamento del permiso para realizar labores en Yom Tov radica en que estas tienen por cometido preparar alimentos sabrosos que alegren la fiesta. Esto se debe a que no es igual el sabor del pan que sale caliente del horno y el de aquel que fue horneado el d\u00eda anterior. No se asemeja el [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[195],"tags":[],"class_list":["post-4797","post","type-post","status-publish","format-standard","hentry","category-12-03"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>08 - Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/12-03-08\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"08 - Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"El fundamento del permiso para realizar labores en Yom Tov radica en que estas tienen por cometido preparar alimentos sabrosos que alegren la fiesta. Esto se debe a que no es igual el sabor del pan que sale caliente del horno y el de aquel que fue horneado el d\u00eda anterior. No se asemeja el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/12-03-08\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-12-02T22:08:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-19T08:04:15+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-08\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-08\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"08 &#8211; Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov\",\"datePublished\":\"2000-12-02T22:08:44+00:00\",\"dateModified\":\"2021-04-19T08:04:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-08\\\/\"},\"wordCount\":560,\"commentCount\":0,\"articleSection\":[\"03 - Reglas relativas a las labores\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-08\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-08\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-08\\\/\",\"name\":\"08 - Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-12-02T22:08:44+00:00\",\"dateModified\":\"2021-04-19T08:04:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-08\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-08\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-03-08\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"08 &#8211; Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"08 - Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/12-03-08\/","og_locale":"es_ES","og_type":"article","og_title":"08 - Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov - Pninei Halaj\u00e1","og_description":"El fundamento del permiso para realizar labores en Yom Tov radica en que estas tienen por cometido preparar alimentos sabrosos que alegren la fiesta. Esto se debe a que no es igual el sabor del pan que sale caliente del horno y el de aquel que fue horneado el d\u00eda anterior. No se asemeja el [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/12-03-08\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-12-02T22:08:44+00:00","article_modified_time":"2021-04-19T08:04:15+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/12-03-08\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/12-03-08\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"08 &#8211; Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov","datePublished":"2000-12-02T22:08:44+00:00","dateModified":"2021-04-19T08:04:15+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/12-03-08\/"},"wordCount":560,"commentCount":0,"articleSection":["03 - Reglas relativas a las labores"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/12-03-08\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/12-03-08\/","url":"https:\/\/ph.yhb.org.il\/es\/12-03-08\/","name":"08 - Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-12-02T22:08:44+00:00","dateModified":"2021-04-19T08:04:15+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/12-03-08\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/12-03-08\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/12-03-08\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"08 &#8211; Alimentos que pudieron haber sido preparados en la v\u00edspera de Yom Tov"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/4797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=4797"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/4797\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=4797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=4797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=4797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}