{"id":4804,"date":"2000-12-04T00:01:37","date_gmt":"2000-12-03T22:01:37","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=4804"},"modified":"2021-04-19T11:09:06","modified_gmt":"2021-04-19T08:09:06","slug":"12-04-01","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/12-04-01\/","title":{"rendered":"01 &#8211; Cosechar (<em>Kotzer<\/em>), trillar (<em>Dash<\/em>) y exprimir (<em>Sojet<\/em>)"},"content":{"rendered":"<p>La labor de cosechar consiste en desprender o separar algo de su fuente vital, y dado que solemos realizar esta acci\u00f3n como necesaria para un tiempo prolongado, se trata de una \u00abobra de trabajo\u00bb (<em>melejet avod\u00e1<\/em>) y est\u00e1 prohibido llevarla a cabo tanto en Yom Tov como en Shabat, e incluso se proh\u00edbe cortar un par de frutas del \u00e1rbol para ser comidas en la comida de Yom Tov.<\/p>\n<p>La labor de trillar consiste en separar los granos de trigo de las espigas y asimismo incluye toda acci\u00f3n similar como, por ejemplo, separar arvejas desgranadas o ch\u00edcharos de sus vainas. Esta labor suele ser realizada por medio de una herramienta tanto sea en el campo como en la f\u00e1brica, y dado que se acostumbra efectuar en vol\u00famenes importantes se trata de una \u00abobra de trabajo\u00bb, cuya realizaci\u00f3n se proh\u00edbe incluso en Yom Tov aunque est\u00e9 destinada a la preparaci\u00f3n de la comida festiva.<\/p>\n<p>Sin embargo, cuando la labor de separar granos de la vaina se lleva a cabo manualmente resulta imposible hacerlo en gran escala y no se trata de una \u00abobra de trabajo\u00bb por lo que est\u00e1 permitido hacerlo en Yom Tov. Por lo tanto, se permite separar manualmente los granos de trigo, arvejas (ch\u00edcharos o guisantes), porotos o frijoles de sus vainas sin que sea necesario realizarlo de un modo diferente al habitual (<em>shinui<\/em>) sino que es posible hacerlo de la manera m\u00e1s c\u00f3moda posible.<\/p>\n<p>Una derivaci\u00f3n de la labor de trillar es la de <em>mefarek<\/em> o \u00abseparar\u00bb que implica extraer una cosa de la otra. En el marco de esta labor se proh\u00edbe exprimir uvas para elaborar vino o aceitunas para obtener aceite, o sea, extraer una bebida de un alimento. Dado que esta labor se realiza para un tiempo prolongado, entra en la categor\u00eda de \u00abobra de trabajo\u00bb y est\u00e1 prohibido efectuarla tanto en Yom Tov como en Shabat y todos los pormenores de sus leyes son id\u00e9nticas a la normativa que en Shabat. Pasemos a enumerarlas brevemente: Est\u00e1 prohibido exprimir frutas para obtener una bebida, pero se permite exprimir un lim\u00f3n sobre una ensalada o un trozo de pescado, dado que al exprimirlo no se crea una bebida, sino que las gotas que dejan la fruta pasan inmediatamente al interior de otro alimento como lo son la ensalada o el pescado (<em>Pnniei Halaj\u00e1 Shabat<\/em> 12:8). Asimismo, se proh\u00edbe orde\u00f1ar una vaca por tratarse de esta misma labor (\u00eddem 20:4) y las reglas que rigen para esta acci\u00f3n en Shabat son id\u00e9nticas a las que aplican para Yom Tov (<em>Shulj\u00e1n Aruj<\/em> 505:1. Ver <em>Pninei Halaj\u00e1 Shabat<\/em> 11:17, 28:7).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La labor de cosechar consiste en desprender o separar algo de su fuente vital, y dado que solemos realizar esta acci\u00f3n como necesaria para un tiempo prolongado, se trata de una \u00abobra de trabajo\u00bb (melejet avod\u00e1) y est\u00e1 prohibido llevarla a cabo tanto en Yom Tov como en Shabat, e incluso se proh\u00edbe cortar un [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[196],"tags":[],"class_list":["post-4804","post","type-post","status-publish","format-standard","hentry","category-12-04"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>01 - Cosechar (Kotzer), trillar (Dash) y exprimir (Sojet) - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/12-04-01\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"01 - Cosechar (Kotzer), trillar (Dash) y exprimir (Sojet) - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"La labor de cosechar consiste en desprender o separar algo de su fuente vital, y dado que solemos realizar esta acci\u00f3n como necesaria para un tiempo prolongado, se trata de una \u00abobra de trabajo\u00bb (melejet avod\u00e1) y est\u00e1 prohibido llevarla a cabo tanto en Yom Tov como en Shabat, e incluso se proh\u00edbe cortar un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/12-04-01\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2000-12-03T22:01:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-19T08:09:06+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-04-01\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-04-01\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"01 &#8211; Cosechar (Kotzer), trillar (Dash) y exprimir (Sojet)\",\"datePublished\":\"2000-12-03T22:01:37+00:00\",\"dateModified\":\"2021-04-19T08:09:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-04-01\\\/\"},\"wordCount\":457,\"commentCount\":0,\"articleSection\":[\"04 - Las labores de los alimentos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-04-01\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-04-01\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-04-01\\\/\",\"name\":\"01 - Cosechar (Kotzer), trillar (Dash) y exprimir (Sojet) - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2000-12-03T22:01:37+00:00\",\"dateModified\":\"2021-04-19T08:09:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-04-01\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-04-01\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/12-04-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"01 &#8211; Cosechar (Kotzer), trillar (Dash) y exprimir (Sojet)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"01 - Cosechar (Kotzer), trillar (Dash) y exprimir (Sojet) - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/12-04-01\/","og_locale":"es_ES","og_type":"article","og_title":"01 - Cosechar (Kotzer), trillar (Dash) y exprimir (Sojet) - Pninei Halaj\u00e1","og_description":"La labor de cosechar consiste en desprender o separar algo de su fuente vital, y dado que solemos realizar esta acci\u00f3n como necesaria para un tiempo prolongado, se trata de una \u00abobra de trabajo\u00bb (melejet avod\u00e1) y est\u00e1 prohibido llevarla a cabo tanto en Yom Tov como en Shabat, e incluso se proh\u00edbe cortar un [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/12-04-01\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2000-12-03T22:01:37+00:00","article_modified_time":"2021-04-19T08:09:06+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/12-04-01\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/12-04-01\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"01 &#8211; Cosechar (Kotzer), trillar (Dash) y exprimir (Sojet)","datePublished":"2000-12-03T22:01:37+00:00","dateModified":"2021-04-19T08:09:06+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/12-04-01\/"},"wordCount":457,"commentCount":0,"articleSection":["04 - Las labores de los alimentos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/12-04-01\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/12-04-01\/","url":"https:\/\/ph.yhb.org.il\/es\/12-04-01\/","name":"01 - Cosechar (Kotzer), trillar (Dash) y exprimir (Sojet) - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2000-12-03T22:01:37+00:00","dateModified":"2021-04-19T08:09:06+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/12-04-01\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/12-04-01\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/12-04-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"01 &#8211; Cosechar (Kotzer), trillar (Dash) y exprimir (Sojet)"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/4804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=4804"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/4804\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=4804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=4804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=4804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}