{"id":5198,"date":"2001-01-03T00:02:58","date_gmt":"2001-01-02T22:02:58","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=5198"},"modified":"2022-10-03T12:31:45","modified_gmt":"2022-10-03T09:31:45","slug":"13-03-02","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/13-03-02\/","title":{"rendered":"02- Habitar la suc\u00e1 decorosamente"},"content":{"rendered":"<p>Durante la totalidad de los siete d\u00edas la suc\u00e1 debe ser la residencia fija y la casa la residencia temporaria, tal como fue dicho (Vaikr\u00e1-Lev\u00edtico 23:42): <em>\u201cEn las caba\u00f1as habitareis siete d\u00edas\u201d<\/em>. Por lo tanto, es necesario mudar a la suc\u00e1 la mesa y las sillas m\u00e1s importantes que se poseen, as\u00ed como tambi\u00e9n la cama con las mejores s\u00e1banas para poder habitar en ella tal como se lo hace en la casa permanente durante todo el a\u00f1o. O sea, no alcanza con comer o dormir en la suc\u00e1, sino que es preciso que \u00e9sta sea el sitio principal de residencia, al tiempo que la casa funja como cocina y dep\u00f3sito destinados a ayudar con las necesidades festivas (Mishn\u00e1 y Guemar\u00e1 Suc\u00e1 28(B)).<\/p>\n<p>Dijeron nuestros sabios que el estudio habitual de Tor\u00e1 es oportuno llevarlo a cabo en la suc\u00e1, y el estudio anal\u00edtico y pormenorizado especialmente arduo realizarlo en la casa o en la casa de estudio ya que all\u00ed resulta m\u00e1s f\u00e1cil concentrarse (Tratado de Suc\u00e1 28(B), Shulj\u00e1n Aruj 639:4). En caso de que resulte dif\u00edcil concentrarse en la suc\u00e1 por causa de la elevada temperatura o del barullo, es mejor llevar a cabo el estudio de Tor\u00e1 en el sitio que resulte m\u00e1s c\u00f3modo para ese prop\u00f3sito, ya que \u00e9sta no es una actividad que se lleve a cabo principalmente en el hogar. Asimismo, quien precise numerosos libros para estudiar y le resulte dificultoso o pesado traerlos a la suc\u00e1, podr\u00e1 a priori estudiar en la casa de estudio o en la habitaci\u00f3n de su hogar donde los guarda.<\/p>\n<p>Si bien una persona debe conducirse en su suc\u00e1 tal como lo hace en su casa permanente, de todas maneras, existe una diferencia entre ambos habit\u00e1culos. En la casa se realizan todas las labores, tanto las agradables como las desagradables. Pero en la suc\u00e1, en virtud de que la honramos, no se realizan labores desagradables y nos conducimos en su interior como suele hacerlo una persona en el comedor de su casa permanente, que es la habitaci\u00f3n m\u00e1s agradable e importante del hogar. Por ello, no se permite colocar en la suc\u00e1 utensilios no decorosos tales como baldes, palanganas y todo objeto que no suele ser colocado en la habitaci\u00f3n m\u00e1s importante de la casa. No se puede lavar los platos en la suc\u00e1 ni tampoco cambiar los pa\u00f1ales de un beb\u00e9 (Tratado de Suc\u00e1 28(B), Shulj\u00e1n Aruj 639:1, Aruj HaShulj\u00e1n 4).<\/p>\n<p>Tras terminar de comer, es preciso retirar lo antes posible los platos y los cubiertos sucios, ya que no es honroso para la suc\u00e1 que se queden en su interior. Sin embargo, los vasos pueden quedarse ya que no contienen suciedad y a veces se desea beber m\u00e1s. En los lugares en los que se acostumbra a traer ollas a la mesa se podr\u00e1 hacerlo en la suc\u00e1, y all\u00ed donde ello no se considere honroso no se podr\u00e1 (Tratado de Suc\u00e1 29(A), Shulj\u00e1n Aruj 639:1, Mishn\u00e1 Berur\u00e1 3-6). No se permite colocar en la suc\u00e1 un bote de basura, pero s\u00ed una papelera y similares, ya que se suele colocar una de \u00e9stas en las habitaciones importantes de la casa.<\/p>\n<p>No se puede colocar en la suc\u00e1 ropa que precise ser lavada, pero quien se acuesta a dormir puede colocar su vestimenta sobre una silla, quitarse los zapatos y los calcetines tal como suele hacerlo en la casa.<\/p>\n<p>No tiene nada de malo hablar de cuestiones mundanas en la suc\u00e1. Por lo tanto, quien desee hablar con un amigo en persona o por tel\u00e9fono en la suc\u00e1 es bueno que lo haga tal como lo har\u00eda en su residencia permanente, y, adem\u00e1s, mientras se encuentre en el interior de la suc\u00e1 estar\u00e1 cumpliendo un precepto (Shulj\u00e1n Aruj 639:1). Asimismo, quienes deseen jugar ajedrez u otro juego de mesa es bueno que lo hagan en la suc\u00e1 (ver Rab\u00ed Ya\u2019akov Ben Yehud\u00e1 Weil 191, Darkei Mosh\u00e9 639:1). Hay quienes proceden con excelencia y se abstienen en la suc\u00e1 de dedicarse a quehaceres mundanos (Shel\u00e1, Kaf HaJa\u00edm 639:5-6 y ver Mishn\u00e1 Berur\u00e1 2). No obstante, si por proceder as\u00ed se pasa menos tiempo en la suc\u00e1, la pr\u00e1ctica carece de excelencia, ya que seg\u00fan la Halaj\u00e1 quien desee dedicarse a cuestiones mundanas es mejor que lo haga en la suc\u00e1 y cumpla as\u00ed con un precepto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la totalidad de los siete d\u00edas la suc\u00e1 debe ser la residencia fija y la casa la residencia temporaria, tal como fue dicho (Vaikr\u00e1-Lev\u00edtico 23:42): \u201cEn las caba\u00f1as habitareis siete d\u00edas\u201d. Por lo tanto, es necesario mudar a la suc\u00e1 la mesa y las sillas m\u00e1s importantes que se poseen, as\u00ed como tambi\u00e9n la [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[220],"tags":[],"class_list":["post-5198","post","type-post","status-publish","format-standard","hentry","category-13-03"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>02- Habitar la suc\u00e1 decorosamente - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/13-03-02\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"02- Habitar la suc\u00e1 decorosamente - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Durante la totalidad de los siete d\u00edas la suc\u00e1 debe ser la residencia fija y la casa la residencia temporaria, tal como fue dicho (Vaikr\u00e1-Lev\u00edtico 23:42): \u201cEn las caba\u00f1as habitareis siete d\u00edas\u201d. Por lo tanto, es necesario mudar a la suc\u00e1 la mesa y las sillas m\u00e1s importantes que se poseen, as\u00ed como tambi\u00e9n la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/13-03-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2001-01-02T22:02:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-03T09:31:45+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/13-03-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/13-03-02\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"02- Habitar la suc\u00e1 decorosamente\",\"datePublished\":\"2001-01-02T22:02:58+00:00\",\"dateModified\":\"2022-10-03T09:31:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/13-03-02\\\/\"},\"wordCount\":752,\"commentCount\":0,\"articleSection\":[\"03 \u2013 Habitar la suc\u00e1\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/13-03-02\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/13-03-02\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/13-03-02\\\/\",\"name\":\"02- Habitar la suc\u00e1 decorosamente - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2001-01-02T22:02:58+00:00\",\"dateModified\":\"2022-10-03T09:31:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/13-03-02\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/13-03-02\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/13-03-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"02- Habitar la suc\u00e1 decorosamente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"02- Habitar la suc\u00e1 decorosamente - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/13-03-02\/","og_locale":"es_ES","og_type":"article","og_title":"02- Habitar la suc\u00e1 decorosamente - Pninei Halaj\u00e1","og_description":"Durante la totalidad de los siete d\u00edas la suc\u00e1 debe ser la residencia fija y la casa la residencia temporaria, tal como fue dicho (Vaikr\u00e1-Lev\u00edtico 23:42): \u201cEn las caba\u00f1as habitareis siete d\u00edas\u201d. Por lo tanto, es necesario mudar a la suc\u00e1 la mesa y las sillas m\u00e1s importantes que se poseen, as\u00ed como tambi\u00e9n la [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/13-03-02\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2001-01-02T22:02:58+00:00","article_modified_time":"2022-10-03T09:31:45+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/13-03-02\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/13-03-02\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"02- Habitar la suc\u00e1 decorosamente","datePublished":"2001-01-02T22:02:58+00:00","dateModified":"2022-10-03T09:31:45+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/13-03-02\/"},"wordCount":752,"commentCount":0,"articleSection":["03 \u2013 Habitar la suc\u00e1"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/13-03-02\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/13-03-02\/","url":"https:\/\/ph.yhb.org.il\/es\/13-03-02\/","name":"02- Habitar la suc\u00e1 decorosamente - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2001-01-02T22:02:58+00:00","dateModified":"2022-10-03T09:31:45+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/13-03-02\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/13-03-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/13-03-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"02- Habitar la suc\u00e1 decorosamente"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/5198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=5198"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/5198\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=5198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=5198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=5198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}