{"id":5721,"date":"2019-01-03T00:04:24","date_gmt":"2019-01-02T22:04:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=5721"},"modified":"2025-05-18T15:19:01","modified_gmt":"2025-05-18T12:19:01","slug":"17-22-04","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-22-04\/","title":{"rendered":"04 \u2013 La preparaci\u00f3n de la carne para su salado"},"content":{"rendered":"<p>Antes de que pasemos a detallar el orden del salado en sus tres etapas, a saber, lavado, salado y enjuagado, es preciso anticipar que el salado sirve para extraer la sangre que est\u00e1 impregnada en la carne, pero no sirve para el caso de la sangre acumulada en los conductos sangu\u00edneos importantes como por ejemplo los del hombro, la quijada o la lengua, porque esta sangre se considera como si estuviera acopiada en un recipiente. Por lo tanto, es preciso cortar estas venas previo al salado para que la sangre acumulada pueda salir (Shulj\u00e1n Aruj 65:1). El salado no sirve para los conductos sangu\u00edneos que se encuentran en las meninges ni en los test\u00edculos del animal macho, a los cuales es preciso retirar o cuanto menos cortar para que la sangre pueda salir durante el salado (Tratado de Jul\u00edn 93(A)).<\/p>\n<p>Carne en la cual se hubiere acumulado sangre a ra\u00edz de un golpe que provocare un enrojecimiento, precisar\u00e1 ser cortada previo a su salado, a los efectos de abrir un pasaje por el cual la sangre pudiera salir. En caso de que tras el salado la carne continuase roja, ello no implicar\u00e1 prohibici\u00f3n. Cuando se kasheriza la carne por medio de su asado, no resulta necesario cortarla pues este m\u00e9todo puede extraer la sangre acumulada sin necesidad de efectuar una incisi\u00f3n (Shulj\u00e1n Aruj 67:4, Kaf HaJa\u00edm 16).<\/p>\n<p>Los gaonitas instruyeron que el salado resulta efectivo a condici\u00f3n de que no hubieren pasado m\u00e1s de tres jornadas (72 horas) desde el momento de la faena. En caso de que hubieran transcurrido, cabe temer que la sangre se haya secado al grado de que el salado no la pueda quitar. En un caso as\u00ed, la carne podr\u00e1 kasherizarse \u00fanicamente por medio de su asado, porque lo que el asado no logre extraer, posteriormente ya no habr\u00e1 de salir. Sin embargo, a priori no se debe cocinar esta carne asada, no sea que hubiere quedado en ella sangre que el asado no pudiere extraer y saliere posteriormente durante la cocci\u00f3n.<\/p>\n<p>A posteriori, si la carne fue cocinada despu\u00e9s de haber sido asada \u2013es kasher. A los efectos de no llegar a este tipo de complicaciones y evitar el error de kasherizar por medio del salado carne que lleva ya tres d\u00edas de faenada, es oportuno tener la precauci\u00f3n de no dejar que la carne quede 72 horas sin ser kasherizada con posterioridad a la faena (Shulj\u00e1n Aruj y Ram\u00e1 69:12). El h\u00edgado puede ser dejado en espera ya que de todas maneras se kasheriza \u00fanicamente por medio de su asado (Jamudei Daniel, Pitjei She\u2019arim 26).<\/p>\n<p>Si antes de que pasen tres d\u00edas de la faena se pone la carne en agua, el proceso de secado de la sangre se detendr\u00e1 por lo que se permitir\u00e1 kasherizar la carne por medio del salado tres d\u00edas m\u00e1s tarde. A posteriori, si se retiran de la carne los hilos de sangre, nos podremos conformar con su enjuagado (<em>shtif\u00e1<\/em>), lo cual permitir\u00e1 su salado durante los pr\u00f3ximos tres d\u00edas (Shulj\u00e1n Aruj 69:13, 16:33).<\/p>\n<p>Hay quienes proh\u00edben dejar la carne (sin kasherizar) durante tres d\u00edas, aunque parte del tiempo est\u00e9 congelada, por temor a que durante el lapso del congelamiento la sangre se seque y se adhiera a la carne (Yaskil Avd\u00ed I Yor\u00e9 De\u00e1 3; Shevet Halev\u00ed 2:25). Sin embargo, en la pr\u00e1ctica, dado que durante el congelamiento la sangre no se seca, sino que se hiela, en caso de necesidad es posible congelar la carne durante largos meses y luego salarla, ya que el per\u00edodo de congelamiento no se suma a la cuenta de los tres d\u00edas (Aruj HaShulj\u00e1n 69:79, Yad Yehud\u00e1 59, Yab\u00eda Omer II Yor\u00e9 De\u00e1 4 y 7:4).<\/p>\n<p>Mientras que la carne se mantenga congelada, el salado y el asado no sirven para kasherizarla porque no pueden extraer la sangre que se encuentra en su interior. A los efectos de descongelarla, est\u00e1 permitido ponerla en agua caliente a una temperatura que no hace \u2018retirar la mano\u2019 (<em>yad soledet b\u00f3<\/em>) y evitar as\u00ed que cocine la carne y le haga absorber la sangre hasta quedar prohibida (Beit Yosef 69:1).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de que pasemos a detallar el orden del salado en sus tres etapas, a saber, lavado, salado y enjuagado, es preciso anticipar que el salado sirve para extraer la sangre que est\u00e1 impregnada en la carne, pero no sirve para el caso de la sangre acumulada en los conductos sangu\u00edneos importantes como por ejemplo [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[243],"tags":[],"class_list":["post-5721","post","type-post","status-publish","format-standard","hentry","category-17-22"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>04 \u2013 La preparaci\u00f3n de la carne para su salado - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-22-04\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"04 \u2013 La preparaci\u00f3n de la carne para su salado - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Antes de que pasemos a detallar el orden del salado en sus tres etapas, a saber, lavado, salado y enjuagado, es preciso anticipar que el salado sirve para extraer la sangre que est\u00e1 impregnada en la carne, pero no sirve para el caso de la sangre acumulada en los conductos sangu\u00edneos importantes como por ejemplo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-22-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-02T22:04:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-18T12:19:01+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-04\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-04\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"04 \u2013 La preparaci\u00f3n de la carne para su salado\",\"datePublished\":\"2019-01-02T22:04:24+00:00\",\"dateModified\":\"2025-05-18T12:19:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-04\\\/\"},\"wordCount\":711,\"commentCount\":0,\"articleSection\":[\"La sangre y la kasherizaci\u00f3n de la carne - 22\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-04\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-04\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-04\\\/\",\"name\":\"04 \u2013 La preparaci\u00f3n de la carne para su salado - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-02T22:04:24+00:00\",\"dateModified\":\"2025-05-18T12:19:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-04\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-04\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"04 \u2013 La preparaci\u00f3n de la carne para su salado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"04 \u2013 La preparaci\u00f3n de la carne para su salado - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-22-04\/","og_locale":"es_ES","og_type":"article","og_title":"04 \u2013 La preparaci\u00f3n de la carne para su salado - Pninei Halaj\u00e1","og_description":"Antes de que pasemos a detallar el orden del salado en sus tres etapas, a saber, lavado, salado y enjuagado, es preciso anticipar que el salado sirve para extraer la sangre que est\u00e1 impregnada en la carne, pero no sirve para el caso de la sangre acumulada en los conductos sangu\u00edneos importantes como por ejemplo [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-22-04\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-02T22:04:24+00:00","article_modified_time":"2025-05-18T12:19:01+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-22-04\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-22-04\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"04 \u2013 La preparaci\u00f3n de la carne para su salado","datePublished":"2019-01-02T22:04:24+00:00","dateModified":"2025-05-18T12:19:01+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-22-04\/"},"wordCount":711,"commentCount":0,"articleSection":["La sangre y la kasherizaci\u00f3n de la carne - 22"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-22-04\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-22-04\/","url":"https:\/\/ph.yhb.org.il\/es\/17-22-04\/","name":"04 \u2013 La preparaci\u00f3n de la carne para su salado - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-02T22:04:24+00:00","dateModified":"2025-05-18T12:19:01+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-22-04\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-22-04\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-22-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"04 \u2013 La preparaci\u00f3n de la carne para su salado"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/5721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=5721"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/5721\/revisions"}],"predecessor-version":[{"id":5722,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/5721\/revisions\/5722"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=5721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=5721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=5721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}