{"id":5744,"date":"2019-01-03T00:14:24","date_gmt":"2019-01-02T22:14:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=5744"},"modified":"2025-05-18T15:29:02","modified_gmt":"2025-05-18T12:29:02","slug":"17-22-14","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-22-14\/","title":{"rendered":"14 \u2013  Sangre de peces, langostas y seres humanos"},"content":{"rendered":"<p>La prohibici\u00f3n de la ingesti\u00f3n de sangre recae sobre la de todas las especies que por ser puras es preciso faenarlas para que su carne sea apta para ser ingerida, esto es, la sangre de las especies de animales dom\u00e9sticos, no dom\u00e9sticos y aves, pero no aplica para la de los pescados y las langostas (grillos o chapulines) (arriba halaj\u00e1 2). Sin embargo, por el principio de que no se hace algo que, aunque est\u00e9 permitido pueda ser vista o percibida como una acci\u00f3n indebida (<em>mar\u2019it ain, <\/em>literalmente \u2018la vista del ojo\u2019), queda prohibido ingerirlo por prescripci\u00f3n rab\u00ednica, (si no resulta claro y evidente que la sangre en cuesti\u00f3n es de peces o langostas), no sea que las personas por error aprendan as\u00ed a comer sangre prohibida. Por ello, cuando se re\u00fane sangre de peces en un recipiente, est\u00e1 prohibido beberla por prescripci\u00f3n rab\u00ednica, y ello estar\u00e1 permitido solamente si resulta claro y evidente que lo es, por ejemplo, si se coloc\u00f3 en el recipiente algo de escamas o trozos de pescado (Shulj\u00e1n Aruj 66:9). En caso de que se hubiese mezclado en el alimento sangre de peces o langostas, mientras no resulte perceptible \u2013la mezcla estar\u00e1 permitida (Ram\u00e1 66:10).<\/p>\n<p>La ingesta de sangre humana no est\u00e1 prohibida por la Tor\u00e1, pero nuestros sabios vedaron comerla por el principio de \u2018<em>mar\u2019it ain<\/em>\u2019 (especificado en el p\u00e1rrafo anterior). Por lo tanto, quien da un mordisco a un trozo de pan o a una manzana y queda sobre \u00e9stos sangre de su boca, es preciso raspar la sangre del pan o de la manzana para posteriormente poder seguir comiendo de ellos. Sin embargo, sangre que sali\u00f3 de entre los dientes est\u00e1 permitido succionarla por cuanto que a\u00fan no sali\u00f3 del cuerpo, y por ende, no recae sobre esta prohibici\u00f3n alguna. M\u00e1s a\u00fan, una persona tiene permitido succionar o lamer sangre que sale de un dedo por cuanto que resulta visible que no se trata de la sangre de un animal dom\u00e9stico o de un ave (Shulj\u00e1n Aruj 66:10, Kaf HaJa\u00edm 47).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prohibici\u00f3n de la ingesti\u00f3n de sangre recae sobre la de todas las especies que por ser puras es preciso faenarlas para que su carne sea apta para ser ingerida, esto es, la sangre de las especies de animales dom\u00e9sticos, no dom\u00e9sticos y aves, pero no aplica para la de los pescados y las langostas [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[243],"tags":[],"class_list":["post-5744","post","type-post","status-publish","format-standard","hentry","category-17-22"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>14 \u2013 Sangre de peces, langostas y seres humanos - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-22-14\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"14 \u2013 Sangre de peces, langostas y seres humanos - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"La prohibici\u00f3n de la ingesti\u00f3n de sangre recae sobre la de todas las especies que por ser puras es preciso faenarlas para que su carne sea apta para ser ingerida, esto es, la sangre de las especies de animales dom\u00e9sticos, no dom\u00e9sticos y aves, pero no aplica para la de los pescados y las langostas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-22-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-02T22:14:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-18T12:29:02+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-14\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-14\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"14 \u2013 Sangre de peces, langostas y seres humanos\",\"datePublished\":\"2019-01-02T22:14:24+00:00\",\"dateModified\":\"2025-05-18T12:29:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-14\\\/\"},\"wordCount\":363,\"commentCount\":0,\"articleSection\":[\"La sangre y la kasherizaci\u00f3n de la carne - 22\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-14\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-14\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-14\\\/\",\"name\":\"14 \u2013 Sangre de peces, langostas y seres humanos - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-02T22:14:24+00:00\",\"dateModified\":\"2025-05-18T12:29:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-14\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-14\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-22-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"14 \u2013 Sangre de peces, langostas y seres humanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"14 \u2013 Sangre de peces, langostas y seres humanos - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-22-14\/","og_locale":"es_ES","og_type":"article","og_title":"14 \u2013 Sangre de peces, langostas y seres humanos - Pninei Halaj\u00e1","og_description":"La prohibici\u00f3n de la ingesti\u00f3n de sangre recae sobre la de todas las especies que por ser puras es preciso faenarlas para que su carne sea apta para ser ingerida, esto es, la sangre de las especies de animales dom\u00e9sticos, no dom\u00e9sticos y aves, pero no aplica para la de los pescados y las langostas [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-22-14\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-02T22:14:24+00:00","article_modified_time":"2025-05-18T12:29:02+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-22-14\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-22-14\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"14 \u2013 Sangre de peces, langostas y seres humanos","datePublished":"2019-01-02T22:14:24+00:00","dateModified":"2025-05-18T12:29:02+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-22-14\/"},"wordCount":363,"commentCount":0,"articleSection":["La sangre y la kasherizaci\u00f3n de la carne - 22"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-22-14\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-22-14\/","url":"https:\/\/ph.yhb.org.il\/es\/17-22-14\/","name":"14 \u2013 Sangre de peces, langostas y seres humanos - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-02T22:14:24+00:00","dateModified":"2025-05-18T12:29:02+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-22-14\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-22-14\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-22-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"14 \u2013 Sangre de peces, langostas y seres humanos"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/5744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=5744"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/5744\/revisions"}],"predecessor-version":[{"id":5745,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/5744\/revisions\/5745"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=5744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=5744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=5744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}