{"id":6039,"date":"2019-01-09T06:00:24","date_gmt":"2019-01-09T04:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6039"},"modified":"2025-05-20T12:13:46","modified_gmt":"2025-05-20T09:13:46","slug":"17-28-06","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-28-06\/","title":{"rendered":"06 \u2013   La primera regla: que no se ingieran crudos"},"content":{"rendered":"<p>La primera regla en lo que respecta a la prohibici\u00f3n de los alimentos cocinados por gentiles se refiere a que se trate de un alimento que no suela comerse crudo. O sea, que se trate de un alimento al cual la cocci\u00f3n lo haga comestible, y por ende, \u00e9sta resulte significativa para \u00e9l. Por lo tanto, se proh\u00edben platillos hechos a base de carne o pescado cocidos por cuanto que estos no son comidos crudos. Asimismo, se proh\u00edben las comidas que contienen cereal y harina, como por ejemplo granos (de cebada), ptit\u00edm<sup><a href='#_te01ftn28_3' id='_te01ftnref28_3' class='aup1'>[3]<\/a><\/sup> y fideos. As\u00ed tambi\u00e9n con comidas que contienen legumbres cocidas tales como lentejas, garbanzos y arroz. \u00a0La prohibici\u00f3n de los alimentos cocidos por gentiles aplica incluso para aquellos alimentos que caso de gran necesidad o apremio pudieran comerse crudos, como por ejemplo el huevo, que en determinados casos puede ser deglutido sin previa cocci\u00f3n (Tratado de Avod\u00e1 Zar\u00e1 38(B), Shulj\u00e1n Aruj 113:14-15).<\/p>\n<p>En el caso de la leche y sus subproductos como la manteca y el queso, no aplica sobre estos la prohibici\u00f3n de que gentiles los cocinen por cuanto que suelen comerse crudos. Si bien en la actualidad se suele hervir la leche para pasteurizarla (esterilizarla de microbios), dado que este procedimiento no tiene por objetivo mejorar el sabor del producto, se considera que a la leche se la consume cruda.<\/p>\n<p>En lo que refiere a frutas, la prohibici\u00f3n no aplica por cuanto que se acostumbra a comerlas crudas. Por lo tanto, no se proh\u00edbe la mermelada de fruta elaborada por un gentil. Asimismo, tampoco se proh\u00edben los condimentos, dado que suelen ser mezclados en alimentos que se ingieren crudos como es el caso de la ensalada (Mishn\u00e1 Berur\u00e1 203:11).<\/p>\n<p>En lo que refiere a la mayor\u00eda de las verduras, esta prohibici\u00f3n no aplica dado que suelen comerse crudas. Por lo tanto, no se proh\u00edbe la ensalada <em>matbuja<sup><a href='#_te01ftn28_4' id='_te01ftnref28_4' class='aup1'>[4]<\/a><\/sup> dado que sus ingredientes -tomates, aj\u00edes y cebollas- se comen crudos. Pero hay verduras que en muchos sitios se acostumbra a no comerlas crudas, como las papas, los zapallitos o zuchinni, la remolacha y la berenjena, y por ende, la prohibici\u00f3n aplica sobre estas. No obstante, en un entorno en el cual estas verduras se suelan comer crudas, por ejemplo, que se mezclen trozos de estas en la ensalada, la prohibici\u00f3n no aplicar\u00e1. Y aunque una persona en particular y su familia no suelan comerlas crudas, dado que saben que muchas personas de su entorno s\u00ed lo hacen, los productos ser\u00e1n considerados como aquellos se comen crudos tambi\u00e9n para estas. Pero si la persona solamente oy\u00f3 que hay quien come la verdura en cuesti\u00f3n cruda, recaer\u00e1 sobre el alimento la prohibici\u00f3n de la ingesti\u00f3n de alimento cocinado por gentiles.<\/p>\n<p>La fijaci\u00f3n del estatus del alimento, si se come o no crudo, depender\u00e1 de su situaci\u00f3n previo a la cocci\u00f3n. Por ejemplo, en el pasado se sol\u00eda comer granos al natural, por lo que si eran cocidos por un gentil no dejaban de ser aptos para su consumo. Pero si los granos fueron molidos para elaborar harina, dado que este no es un alimento que se ingiera crudo, cualquier platillo que elabore un gentil a partir de esta quedar\u00e1 prohibido. En la actualidad no se acostumbra a comer granos sin cocer, por lo que la prohibici\u00f3n recae sobre estos. Pescado y carne que fueron salados al punto de que se tornaron comestibles, si luego son cocinados por un gentil, no quedar\u00e1n prohibidos por cuanto que previo a su cocci\u00f3n ya se pod\u00edan ingerir (Shulj\u00e1n Aruj 113:12).<\/p>\n<p>Si se mezclaron en una misma comida alimentos que suelen comerse crudos como en el caso del queso y las verduras, y otros que no se comen crudos como huevos y harina, se definir\u00e1 el estatus del alimento en su totalidad conforme al ingrediente principal que es aquel que fija la bendici\u00f3n a recitar (Shulj\u00e1n Aruj 113:2).<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref28_3' id='_te01ftn28_3'>[3]<\/a>. Ptit\u00edm: tambi\u00e9n llamados \u201carroz Ben Guri\u00f3n\u201d o \u201ccusc\u00fas israel\u00ed\u201d son granos elaborados con ingredientes similares a la pasta, pero que, a diferencia de ella, pasan por un proceso de horneado. Los ptit\u00edm se inventaron en Israel durante per\u00edodo de la escasez o austeridad (<em>tzena<\/em>) y se considera una de las contribuciones culinarias m\u00e1s originales que dio Israel al mundo. Los ptit\u00edm pertenecen a la familia de las pastas cortas, a la que tambi\u00e9n pertenece el plato ashkenaz\u00ed denominado \u201cfarfalaj\u201d (N. de E.).<\/p>\n<p>&lt;<a href='#_te01ftnref28_4' id='_te01ftn28_4'>[4]<\/a>. La \u201cmatbuja\u201d, llamada a menudo por los jud\u00edos de Ceuta, Melilla y el norte de Marruecos \u2018ensalada cocha\u2019, es una especie de ensalada elaborada principalmente con tomates, pimientos asados, aceite de oliva y ajo, todo ello cocinado junto. El nombre del plato proviene del \u00e1rabe <em>matbuja<\/em>, que significa \u201ccocinada\u201d (N. de E.).\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La primera regla en lo que respecta a la prohibici\u00f3n de los alimentos cocinados por gentiles se refiere a que se trate de un alimento que no suela comerse crudo. O sea, que se trate de un alimento al cual la cocci\u00f3n lo haga comestible, y por ende, \u00e9sta resulte significativa para \u00e9l. Por lo [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[257],"tags":[],"class_list":["post-6039","post","type-post","status-publish","format-standard","hentry","category-17-28"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>06 \u2013  La primera regla: que no se ingieran crudos - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-28-06\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"06 \u2013  La primera regla: que no se ingieran crudos - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"La primera regla en lo que respecta a la prohibici\u00f3n de los alimentos cocinados por gentiles se refiere a que se trate de un alimento que no suela comerse crudo. O sea, que se trate de un alimento al cual la cocci\u00f3n lo haga comestible, y por ende, \u00e9sta resulte significativa para \u00e9l. Por lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-28-06\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-09T04:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T09:13:46+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-28-06\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-28-06\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"06 \u2013 La primera regla: que no se ingieran crudos\",\"datePublished\":\"2019-01-09T04:00:24+00:00\",\"dateModified\":\"2025-05-20T09:13:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-28-06\\\/\"},\"wordCount\":828,\"commentCount\":0,\"articleSection\":[\"El pan horneado y la comida cocinada por gentiles \u2013 28\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-28-06\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-28-06\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-28-06\\\/\",\"name\":\"06 \u2013 La primera regla: que no se ingieran crudos - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-09T04:00:24+00:00\",\"dateModified\":\"2025-05-20T09:13:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-28-06\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-28-06\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-28-06\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"06 \u2013 La primera regla: que no se ingieran crudos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"06 \u2013  La primera regla: que no se ingieran crudos - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-28-06\/","og_locale":"es_ES","og_type":"article","og_title":"06 \u2013  La primera regla: que no se ingieran crudos - Pninei Halaj\u00e1","og_description":"La primera regla en lo que respecta a la prohibici\u00f3n de los alimentos cocinados por gentiles se refiere a que se trate de un alimento que no suela comerse crudo. O sea, que se trate de un alimento al cual la cocci\u00f3n lo haga comestible, y por ende, \u00e9sta resulte significativa para \u00e9l. Por lo [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-28-06\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-09T04:00:24+00:00","article_modified_time":"2025-05-20T09:13:46+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-28-06\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-28-06\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"06 \u2013 La primera regla: que no se ingieran crudos","datePublished":"2019-01-09T04:00:24+00:00","dateModified":"2025-05-20T09:13:46+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-28-06\/"},"wordCount":828,"commentCount":0,"articleSection":["El pan horneado y la comida cocinada por gentiles \u2013 28"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-28-06\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-28-06\/","url":"https:\/\/ph.yhb.org.il\/es\/17-28-06\/","name":"06 \u2013 La primera regla: que no se ingieran crudos - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-09T04:00:24+00:00","dateModified":"2025-05-20T09:13:46+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-28-06\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-28-06\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-28-06\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"06 \u2013 La primera regla: que no se ingieran crudos"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6039"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6039\/revisions"}],"predecessor-version":[{"id":6040,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6039\/revisions\/6040"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}