{"id":6082,"date":"2019-01-11T02:00:24","date_gmt":"2019-01-11T00:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6082"},"modified":"2025-05-20T12:49:37","modified_gmt":"2025-05-20T09:49:37","slug":"17-30-02","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-30-02\/","title":{"rendered":"02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed)"},"content":{"rendered":"<p>Nuestros sabios prohibieron que un jud\u00edo ingiera leche orde\u00f1ada por un gentil, no sea que \u00e9ste \u00faltimo mezclare en la leche pura otra que es impura (Tratado de Avod\u00e1 Zar\u00e1 35(B)). De todas maneras, la probabilidad de que ello ocurra es muy baja, ya que la mayor\u00eda absoluta de la leche que los seres humanos est\u00e1n habituados a consumir es pura. Adem\u00e1s, hay diferencia entre la leche pura y la impura, ya que el color de la primera es blanco y el de la segunda amarillento, y por ende, si la leche es blanca y no se percibe en ella un sabor diferente, y aun cuando el gentil mezclare en ella leche impura, seg\u00fan la Tor\u00e1 esta se anular\u00e1 en la mayor\u00eda de la leche que es pura.<\/p>\n<p>A pesar de ello, los sabios adoptaron una actitud mucho m\u00e1s estricta y prohibieron la leche orde\u00f1ada por un gentil (<em>jalav nojr\u00ed<\/em>) por temor a que este la haya mezclado con leche impura. Esto y m\u00e1s, incluso si un jud\u00edo elabor\u00f3 queso con jalav nojr\u00ed, y aparentemente est\u00e1 demostrado que se trataba de leche pura, ya que, a partir de la impura no es posible elaborar queso, los sabios prohibieron el queso por temor a que leche impura que no haya cuajado permanezca bajo la forma de humedad en los orificios y en las ranuras del queso. Tal como parece, los sabios adoptaron una actitud estricta por temor a transgredir una prohibici\u00f3n de un modo que excede a lo com\u00fanmente aceptado en las dem\u00e1s prohibiciones alimentarias, en el marco de la intenci\u00f3n general de alejar a los jud\u00edos de los alimentos de los gentiles.<\/p>\n<p>No obstante, cuando un jud\u00edo inspecciona o vigila que el gentil no mezcle leche impura con la pura \u2013la leche ser\u00e1 kasher. Si se sabe con certeza que el gentil no posee un animal impuro, alcanza con que el jud\u00edo revise que en medio del orde\u00f1ado el gentil no traiga leche de otro origen. Si el gentil poseyere un animal dom\u00e9stico impuro, el jud\u00edo deber\u00e1 revisar que orde\u00f1e al animal puro y no mezcle leche del impuro con la del puro. No es preciso que observe todo el orde\u00f1ado, sino que alcanza con que el gentil sepa que el jud\u00edo lo vigila, y puede verlo con facilidad, por ejemplo, que si se pone de pie habr\u00e1 de verlo orde\u00f1ar o que en cualquier momento puede ingresar y verlo en su labor (Tratado de Avod\u00e1 Zar\u00e1 39(B), Shulj\u00e1n Aruj 115:1). Cuando cabe temer que en el balde de orde\u00f1e del gentil pudieran quedar restos de leche impura de un orde\u00f1ado anterior, el jud\u00edo deber\u00e1 revisar que el recipiente est\u00e9 limpio de restos de leche (\u00eddem Ram\u00e1 y otros comentaristas).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestros sabios prohibieron que un jud\u00edo ingiera leche orde\u00f1ada por un gentil, no sea que \u00e9ste \u00faltimo mezclare en la leche pura otra que es impura (Tratado de Avod\u00e1 Zar\u00e1 35(B)). De todas maneras, la probabilidad de que ello ocurra es muy baja, ya que la mayor\u00eda absoluta de la leche que los seres humanos [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[259],"tags":[],"class_list":["post-6082","post","type-post","status-publish","format-standard","hentry","category-17-30"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed) - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-30-02\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed) - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Nuestros sabios prohibieron que un jud\u00edo ingiera leche orde\u00f1ada por un gentil, no sea que \u00e9ste \u00faltimo mezclare en la leche pura otra que es impura (Tratado de Avod\u00e1 Zar\u00e1 35(B)). De todas maneras, la probabilidad de que ello ocurra es muy baja, ya que la mayor\u00eda absoluta de la leche que los seres humanos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-30-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-11T00:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T09:49:37+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-02\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed)\",\"datePublished\":\"2019-01-11T00:00:24+00:00\",\"dateModified\":\"2025-05-20T09:49:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-02\\\/\"},\"wordCount\":490,\"commentCount\":0,\"articleSection\":[\"La leche y sus derivados - 30\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-02\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-02\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-02\\\/\",\"name\":\"02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed) - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-11T00:00:24+00:00\",\"dateModified\":\"2025-05-20T09:49:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-02\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-02\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed) - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-30-02\/","og_locale":"es_ES","og_type":"article","og_title":"02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed) - Pninei Halaj\u00e1","og_description":"Nuestros sabios prohibieron que un jud\u00edo ingiera leche orde\u00f1ada por un gentil, no sea que \u00e9ste \u00faltimo mezclare en la leche pura otra que es impura (Tratado de Avod\u00e1 Zar\u00e1 35(B)). De todas maneras, la probabilidad de que ello ocurra es muy baja, ya que la mayor\u00eda absoluta de la leche que los seres humanos [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-30-02\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-11T00:00:24+00:00","article_modified_time":"2025-05-20T09:49:37+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-30-02\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-30-02\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed)","datePublished":"2019-01-11T00:00:24+00:00","dateModified":"2025-05-20T09:49:37+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-30-02\/"},"wordCount":490,"commentCount":0,"articleSection":["La leche y sus derivados - 30"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-30-02\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-30-02\/","url":"https:\/\/ph.yhb.org.il\/es\/17-30-02\/","name":"02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed) - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-11T00:00:24+00:00","dateModified":"2025-05-20T09:49:37+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-30-02\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-30-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-30-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"02 \u2013 La prohibici\u00f3n de consumir leche orde\u00f1ada por gentiles (jalav nojr\u00ed)"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6082"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6082\/revisions"}],"predecessor-version":[{"id":6083,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6082\/revisions\/6083"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}