{"id":6096,"date":"2019-01-11T09:00:24","date_gmt":"2019-01-11T07:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6096"},"modified":"2025-05-20T13:03:15","modified_gmt":"2025-05-20T10:03:15","slug":"17-30-09","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-30-09\/","title":{"rendered":"09 \u2013 Los quesos blandos"},"content":{"rendered":"<p>Los juristas debatieron respecto de los quesos blandos tales como el blanco, el cottage, la leche cuajada (<em>leben<\/em>) y el yogurt que se producen a partir de fermentaci\u00f3n natural. O sea, cuando se coloca la leche en un sitio c\u00e1lido, naturalmente esta fermenta y se vuelve espesa por efecto de los microbios que esta contiene. En una primera etapa se tornar\u00e1 cuajada (<em>leben<\/em>), y luego, se espesar\u00e1 m\u00e1s y se transformar\u00e1 un en queso blando. Para acelerar su proceso de elaboraci\u00f3n, se le agregar\u00e1 restos de leche cuajada o queso que fermentaron y poseen cultivos de bacterias, tal que distintos tipos de fermentaci\u00f3n dar\u00e1n lugar a distintos tipos de productos l\u00e1cteos, que lo com\u00fan a todos ellos es que no se solidificaron como el queso (duro) por medio de enzimas, sino que se condensaron por medio de la fermentaci\u00f3n de las bacterias. En la actualidad, en los laboratorios modernos se producen distintos concentrados de microorganismos que resultan excelentes para hacer fermentar a la leche de manera exacta de acuerdo con el producto final deseado, y de ese modo, se producen diferentes derivados de la leche con distintas consistencias o texturas y sabores espec\u00edficos.<\/p>\n<p>Hay quienes permiten consumir quesos blandos elaborados por gentiles ya que el decreto prohibitorio sobre el queso es por temor a que este sea cuajado por medio de un trozo de est\u00f3mago de vaca no faenada seg\u00fan la Halaj\u00e1, y por ende, recae \u00fanicamente sobre aquellos quesos que son elaborados a partir de enzimas que se encuentran en el est\u00f3mago, pero los quesos blandos fermentan a partir de bacterias y no de enzimas por lo que est\u00e1n permitidos dado que no est\u00e1n comprendidos en las generales de la prohibici\u00f3n.<\/p>\n<p>Sin embargo, seg\u00fan la opini\u00f3n mayoritaria de las autoridades hal\u00e1jicas, aunque digamos que los sabios decretaron una prohibici\u00f3n sobre el queso elaborado por gentiles por temor al uso de enzimas provenientes de piel de est\u00f3mago de un animal no faenado seg\u00fan la Halaj\u00e1, esta recae sobre todos los productos l\u00e1cteos que se hubieren condensado. Adem\u00e1s de ello, hay quienes dicen que el queso tambi\u00e9n fue prohibido por temor a que se pudiera haber mezclado leche de un animal impuro con la de uno puro, y cuanto m\u00e1s blando sea el queso mayor ser\u00e1 este temor.<\/p>\n<p>A los efectos de la norma, es correcto adoptar una actitud estricta en conformidad con la opini\u00f3n de la mayor\u00eda de los juristas, y quienes deseen flexibilizar su proceder, podr\u00e1n hacerlo. De hecho, hay en el extranjero (se refiere a fuera del Estado de Israel) entidades de supervisi\u00f3n de la kashrut que adoptan una actitud flexible y conceden el sello de kasher a quesos blandos elaborados por gentiles, revisando que est\u00e9n hechos a partir de materias primas kasher. Por su parte, en la tierra de Israel se procede seg\u00fan la opini\u00f3n mayoritaria de las eminencias hal\u00e1jicas y no se concede sello de kashrut a quesos blandos elaborados por gentiles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los juristas debatieron respecto de los quesos blandos tales como el blanco, el cottage, la leche cuajada (leben) y el yogurt que se producen a partir de fermentaci\u00f3n natural. O sea, cuando se coloca la leche en un sitio c\u00e1lido, naturalmente esta fermenta y se vuelve espesa por efecto de los microbios que esta contiene. [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[259],"tags":[],"class_list":["post-6096","post","type-post","status-publish","format-standard","hentry","category-17-30"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>09 \u2013 Los quesos blandos - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-30-09\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"09 \u2013 Los quesos blandos - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Los juristas debatieron respecto de los quesos blandos tales como el blanco, el cottage, la leche cuajada (leben) y el yogurt que se producen a partir de fermentaci\u00f3n natural. O sea, cuando se coloca la leche en un sitio c\u00e1lido, naturalmente esta fermenta y se vuelve espesa por efecto de los microbios que esta contiene. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-30-09\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-11T07:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T10:03:15+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-09\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-09\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"09 \u2013 Los quesos blandos\",\"datePublished\":\"2019-01-11T07:00:24+00:00\",\"dateModified\":\"2025-05-20T10:03:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-09\\\/\"},\"wordCount\":523,\"commentCount\":0,\"articleSection\":[\"La leche y sus derivados - 30\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-09\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-09\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-09\\\/\",\"name\":\"09 \u2013 Los quesos blandos - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-11T07:00:24+00:00\",\"dateModified\":\"2025-05-20T10:03:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-09\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-09\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-30-09\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"09 \u2013 Los quesos blandos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"09 \u2013 Los quesos blandos - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-30-09\/","og_locale":"es_ES","og_type":"article","og_title":"09 \u2013 Los quesos blandos - Pninei Halaj\u00e1","og_description":"Los juristas debatieron respecto de los quesos blandos tales como el blanco, el cottage, la leche cuajada (leben) y el yogurt que se producen a partir de fermentaci\u00f3n natural. O sea, cuando se coloca la leche en un sitio c\u00e1lido, naturalmente esta fermenta y se vuelve espesa por efecto de los microbios que esta contiene. [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-30-09\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-11T07:00:24+00:00","article_modified_time":"2025-05-20T10:03:15+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-30-09\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-30-09\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"09 \u2013 Los quesos blandos","datePublished":"2019-01-11T07:00:24+00:00","dateModified":"2025-05-20T10:03:15+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-30-09\/"},"wordCount":523,"commentCount":0,"articleSection":["La leche y sus derivados - 30"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-30-09\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-30-09\/","url":"https:\/\/ph.yhb.org.il\/es\/17-30-09\/","name":"09 \u2013 Los quesos blandos - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-11T07:00:24+00:00","dateModified":"2025-05-20T10:03:15+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-30-09\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-30-09\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-30-09\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"09 \u2013 Los quesos blandos"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6096"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6096\/revisions"}],"predecessor-version":[{"id":6097,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6096\/revisions\/6097"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}