{"id":6106,"date":"2019-01-12T02:00:24","date_gmt":"2019-01-12T00:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6106"},"modified":"2025-05-20T13:35:48","modified_gmt":"2025-05-20T10:35:48","slug":"17-31-02","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-31-02\/","title":{"rendered":"02 \u2013  Utensilios de metal, vidrio y dem\u00e1s materiales"},"content":{"rendered":"<p>Los utensilios que deben ser sumergidos por prescripci\u00f3n de la Tor\u00e1 son aquellos que est\u00e1n hechos de metales que fueran detallados en el texto, por ejemplo: oro, plata, cobre, hierro, esta\u00f1o y plomo y todos los dem\u00e1s tipos de metal. Nuestros sabios agregaron que tambi\u00e9n se sumerjan utensilios de vidrio en virtud de su similitud a los met\u00e1licos, ya que, as\u00ed como se puede fundir un metal para hacer de \u00e9ste nuevos utensilios, de igual manera es posible fundir vidrio con el mismo prop\u00f3sito (Tratado de Avod\u00e1 Zar\u00e1 75(B)).<\/p>\n<p>Sin embargo, los utensilios elaborados a partir de los dem\u00e1s materiales como loza, porcelana, cer\u00e1mica, piedra, madera y pl\u00e1stico en sus distintas variedades -est\u00e1n exentos de inmersi\u00f3n. Y si bien es posible fundir objetos de pl\u00e1stico, tal como se hace con el vidrio, no debemos aplicar este decreto sobre otros objetos similares al vidrio seg\u00fan nuestro criterio.<\/p>\n<p>Utensilios met\u00e1licos recubiertos con diferentes materiales tales como el tefl\u00f3n, el esmalte o una cobertura cer\u00e1mica -deben ser sumergidos recitando la bendici\u00f3n correspondiente, pues est\u00e1n compuestos principalmente de metal. Lo mismo ocurre con los platos de coralina, los cuales est\u00e1n compuestos principalmente de vidrio.<\/p>\n<p>Los utensilios de porcelana, que est\u00e1n compuestos principalmente de loza y recubiertos con una capa fina de vidrio, por cuanto que el material que recubre es secundario respecto a la loza -est\u00e1n exentos de ser sumergidos (Kneset Haguedol\u00e1, Jaim David Azulay, Sheelat Yaabetz y Yad Efraim).<\/p>\n<p>Una olla met\u00e1lica que posea asas de pl\u00e1stico, as\u00ed como tambi\u00e9n un cuchillo cuyo mango sea de madera \u2013deber\u00e1n ser sumergidos, y ser\u00e1 preciso sumergir la totalidad del utensilio, incluida la parte que est\u00e1 elaborada de otro material que no precisa ser sumergido. Esta es la regla general: siempre que el componente central de un utensilio (o sea, aquel que tiene contacto directo con el alimento) est\u00e9 hecho de metal o de vidrio -el utensilio entero deber\u00e1 ser sumergido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los utensilios que deben ser sumergidos por prescripci\u00f3n de la Tor\u00e1 son aquellos que est\u00e1n hechos de metales que fueran detallados en el texto, por ejemplo: oro, plata, cobre, hierro, esta\u00f1o y plomo y todos los dem\u00e1s tipos de metal. Nuestros sabios agregaron que tambi\u00e9n se sumerjan utensilios de vidrio en virtud de su similitud [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[260],"tags":[],"class_list":["post-6106","post","type-post","status-publish","format-standard","hentry","category-17-31"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>02 \u2013 Utensilios de metal, vidrio y dem\u00e1s materiales - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-31-02\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"02 \u2013 Utensilios de metal, vidrio y dem\u00e1s materiales - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Los utensilios que deben ser sumergidos por prescripci\u00f3n de la Tor\u00e1 son aquellos que est\u00e1n hechos de metales que fueran detallados en el texto, por ejemplo: oro, plata, cobre, hierro, esta\u00f1o y plomo y todos los dem\u00e1s tipos de metal. Nuestros sabios agregaron que tambi\u00e9n se sumerjan utensilios de vidrio en virtud de su similitud [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-31-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-12T00:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T10:35:48+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-31-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-31-02\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"02 \u2013 Utensilios de metal, vidrio y dem\u00e1s materiales\",\"datePublished\":\"2019-01-12T00:00:24+00:00\",\"dateModified\":\"2025-05-20T10:35:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-31-02\\\/\"},\"wordCount\":349,\"commentCount\":0,\"articleSection\":[\"La inmersi\u00f3n ritual de los utensilios (tevilat kelim) - 31\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-31-02\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-31-02\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-31-02\\\/\",\"name\":\"02 \u2013 Utensilios de metal, vidrio y dem\u00e1s materiales - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-12T00:00:24+00:00\",\"dateModified\":\"2025-05-20T10:35:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-31-02\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-31-02\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-31-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"02 \u2013 Utensilios de metal, vidrio y dem\u00e1s materiales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"02 \u2013 Utensilios de metal, vidrio y dem\u00e1s materiales - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-31-02\/","og_locale":"es_ES","og_type":"article","og_title":"02 \u2013 Utensilios de metal, vidrio y dem\u00e1s materiales - Pninei Halaj\u00e1","og_description":"Los utensilios que deben ser sumergidos por prescripci\u00f3n de la Tor\u00e1 son aquellos que est\u00e1n hechos de metales que fueran detallados en el texto, por ejemplo: oro, plata, cobre, hierro, esta\u00f1o y plomo y todos los dem\u00e1s tipos de metal. Nuestros sabios agregaron que tambi\u00e9n se sumerjan utensilios de vidrio en virtud de su similitud [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-31-02\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-12T00:00:24+00:00","article_modified_time":"2025-05-20T10:35:48+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-31-02\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-31-02\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"02 \u2013 Utensilios de metal, vidrio y dem\u00e1s materiales","datePublished":"2019-01-12T00:00:24+00:00","dateModified":"2025-05-20T10:35:48+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-31-02\/"},"wordCount":349,"commentCount":0,"articleSection":["La inmersi\u00f3n ritual de los utensilios (tevilat kelim) - 31"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-31-02\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-31-02\/","url":"https:\/\/ph.yhb.org.il\/es\/17-31-02\/","name":"02 \u2013 Utensilios de metal, vidrio y dem\u00e1s materiales - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-12T00:00:24+00:00","dateModified":"2025-05-20T10:35:48+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-31-02\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-31-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-31-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"02 \u2013 Utensilios de metal, vidrio y dem\u00e1s materiales"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6106"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6106\/revisions"}],"predecessor-version":[{"id":6107,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6106\/revisions\/6107"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}