{"id":6176,"date":"2019-01-15T02:00:24","date_gmt":"2019-01-15T00:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6176"},"modified":"2025-05-20T14:47:01","modified_gmt":"2025-05-20T11:47:01","slug":"17-34-02","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-34-02\/","title":{"rendered":"02 \u2013 Resumen de los cuatro tipos de mezcla"},"content":{"rendered":"<p>Resulta entonces que hay dos divisiones en las leyes referentes a las mezclas. La primera es una mezcla entre dos alimentos del mismo tipo o especie, <em>min bemin\u00f3<\/em>, y la segunda es la mezcla entre dos alimentos diferentes, <em>min besheein\u00f3 min\u00f3<\/em>. En el primer caso, el sabor del alimento prohibido es id\u00e9ntico al del alimento permitido, al tiempo que en el segundo, el sabor del alimento prohibido es diferente al del permitido.<\/p>\n<p>La segunda divisi\u00f3n es entre la mezcla de alimentos l\u00edquidos o h\u00famedos (<em>laj belaj<\/em>) y la de alimentos secos (<em>iavesh beiavesh<\/em>). En el primer caso, el sabor del alimento prohibido se fusiona en la mezcla. Por ejemplo, cuando carne taref se cocina junto a carne kasher, por medio de la cocci\u00f3n los sabores se mezclan en todo el guiso. Una harina prohibida que se mezcla con otra permitida se considera tambi\u00e9n una mezcla entre dos alimentos h\u00famedos o l\u00edquidos, por cuanto que al ser esta muy fina, las part\u00edculas prohibidas se mezclan perfectamente con las permitidas fusion\u00e1ndose (Pninei Halaj\u00e1 Pesaj 7:4).<\/p>\n<p>Por el contrario, en el caso de una mezcla entre alimentos secos (<em>iavesh beiavesh<\/em>), no sabemos cu\u00e1l es el kasher y cu\u00e1l el prohibido, pero no se mezclan el uno con el otro. Otro tanto ocurre con un vaso que contiene salsa de carne taref que se mezcl\u00f3 con dos vasos que contienen salsa de carne kasher, la cual se considera una mezcla entre alimentos secos (<em>iavesh beiavesh<\/em>) porque las salsas se encuentran en vasos separados y no se mezclan entre s\u00ed.<\/p>\n<p>Dado que las dos divisiones se combinan entre s\u00ed, resulta que tenemos cuatro tipos de mezcla: 1) La mezcla de dos especies distintas l\u00edquidas (<em>min besheein\u00f3 min\u00f3 laj belaj<\/em>); 2) la mezcla de dos especies distintas secas (<em>min besheein\u00f3 min\u00f3 iavesh beiavesh<\/em>); 3) la mezcla de dos especies similares l\u00edquidas (<em>bin bemin\u00f3 laj belaj<\/em>) y 4) la mezcla de dos especies similares secas (<em>min bemin\u00f3 iavesh beiavesh<\/em>).<\/p>\n<p>En los tres primeros tipos de mezcla se requiere que el volumen del alimento permitido sea sesenta veces mayor al del prohibido para poder anularlo. En el primer tipo, dicta la normativa (<em>ikar had\u00edn<\/em>), que se precisa de sesenta veces en virtud del sabor que el alimento prohibido le confiere a la mezcla. En el segundo y el tercero, seg\u00fan la Tor\u00e1, el alimento prohibido se anula por mayor\u00eda en el alimento permitido, pero los sabios decretaron que no se anule en menos de sesenta veces; y solamente en la mezcla del cuarto tipo (dos especies similares secas \u2013 <em>min bemin\u00f3 iavesh beiavesh<\/em>), en la pr\u00e1ctica, el alimento prohibido se anula en el permitido por mayor\u00eda.<\/p>\n<p>Sin embargo, hay autoridades hal\u00e1jicas que entienden que los sabios igualaron todas las proporciones, y establecieron que ninguna prohibici\u00f3n se anule en menos de sesenta veces. No obstante, en la pr\u00e1ctica, la halaj\u00e1 final es conforme la opini\u00f3n de la mayor\u00eda de los sabios medievales (<em>rishonim<\/em>) que entienden que una mezcla del cuarto tipo (dos alimentos similares secos) se anula por mayor\u00eda, y esta es la circunstancia o el caso en el cual rige el principio fundamental de la anulaci\u00f3n por mayor\u00eda.<\/p>\n<p>Sin embargo, precisamente en lo que refiere a una mezcla del cuarto tipo (dos especies similares secas), cuando hay excesiva severidad en la prohibici\u00f3n, los sabios adoptaron una actitud mucho m\u00e1s estricta que en el resto de las mezclas, las cuales se anulan en sesenta veces. Si el alimento prohibido son frutas de la ofrenda destinada al cohen (<em>terum\u00e1<\/em>) que se mezclaron con otras comunes, dado que la prohibici\u00f3n de ingerir <em>terum\u00e1<\/em> es de una enorme severidad, al punto de que un extra\u00f1o que come de ella tiene pena de muerte, solamente si entre las frutas comunes (<em>jul\u00edn<\/em>) hay cien veces m\u00e1s, los frutos de la <em>terum\u00e1<\/em> quedar\u00e1n anulados. Cuando la prohibici\u00f3n se refiere a frutos del \u00e1rbol de los primeros tres a\u00f1os (<em>orl\u00e1<\/em>) o de la hibridaci\u00f3n de la vi\u00f1a (<em>kil\u2019ei hakerem<\/em>) de los cuales est\u00e1 prohibido tambi\u00e9n obtener beneficio o deleite, s\u00f3lo si hay en los frutos permitidos doscientas veces m\u00e1s, la prohibici\u00f3n queda anulada (ver adelante halaj\u00e1 9).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resulta entonces que hay dos divisiones en las leyes referentes a las mezclas. La primera es una mezcla entre dos alimentos del mismo tipo o especie, min bemin\u00f3, y la segunda es la mezcla entre dos alimentos diferentes, min besheein\u00f3 min\u00f3. En el primer caso, el sabor del alimento prohibido es id\u00e9ntico al del alimento [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[263],"tags":[],"class_list":["post-6176","post","type-post","status-publish","format-standard","hentry","category-17-34"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>02 \u2013 Resumen de los cuatro tipos de mezcla - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-34-02\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"02 \u2013 Resumen de los cuatro tipos de mezcla - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Resulta entonces que hay dos divisiones en las leyes referentes a las mezclas. La primera es una mezcla entre dos alimentos del mismo tipo o especie, min bemin\u00f3, y la segunda es la mezcla entre dos alimentos diferentes, min besheein\u00f3 min\u00f3. En el primer caso, el sabor del alimento prohibido es id\u00e9ntico al del alimento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-34-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-15T00:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T11:47:01+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-02\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"02 \u2013 Resumen de los cuatro tipos de mezcla\",\"datePublished\":\"2019-01-15T00:00:24+00:00\",\"dateModified\":\"2025-05-20T11:47:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-02\\\/\"},\"wordCount\":724,\"commentCount\":0,\"articleSection\":[\"Leyes referentes a las mezclas - 34\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-02\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-02\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-02\\\/\",\"name\":\"02 \u2013 Resumen de los cuatro tipos de mezcla - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-15T00:00:24+00:00\",\"dateModified\":\"2025-05-20T11:47:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-02\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-02\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"02 \u2013 Resumen de los cuatro tipos de mezcla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"02 \u2013 Resumen de los cuatro tipos de mezcla - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-34-02\/","og_locale":"es_ES","og_type":"article","og_title":"02 \u2013 Resumen de los cuatro tipos de mezcla - Pninei Halaj\u00e1","og_description":"Resulta entonces que hay dos divisiones en las leyes referentes a las mezclas. La primera es una mezcla entre dos alimentos del mismo tipo o especie, min bemin\u00f3, y la segunda es la mezcla entre dos alimentos diferentes, min besheein\u00f3 min\u00f3. En el primer caso, el sabor del alimento prohibido es id\u00e9ntico al del alimento [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-34-02\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-15T00:00:24+00:00","article_modified_time":"2025-05-20T11:47:01+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-02\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-02\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"02 \u2013 Resumen de los cuatro tipos de mezcla","datePublished":"2019-01-15T00:00:24+00:00","dateModified":"2025-05-20T11:47:01+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-02\/"},"wordCount":724,"commentCount":0,"articleSection":["Leyes referentes a las mezclas - 34"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-34-02\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-02\/","url":"https:\/\/ph.yhb.org.il\/es\/17-34-02\/","name":"02 \u2013 Resumen de los cuatro tipos de mezcla - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-15T00:00:24+00:00","dateModified":"2025-05-20T11:47:01+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-02\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-34-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"02 \u2013 Resumen de los cuatro tipos de mezcla"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6176"}],"version-history":[{"count":3,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6176\/revisions"}],"predecessor-version":[{"id":6179,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6176\/revisions\/6179"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}