{"id":6184,"date":"2019-01-15T05:00:24","date_gmt":"2019-01-15T03:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6184"},"modified":"2025-05-20T14:58:08","modified_gmt":"2025-05-20T11:58:08","slug":"17-34-05","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-34-05\/","title":{"rendered":"05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta"},"content":{"rendered":"<p>Algunas de las grandes eminencias hal\u00e1jicas medievales de Ashkenaz escribieron que la costumbre pr\u00e1ctica es no confiar en la degustaci\u00f3n de un gentil, y si el alimento permitido en la mezcla fuere sesenta veces mayor en volumen que el prohibido, la mezcla ser\u00e1 kasher, y en caso de que no se alcance esa proporci\u00f3n, la mezcla no lo ser\u00e1. Tal como parece, los juristas vieron que, en la pr\u00e1ctica, el confiar en la degustaci\u00f3n del guisado genera dificultades por cuanto que el sabor es elusivo, y a veces, ha ocurrido que un gentil respondi\u00f3 que la mezcla carec\u00eda de sabor a carne y cuando los jud\u00edos la probaron sintieron efectivamente que lo ten\u00eda. Y a veces, ha habido personas que s\u00ed sintieron el sabor del alimento prohibido y otras que no.<\/p>\n<p>Asimismo, la definici\u00f3n de sabor no resulta clara, \u00bfacaso se refiere a sentir el sabor diferenciado del alimento prohibido o alcanza con que a ra\u00edz de la mezcla se perciba en el guisado un gusto diferente? Por lo tanto, algunas de las eminencias medievales instruyeron que no se conf\u00ede en la degustaci\u00f3n de un gentil, y que todos los alimentos prohibidos se anulen en sesenta. Con el correr de los a\u00f1os, se difundi\u00f3 esta pr\u00e1ctica entre todas las comunidades jud\u00edas, al punto de que, en las \u00faltimas generaciones, todos los jud\u00edos acostumbran a anular el alimento prohibido en sesenta y a no recurrir a la degustaci\u00f3n de un gentil (Ram\u00e1 98:1, Kaf HaJa\u00edm 2:11).<\/p>\n<p>No obstante, en caso de gran necesidad o apremio (<em>sheat hadjak<\/em>), cuando un gentil confiable dice con absoluta certeza que un guiso determinado carece de sabor a alimento prohibido, se lo puede autorizar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algunas de las grandes eminencias hal\u00e1jicas medievales de Ashkenaz escribieron que la costumbre pr\u00e1ctica es no confiar en la degustaci\u00f3n de un gentil, y si el alimento permitido en la mezcla fuere sesenta veces mayor en volumen que el prohibido, la mezcla ser\u00e1 kasher, y en caso de que no se alcance esa proporci\u00f3n, la [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[263],"tags":[],"class_list":["post-6184","post","type-post","status-publish","format-standard","hentry","category-17-34"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-34-05\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Algunas de las grandes eminencias hal\u00e1jicas medievales de Ashkenaz escribieron que la costumbre pr\u00e1ctica es no confiar en la degustaci\u00f3n de un gentil, y si el alimento permitido en la mezcla fuere sesenta veces mayor en volumen que el prohibido, la mezcla ser\u00e1 kasher, y en caso de que no se alcance esa proporci\u00f3n, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-34-05\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-15T03:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T11:58:08+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-05\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-05\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta\",\"datePublished\":\"2019-01-15T03:00:24+00:00\",\"dateModified\":\"2025-05-20T11:58:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-05\\\/\"},\"wordCount\":303,\"commentCount\":0,\"articleSection\":[\"Leyes referentes a las mezclas - 34\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-05\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-05\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-05\\\/\",\"name\":\"05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-15T03:00:24+00:00\",\"dateModified\":\"2025-05-20T11:58:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-05\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-34-05\/","og_locale":"es_ES","og_type":"article","og_title":"05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta - Pninei Halaj\u00e1","og_description":"Algunas de las grandes eminencias hal\u00e1jicas medievales de Ashkenaz escribieron que la costumbre pr\u00e1ctica es no confiar en la degustaci\u00f3n de un gentil, y si el alimento permitido en la mezcla fuere sesenta veces mayor en volumen que el prohibido, la mezcla ser\u00e1 kasher, y en caso de que no se alcance esa proporci\u00f3n, la [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-34-05\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-15T03:00:24+00:00","article_modified_time":"2025-05-20T11:58:08+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-05\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-05\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta","datePublished":"2019-01-15T03:00:24+00:00","dateModified":"2025-05-20T11:58:08+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-05\/"},"wordCount":303,"commentCount":0,"articleSection":["Leyes referentes a las mezclas - 34"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-34-05\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-05\/","url":"https:\/\/ph.yhb.org.il\/es\/17-34-05\/","name":"05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-15T03:00:24+00:00","dateModified":"2025-05-20T11:58:08+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-05\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-34-05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"05 \u2013 La costumbre pr\u00e1ctica es anular en sesenta"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6184"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6184\/revisions"}],"predecessor-version":[{"id":6185,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6184\/revisions\/6185"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}