{"id":6186,"date":"2019-01-15T06:00:24","date_gmt":"2019-01-15T04:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6186"},"modified":"2025-05-20T15:04:17","modified_gmt":"2025-05-20T12:04:17","slug":"17-34-06","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-34-06\/","title":{"rendered":"06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\/o mejoran definitivamente la forma o la esencia de un alimento (ma&#8217;amid)"},"content":{"rendered":"<p>Un condimento o especie aporta sabor m\u00e1s que sesenta veces su volumen, y por ello, si se mezcla en el alimento un condimento no kasher, siempre y cuando su sabor sea perceptible, tornar\u00e1 en prohibido a la totalidad del alimento, aunque este sea mil o m\u00e1s veces m\u00e1s abundante (Ram\u00e1 98:8).<\/p>\n<p>Nuestros sabios adoptaron una actitud m\u00e1s estricta en el caso de un producto prohibido que hace que la mezcla cambie de forma o de esencia (<em>ma&#8217;amid<\/em>), y estipularon que, aunque el alimento permitido en la mezcla sea sesenta veces m\u00e1s abundante que el prohibido, este \u00faltimo no se ver\u00e1 anulado, por cuanto que su influencia resultar\u00e1 identificable. Por lo tanto, si se colocare piel del est\u00f3mago de un animal prohibido (<em>nevel\u00e1<\/em>) cuyas enzimas habr\u00e1n de transformar a la leche en queso, este \u00faltimo quedar\u00e1 vedado por cuanto que la leche fue cuajada por medio de un animal prohibido (ver arriba 30:6).<\/p>\n<p>Asimismo, si se leudare la masa con una levadura no kasher, la masa quedar\u00e1 prohibida, aunque sea sesenta veces m\u00e1s abundante que la levadura. Lo mismo ocurre si se hace fermentar una bebida a base de miel o un jugo de frutas por medio de una levadura o un vinagre prohibido torn\u00e1ndola as\u00ed en licor, este \u00faltimo quedar\u00e1 prohibido, aunque sea sesenta veces m\u00e1s abundante que el material que lo hizo fermentar (Shulj\u00e1n Aruj y Ram\u00e1 87:11).<\/p>\n<p>Si el alimento prohibido no fuere suficiente como para conferirle sabor a la comida o para cuajarla, y esto resultare posible \u00fanicamente por medio de un ingrediente o un cuajo permitido, su estatus ser\u00e1 similar al del resto de los componentes prohibidos, y mientras hubiere sesenta veces m\u00e1s del ingrediente permitido en la mezcla que del prohibido, el alimento ser\u00e1 kasher (Ram\u00e1 \u00eddem). Esta regla general se denomina: \u201cCuando esto y aquello son el causante, est\u00e1 permitido\u201d<sup><a href='#_te01ftn34_1' id='_te01ftnref34_1' class='aup1'>[1]<\/a><\/sup> (<em>ze vez\u00e9 gorem \u2013mutar<\/em>).<\/p>\n<div>\n<hr size=\"1\" \/>\n<div><a id=\"_te01ftn34_1\" href=\"#_te01ftnref34_1\">[1]<\/a>. Cuando una prohibici\u00f3n (<em>isur<\/em>) y algo permitido (<em>heter<\/em>) generan en conjunto un resultado determinado, algo que se ha conformado por dos factores en com\u00fan, uno prohibido y otro permitido. Por ejemplo, un campo que fue abonado con esti\u00e9rcol que serv\u00eda para la adoraci\u00f3n de \u00eddolos, donde el esti\u00e9rcol est\u00e1 prohibido y act\u00faa sobre un terreno permitido, y ambos provocan el crecimiento de hortalizas y verduras, algunos sostienen que \u201c<em>ze ve-z\u00e9 gorem: asur<\/em> (esto y aquello es el causante) y estar\u00e1 prohibido; y otros aseveran -y as\u00ed se dictamina la halaj\u00e1- \u201c<em>ze ve-z\u00e9 gorem: mutar<\/em>\u201d, es decir que cuando dos factores son coadyuvantes (m\u00e1s all\u00e1 de la realidad de ambos), queda permitido. Por lo tanto, en un campo abonado con esti\u00e9rcol que sirve a la idolatr\u00eda, sus frutos est\u00e1n permitidos (N. de E.).<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un condimento o especie aporta sabor m\u00e1s que sesenta veces su volumen, y por ello, si se mezcla en el alimento un condimento no kasher, siempre y cuando su sabor sea perceptible, tornar\u00e1 en prohibido a la totalidad del alimento, aunque este sea mil o m\u00e1s veces m\u00e1s abundante (Ram\u00e1 98:8). Nuestros sabios adoptaron una [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[263],"tags":[],"class_list":["post-6186","post","type-post","status-publish","format-standard","hentry","category-17-34"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\/o mejoran definitivamente la forma o la esencia de un alimento (ma&#039;amid) - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-34-06\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\/o mejoran definitivamente la forma o la esencia de un alimento (ma&#039;amid) - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Un condimento o especie aporta sabor m\u00e1s que sesenta veces su volumen, y por ello, si se mezcla en el alimento un condimento no kasher, siempre y cuando su sabor sea perceptible, tornar\u00e1 en prohibido a la totalidad del alimento, aunque este sea mil o m\u00e1s veces m\u00e1s abundante (Ram\u00e1 98:8). Nuestros sabios adoptaron una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-34-06\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-15T04:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T12:04:17+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-06\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-06\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\\\/o mejoran definitivamente la forma o la esencia de un alimento (ma&#8217;amid)\",\"datePublished\":\"2019-01-15T04:00:24+00:00\",\"dateModified\":\"2025-05-20T12:04:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-06\\\/\"},\"wordCount\":488,\"commentCount\":0,\"articleSection\":[\"Leyes referentes a las mezclas - 34\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-06\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-06\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-06\\\/\",\"name\":\"06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\\\/o mejoran definitivamente la forma o la esencia de un alimento (ma'amid) - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-15T04:00:24+00:00\",\"dateModified\":\"2025-05-20T12:04:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-06\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-06\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-06\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\\\/o mejoran definitivamente la forma o la esencia de un alimento (ma&#8217;amid)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\/o mejoran definitivamente la forma o la esencia de un alimento (ma'amid) - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-34-06\/","og_locale":"es_ES","og_type":"article","og_title":"06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\/o mejoran definitivamente la forma o la esencia de un alimento (ma'amid) - Pninei Halaj\u00e1","og_description":"Un condimento o especie aporta sabor m\u00e1s que sesenta veces su volumen, y por ello, si se mezcla en el alimento un condimento no kasher, siempre y cuando su sabor sea perceptible, tornar\u00e1 en prohibido a la totalidad del alimento, aunque este sea mil o m\u00e1s veces m\u00e1s abundante (Ram\u00e1 98:8). Nuestros sabios adoptaron una [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-34-06\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-15T04:00:24+00:00","article_modified_time":"2025-05-20T12:04:17+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-06\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-06\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\/o mejoran definitivamente la forma o la esencia de un alimento (ma&#8217;amid)","datePublished":"2019-01-15T04:00:24+00:00","dateModified":"2025-05-20T12:04:17+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-06\/"},"wordCount":488,"commentCount":0,"articleSection":["Leyes referentes a las mezclas - 34"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-34-06\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-06\/","url":"https:\/\/ph.yhb.org.il\/es\/17-34-06\/","name":"06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\/o mejoran definitivamente la forma o la esencia de un alimento (ma'amid) - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-15T04:00:24+00:00","dateModified":"2025-05-20T12:04:17+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-06\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-34-06\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-06\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"06 \u2013 Los condimentos y los ingredientes que (como el cuajo) modifican y\/o mejoran definitivamente la forma o la esencia de un alimento (ma&#8217;amid)"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6186"}],"version-history":[{"count":2,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6186\/revisions"}],"predecessor-version":[{"id":6191,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6186\/revisions\/6191"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}