{"id":6200,"date":"2019-01-15T12:00:24","date_gmt":"2019-01-15T10:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6200"},"modified":"2025-05-20T15:10:26","modified_gmt":"2025-05-20T12:10:26","slug":"17-34-12","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-34-12\/","title":{"rendered":"12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba)"},"content":{"rendered":"<p>Nuestros sabios establecieron que una porci\u00f3n (en hebreo <em>jatij\u00e1<\/em>, lit. \u201ctrozo\u201d) digna de ser servida a un invitado no se anule ni siquiera en mil, porque en virtud de su gran importancia, aunque se mezcle en sesenta, no se anular\u00e1 en la mente de la persona.<\/p>\n<p>Se trata de una trozo o porci\u00f3n que puede serv\u00edrsele a un invitado honorable como plato principal para que, por su intermedio, sumado al pan, al arroz u otro acompa\u00f1amiento, quede satisfecho. Esto depende del tiempo y del lugar. Hubo \u00e9pocas en las que a un invitado se le sol\u00eda servir una porci\u00f3n mediana de carne o de queso duro, pues a estos se los sol\u00eda acompa\u00f1ar con grandes cantidades de pan, y al ingerirlos conjuntamente, la gente quedaba satisfecha.<\/p>\n<p>En cambio, en nuestros d\u00edas, en los que los alimentos abundan, una porci\u00f3n digna de ser servida a un invitado importante debe ser cuanto menos un cuarto grande de pollo o un trozo de carne vacuna de id\u00e9ntico volumen. Cuando cabe dudar si la porci\u00f3n es o no digna de ser servida a un invitado de honor, dado que se trata de una normativa de prescripci\u00f3n rab\u00ednica, se adopta una actitud flexible y se la considera como un alimento prohibido com\u00fan.<\/p>\n<p>Hay quienes dicen que solamente se considera una porci\u00f3n digna de ser servida a un invitado importante a aquella que ya est\u00e1 pronta para ser ingerida, pero si su cocci\u00f3n a\u00fan no finaliz\u00f3, o si es demasiado grande, ingresa en la categor\u00eda de los dem\u00e1s alimentos prohibidos (Rabenu Nisim, Shulj\u00e1n Aruj 101:3).<\/p>\n<p>Si bien muchos de los sabios medievales (<em>rishonim<\/em>) y los de las \u00faltimas generaciones (<em>ajaronim<\/em>) adoptaron hacia esta cuesti\u00f3n una actitud estricta y la consideraron como tal aun estando cruda o siendo de gran tama\u00f1o, dado que se trata de una norma de prescripci\u00f3n rab\u00ednica, en caso de gran necesidad o apremio es posible respaldarse en la opini\u00f3n flexible.<\/p>\n<p>Asimismo, cuando la porci\u00f3n est\u00e1 prohibida por prescripci\u00f3n rab\u00ednica, si es digna de ser servida a un invitado importante, no se anula. La actitud estricta de no anular una porci\u00f3n digna de ser servida a un invitado importante rige a condici\u00f3n de que esta sea en s\u00ed misma no kasher, por ejemplo, que se trate de carne taref o que se cocin\u00f3 con leche. Sin embargo, si result\u00f3 prohibida a ra\u00edz de que absorbi\u00f3 sabor no kasher, por ejemplo, si se coci\u00f3 con salsa taref, dado que el componente prohibido no es digno de ser servido a una persona honorable, la porci\u00f3n en su totalidad es considerada como un alimento prohibido com\u00fan (Shulj\u00e1n Aruj y Ram\u00e1 101:2). En caso de que las porciones se hubieren cortado en pedazos m\u00e1s chicos al punto de que ya no son dignas de ser servidas a un invitado importante, retornan a su estatus de alimentos prohibidos comunes que se anulan en las proporciones ordinarias (Shulj\u00e1n Aruj 101:6).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestros sabios establecieron que una porci\u00f3n (en hebreo jatij\u00e1, lit. \u201ctrozo\u201d) digna de ser servida a un invitado no se anule ni siquiera en mil, porque en virtud de su gran importancia, aunque se mezcle en sesenta, no se anular\u00e1 en la mente de la persona. Se trata de una trozo o porci\u00f3n que puede [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[263],"tags":[],"class_list":["post-6200","post","type-post","status-publish","format-standard","hentry","category-17-34"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba) - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-34-12\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba) - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Nuestros sabios establecieron que una porci\u00f3n (en hebreo jatij\u00e1, lit. \u201ctrozo\u201d) digna de ser servida a un invitado no se anule ni siquiera en mil, porque en virtud de su gran importancia, aunque se mezcle en sesenta, no se anular\u00e1 en la mente de la persona. Se trata de una trozo o porci\u00f3n que puede [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-34-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-15T10:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T12:10:26+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-12\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba)\",\"datePublished\":\"2019-01-15T10:00:24+00:00\",\"dateModified\":\"2025-05-20T12:10:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-12\\\/\"},\"wordCount\":529,\"commentCount\":0,\"articleSection\":[\"Leyes referentes a las mezclas - 34\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-12\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-12\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-12\\\/\",\"name\":\"12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba) - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-15T10:00:24+00:00\",\"dateModified\":\"2025-05-20T12:10:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-12\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-12\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-34-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba) - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-34-12\/","og_locale":"es_ES","og_type":"article","og_title":"12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba) - Pninei Halaj\u00e1","og_description":"Nuestros sabios establecieron que una porci\u00f3n (en hebreo jatij\u00e1, lit. \u201ctrozo\u201d) digna de ser servida a un invitado no se anule ni siquiera en mil, porque en virtud de su gran importancia, aunque se mezcle en sesenta, no se anular\u00e1 en la mente de la persona. Se trata de una trozo o porci\u00f3n que puede [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-34-12\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-15T10:00:24+00:00","article_modified_time":"2025-05-20T12:10:26+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-12\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-12\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba)","datePublished":"2019-01-15T10:00:24+00:00","dateModified":"2025-05-20T12:10:26+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-12\/"},"wordCount":529,"commentCount":0,"articleSection":["Leyes referentes a las mezclas - 34"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-34-12\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-12\/","url":"https:\/\/ph.yhb.org.il\/es\/17-34-12\/","name":"12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba) - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-15T10:00:24+00:00","dateModified":"2025-05-20T12:10:26+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-34-12\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-34-12\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-34-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"12 \u2013 Una porci\u00f3n digna de ser servida a una visita (jatij\u00e1 hareui\u00e1 lehitkabed ba)"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6200"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6200\/revisions"}],"predecessor-version":[{"id":6201,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6200\/revisions\/6201"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}