{"id":6234,"date":"2019-01-16T09:00:24","date_gmt":"2019-01-16T07:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6234"},"modified":"2025-05-20T16:07:55","modified_gmt":"2025-05-20T13:07:55","slug":"17-35-09","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-35-09\/","title":{"rendered":"09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal)"},"content":{"rendered":"<p>Dijeron nuestros sabios que un encurtido es considerado como cocido, o sea, cuando se pone alimentos en l\u00edquido durante un d\u00eda entero, todos los sabores de los alimentos que se encuentran sumergidos en el l\u00edquido se absorben entre s\u00ed como si se tratase de una cocci\u00f3n. Por lo tanto, si se pusieron en remojo durante todo un d\u00eda un alimento kasher junto a otro que no lo es y el volumen del kasher no fuere sesenta veces mayor que el del taref, todo queda prohibido.<\/p>\n<p>Si el encurtido se hiciere con l\u00edquidos muy salados o picantes, se considerar\u00e1 que los alimentos resultaron cocidos tras haber pasado el lapso necesario para hervirlos sobre el fuego (Shulj\u00e1n Aruj 105:1). Muchos estimaron este tiempo en dieciocho minutos. Si el tiempo de la inmersi\u00f3n fuere inferior a este lapso, ser\u00e1 necesario retirar del alimento kasher una capa del grosor de una c\u00e1scara (<em>kedei klip\u00e1<\/em>) (\u00eddem).<\/p>\n<p>Las autoridades hal\u00e1jicas debatieron respecto de si un utensilio absorbe tambi\u00e9n sabor por medio del encurtido o decapado, por ejemplo, si se dejare sopa de carne no kasher durante todo un d\u00eda dentro de una olla, \u00bfser\u00e1 preciso kasherizarla? En la pr\u00e1ctica, se sentenci\u00f3 que a priori es preciso adoptar una actitud estricta y kasherizarla por medio de su inmersi\u00f3n en agua hirviendo (<em>hag\u2019al\u00e1<\/em>), pero si ya se cocin\u00f3 en \u00e9sta otro alimento, no se lo proh\u00edbe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dijeron nuestros sabios que un encurtido es considerado como cocido, o sea, cuando se pone alimentos en l\u00edquido durante un d\u00eda entero, todos los sabores de los alimentos que se encuentran sumergidos en el l\u00edquido se absorben entre s\u00ed como si se tratase de una cocci\u00f3n. Por lo tanto, si se pusieron en remojo durante [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[264],"tags":[],"class_list":["post-6234","post","type-post","status-publish","format-standard","hentry","category-17-35"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal) - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-35-09\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal) - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Dijeron nuestros sabios que un encurtido es considerado como cocido, o sea, cuando se pone alimentos en l\u00edquido durante un d\u00eda entero, todos los sabores de los alimentos que se encuentran sumergidos en el l\u00edquido se absorben entre s\u00ed como si se tratase de una cocci\u00f3n. Por lo tanto, si se pusieron en remojo durante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-35-09\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-16T07:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T13:07:55+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-35-09\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-35-09\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal)\",\"datePublished\":\"2019-01-16T07:00:24+00:00\",\"dateModified\":\"2025-05-20T13:07:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-35-09\\\/\"},\"wordCount\":252,\"commentCount\":0,\"articleSection\":[\"Tipos de absorci\u00f3n y contacto - 35\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-35-09\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-35-09\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-35-09\\\/\",\"name\":\"09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal) - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-16T07:00:24+00:00\",\"dateModified\":\"2025-05-20T13:07:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-35-09\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-35-09\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-35-09\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal) - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-35-09\/","og_locale":"es_ES","og_type":"article","og_title":"09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal) - Pninei Halaj\u00e1","og_description":"Dijeron nuestros sabios que un encurtido es considerado como cocido, o sea, cuando se pone alimentos en l\u00edquido durante un d\u00eda entero, todos los sabores de los alimentos que se encuentran sumergidos en el l\u00edquido se absorben entre s\u00ed como si se tratase de una cocci\u00f3n. Por lo tanto, si se pusieron en remojo durante [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-35-09\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-16T07:00:24+00:00","article_modified_time":"2025-05-20T13:07:55+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-35-09\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-35-09\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal)","datePublished":"2019-01-16T07:00:24+00:00","dateModified":"2025-05-20T13:07:55+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-35-09\/"},"wordCount":252,"commentCount":0,"articleSection":["Tipos de absorci\u00f3n y contacto - 35"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-35-09\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-35-09\/","url":"https:\/\/ph.yhb.org.il\/es\/17-35-09\/","name":"09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal) - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-16T07:00:24+00:00","dateModified":"2025-05-20T13:07:55+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-35-09\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-35-09\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-35-09\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"09 \u2013 Al encurtido se lo considera como cocido (kavush kimvushal)"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6234"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6234\/revisions"}],"predecessor-version":[{"id":6235,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6234\/revisions\/6235"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}