{"id":6266,"date":"2019-01-18T06:00:24","date_gmt":"2019-01-18T04:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6266"},"modified":"2025-05-20T17:04:33","modified_gmt":"2025-05-20T14:04:33","slug":"17-37-06","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-37-06\/","title":{"rendered":"06 \u2013 Schlack (goma laca)"},"content":{"rendered":"<p>En numerosas partes del mundo, se acostumbra a untar a las frutas y a los dulces con schlack para que se vean brillantes y bonitos. El schlack es un tipo de resina que se produce a partir de la secreci\u00f3n de un insecto llamado laca que se encuentra en las inmediaciones de Tailandia y la India, secreci\u00f3n que se vuelve espesa y pegajosa, y para poder untarla en los dulces y las frutas suele ser disuelta con alcohol (su signo es E904 en la serie de los materiales que son considerados como agentes de acristalamiento o pulido).<\/p>\n<p>Hay quienes proh\u00edben las frutas y los dulces que fueron recubiertos con schlack (goma laca) ya que la sustancia secretada por el insecto es la que fija (<em>ma\u2019amid<\/em>) la goma laca confiri\u00e9ndole cuerpo, y hace que se pegue a los frutos y los dulces, y esta sustancia est\u00e1 prohibida ya que proviene de un insecto impuro (Rab\u00ed Mordejai Eliahu, Emek HaTeshuv\u00e1 66 en nombre de Reisha y otros).<\/p>\n<p>Y hay quienes las autorizan, porque el material secretado por los insectos es duro como la madera y su sabor es amargo, y por ende, se anula en el schlack en su car\u00e1cter de producto que aporta un sabor desagradable y estropeado (<em>not\u00e9n ta\u2019am lifgam<\/em>) que al ser agregado no torna a la mezcla en prohibida. El hecho de que fije el color no lo hace ingresar en la categor\u00eda de <em>ma\u2019amid<\/em> en lo que respecta a las ingestas prohibidas (ver Igrot Mosh\u00e9 II Yor\u00e9 De\u00e1 24, Tola\u2019at Shan\u00ed I 6:42).<\/p>\n<p>En la pr\u00e1ctica, se acostumbra a no otorgar el car\u00e1cter de kasher a los alimentos que fueron recubiertos con schlack, adem\u00e1s, no hay gran necesidad de ello, ya que se puede tambi\u00e9n recubrirlos con materiales permitidos. Quien comprare frutas y temiere que pudieran estar recubiertas con schlack, que las lave bien para quitarles la cobertura. No se debe temer a no poder retirar la totalidad de la cobertura dado que se trata de un caso de duda doble (<em>sfek sfeika<\/em>) respecto de una norma rab\u00ednica: se duda si la fruta fue o no efectivamente recubierta con schlack, y se duda si qued\u00f3 sobre \u00e9sta algo del producto tras haberla lavado. Y se trata de una controversia sobre una norma rab\u00ednica porque el producto en cuesti\u00f3n no saboriza al alimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En numerosas partes del mundo, se acostumbra a untar a las frutas y a los dulces con schlack para que se vean brillantes y bonitos. El schlack es un tipo de resina que se produce a partir de la secreci\u00f3n de un insecto llamado laca que se encuentra en las inmediaciones de Tailandia y la [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[266],"tags":[],"class_list":["post-6266","post","type-post","status-publish","format-standard","hentry","category-17-37"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>06 \u2013 Schlack (goma laca) - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-37-06\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"06 \u2013 Schlack (goma laca) - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"En numerosas partes del mundo, se acostumbra a untar a las frutas y a los dulces con schlack para que se vean brillantes y bonitos. El schlack es un tipo de resina que se produce a partir de la secreci\u00f3n de un insecto llamado laca que se encuentra en las inmediaciones de Tailandia y la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-37-06\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-18T04:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T14:04:33+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-06\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-06\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"06 \u2013 Schlack (goma laca)\",\"datePublished\":\"2019-01-18T04:00:24+00:00\",\"dateModified\":\"2025-05-20T14:04:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-06\\\/\"},\"wordCount\":403,\"commentCount\":0,\"articleSection\":[\"La industria alimentaria - 37\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-06\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-06\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-06\\\/\",\"name\":\"06 \u2013 Schlack (goma laca) - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-18T04:00:24+00:00\",\"dateModified\":\"2025-05-20T14:04:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-06\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-06\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-06\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"06 \u2013 Schlack (goma laca)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"06 \u2013 Schlack (goma laca) - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-37-06\/","og_locale":"es_ES","og_type":"article","og_title":"06 \u2013 Schlack (goma laca) - Pninei Halaj\u00e1","og_description":"En numerosas partes del mundo, se acostumbra a untar a las frutas y a los dulces con schlack para que se vean brillantes y bonitos. El schlack es un tipo de resina que se produce a partir de la secreci\u00f3n de un insecto llamado laca que se encuentra en las inmediaciones de Tailandia y la [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-37-06\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-18T04:00:24+00:00","article_modified_time":"2025-05-20T14:04:33+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-37-06\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-37-06\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"06 \u2013 Schlack (goma laca)","datePublished":"2019-01-18T04:00:24+00:00","dateModified":"2025-05-20T14:04:33+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-37-06\/"},"wordCount":403,"commentCount":0,"articleSection":["La industria alimentaria - 37"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-37-06\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-37-06\/","url":"https:\/\/ph.yhb.org.il\/es\/17-37-06\/","name":"06 \u2013 Schlack (goma laca) - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-18T04:00:24+00:00","dateModified":"2025-05-20T14:04:33+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-37-06\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-37-06\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-37-06\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"06 \u2013 Schlack (goma laca)"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6266"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6266\/revisions"}],"predecessor-version":[{"id":6267,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6266\/revisions\/6267"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}