{"id":6268,"date":"2019-01-18T07:00:24","date_gmt":"2019-01-18T05:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6268"},"modified":"2025-05-20T17:20:51","modified_gmt":"2025-05-20T14:20:51","slug":"17-37-07","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-37-07\/","title":{"rendered":"07 \u2013 Productos que crecieron sobre una plataforma prohibida"},"content":{"rendered":"<p>Un alimento que fue declarado incomible para un perro pierde su estatus de prohibido. Sin embargo, cuando el elemento que perdi\u00f3 el estatus de alimento para un perro le sirve al hombre para mejorar otro tipo de productos, por ejemplo, una masa fermentada que es incorporada a la masa (Tosefta Beitz\u00e1 1:5), o bien las levaduras que hacen fermentar al vino y a la cerveza o la leche agria que acelera el cuajado de la leche y su transformaci\u00f3n en queso, mantiene su importancia y su car\u00e1cter prohibido, vedando al alimento al cual mejor\u00f3.<\/p>\n<p>En el \u00faltimo tiempo ya no se utiliza leche agria para transformar a la leche en queso blando, ni se usa el est\u00f3mago o el cuajo para elaborar queso duro, ni se emplea a la masa fermentada para hacer crecer la masa. En vez de ello se toman microbios u hongos de levadura (microorganismos) y se los cultiva en un medio de crecimiento que contiene materiales de los cuales se nutren. A consecuencia de ello, se multiplican y se replican r\u00e1pidamente hasta que pasados unos d\u00edas se obtienen millones de hongos o de microbios de los cuales se pueden producir enzimas. Una vez que alcanzan la cantidad apropiada, se los a\u00edsla de la plataforma de crecimiento y se los congela para comercializarlos a las f\u00e1bricas. Por medio de estas enzimas se elaboran los quesos duros, a trav\u00e9s de los hongos de levadura se infla a la masa y se hace fermentar al vino y a la cerveza, y por medio de los microbios se preparan quesos blandos.<\/p>\n<p>A los efectos de la halaj\u00e1, aunque el medio donde se cultivan estos microorganismos contenga productos prohibidos, los seres que crecen sobre ella son considerados kasher. En primer lugar, porque la plataforma de crecimiento siempre est\u00e1 compuesta de productos kasher, sin los cuales los microorganismos perecer\u00edan, por lo que se considera que se desarrollan en la modalidad \u201cesto y aquello son el causante\u201d (<em>ze vez\u00e9 gorem<\/em>) y que est\u00e1n permitidos a posteriori (ver arriba 34:6).<\/p>\n<p>Adem\u00e1s, los microrganismos que se nutren de los componentes de la plataforma no se cr\u00edan a partir de esta, sino por causa de los nutrientes que el medio les aporta, y se asemejan a un animal que ingiere productos prohibidos, pero cuya carne, seg\u00fan la opini\u00f3n mayoritaria de las autoridades hal\u00e1jicas, puede ser ingerida. Quienes adoptan una actitud estricta reconocen tambi\u00e9n que, si el animal se alimenta tambi\u00e9n de otras cosas, est\u00e1 permitido.<\/p>\n<p>Sin embargo, hay una opini\u00f3n que disiente y que considera que el alimento prohibido pasa por un proceso entero de digesti\u00f3n en el cuerpo del animal, y por ello, su car\u00e1cter prohibido queda sin efecto antes de que participe en la construcci\u00f3n de las c\u00e9lulas de la bestia, al tiempo que los microrganismos se alimentan de manera directa del producto prohibido.<\/p>\n<p>Asimismo, la idea de que \u201cesto y aquello son el causante\u201d permite autorizar algo solamente a posteriori, y en la actualidad es posible encontrar sustitutos kasher a los productos prohibidos que conforman la plataforma o medio de crecimiento. Por lo tanto, los organismos de supervisi\u00f3n de la kashrut exigen que la plataforma est\u00e9 compuesta de elementos kasher. Y solo cuando ello resulta imposible o sumamente dif\u00edcil de ejecutar, se conf\u00eda en el razonamiento que conduce a la autorizaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un alimento que fue declarado incomible para un perro pierde su estatus de prohibido. Sin embargo, cuando el elemento que perdi\u00f3 el estatus de alimento para un perro le sirve al hombre para mejorar otro tipo de productos, por ejemplo, una masa fermentada que es incorporada a la masa (Tosefta Beitz\u00e1 1:5), o bien las [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[266],"tags":[],"class_list":["post-6268","post","type-post","status-publish","format-standard","hentry","category-17-37"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>07 \u2013 Productos que crecieron sobre una plataforma prohibida - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-37-07\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"07 \u2013 Productos que crecieron sobre una plataforma prohibida - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Un alimento que fue declarado incomible para un perro pierde su estatus de prohibido. Sin embargo, cuando el elemento que perdi\u00f3 el estatus de alimento para un perro le sirve al hombre para mejorar otro tipo de productos, por ejemplo, una masa fermentada que es incorporada a la masa (Tosefta Beitz\u00e1 1:5), o bien las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-37-07\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-18T05:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T14:20:51+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-07\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-07\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"07 \u2013 Productos que crecieron sobre una plataforma prohibida\",\"datePublished\":\"2019-01-18T05:00:24+00:00\",\"dateModified\":\"2025-05-20T14:20:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-07\\\/\"},\"wordCount\":579,\"commentCount\":0,\"articleSection\":[\"La industria alimentaria - 37\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-07\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-07\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-07\\\/\",\"name\":\"07 \u2013 Productos que crecieron sobre una plataforma prohibida - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-18T05:00:24+00:00\",\"dateModified\":\"2025-05-20T14:20:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-07\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-07\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-07\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"07 \u2013 Productos que crecieron sobre una plataforma prohibida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"07 \u2013 Productos que crecieron sobre una plataforma prohibida - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-37-07\/","og_locale":"es_ES","og_type":"article","og_title":"07 \u2013 Productos que crecieron sobre una plataforma prohibida - Pninei Halaj\u00e1","og_description":"Un alimento que fue declarado incomible para un perro pierde su estatus de prohibido. Sin embargo, cuando el elemento que perdi\u00f3 el estatus de alimento para un perro le sirve al hombre para mejorar otro tipo de productos, por ejemplo, una masa fermentada que es incorporada a la masa (Tosefta Beitz\u00e1 1:5), o bien las [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-37-07\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-18T05:00:24+00:00","article_modified_time":"2025-05-20T14:20:51+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-37-07\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-37-07\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"07 \u2013 Productos que crecieron sobre una plataforma prohibida","datePublished":"2019-01-18T05:00:24+00:00","dateModified":"2025-05-20T14:20:51+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-37-07\/"},"wordCount":579,"commentCount":0,"articleSection":["La industria alimentaria - 37"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-37-07\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-37-07\/","url":"https:\/\/ph.yhb.org.il\/es\/17-37-07\/","name":"07 \u2013 Productos que crecieron sobre una plataforma prohibida - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-18T05:00:24+00:00","dateModified":"2025-05-20T14:20:51+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-37-07\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-37-07\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-37-07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"07 \u2013 Productos que crecieron sobre una plataforma prohibida"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6268"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6268\/revisions"}],"predecessor-version":[{"id":6269,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6268\/revisions\/6269"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}