{"id":6273,"date":"2019-01-18T09:00:24","date_gmt":"2019-01-18T07:00:24","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6273"},"modified":"2025-05-20T17:11:26","modified_gmt":"2025-05-20T14:11:26","slug":"17-37-09","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/17-37-09\/","title":{"rendered":"09 \u2013 El alcohol y las bebidas espirituosas"},"content":{"rendered":"<p>Se puede extraer alcohol a partir de alimentos que contienen az\u00facar, transform\u00e1ndolos en l\u00edquidos (como en el caso del jugo de uva) y ferment\u00e1ndolos por medio de levaduras (hongos especiales) que transforman el az\u00facar en alcohol (etanol). A trav\u00e9s del calentamiento de estos l\u00edquidos y la evaporaci\u00f3n del alcohol, se puede destilar el etanol y aislarlo del fluido en el que previamente estaba mezclado.<\/p>\n<p>En la pr\u00e1ctica, si bien su sabor y su aroma difieren completamente de los del l\u00edquido del cual fue destilado, a los efectos de la halaj\u00e1 est\u00e1 consensuado que el estatus del alcohol se asemeja al del producto a partir del cual fue producido. Por lo tanto, un alcohol destilado a partir de un vino elaborado por gentiles y del cual se produjo una bebida tal como el brandy -est\u00e1 prohibido consumirlo (Responsa Rav Ytzjak bar Sheshet 255). Y un alcohol producido a partir de cereales fermentados como el whisky o la cerveza, es considerado jametz seg\u00fan la Tor\u00e1.<\/p>\n<p><strong>Las bebidas espirituosas y el whisky<\/strong><\/p>\n<p>As\u00ed como todos los alimentos y las bebidas precisan certificaci\u00f3n kasher, otro tanto ocurre con toda la gama de las bebidas alcoh\u00f3licas. Sin embargo, en lo que respecta al whisky, dado que su procedimiento de elaboraci\u00f3n a partir de cereales es muy conocido, muchas autoridades hal\u00e1jicas permitieron consumirlo sin certificaci\u00f3n y as\u00ed es como proceden muchas personas. Y si bien hay productores de esta bebida que acostumbran a a\u00f1ejarla en barriles de madera que fueron previamente usados con vino y por ende absorbieron sabor a vino elaborado por gentiles, por lo que el whisky podr\u00eda impregnarse de ese sabor, dado que la cantidad del vino que sale de las paredes del barril no alcanza una proporci\u00f3n que pudiera influir en el gusto del whisky (not\u00e9n ta\u2019am), est\u00e1 permitido consumirlo. No obstante, esta autorizaci\u00f3n fue dada para el whisky aut\u00e9ntico y de alta calidad cuyas reglas de elaboraci\u00f3n son bien conocidas y su omisi\u00f3n se considera un atentado contra el consumidor. Pero en el caso del whisky de baja calidad o al cual se le incorporaron sabores suplementarios u otras bebidas alcoh\u00f3licas, no debe ser ingerido de no mediar certificaci\u00f3n kasher por temor a que se le pudieran haber mezclado ingredientes prohibidos.<\/p>\n<p>De igual manera, en diferentes lugares del mundo en los que se sabe que la cerveza u otras bebidas alcoh\u00f3licas est\u00e1n producidas con ingredientes kasher, y acostumbran a cuidar y preservar la tradici\u00f3n de su elaboraci\u00f3n y no mezclar en \u00e9stas ning\u00fan otro componente, los rabinos locales permiten beberlas sin que medie la certificaci\u00f3n kasher.<\/p>\n<p>Sin embargo, cuando no se tiene un conocimiento preciso en estas cuestiones, se debe regresar a la regla b\u00e1sica de no comer ning\u00fan alimento o ingerir bebida alguna que no tenga certificaci\u00f3n kasher.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se puede extraer alcohol a partir de alimentos que contienen az\u00facar, transform\u00e1ndolos en l\u00edquidos (como en el caso del jugo de uva) y ferment\u00e1ndolos por medio de levaduras (hongos especiales) que transforman el az\u00facar en alcohol (etanol). A trav\u00e9s del calentamiento de estos l\u00edquidos y la evaporaci\u00f3n del alcohol, se puede destilar el etanol y [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[266],"tags":[],"class_list":["post-6273","post","type-post","status-publish","format-standard","hentry","category-17-37"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>09 \u2013 El alcohol y las bebidas espirituosas - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/17-37-09\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"09 \u2013 El alcohol y las bebidas espirituosas - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"Se puede extraer alcohol a partir de alimentos que contienen az\u00facar, transform\u00e1ndolos en l\u00edquidos (como en el caso del jugo de uva) y ferment\u00e1ndolos por medio de levaduras (hongos especiales) que transforman el az\u00facar en alcohol (etanol). A trav\u00e9s del calentamiento de estos l\u00edquidos y la evaporaci\u00f3n del alcohol, se puede destilar el etanol y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/17-37-09\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-18T07:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T14:11:26+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-09\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-09\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"headline\":\"09 \u2013 El alcohol y las bebidas espirituosas\",\"datePublished\":\"2019-01-18T07:00:24+00:00\",\"dateModified\":\"2025-05-20T14:11:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-09\\\/\"},\"wordCount\":499,\"commentCount\":0,\"articleSection\":[\"La industria alimentaria - 37\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-09\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-09\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-09\\\/\",\"name\":\"09 \u2013 El alcohol y las bebidas espirituosas - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2019-01-18T07:00:24+00:00\",\"dateModified\":\"2025-05-20T14:11:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-09\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-09\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/17-37-09\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"09 \u2013 El alcohol y las bebidas espirituosas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/7866b763cf3f205e4ae075eebce0d674\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/eladgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"09 \u2013 El alcohol y las bebidas espirituosas - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/17-37-09\/","og_locale":"es_ES","og_type":"article","og_title":"09 \u2013 El alcohol y las bebidas espirituosas - Pninei Halaj\u00e1","og_description":"Se puede extraer alcohol a partir de alimentos que contienen az\u00facar, transform\u00e1ndolos en l\u00edquidos (como en el caso del jugo de uva) y ferment\u00e1ndolos por medio de levaduras (hongos especiales) que transforman el az\u00facar en alcohol (etanol). A trav\u00e9s del calentamiento de estos l\u00edquidos y la evaporaci\u00f3n del alcohol, se puede destilar el etanol y [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/17-37-09\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2019-01-18T07:00:24+00:00","article_modified_time":"2025-05-20T14:11:26+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/17-37-09\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-37-09\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"headline":"09 \u2013 El alcohol y las bebidas espirituosas","datePublished":"2019-01-18T07:00:24+00:00","dateModified":"2025-05-20T14:11:26+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-37-09\/"},"wordCount":499,"commentCount":0,"articleSection":["La industria alimentaria - 37"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/17-37-09\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/17-37-09\/","url":"https:\/\/ph.yhb.org.il\/es\/17-37-09\/","name":"09 \u2013 El alcohol y las bebidas espirituosas - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2019-01-18T07:00:24+00:00","dateModified":"2025-05-20T14:11:26+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/17-37-09\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/17-37-09\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/17-37-09\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"09 \u2013 El alcohol y las bebidas espirituosas"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/7866b763cf3f205e4ae075eebce0d674","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f73aec4c538c25ed89bfe678bd2c8d6c4c68e602d853cddfe42d3dbab083bc82?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/eladgg\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6273"}],"version-history":[{"count":1,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6273\/revisions"}],"predecessor-version":[{"id":6274,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6273\/revisions\/6274"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}