{"id":6630,"date":"2025-11-03T02:00:15","date_gmt":"2025-11-03T00:00:15","guid":{"rendered":"https:\/\/ph.yhb.org.il\/es\/?p=6630"},"modified":"2025-11-26T16:52:21","modified_gmt":"2025-11-26T14:52:21","slug":"18-03-02","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/es\/18-03-02\/","title":{"rendered":"02 &#8211; C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido"},"content":{"rendered":"<p>A modo de medida protectora -cerco- ante la prohibici\u00f3n, durante los d\u00edas de la veda de contacto entre los c\u00f3nyuges se proh\u00edbe tambi\u00e9n todo tipo de conversaci\u00f3n vinculada a la alegr\u00eda de la uni\u00f3n y las circunstancias que llevan a ella. A esto se refiere la Tor\u00e1 cuando advierte: <em>\u201cY a una mujer en la impureza de su menstruaci\u00f3n, no te acercar\u00e1s para descubrir su desnudez\u201d<\/em>, lo cual quiere decir que no abrace y no bese a su mujer ni hable con ella \u201cde cuestiones inapropiadas (<em>devarim betelim<\/em>)\u201d (Avot DeRab\u00ed Nat\u00e1n 2). O sea, si bien durante los d\u00edas en que la mujer est\u00e1 pura hablar sobre cuestiones relativas a la alegr\u00eda del v\u00ednculo conyugal es parte del cumplimiento del precepto de <em>on\u00e1<\/em>, en estos d\u00edas, este tipo de conversaci\u00f3n est\u00e1 prohibida y por lo tanto se la considera inadecuada.<\/p>\n<p>Adem\u00e1s, durante los d\u00edas en los que el contacto est\u00e1 prohibido es preciso abstenerse de hablar prolongadamente sobre diferentes asuntos que pudieran despertar el deseo, cada pareja conforme a lo que saben por experiencia que pudiera provocarlos. Seg\u00fan la opini\u00f3n de muchas autoridades hal\u00e1jicas, a eso se refirieron nuestros sabios cuando advirtieron: \u201cNo abundes en conversaci\u00f3n con la mujer, esto es, con su mujer (<em>nid\u00e1<\/em>), y por lo tanto mucho menos con la mujer del pr\u00f3jimo\u201d (Mishn\u00e1 Tratado de Avot 1:5, seg\u00fan la explicaci\u00f3n del Or Zar\u00faa 1:360, Shas, Rokeaj, Manhig, Melejet Shlom\u00f3 y otros). Adem\u00e1s, en los d\u00edas de la prohibici\u00f3n es preciso abstenerse de salir a vacaciones de pareja, las cuales, naturalmente, suelen generar una cercan\u00eda m\u00e1s intensa.<\/p>\n<p>En este sentido, esto es lo que aprendemos de las palabras de los sabios de Israel (Tratado de Shabat 64(B)) quienes vacilaron respecto de si es correcto o no que durante estos d\u00edas la mujer se arregle y se maquille. Los primeros ancianos explicaron que en la expresi\u00f3n <em>\u201cy para la menstruosa en su per\u00edodo de alejamiento (nidat\u00e1)\u201d<\/em> (Vaikr\u00e1-Lev\u00edtico 15:33), \u201csu per\u00edodo\u201d &#8211; \u201c<em>nidat\u00e1<\/em>\u201d- proviene en hebreo de \u201c<em>nidui verijuk<\/em>\u201d (apartamiento y alejamiento), y, por lo tanto, durante esos d\u00edas \u201cque no delinee con azul sus ojos, que no maquille su rostro ni se vista con prendas coloridas. Esto fue as\u00ed hasta que lleg\u00f3 Rab\u00ed Akiva y ense\u00f1\u00f3: Si de esa forma la vuelves desagradable a los ojos de su marido, al final este terminar\u00e1 divorci\u00e1ndola. Por eso, la Tor\u00e1 dice <em>\u201cpara la menstruosa en su per\u00edodo de alejamiento\u201d<\/em>, que se mantenga alejada (que recaiga sobre ella el deber de la separaci\u00f3n) hasta que se sumerja en el agua\u201d, esto es, si la mujer no se va a ver bien se teme que el marido se aleje de ella y no la extra\u00f1e, y en casos extremos terminen divorci\u00e1ndose. Por lo tanto, la mujer no debe arreglarse o maquillarse en la medida que considere necesaria.<\/p>\n<p>De esto vemos que durante los d\u00edas de la prohibici\u00f3n de contacto la pareja debe conducirse por un camino intermedio, por una parte, tener el recaudo de no despertar el deseo, y por la otra cuidar de no exagerar en lo que respecta al distanciamiento. En ese sentido, ya aprendimos anteriormente (1:4) que uno de los motivos de los d\u00edas de prohibici\u00f3n del contacto conyugal es el renovar los anhelos y el amor. \u201cDijo la Tor\u00e1: Que est\u00e9 impura durante siete d\u00edas para que sea agradable ante su marido como en el momento en que entr\u00f3 al palio nupcial\u201d (Tratado de Nid\u00e1 31(B)). Y si durante los d\u00edas de la separaci\u00f3n la mujer se va a tornar desagradable a ojos de su marido o el marido a ojos de su mujer o van a sentirse excesivamente distantes, cuando vuelvan a estar mutuamente permitidos no gozar\u00e1n de la renovaci\u00f3n de su amor.<\/p>\n<p>Por lo tanto, la mujer tiene permitido ataviarse durante los d\u00edas en que se mantiene <em>nid\u00e1<\/em>, teniendo el recaudo de no despertar el deseo en la pareja para no terminar incurriendo en una transgresi\u00f3n (Shulj\u00e1n Aruj 195:9, Torat Hashelamim 11). Asimismo, es bueno que durante estos d\u00edas los c\u00f3nyuges conversen amistosamente y se halaguen mutuamente para preservar el amor que los une vigoroso, pero no habr\u00e1n de conversar en exceso sobre cuestiones que pudieran suscitar en su interior el deseo por unirse.<\/p>\n<p>El principio general es comprensible, empero el camino a su implementaci\u00f3n es complejo, porque, por una parte, toda expresi\u00f3n de cari\u00f1o y de amor puede llegar a despertar la pasi\u00f3n. Por otra parte, la abstenci\u00f3n de expresiones de cercan\u00eda y amor pueden generar dolor y ofuscaci\u00f3n. Hay quienes proponen que en estos d\u00edas la pareja lleve a cabo conjuntamente tareas agotadoras tales como las de limpieza y mantenimiento, o complete labores vinculadas al trabajo o a los estudios, de modo tal que la sed por el contacto se vea reducida. Asimismo, se puede aprovechar este tiempo para visitas familiares tales como pasar el Shabat en casa de los padres.<\/p>\n<p>Cabe se\u00f1alar que, en el caso de numerosas parejas, los hombres est\u00e1n interesados en abstenerse de expresiones de cercan\u00eda, por temor a que su deseo se intensifique y el dolor por la separaci\u00f3n se les torne demasiado dif\u00edcil. Por su parte, las mujeres est\u00e1n interesadas en manifestaciones de amistad para que, aun durante esos d\u00edas, puedan sentirse amadas. Por lo tanto, sobre cada pareja recae la responsabilidad de determinar un modus operandi propio que les permita transitar por el tipo de camino intermedio que les resulte apropiado, en el marco de las limitaciones dispuestas por la Halaj\u00e1, tanto en las medidas destinadas a evitar una cercan\u00eda excesiva como la precauci\u00f3n por evitar infligir dolor a la pareja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A modo de medida protectora -cerco- ante la prohibici\u00f3n, durante los d\u00edas de la veda de contacto entre los c\u00f3nyuges se proh\u00edbe tambi\u00e9n todo tipo de conversaci\u00f3n vinculada a la alegr\u00eda de la uni\u00f3n y las circunstancias que llevan a ella. A esto se refiere la Tor\u00e1 cuando advierte: \u201cY a una mujer en la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278],"tags":[],"class_list":["post-6630","post","type-post","status-publish","format-standard","hentry","category-03-las-prohibiciones-que-requieren-de-alejamiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>02 - C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido - Pninei Halaj\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/es\/18-03-02\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"02 - C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido - Pninei Halaj\u00e1\" \/>\n<meta property=\"og:description\" content=\"A modo de medida protectora -cerco- ante la prohibici\u00f3n, durante los d\u00edas de la veda de contacto entre los c\u00f3nyuges se proh\u00edbe tambi\u00e9n todo tipo de conversaci\u00f3n vinculada a la alegr\u00eda de la uni\u00f3n y las circunstancias que llevan a ella. A esto se refiere la Tor\u00e1 cuando advierte: \u201cY a una mujer en la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/es\/18-03-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Pninei Halaj\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-03T00:00:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T14:52:21+00:00\" \/>\n<meta name=\"author\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/18-03-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/18-03-02\\\/\"},\"author\":{\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"headline\":\"02 &#8211; C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido\",\"datePublished\":\"2025-11-03T00:00:15+00:00\",\"dateModified\":\"2025-11-26T14:52:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/18-03-02\\\/\"},\"wordCount\":1008,\"commentCount\":0,\"articleSection\":[\"03- Las prohibiciones que requieren de alejamiento\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/18-03-02\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/18-03-02\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/18-03-02\\\/\",\"name\":\"02 - C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido - Pninei Halaj\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\"},\"datePublished\":\"2025-11-03T00:00:15+00:00\",\"dateModified\":\"2025-11-26T14:52:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/18-03-02\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/18-03-02\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/18-03-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"02 &#8211; C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/\",\"name\":\"Pninei Halaj\u00e1\",\"description\":\"Rabino Eliezer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/#\\\/schema\\\/person\\\/716cb852d9b9d1fb36cf3b60a4415178\",\"name\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g\",\"caption\":\"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/es\\\/author\\\/thfvhacvcss\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"02 - C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido - Pninei Halaj\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/es\/18-03-02\/","og_locale":"es_ES","og_type":"article","og_title":"02 - C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido - Pninei Halaj\u00e1","og_description":"A modo de medida protectora -cerco- ante la prohibici\u00f3n, durante los d\u00edas de la veda de contacto entre los c\u00f3nyuges se proh\u00edbe tambi\u00e9n todo tipo de conversaci\u00f3n vinculada a la alegr\u00eda de la uni\u00f3n y las circunstancias que llevan a ella. A esto se refiere la Tor\u00e1 cuando advierte: \u201cY a una mujer en la [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/es\/18-03-02\/","og_site_name":"Pninei Halaj\u00e1","article_published_time":"2025-11-03T00:00:15+00:00","article_modified_time":"2025-11-26T14:52:21+00:00","author":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/es\/18-03-02\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/18-03-02\/"},"author":{"name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"headline":"02 &#8211; C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido","datePublished":"2025-11-03T00:00:15+00:00","dateModified":"2025-11-26T14:52:21+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/es\/18-03-02\/"},"wordCount":1008,"commentCount":0,"articleSection":["03- Las prohibiciones que requieren de alejamiento"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ph.yhb.org.il\/es\/18-03-02\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/es\/18-03-02\/","url":"https:\/\/ph.yhb.org.il\/es\/18-03-02\/","name":"02 - C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido - Pninei Halaj\u00e1","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/es\/#website"},"datePublished":"2025-11-03T00:00:15+00:00","dateModified":"2025-11-26T14:52:21+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/es\/18-03-02\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/es\/18-03-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/es\/18-03-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ph.yhb.org.il\/es\/"},{"@type":"ListItem","position":2,"name":"02 &#8211; C\u00f3mo conducirse durante los d\u00edas en los que el contacto est\u00e1 prohibido"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/es\/#website","url":"https:\/\/ph.yhb.org.il\/es\/","name":"Pninei Halaj\u00e1","description":"Rabino Eliezer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/es\/#\/schema\/person\/716cb852d9b9d1fb36cf3b60a4415178","name":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8ba17770ba8ce22dc07b91d8f4d0b098f24d0589815cb02522b506f7d0ee9d94?s=96&d=mm&r=g","caption":"\u05de\u05e0\u05d4\u05dc \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/es\/author\/thfvhacvcss\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/comments?post=6630"}],"version-history":[{"count":2,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6630\/revisions"}],"predecessor-version":[{"id":6664,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/posts\/6630\/revisions\/6664"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/media?parent=6630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/categories?post=6630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/es\/wp-json\/wp\/v2\/tags?post=6630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}