{"id":1599,"date":"2016-01-21T00:15:10","date_gmt":"2016-01-20T22:15:10","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=1599"},"modified":"2017-07-24T10:38:03","modified_gmt":"2017-07-24T07:38:03","slug":"01-21-15","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/","title":{"rendered":"15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments"},"content":{"rendered":"<p><strong>\u00a0\u00a0\u00a0 <\/strong>\u00a0Les d\u00e9cisionnaires sont partag\u00e9s sur la question de la montre-bracelet. Certains disent qu\u2019il n\u2019est permis de sortir dans le domaine public avec sa montre que dans le cas o\u00f9 elle fait office de bijou. Ce qui est d\u00e9terminant, \u00e0 ce sujet, est la mani\u00e8re dont on se comporte quand la montre cesse de fonctionner : si l\u2019on a l\u2019habitude de l&rsquo;enlever, c\u2019est le signe qu\u2019elle n\u2019est pas un bijou, et qu\u2019on ne l\u2019a prise que pour conna\u00eetre l\u2019heure\u00a0; puisqu\u2019elle n\u2019est pas n\u00e9cessaire au corps, il est interdit de sortir avec une telle montre dans le domaine public. Mais si, m\u00eame au moment o\u00f9 elle cesse de fonctionner, on a l\u2019habitude de la garder au poignet en raison de sa beaut\u00e9 \u2013 par exemple si elle est en or \u2013 c\u2019est qu\u2019il s\u2019agit d\u2019un bijou, et il est permis de l\u2019avoir au poignet dans le domaine public.<\/p>\n<p>Mais de nombreux d\u00e9cisionnaires estiment que, puisque l\u2019on porte sa montre sur le corps, comme on le ferait d\u2019un v\u00eatement, que celui qui va sans sa montre a l\u2019impression qu\u2019il manque quelque chose \u00e0 ses effets, et que tel est l\u2019usage normal que de consulter sa montre quand elle se trouve \u00e0 son poignet, il appara\u00eet que la montre est l\u2019accessoire du corps, et que son statut est semblable \u00e0 celui des v\u00eatements et des bijoux, si bien qu\u2019il est permis de l\u2019avoir \u00e0 son poignet dans le domaine public. L\u2019opinion essentielle est ici celle des d\u00e9cisionnaires indulgents\u00a0; quant \u00e0 ceux qui sont rigoureux pour eux-m\u00eames, ils seront b\u00e9nis pour cela<sup><a href='#_te01ftn21_17' id='_te01ftnref21_17' class='aup1'>[17]<\/a><\/sup>.<\/p>\n<p>Une question d\u00e9licate se pose \u00e0 celui qui habite \u2013 ou est invit\u00e9 \u2013 en un lieu qui n\u2019est pas entour\u00e9 d\u2019un <em>\u00e9rouv<\/em>, dans le cas o\u00f9 il voudrait sortir de chez lui et ne saurait que faire de ses cl\u00e9s. La solution consiste \u00e0 se servir de la cl\u00e9 comme il le ferait de la boucle d\u2019une ceinture. On prendra un lacet auquel on enfilera la cl\u00e9, que l\u2019on attachera au moyen d\u2019un n\u0153ud de rosette, puis on se ceindra de ce lacet, de mani\u00e8re que la cl\u00e9 constitue la \u00ab\u00a0boucle\u00a0\u00bb de cette ceinture<sup><a href='#_te01ftn21_h' id='_te01ftnref21_h' class='aup1'>[h]<\/a><\/sup>. De cette mani\u00e8re, il sera permis de se rendre dans le domaine public (<em>Chemirat Chabbat Kehilkhata<\/em> 18, 49-50\u00a0; cf. ci-dessus, note 10).<\/p>\n<p>Dans certains endroits, il est interdit d\u2019aller dans la rue sans sa carte d\u2019identit\u00e9\u00a0; quand on doit sortir le Chabbat, pour une grande n\u00e9cessit\u00e9 ou pour les besoins d\u2019une mitsva, on portera sa carte de mani\u00e8re inhabituelle, par exemple en la pla\u00e7ant sous son chapeau, ou encore \u00e0 l\u2019int\u00e9rieur de sa chemise (de mani\u00e8re que la ceinture l\u2019emp\u00eache de tomber) ; de cette fa\u00e7on, le port se fait sur le mode de <em>chevout de-chevout<\/em> (deux \u00e9l\u00e9ments de limitation rabbinique), ce que les sages permettent pour une grande n\u00e9cessit\u00e9 ou pour les besoins d\u2019une mitsva (cf. chap. 9 \u00a7 11).<\/p>\n<p>De m\u00eame, un malade auquel le m\u00e9decin prescrit de ne pas sortir de chez soi sans avoir sur soi tel m\u00e9dicament, est autoris\u00e9 \u00e0 porter celui-ci, dans le cas o\u00f9 il doit sortir pour une grande n\u00e9cessit\u00e9 ou pour les besoins d\u2019une mitsva\u00a0; cela, \u00e0 condition de porter le m\u00e9dicament de mani\u00e8re inhabituelle. Si l\u2019on a besoin de profiter de cette indulgence, il est juste de ne pas se tenir immobile dans le domaine public, mais de marcher continument, jusqu\u2019\u00e0 ce que l\u2019on arrive au domaine particulier o\u00f9 l\u2019on avait l\u2019intention de se rendre (<em>Chemirat Chabbat Kehilkhata<\/em> 40, 7\u00a0; cf. ci-dessus note 3)<sup><a href='#_te01ftn21_18' id='_te01ftnref21_18' class='aup1'>[18]<\/a><\/sup>.<\/p>\n<p>En un endroit qui n\u2019est pas entour\u00e9 d\u2019un <em>\u00e9rouv<\/em>, et o\u00f9 il est n\u00e9cessaire, relativement \u00e0 l\u2019int\u00e9grit\u00e9 et \u00e0 la s\u00fbret\u00e9 des personnes (<em>piqoua\u2019h n\u00e9fech<\/em>), que certains puissent disposer imm\u00e9diatement de leur arme et de leur t\u00e9l\u00e9phone portable, il est permis \u00e0 ceux-l\u00e0 de sortir avec arme et t\u00e9l\u00e9phone, dans les limites des sorties usuelles<sup><a href='#_te01ftn21_i' id='_te01ftnref21_i' class='aup1'>[i]<\/a><\/sup> le Chabbat. On portera le t\u00e9l\u00e9phone de mani\u00e8re inhabituelle\u00a0; mais quant \u00e0 l\u2019arme, on la portera de mani\u00e8re habituelle, car il serait dangereux de la porter de fa\u00e7on inhabituelle. Pour les besoins d\u2019une promenade, il est interdit de prendre son arme, ni son instrument de liaison. Cette r\u00e8gle sera expliqu\u00e9e plus largement ci-apr\u00e8s, chap. 27 \u00a7 17.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref21_17' id='_te01ftn21_17'>[17]<\/a>. Le <em>Chemirat Chabbat Kehilkhata<\/em> 18, 27 tranche selon la premi\u00e8re opinion, mais pr\u00e9cise que ceux qui veulent \u00eatre indulgents ont sur qui s\u2019appuyer. Le <em>Yaskil \u2018Avdi<\/em> VII 19 et le <em>Oulhorot Natan<\/em> 4, 26 se prononcent dans le m\u00eame sens. Des propos du <em>Min\u2019hat Yits\u2019haq<\/em> I 67, il ressort que l\u2019auteur est rigoureux, m\u00eame s\u2019il s\u2019agit d\u2019une montre en or. Face \u00e0 cela, le Rav Chelomo Zalman Auerbach est indulgent, comme le rapporte le <em>Chemirat Chabbat Kehilkhata <\/em>18, note 113. De m\u00eame, selon le <em>Igrot Moch\u00e9, Ora\u2019h \u2018Ha\u00efm<\/em> I 111, si l\u2019on s\u2019en tient \u00e0 la stricte r\u00e8gle de droit, la chose est permise. C\u2019est aussi la position du <em>Ye\u2019hav\u00e9 Da\u2019at<\/em> III 23 et du <em>Menou\u2019hat Ahava<\/em> III 27, 33. Si le lieu est entour\u00e9 d\u2019un <em>\u00e9rouv<\/em>, ceux-l\u00e0 m\u00eame qui ont l\u2019usage d\u2019\u00eatre rigoureux en ce qu\u2019ils ne se fient pas \u00e0 la pr\u00e9sence d\u2019un <em>\u00e9rouv<\/em> du type <em>tsourat hap\u00e9ta\u2019h<\/em> dans des rues larges de 16 <em>amot<\/em>, peuvent s\u2019appuyer sur les d\u00e9cisionnaires indulgents en ce qui concerne le port d\u2019une montre-bracelet.<\/p>\n<p><a href='#_te01ftnref21_h' id='_te01ftn21_h'>[h]<\/a>. On doit veiller \u00e0 ce que la cl\u00e9 ne soit pas simplement suspendue, mais constitue un maillon de la cha\u00eene, c\u2019est-\u00e0-dire que deux branches de la ceinture soient attach\u00e9es par le trou de la cl\u00e9, chacune d\u2019un c\u00f4t\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><a href='#_te01ftnref21_18' id='_te01ftn21_18'>[18]<\/a>. La mani\u00e8re inhabituelle (<em>chinou\u00ef<\/em>, changement) est un \u00e9l\u00e9ment d\u2019abstention rabbinique reconnu par tous (<em>chevout<\/em>). Il faut y ajouter l\u2019avis selon lequel le domaine public de notre temps a seulement rang rabbinique\u00a0; nous avons d\u00e8s lors deux \u00e9l\u00e9ments d\u2019abstention rabbinique\u00a0(<em>chevout de-chevout<\/em>). Le Maharach Angel (3, 43) a propos\u00e9 un autre motif de permission\u00a0: le fait de porter est, dans de tels cas, une <em>m\u00e9lakha <\/em>dont la n\u00e9cessit\u00e9 ne r\u00e9side pas en elle-m\u00eame (<em>m\u00e9lakha ch\u00e9-eina tsrikha l\u00e9goufah<\/em>), car on n\u2019a pas besoin de la carte d\u2019identit\u00e9 pour elle-m\u00eame, mais uniquement pour \u00e9chapper \u00e0 des pr\u00e9judices administratifs. Par contre, quand il s\u2019agit de m\u00e9dicaments, il est difficile de soutenir que leur n\u00e9cessit\u00e9 ne r\u00e9side pas en eux-m\u00eames (cf. <em>Tsits Eli\u00e9zer<\/em> XIII 34). Par cons\u00e9quent, pour ceux qui estiment que le domaine public est, de nos jours encore, un domaine soumis \u00e0 l\u2019interdit toranique, il n\u2019y a pas lieu d\u2019\u00eatre indulgent\u00a0; aussi sera-t-il bon de ne pas rester immobile dans le domaine public, comme nous l\u2019expliquons en note 3 (cf. <em>Nichmat Avraham<\/em> 301, 2, 1). A priori, s\u2019agissant m\u00eame de la carte d\u2019identit\u00e9, il convient d\u2019agir ainsi.<\/p>\n<p>&nbsp;<\/p>\n<p><a href='#_te01ftnref21_i' id='_te01ftn21_i'>[i]<\/a>. Par exemple\u00a0: aller \u00e0 la synagogue, se rendre chez un camarade pour \u00e9tudier la Torah avec lui, se rendre chez ses amis \u00e0 leur invitation\u2026<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0 \u00a0Les d\u00e9cisionnaires sont partag\u00e9s sur la question de la montre-bracelet. Certains disent qu\u2019il n\u2019est permis de sortir dans le domaine public avec sa montre que dans le cas o\u00f9 elle fait office de bijou. Ce qui est d\u00e9terminant, \u00e0 ce sujet, est la mani\u00e8re dont on se comporte quand la montre cesse de fonctionner [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[],"class_list":["post-1599","post","type-post","status-publish","format-standard","hentry","category-01-21"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"\u00a0\u00a0\u00a0 \u00a0Les d\u00e9cisionnaires sont partag\u00e9s sur la question de la montre-bracelet. Certains disent qu\u2019il n\u2019est permis de sortir dans le domaine public avec sa montre que dans le cas o\u00f9 elle fait office de bijou. Ce qui est d\u00e9terminant, \u00e0 ce sujet, est la mani\u00e8re dont on se comporte quand la montre cesse de fonctionner [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-20T22:15:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-24T07:38:03+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-21-15\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-21-15\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments\",\"datePublished\":\"2016-01-20T22:15:10+00:00\",\"dateModified\":\"2017-07-24T07:38:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-21-15\\\/\"},\"wordCount\":1232,\"articleSection\":[\"Chapitre 21 - Transfert et port d\u2019objets (hotsaa)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-21-15\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-21-15\\\/\",\"name\":\"15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-01-20T22:15:10+00:00\",\"dateModified\":\"2017-07-24T07:38:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-21-15\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-21-15\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-21-15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/","og_locale":"fr_FR","og_type":"article","og_title":"15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments - Pnin\u00e9 Halakha","og_description":"\u00a0\u00a0\u00a0 \u00a0Les d\u00e9cisionnaires sont partag\u00e9s sur la question de la montre-bracelet. Certains disent qu\u2019il n\u2019est permis de sortir dans le domaine public avec sa montre que dans le cas o\u00f9 elle fait office de bijou. Ce qui est d\u00e9terminant, \u00e0 ce sujet, est la mani\u00e8re dont on se comporte quand la montre cesse de fonctionner [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-01-20T22:15:10+00:00","article_modified_time":"2017-07-24T07:38:03+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments","datePublished":"2016-01-20T22:15:10+00:00","dateModified":"2017-07-24T07:38:03+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/"},"wordCount":1232,"articleSection":["Chapitre 21 - Transfert et port d\u2019objets (hotsaa)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/","url":"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/","name":"15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-01-20T22:15:10+00:00","dateModified":"2017-07-24T07:38:03+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/01-21-15\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/01-21-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"15. Montre, cl\u00e9, carte d\u2019identit\u00e9, m\u00e9dicaments"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/1599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=1599"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/1599\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=1599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=1599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=1599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}