{"id":1867,"date":"2016-01-30T00:13:47","date_gmt":"2016-01-29T22:13:47","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=1867"},"modified":"2017-07-26T11:41:02","modified_gmt":"2017-07-26T08:41:02","slug":"01-30-13","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/","title":{"rendered":"13. <strong>Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction<\/strong>"},"content":{"rendered":"<p>Si l\u2019on veut \u00e9tablir son <em>\u00e9rouv<\/em> en d\u00e9posant de la nourriture, il faut d\u00e9poser, avant le coucher du soleil, une nourriture suffisante pour deux repas. S\u2019il s\u2019agit de pain, il doit y avoir le volume de huit <em>kabeitsa<\/em><sup><a href='#_te01ftn30_f' id='_te01ftnref30_f' class='aup1'>[f]<\/a><\/sup>, ce qui \u00e9quivaut \u00e0 400 cm\u00b3 (certains disent six <em>kabeitsa<\/em>). Si l\u2019on veut d\u00e9poser un aliment dont on tartine le pain, il suffit de pr\u00e9voir la quantit\u00e9 dont on a coutume d\u2019user pour tartiner un volume de huit <em>kabeitsa <\/em>de pain (<em>Choul\u2019han \u2018Aroukh<\/em> 409, 7). Si l\u2019on veut d\u00e9poser un <em>\u00e9rouv<\/em> suffisant pour plusieurs personnes, il faut pr\u00e9voir, pour chaque personne, la nourriture correspondant \u00e0 deux repas. S\u2019il s\u2019agit de nombreuses personnes, et que l\u2019on veuille limiter la quantit\u00e9 de l\u2019<em>\u00e9rouv<\/em>, on peut faire un d\u00e9p\u00f4t d\u2019huile d\u2019olive ou de p\u00e2te de chocolat\u00a0; en effet, on peut, avec une quantit\u00e9 relativement petite, y tremper \u2013 ou tartiner \u2013 beaucoup de pain. On peut encore d\u00e9poser 75 ml de vinaigre, mesure suffisante pour assaisonner deux repas de l\u00e9gumes (<em>Michna Beroura<\/em> 386, 35\u00a0; 409, 36). On peut \u00e9galement op\u00e9rer la jonction de p\u00e9rim\u00e8tres par le biais d\u2019une boisson\u00a0: on pr\u00e9voira 150 ml par personne (<em>Choul\u2019han \u2018Aroukh<\/em> 386, 6), ce qui correspond \u00e0 deux fois la mesure d\u2019un <em>revi\u2019it<\/em>. Mais on ne peut d\u00e9poser, comme <em>\u00e9rouv<\/em>, de l\u2019eau, ni du sel (<em>\u2018Erouvin<\/em> 26a)<sup><a href='#_te01ftn30_15' id='_te01ftnref30_15' class='aup1'>[15]<\/a><\/sup>.<\/p>\n<p>Il faut que la nourriture appartienne \u00e0 celui qui aura l\u2019usage de l\u2019<em>\u00e9rouv<\/em>, car ce n\u2019est qu\u2019ainsi qu\u2019il pourra \u00e9tablir le \u00ab\u00a0lieu\u00a0\u00bb de son Chabbat \u00e0 l\u2019endroit de l\u2019<em>\u00e9rouv<\/em>. Lorsqu\u2019on d\u00e9pose un<em> \u00e9rouv<\/em> \u00e0 l\u2019intention de plusieurs personnes, le propri\u00e9taire de la nourriture doit leur faire acqu\u00e9rir celle-ci, afin qu\u2019elles y soient associ\u00e9es. On accomplit cela par le biais d\u2019un tiers, qui soul\u00e8ve la nourriture, avec l\u2019intention de l\u2019acqu\u00e9rir pour le compte de ceux qui ont besoin de cet <em>\u00e9rouv<\/em> (<em>Choul\u2019han \u2018Aroukh<\/em> 413, 1).<\/p>\n<p>Si la nourriture d\u00e9pos\u00e9e en tant qu\u2019<em>\u00e9rouv<\/em> est consomm\u00e9e le vendredi avant le cr\u00e9puscule, l\u2019<em>\u00e9rouv<\/em> est annul\u00e9. Il est en revanche permis de la consommer apr\u00e8s le cr\u00e9puscule\u00a0: puisque l\u2019on a d\u00e9j\u00e0 fix\u00e9 le \u00ab\u00a0lieu\u00a0\u00bb de son Chabbat au cr\u00e9puscule, l\u2019<em>\u00e9rouv<\/em> restera efficace durant tout le Chabbat (Rama 394, 2). Si l\u2019on a d\u00e9pos\u00e9 la nourriture de l\u2019<em>\u00e9rouv<\/em> en un lieu tel qu\u2019un interdit toranique emp\u00eacherait de le prendre durant le cr\u00e9puscule \u2013 par exemple s\u2019il fallait d\u00e9blayer un tas de pierres pour l\u2019en extraire \u2013 cette nourriture ne constitue pas un <em>\u00e9rouv<\/em> (<em>Choul\u2019han \u2018Aroukh<\/em> 394, 3\u00a0; 409, 3-4).<\/p>\n<p>En pla\u00e7ant l\u2019<em>\u00e9rouv<\/em>, on r\u00e9citera la b\u00e9n\u00e9diction\u00a0: \u00ab\u00a0B\u00e9ni sois-Tu, Eternel, notre Dieu, Roi de l\u2019univers, qui nous as sanctifi\u00e9s par tes commandements, et nous as prescrit la mitsva de la jonction\u00a0\u00bb (<em>Baroukh Ata, Ado-na\u00ef, Elo-h\u00e9nou, M\u00e9lekh ha\u2019olam, acher qidechanou bemitsvotav, v\u00e9tsivanou \u2018al mitsvat \u2018\u00e9rouv<\/em>). Puis on d\u00e9clarera\u00a0: \u00ab\u00a0Par cet <em>\u00e9rouv<\/em>, il me sera permis de marcher, depuis cet endroit, deux mille <em>ama<\/em> dans chaque direction\u00a0\u00bb (<em>Bez\u00e9 ha\u2019\u00e9rouv, yihy\u00e9 moutar li leilekh mimaqom z\u00e9 alpayim ama lekhol roua\u2019h<\/em>). A posteriori, si l\u2019on s\u2019est content\u00e9 de dire\u00a0: \u00ab\u00a0Ce sera l\u2019<em>\u00e9rouv<\/em>\u00a0\u00bb, la jonction reste valable. Mais si l\u2019on n\u2019a rien dit, on n\u2019a point \u00e9tabli d\u2019<em>\u00e9rouv <\/em>(<em>Choul\u2019han \u2018Aroukh<\/em> 415, 4\u00a0; <em>Michna Beroura<\/em> 15).<\/p>\n<p>Quand l\u2019<em>\u00e9rouv<\/em> est destin\u00e9 \u00e0 plusieurs personnes, on mentionnera explicitement \u00e0 qui il est destin\u00e9. On veillera bien \u00e0 ce que l\u2019<em>\u00e9rouv<\/em> contienne une quantit\u00e9 de nourriture qui suffit \u00e0 deux repas, pour chacune des personnes qui en ont besoin (<em>Choul\u2019han \u2018Aroukh<\/em> 415, 4). Si l\u2019on veut que l\u2019<em>\u00e9rouv<\/em> serve de nombreux Chabbats, on dira\u00a0: \u00ab\u00a0pour tous les Chabbats de l\u2019ann\u00e9e\u00a0\u00bb (<em>lekhol chabbetot hachana<\/em>)\u00a0; alors, tant que l\u2019<em>\u00e9rouv<\/em> existera, il sera efficace (<em>Michna Beroura<\/em> 16).<\/p>\n<p>On peut \u00e9tablir l\u2019<em>\u00e9rouv<\/em> par le biais d\u2019un mandataire (<em>chalia\u2019h<\/em>). Mais un mineur, un non-Juif, ou un Juif majeur qui n\u2019a pas foi dans la mitsva de l\u2019<em>\u00e9rouv<\/em>, ne peuvent \u00eatre mandataires. Le mandataire doit prononcer la b\u00e9n\u00e9diction et le texte traditionnel\u00a0; s\u2019il ne dit rien, l\u2019<em>\u00e9rouv<\/em> n\u2019est pas valide (<em>Choul\u2019han \u2018Aroukh<\/em> 409, 8). Si l\u2019initiateur de l\u2019<em>\u00e9rouv <\/em>d\u00e9clare\u00a0: \u00ab\u00a0Par cet <em>\u00e9rouv<\/em>, que place mon mandataire, il me sera permis de marcher, depuis l\u2019emplacement de l\u2019<em>\u00e9rouv<\/em>, deux mille <em>ama <\/em>dans chaque direction\u00a0\u00bb, l\u2019<em>\u00e9rouv<\/em> est valide (<em>B\u00e9our Halakha<\/em>, passage commen\u00e7ant par <em>Vayomer<\/em>).<\/p>\n<p>On ne peut \u00e9tablir un <em>\u00e9rouv<\/em> \u00e0 l\u2019intention de son prochain \u00e0 son insu. Pour les membres mineurs de sa famille, on est autoris\u00e9 \u00e0 \u00e9tablir un <em>\u00e9rouv<\/em>\u00a0; celui-ci les engagera. De m\u00eame, on peut \u00e9tablir un <em>\u00e9rouv<\/em> \u00e0 l\u2019intention des membres de sa famille qui sont parvenus \u00e0 l\u2019\u00e2ge des mitsvot\u00a0; simplement, si ceux-ci d\u00e9clarent, apr\u00e8s avoir pris connaissance de l\u2019existence de cet <em>\u00e9rouv<\/em>, ne pas vouloir en tenir compte, l\u2019<em>\u00e9rouv<\/em> ne les engagera pas. Un mineur de moins de six ans est consid\u00e9r\u00e9 comme assimil\u00e9 \u00e0 sa m\u00e8re\u00a0; l\u2019<em>\u00e9rouv<\/em> qui a effet sur elle aura donc \u00e9galement effet sur lui (<em>Choul\u2019han \u2018Aroukh<\/em> 414, 1-2).<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref30_f' id='_te01ftn30_f'>[f]<\/a>. <em>Kabeitsa <\/em>: \u00ab\u00a0volume d\u2019un \u0153uf\u00a0\u00bb.<\/p>\n<p><a href='#_te01ftnref30_15' id='_te01ftn30_15'>[15]<\/a>. Au trait\u00e9 <em>\u2018Erouvin<\/em> du Talmud (26a), il est dit que l\u2019on peut faire l\u2019<em>\u00e9rouv<\/em> avec un m\u00e9lange d\u2019eau et de sel ; Ma\u00efmonide tranche en ce sens (<em>\u2018Erouvin<\/em> 1, 8). Selon <em>Tossephot <\/em>(\u05d3\u00a0\u00bb\u05d4 \u05d0\u05d1\u05dc), en revanche, se fondant sur la suite de la Gu\u00e9mara, ce m\u00e9lange ne peut valablement servir d\u2019<em>\u00e9rouv<\/em> que lorsqu\u2019on a m\u00eal\u00e9 de l\u2019huile \u00e0 l\u2019eau et au sel. Le <em>Choul\u2019han \u2018Aroukh<\/em> (386, 5) tranche, sans autre mention, en reprenant l\u2019avis de Ma\u00efmonide, mais cite la position de <em>Tossephot<\/em> comme opinion alternative. Le <em>Michna Beroura<\/em> (29) \u00e9crit que la r\u00e8gle est d\u2019\u00eatre indulgent, conform\u00e9ment au premier avis.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si l\u2019on veut \u00e9tablir son \u00e9rouv en d\u00e9posant de la nourriture, il faut d\u00e9poser, avant le coucher du soleil, une nourriture suffisante pour deux repas. S\u2019il s\u2019agit de pain, il doit y avoir le volume de huit kabeitsa[f], ce qui \u00e9quivaut \u00e0 400 cm\u00b3 (certains disent six kabeitsa). Si l\u2019on veut d\u00e9poser un aliment dont [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111],"tags":[],"class_list":["post-1867","post","type-post","status-publish","format-standard","hentry","category-01-30"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>13. Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13. Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Si l\u2019on veut \u00e9tablir son \u00e9rouv en d\u00e9posant de la nourriture, il faut d\u00e9poser, avant le coucher du soleil, une nourriture suffisante pour deux repas. S\u2019il s\u2019agit de pain, il doit y avoir le volume de huit kabeitsa[f], ce qui \u00e9quivaut \u00e0 400 cm\u00b3 (certains disent six kabeitsa). Si l\u2019on veut d\u00e9poser un aliment dont [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-29T22:13:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-26T08:41:02+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-30-13\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-30-13\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"13. Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction\",\"datePublished\":\"2016-01-29T22:13:47+00:00\",\"dateModified\":\"2017-07-26T08:41:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-30-13\\\/\"},\"wordCount\":1001,\"articleSection\":[\"Chapitre 30 - Zones d\u2019habitation (te\u2019houmin)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-30-13\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-30-13\\\/\",\"name\":\"13. Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-01-29T22:13:47+00:00\",\"dateModified\":\"2017-07-26T08:41:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-30-13\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-30-13\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/01-30-13\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"13. Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13. Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/","og_locale":"fr_FR","og_type":"article","og_title":"13. Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction - Pnin\u00e9 Halakha","og_description":"Si l\u2019on veut \u00e9tablir son \u00e9rouv en d\u00e9posant de la nourriture, il faut d\u00e9poser, avant le coucher du soleil, une nourriture suffisante pour deux repas. S\u2019il s\u2019agit de pain, il doit y avoir le volume de huit kabeitsa[f], ce qui \u00e9quivaut \u00e0 400 cm\u00b3 (certains disent six kabeitsa). Si l\u2019on veut d\u00e9poser un aliment dont [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-01-29T22:13:47+00:00","article_modified_time":"2017-07-26T08:41:02+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"13. Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction","datePublished":"2016-01-29T22:13:47+00:00","dateModified":"2017-07-26T08:41:02+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/"},"wordCount":1001,"articleSection":["Chapitre 30 - Zones d\u2019habitation (te\u2019houmin)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/","url":"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/","name":"13. Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-01-29T22:13:47+00:00","dateModified":"2017-07-26T08:41:02+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/01-30-13\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/01-30-13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"13. Comment on op\u00e8re la jonction des zones\u00a0; b\u00e9n\u00e9diction"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/1867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=1867"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/1867\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=1867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=1867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=1867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}