{"id":1974,"date":"2016-05-02T00:09:09","date_gmt":"2016-05-01T21:09:09","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=1974"},"modified":"2018-03-15T12:47:46","modified_gmt":"2018-03-15T10:47:46","slug":"05-02-09","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/","title":{"rendered":"09. Les femmes et le compte de l\u2019<em>omer<\/em>"},"content":{"rendered":"<p>Conform\u00e9ment au principe bien connu selon lequel les femmes sont exempt\u00e9es des mitsvot \u00ab\u00a0positives\u00a0\u00bb (c\u2019est-\u00e0-dire des obligations de faire) conditionn\u00e9es par le temps, les femmes sont exempt\u00e9es de la mitsva de compter l\u2019<em>omer<\/em>, puisque cette mitsva est d\u00e9pendante du temps (cf. <em>La Pri\u00e8re juive au f\u00e9minin<\/em>, chap. 3, quant \u00e0 la signification de ce principe).<\/p>\n<p>Mais une femme qui le souhaite peut accomplir une mitsva positive conditionn\u00e9e par le temps, et, ce faisant, son acte participe de la mitsva. Nous voyons ainsi que les femmes ont coutume d\u2019\u00e9couter la sonnerie du chofar \u00e0 Roch hachana, saisissent le <em>loulav<\/em> \u00e0 Soukot et s\u2019installent sous la souka. Simplement, les d\u00e9cisionnaires sont partag\u00e9s quant \u00e0 la question de la b\u00e9n\u00e9diction.<\/p>\n<p>Selon le <em>Choul\u2019han \u2018Aroukh<\/em> (<em>Ora\u2019h \u2018Ha\u00efm<\/em> 589, 6), elles ne prononcent pas la b\u00e9n\u00e9diction\u00a0; et telle est la coutume la plus r\u00e9pandue parmi les femmes s\u00e9farades. Selon le Rama, une femme qui accomplit une mitsva positive d\u00e9termin\u00e9e par le temps est autoris\u00e9e \u00e0 r\u00e9citer la b\u00e9n\u00e9diction y aff\u00e9rente. Tel est l\u2019usage ashk\u00e9naze (<em>La Pri\u00e8re juive au f\u00e9minin<\/em> 2, 8). Toutefois, certains d\u00e9cisionnaires ashk\u00e9nazes estiment qu\u2019il est pr\u00e9f\u00e9rable pour la femme de ne point dire la b\u00e9n\u00e9diction sur le compte de l\u2019<em>omer<\/em>. En effet, puisqu\u2019elle ne se trouve pas \u00e0 la synagogue, il y a davantage de risque qu\u2019elle n\u2019oublie de compter quelque jour\u00a0; il est donc \u00e0 craindre qu\u2019elle ne s\u2019aper\u00e7oive pas de cet oubli, et qu\u2019elle continue \u00e0 compter les jours suivants en disant la b\u00e9n\u00e9diction. Or nous avons vu que, si l\u2019on oublie de compter un jour, on n\u2019est plus autoris\u00e9 \u00e0 dire la b\u00e9n\u00e9diction sur le compte des jours suivants (<em>Michna Beroura<\/em> 489, 3). Certains auteurs \u00e9crivent que, selon la Kabbale, les femmes ne doivent pas compter l\u2019<em>omer<\/em> (<em>Rav Pe\u2019alim<\/em> I <em>Sod Y\u00e9charim<\/em> 12). \u00c0 l\u2019inverse, d\u2019autres auteurs \u00e9crivent que la coutume ashk\u00e9naze veut que les femmes comptent l\u2019<em>omer<\/em> (<em>Maguen Avraham<\/em> 489, 1).<\/p>\n<p>En pratique, une femme qui sait, en son for int\u00e9rieur, qu\u2019elle peut compter tous les jours de l\u2019<em>omer<\/em>, et que, si elle oubliait un jour, elle saurait continuer sans b\u00e9n\u00e9diction, est autoris\u00e9e, suivant la coutume ashk\u00e9naze, \u00e0 compter avec b\u00e9n\u00e9diction. En particulier, quand une femme a l\u2019usage de r\u00e9citer chaque soir la pri\u00e8re d\u2019Arvit, ou que sa famille a l\u2019habitude de lui rappeler de compter, la crainte d\u2019oublier la mitsva de l\u2019<em>omer<\/em> est moindre. Et si elle le veut, elle pourra, selon la coutume ashk\u00e9naze, r\u00e9citer la b\u00e9n\u00e9diction.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conform\u00e9ment au principe bien connu selon lequel les femmes sont exempt\u00e9es des mitsvot \u00ab\u00a0positives\u00a0\u00bb (c\u2019est-\u00e0-dire des obligations de faire) conditionn\u00e9es par le temps, les femmes sont exempt\u00e9es de la mitsva de compter l\u2019omer, puisque cette mitsva est d\u00e9pendante du temps (cf. La Pri\u00e8re juive au f\u00e9minin, chap. 3, quant \u00e0 la signification de ce principe). [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114],"tags":[],"class_list":["post-1974","post","type-post","status-publish","format-standard","hentry","category-05-02"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>09. Les femmes et le compte de l\u2019omer - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"09. Les femmes et le compte de l\u2019omer - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Conform\u00e9ment au principe bien connu selon lequel les femmes sont exempt\u00e9es des mitsvot \u00ab\u00a0positives\u00a0\u00bb (c\u2019est-\u00e0-dire des obligations de faire) conditionn\u00e9es par le temps, les femmes sont exempt\u00e9es de la mitsva de compter l\u2019omer, puisque cette mitsva est d\u00e9pendante du temps (cf. La Pri\u00e8re juive au f\u00e9minin, chap. 3, quant \u00e0 la signification de ce principe). [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-01T21:09:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-15T10:47:46+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-02-09\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-02-09\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"09. Les femmes et le compte de l\u2019omer\",\"datePublished\":\"2016-05-01T21:09:09+00:00\",\"dateModified\":\"2018-03-15T10:47:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-02-09\\\/\"},\"wordCount\":471,\"articleSection\":[\"Chapitre 02 - Le compte de l\u2019omer\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-02-09\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-02-09\\\/\",\"name\":\"09. Les femmes et le compte de l\u2019omer - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-05-01T21:09:09+00:00\",\"dateModified\":\"2018-03-15T10:47:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-02-09\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-02-09\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-02-09\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"09. Les femmes et le compte de l\u2019omer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"09. Les femmes et le compte de l\u2019omer - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/","og_locale":"fr_FR","og_type":"article","og_title":"09. Les femmes et le compte de l\u2019omer - Pnin\u00e9 Halakha","og_description":"Conform\u00e9ment au principe bien connu selon lequel les femmes sont exempt\u00e9es des mitsvot \u00ab\u00a0positives\u00a0\u00bb (c\u2019est-\u00e0-dire des obligations de faire) conditionn\u00e9es par le temps, les femmes sont exempt\u00e9es de la mitsva de compter l\u2019omer, puisque cette mitsva est d\u00e9pendante du temps (cf. La Pri\u00e8re juive au f\u00e9minin, chap. 3, quant \u00e0 la signification de ce principe). [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-05-01T21:09:09+00:00","article_modified_time":"2018-03-15T10:47:46+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"09. Les femmes et le compte de l\u2019omer","datePublished":"2016-05-01T21:09:09+00:00","dateModified":"2018-03-15T10:47:46+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/"},"wordCount":471,"articleSection":["Chapitre 02 - Le compte de l\u2019omer"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/","url":"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/","name":"09. Les femmes et le compte de l\u2019omer - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-05-01T21:09:09+00:00","dateModified":"2018-03-15T10:47:46+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/05-02-09\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/05-02-09\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"09. Les femmes et le compte de l\u2019omer"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/1974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=1974"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/1974\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=1974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=1974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=1974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}