{"id":1986,"date":"2016-05-03T00:05:30","date_gmt":"2016-05-02T21:05:30","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=1986"},"modified":"2018-03-15T13:11:39","modified_gmt":"2018-03-15T11:11:39","slug":"05-03-05","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/","title":{"rendered":"05. Mariage et fian\u00e7ailles pendant l\u2019<em>omer<\/em>"},"content":{"rendered":"<p>Apr\u00e8s avoir abord\u00e9 la question des limites temporelles des r\u00e8gles de deuil, nous r\u00e9sumerons ici les diff\u00e9rentes coutumes plus en d\u00e9tail. Les Gu\u00e9onim ont \u00e9crit que, depuis la mort des disciples de Rabbi Aqiba entre Pessa\u2019h et Chavou\u2019ot, les Juifs ont l\u2019usage de ne pas se marier durant cette p\u00e9riode.<\/p>\n<p>Selon certains d\u00e9cisionnaires, c\u2019est seulement de mariages \u00ab\u00a0facultatifs\u00a0\u00bb que l\u2019on doit s\u2019abstenir\u00a0: par exemple, si l\u2019on a d\u00e9j\u00e0 \u00e9t\u00e9 mari\u00e9, et que l\u2019on ait accompli la mitsva de procr\u00e9er. En revanche, si l\u2019on n\u2019a pas encore accompli cette mitsva, on peut, selon cette opinion, se marier durant l\u2019<em>omer<\/em>, car la mitsva du mariage repousse la simple coutume (Radbaz, <em>Peri \u2018Hadach<\/em>). Mais en pratique, les A\u2019haronim s\u2019accordent \u00e0 dire que l\u2019usage est de ne point se marier durant cette p\u00e9riode, m\u00eame si l\u2019on n\u2019a pas encore accompli la mitsva de procr\u00e9er\u00a0; en effet, permettre ces mariages reviendrait \u00e0 \u00f4ter presque toute signification \u00e0 cet usage de deuil. Toutefois, il est permis de se remarier avec une femme dont on avait divorc\u00e9, car cela constitue une mitsva sans qu\u2019il y ait l\u00e0 de grande occasion festive (<em>Michna Beroura<\/em> 493, 1\u00a0; <em>Kaf Ha\u2019ha\u00efm<\/em> 2-3).<\/p>\n<p>Suivant la coutume de la majorit\u00e9 des S\u00e9farades, l\u2019interdit de se marier court du d\u00e9but de l\u2019<em>omer<\/em> jusqu\u2019au trente-quatri\u00e8me jour\u00a0; d\u00e8s le matin du trente-quatri\u00e8me jour, il redevient permis de c\u00e9l\u00e9brer un mariage. Dans certaines communaut\u00e9s s\u00e9farades, on a coutume d\u2019\u00eatre plus indulgent, et de permettre de se marier d\u00e8s le trente-troisi\u00e8me jour (Lag ba\u2019omer) ; en cas de n\u00e9cessit\u00e9 pressante, on peut, apr\u00e8s consultation d\u2019un rabbin, agir ainsi (cf. note 3 ci-dessus).<\/p>\n<p>La coutume ashk\u00e9naze, en terre d\u2019Isra\u00ebl, interdit les mariages du d\u00e9but de l\u2019<em>omer<\/em> au 29 iyar, et les permet depuis Roch \u2018hodech du mois de sivan. Certains rabbins, indulgents, permettent \u00e0 ceux qui n\u2019ont pas encore accompli la mitsva de procr\u00e9ation de se marier d\u00e8s Lag ba\u2019omer. Si l\u2019on veut se fonder sur cette indulgence, s\u2019agissant d\u2019une mitsva si importante, on y est autoris\u00e9. S\u2019agissant du jour de Lag ba\u2019omer lui-m\u00eame, toutes les coutumes ashk\u00e9nazes s\u2019accordent \u00e0 y autoriser de se marier. Certains permettent m\u00eame de se marier le soir de Lag ba\u2019omer, et cela est permis \u00e0 ceux qui veulent \u00eatre indulgents \u00e0 cet \u00e9gard. Si le mariage a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9 dans la journ\u00e9e de Lag ba\u2019omer, tous les avis s\u2019accordent \u00e0 permettre de poursuivre les festivit\u00e9s dans la nuit du trente-quatri\u00e8me jour de l\u2019<em>omer<\/em><sup><a href='#_te01ftn3_6' id='_te01ftnref3_6' class='aup1'>[6]<\/a><\/sup>.<\/p>\n<p>Si l\u2019on est invit\u00e9 \u00e0 un mariage, un jour o\u00f9, selon sa propre coutume, il n\u2019est pas permis de se marier, mais o\u00f9, selon la coutume du mari\u00e9 lui-m\u00eame, cela est permis, on sera autoris\u00e9 \u00e0 se rendre aux noces, \u00e0 participer au repas et \u00e0 r\u00e9jouir les \u00e9poux en prenant part aux danses (<em>Igrot Moch\u00e9, Ora\u2019h \u2018Ha\u00efm<\/em> I 159).<\/p>\n<p>Seuls les mariages sont interdits, mais il est en revanche permis de c\u00e9l\u00e9brer ce que, de nos jours, on appelle fian\u00e7ailles<sup><a href='#_te01ftn3_a' id='_te01ftnref3_a' class='aup1'>[a]<\/a><\/sup>, \u00e0 la condition de ne pas y diffuser de musique<sup><a href='#_te01ftn3_7' id='_te01ftnref3_7' class='aup1'>[7]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref3_6' id='_te01ftn3_6'>[6]<\/a>. S\u2019agissant de l\u2019interdit de se marier jusqu\u2019\u00e0 Roch \u2018hodech sivan, voir ci-dessus, note 4. Quoi qu\u2019il en soit, le 28 iyar, jour de la Lib\u00e9ration de J\u00e9rusalem, le grand rabbinat d\u2019Isra\u00ebl autorise, d\u2019apr\u00e8s l\u2019ensemble des coutumes ashk\u00e9nazes, \u00e0 se marier. Quant \u00e0 la nuit de Lag ba\u2019omer, cf. ci-dessus, note 5. Si le mariage a eu lieu dans la journ\u00e9e de Lag ba\u2019omer, on peut prolonger le repas et les danses dans la soir\u00e9e du trente-quatri\u00e8me jour (cf. <em>Pisq\u00e9 Techouvot<\/em> 493, 11). Cf. <em>Hanissou\u00efn Kehilkhatam<\/em> 5, 19-34 et <em>Matsa Tov<\/em> pp. 274-279. Selon certains, il est pr\u00e9f\u00e9rable de se marier dans la nuit de Lag ba\u2019omer, afin que la f\u00eate et les danses ne se prolongent pas pendant le trente-quatri\u00e8me jour (<em>Hilkhot \u2018Hag Be\u2019hag<\/em> 7, note 71).<\/p>\n<p>Quand Lag ba\u2019omer tombe le dimanche, certains d\u00e9cisionnaires ashk\u00e9nazes permettent, en cas de n\u00e9cessit\u00e9 pressante, de se marier le vendredi, \u00e0 l\u2019instar du Rama en mati\u00e8re de coupe de cheveux\u00a0; d\u2019autres l\u2019interdisent (cf. <em>Hanissou\u00efn Kehilkhatam<\/em> 5, 23, <em>Pisq\u00e9 Techouvot<\/em> 493, 11). D\u2019apr\u00e8s la coutume s\u00e9farade, il semble certain qu\u2019il n\u2019y a pas lieu d\u2019\u00eatre indulgent \u00e0 cet \u00e9gard.<\/p>\n<p>Si Roch \u2018hodech iyar tombe le Chabbat, et dans la mesure o\u00f9 la joie est alors double, le <em>Michna Beroura<\/em> 493, 5 estime qu\u2019il est permis de se marier le vendredi pr\u00e9c\u00e9dent, et d\u2019organiser le repas de mariage et la r\u00e9ception festive pendant Chabbat-Roch \u2018hodech. D\u2019apr\u00e8s la coutume s\u00e9farade, on n\u2019est indulgent en la mati\u00e8re qu\u2019en cas de n\u00e9cessit\u00e9 pressante (<em>Kaf Ha\u2019ha\u00efm<\/em> 493, 42, qui se fonde sur le <em>Beit David<\/em> et le \u2018Hida).<\/p>\n<p><a href='#_te01ftnref3_a' id='_te01ftn3_a'>[a]<\/a>. <em>Iroussin\u00a0<\/em>: ce terme d\u00e9signe, en h\u00e9breu moderne, les fian\u00e7ailles. Mais en droit talmudique, il vise tout autre chose\u00a0: la premi\u00e8re partie des v\u00e9ritables noces, au cours de laquelle l\u2019anneau est remis, et l\u2019\u00e9pous\u00e9e se voit d\u00e9j\u00e0 consacr\u00e9e \u00e0 son \u00e9poux.<\/p>\n<p><a href='#_te01ftnref3_7' id='_te01ftn3_7'>[7]<\/a>. Bien que la c\u00e9l\u00e9bration de fian\u00e7ailles se caract\u00e9rise par la joie, elles participent quelque peu d\u2019une mitsva, puisqu\u2019elles renforcent le lien existant entre les deux promis. Il ne faut cependant pas y faire entendre de musique, car une telle r\u00e9union n\u2019est pas consid\u00e9r\u00e9e comme un v\u00e9ritable repas donn\u00e9 \u00e0 l\u2019occasion d\u2019une mitsva, comme l\u2019explique le <em>Maguen Avraham<\/em> 493, 1, et comme le note le <em>Michna Beroura<\/em> 3 au sujet d\u2019une <em>s\u00e9\u2019oudat chidoukhim <\/em>[repas donn\u00e9 \u00e0 l\u2019occasion de la rencontre pr\u00e9liminaire entre les familles, pour exprimer leur accord], et contrairement \u00e0 l\u2019interpr\u00e9tation du <em>Yalqout Yossef<\/em> au paragraphe 35.<\/p>\n<p>Nous le verrons ci-apr\u00e8s, \u00a7 9, m\u00eame lors d\u2019un repas donn\u00e9 \u00e0 l\u2019occasion d\u2019une mitsva, tel qu\u2019un repas de <em>berit-mila<\/em> (circoncision), il n\u2019est permis de diffuser de la musique qu\u2019en une localit\u00e9\u00a0o\u00f9 l\u2019on a l\u2019habitude constante de diffuser de la musique en une semblable circonstance. Or, dans les f\u00eates donn\u00e9es \u00e0 l\u2019occasion de fian\u00e7ailles, nombreux sont ceux qui n\u2019ont pas coutume de diffuser de la musique. Ces derni\u00e8res ann\u00e9es, l\u2019usage s\u2019est toutefois r\u00e9pandu de faire entendre de la musique et de danser lors de f\u00eates de fian\u00e7ailles. Si l\u2019on estime que tel est l\u2019usage de tout son entourage, on pourra, si l\u2019on veut, \u00eatre indulgent, en ne s\u2019autorisant que le minimum admis. En un tel cas, il sera bon, afin de justifier davantage la pr\u00e9sence de musique, d\u2019organiser \u00e0 cette m\u00eame occasion la cl\u00f4ture de l\u2019\u00e9tude d\u2019un trait\u00e9 talmudique (<em>siyoum mass\u00e9khet<\/em>).<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s avoir abord\u00e9 la question des limites temporelles des r\u00e8gles de deuil, nous r\u00e9sumerons ici les diff\u00e9rentes coutumes plus en d\u00e9tail. Les Gu\u00e9onim ont \u00e9crit que, depuis la mort des disciples de Rabbi Aqiba entre Pessa\u2019h et Chavou\u2019ot, les Juifs ont l\u2019usage de ne pas se marier durant cette p\u00e9riode. Selon certains d\u00e9cisionnaires, c\u2019est seulement [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-1986","post","type-post","status-publish","format-standard","hentry","category-05-03"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>05. Mariage et fian\u00e7ailles pendant l\u2019omer - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"05. Mariage et fian\u00e7ailles pendant l\u2019omer - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s avoir abord\u00e9 la question des limites temporelles des r\u00e8gles de deuil, nous r\u00e9sumerons ici les diff\u00e9rentes coutumes plus en d\u00e9tail. Les Gu\u00e9onim ont \u00e9crit que, depuis la mort des disciples de Rabbi Aqiba entre Pessa\u2019h et Chavou\u2019ot, les Juifs ont l\u2019usage de ne pas se marier durant cette p\u00e9riode. Selon certains d\u00e9cisionnaires, c\u2019est seulement [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-02T21:05:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-15T11:11:39+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-03-05\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-03-05\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"05. Mariage et fian\u00e7ailles pendant l\u2019omer\",\"datePublished\":\"2016-05-02T21:05:30+00:00\",\"dateModified\":\"2018-03-15T11:11:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-03-05\\\/\"},\"wordCount\":1188,\"articleSection\":[\"Chapitre 03 - Usages de deuil pendant l\u2019omer\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-03-05\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-03-05\\\/\",\"name\":\"05. Mariage et fian\u00e7ailles pendant l\u2019omer - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-05-02T21:05:30+00:00\",\"dateModified\":\"2018-03-15T11:11:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-03-05\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-03-05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/05-03-05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"05. Mariage et fian\u00e7ailles pendant l\u2019omer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"05. Mariage et fian\u00e7ailles pendant l\u2019omer - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/","og_locale":"fr_FR","og_type":"article","og_title":"05. Mariage et fian\u00e7ailles pendant l\u2019omer - Pnin\u00e9 Halakha","og_description":"Apr\u00e8s avoir abord\u00e9 la question des limites temporelles des r\u00e8gles de deuil, nous r\u00e9sumerons ici les diff\u00e9rentes coutumes plus en d\u00e9tail. Les Gu\u00e9onim ont \u00e9crit que, depuis la mort des disciples de Rabbi Aqiba entre Pessa\u2019h et Chavou\u2019ot, les Juifs ont l\u2019usage de ne pas se marier durant cette p\u00e9riode. Selon certains d\u00e9cisionnaires, c\u2019est seulement [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-05-02T21:05:30+00:00","article_modified_time":"2018-03-15T11:11:39+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"05. Mariage et fian\u00e7ailles pendant l\u2019omer","datePublished":"2016-05-02T21:05:30+00:00","dateModified":"2018-03-15T11:11:39+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/"},"wordCount":1188,"articleSection":["Chapitre 03 - Usages de deuil pendant l\u2019omer"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/","url":"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/","name":"05. Mariage et fian\u00e7ailles pendant l\u2019omer - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-05-02T21:05:30+00:00","dateModified":"2018-03-15T11:11:39+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/05-03-05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/05-03-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"05. Mariage et fian\u00e7ailles pendant l\u2019omer"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/1986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=1986"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/1986\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=1986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=1986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=1986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}