{"id":2082,"date":"2016-02-17T20:00:22","date_gmt":"2016-02-17T18:00:22","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2082"},"modified":"2017-08-13T12:35:05","modified_gmt":"2017-08-13T09:35:05","slug":"02-17-20","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/","title":{"rendered":"20 \u2013 Lorsqu\u2019on termine sa \u2018Amida"},"content":{"rendered":"<p dir=\"ltr\">Si l\u2019on termine la lecture de la \u2018Amida, et que derri\u00e8re soi se tienne un autre fid\u00e8le qui, lui, n\u2019a pas achev\u00e9 sa \u2018Amida\u00a0; si cet autre fid\u00e8le se trouve \u00e0 une distance de quatre <em>amot <\/em>additionn\u00e9es de trois pas \u2013 de telle fa\u00e7on que, si l\u2019on reculait de trois pas, on n\u2019entrerait pas \u00e0 l\u2019int\u00e9rieur de ses quatre <em>amot<\/em> \u2013, on recule de trois pas. Mais si l\u2019autre fid\u00e8le est plus proche, on ne recule pas avant qu\u2019il ait achev\u00e9 sa \u2018Amida. M\u00eame si le fid\u00e8le qui se trouve derri\u00e8re soi a commenc\u00e9 \u00e0 prier plus tard, et qu\u2019il prie lentement, il reste interdit de marcher dans ses quatre <em>amot<\/em>. Simplement, comme nous l\u2019avons vu, les A\u2019haronim divergent quant \u00e0 l\u2019\u00e9tendue de l\u2019interdit.<\/p>\n<p dir=\"ltr\">En effet, selon le <em>Maguen Avraham<\/em>, m\u00eame si l\u2019autre fid\u00e8le ne se tient pas juste derri\u00e8re soi, il faut attendre que celui-ci ach\u00e8ve sa pri\u00e8re, d\u00e8s lors que les pas que l\u2019on serait amen\u00e9 \u00e0 faire s\u2019inscrivent dans un rayon de quatre <em>amot<\/em> en avant de ce fid\u00e8le. Selon le <em>Elya Rabba<\/em>, ce n\u2019est que si l\u2019on se tient v\u00e9ritablement <em>devant<\/em> l\u2019autre fid\u00e8le qu\u2019il est interdit de reculer de trois pas devant lui. En revanche, si le fid\u00e8le qui se trouve derri\u00e8re soi n\u2019est pas v\u00e9ritablement plac\u00e9 sur la m\u00eame ligne, il est permis de reculer de trois pas. A priori, il est bon d\u2019adopter la conduite du <em>Maguen Avraham<\/em>, mais en cas de n\u00e9cessit\u00e9, on peut \u00eatre indulgent et suivre l\u2019avis du <em>Elya Rabba <\/em>(<em>Michna Beroura <\/em>102, 18-19). En cas de n\u00e9cessit\u00e9 imp\u00e9rieuse, m\u00eame si un fid\u00e8le se trouve v\u00e9ritablement derri\u00e8re soi, on peut reculer en diagonale. En effet, certains d\u00e9cisionnaires expliquent que, selon le <em>Elya Rabba<\/em>, reculer est chose permise tant que, ce faisant, on ne se rapproche pas du fid\u00e8le en pri\u00e8re (propos rapport\u00e9s au nom du <em>\u2018Hazon Ich<\/em> par l\u2019ouvrage <em>Arba Amot chel tephila<\/em>, p. 50, 363\u00a0; cf. <em>Ich\u00e9 Isra\u00ebl<\/em> 29, 7 et 32, note 73).<\/p>\n<p dir=\"ltr\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-2174\" src=\"https:\/\/ph.yhb.org.il\/fr\/wp-content\/uploads\/sites\/5\/2016\/02\/\u05e4\u05e8\u05e7-17-\u05ea3.png\" alt=\"\" width=\"487\" height=\"107\" srcset=\"https:\/\/ph.yhb.org.il\/fr\/wp-content\/uploads\/sites\/5\/2016\/02\/\u05e4\u05e8\u05e7-17-\u05ea3.png 487w, https:\/\/ph.yhb.org.il\/fr\/wp-content\/uploads\/sites\/5\/2016\/02\/\u05e4\u05e8\u05e7-17-\u05ea3-300x66.png 300w\" sizes=\"(max-width: 487px) 100vw, 487px\" \/><br \/>\nSi, entre le fid\u00e8le en pri\u00e8re et soi-m\u00eame, se tient un tiers qui a, lui, achev\u00e9 sa \u2018Amida, on est autoris\u00e9 \u00e0 reculer, car celui qui a achev\u00e9 sa \u2018Amida constitue une s\u00e9paration entre le fid\u00e8le en pri\u00e8re et soi-m\u00eame, bien que celui qui fait ainsi \u00e9cran n\u2019a pas encore recul\u00e9 lui-m\u00eame de trois pas.<\/p>\n<p dir=\"ltr\">En cas de n\u00e9cessit\u00e9, on peut \u00e9galement \u00eatre indulgent lorsque, entre le fid\u00e8le en pri\u00e8re et soi-m\u00eame, se trouve une cloison haute d\u2019au-moins dix <em>tefa\u2019him<\/em> (80 cm), et large d\u2019au moins quatre <em>tefa\u2019him <\/em>(32 cm). Ceux qui veulent \u00eatre indulgents peuvent consid\u00e9rer les grands si\u00e8ges fixes que l\u2019on trouve dans les synagogues comme constituant une cloison, dans la mesure o\u00f9 leur hauteur est d\u2019au moins dix <em>tefa\u2019him<\/em><sup><a id=\"_te01ftnref17_19\" class=\"aup1\" href=\"#_te01ftn17_19\">[19]<\/a><\/sup>.<\/p>\n<p dir=\"ltr\">Si l\u2019on ne peut reculer, en raison de la pr\u00e9sence d\u2019un fid\u00e8le en pri\u00e8re derri\u00e8re soi, on est autoris\u00e9 \u00e0 r\u00e9pondre amen, <em>Baroukh Hou ouvaroukh Ch\u00e9mo <\/em>(\u00ab\u00a0b\u00e9ni soit-Il et b\u00e9ni soit Son nom\u00a0\u00bb), et \u00e0 r\u00e9citer toutes les autres parties de la pri\u00e8re, bien que l\u2019on n\u2019ait pas encore pris enti\u00e8rement cong\u00e9 de sa \u2018Amida. Si l\u2019assembl\u00e9e en est arriv\u00e9e aux supplications (<em>Ta\u2019hanounim<\/em>, cf. chap. 21), on est autoris\u00e9 \u00e0 s\u2019asseoir pour prononcer la partie qui se dit assis, \u00e0 condition de ne pas s\u2019asseoir v\u00e9ritablement devant l\u2019autre fid\u00e8le (voir note 15)\u00a0; ensuite, on se rel\u00e8vera, et lorsque le fid\u00e8le plac\u00e9 derri\u00e8re soi aura termin\u00e9 sa \u2018Amida, on reculera de trois pas et l\u2019on dira <em>Oss\u00e9 Chalom<\/em>\u2026\u00a0 (\u00ab\u00a0Celui qui fait r\u00e9gner la paix dans ses cieux\u2026\u00a0\u00bb) (<em>Michna Beroura<\/em> 122, 4\u00a0; voir aussi 104, 9. Voir ci-dessus \u00a7 13).<\/p>\n<div dir=\"ltr\">\n<hr size=\"1\" \/>\n<div><a id=\"_te01ftn17_19\" href=\"#_te01ftnref17_19\">[19]<\/a>. Un homme constitue une s\u00e9paration, comme l\u2019expliquent le <em>Beit Baroukh<\/em> 26, 23, <em>Az Nidberou<\/em> III 45 et VI 47 et <em>Ich\u00e9 Isra\u00ebl<\/em> 29, 9.En ce qui concerne une cloison haute de 10 <em>tefa\u2019him<\/em>, certains interdisent de s\u2019en contenter, car cette taille reste petite, et le fid\u00e8le qui r\u00e9cite la \u2018Amida risque de voir celui qui recule et d\u2019en \u00eatre d\u00e9rang\u00e9 dans sa pri\u00e8re. C\u2019est ce que laisse entendre le <em>Michna Beroura<\/em> 102, 2. Selon le <em>Echel Avraham<\/em> 102, m\u00eame si l\u2019on n\u2019est s\u00e9par\u00e9 que par un pupitre de pri\u00e8re (qui ne constitue pas une s\u00e9paration en bonne et due forme), il est permis de reculer, et m\u00eame de passer devant l\u2019autre, car l\u2019interdit est motiv\u00e9 par le fait que le fid\u00e8le en pri\u00e8re craint qu\u2019on ne le touche. Or lorsqu\u2019il y a un pupitre devant soi, et \u00e0 plus forte raison une cloison en bonne et due forme, on n\u2019\u00e9prouve plus de telles craintes. Le \u2018<em>Aroukh Hachoul\u2019han<\/em> 102, 13 consid\u00e8re \u00e9galement la cloison comme efficace.<\/p>\n<p>Les si\u00e8ges de synagogues sont parfois ouverts par en bas. Or si l\u2019espace est de plus de 24 cm (3 <em>tefa\u2019him<\/em>), ces si\u00e8ges ne peuvent \u00eatre consid\u00e9r\u00e9s comme une s\u00e9paration. Cependant, durant la \u2018Amida, on rabat g\u00e9n\u00e9ralement le si\u00e8ge, et il n\u2019y a plus, d\u00e8s lors, 24 cm entre le sol et le si\u00e8ge, si bien que celui-ci peut \u00eatre consid\u00e9r\u00e9 comme une s\u00e9paration. M\u00eame quand l\u2019espace est sup\u00e9rieur \u00e0 24 cm et que le si\u00e8ge n\u2019est donc pas consid\u00e9r\u00e9 comme une cloison en bonne et due forme, il est permis de reculer devant le fid\u00e8le en pri\u00e8re selon le <em>Echel Avraham<\/em>, puisque ce fid\u00e8le ne craint pas qu\u2019on tr\u00e9buche contre lui. Si l\u2019on veut \u00eatre indulgent, on peut s\u2019appuyer sur cette opinion. Par ailleurs, m\u00eame si le si\u00e8ge constitue une cloison en bonne et due forme, il semble qu\u2019il ne soit pas convenable de s\u2019asseoir v\u00e9ritablement face au fid\u00e8le, car celui-ci donnerait l\u2019impression de se prosterner devant son prochain (comme nous l\u2019avons vu au \u00a7 17, note 15).<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si l\u2019on termine la lecture de la \u2018Amida, et que derri\u00e8re soi se tienne un autre fid\u00e8le qui, lui, n\u2019a pas achev\u00e9 sa \u2018Amida\u00a0; si cet autre fid\u00e8le se trouve \u00e0 une distance de quatre amot additionn\u00e9es de trois pas \u2013 de telle fa\u00e7on que, si l\u2019on reculait de trois pas, on n\u2019entrerait pas \u00e0 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117],"tags":[],"class_list":["post-2082","post","type-post","status-publish","format-standard","hentry","category-02-17"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>20 \u2013 Lorsqu\u2019on termine sa \u2018Amida - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20 \u2013 Lorsqu\u2019on termine sa \u2018Amida - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Si l\u2019on termine la lecture de la \u2018Amida, et que derri\u00e8re soi se tienne un autre fid\u00e8le qui, lui, n\u2019a pas achev\u00e9 sa \u2018Amida\u00a0; si cet autre fid\u00e8le se trouve \u00e0 une distance de quatre amot additionn\u00e9es de trois pas \u2013 de telle fa\u00e7on que, si l\u2019on reculait de trois pas, on n\u2019entrerait pas \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-17T18:00:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-13T09:35:05+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-17-20\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-17-20\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"20 \u2013 Lorsqu\u2019on termine sa \u2018Amida\",\"datePublished\":\"2016-02-17T18:00:22+00:00\",\"dateModified\":\"2017-08-13T09:35:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-17-20\\\/\"},\"wordCount\":1046,\"articleSection\":[\"Chapitre 17 \u2013 La \u2018Amida\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-17-20\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-17-20\\\/\",\"name\":\"20 \u2013 Lorsqu\u2019on termine sa \u2018Amida - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-02-17T18:00:22+00:00\",\"dateModified\":\"2017-08-13T09:35:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-17-20\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-17-20\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-17-20\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"20 \u2013 Lorsqu\u2019on termine sa \u2018Amida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20 \u2013 Lorsqu\u2019on termine sa \u2018Amida - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/","og_locale":"fr_FR","og_type":"article","og_title":"20 \u2013 Lorsqu\u2019on termine sa \u2018Amida - Pnin\u00e9 Halakha","og_description":"Si l\u2019on termine la lecture de la \u2018Amida, et que derri\u00e8re soi se tienne un autre fid\u00e8le qui, lui, n\u2019a pas achev\u00e9 sa \u2018Amida\u00a0; si cet autre fid\u00e8le se trouve \u00e0 une distance de quatre amot additionn\u00e9es de trois pas \u2013 de telle fa\u00e7on que, si l\u2019on reculait de trois pas, on n\u2019entrerait pas \u00e0 [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-02-17T18:00:22+00:00","article_modified_time":"2017-08-13T09:35:05+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"20 \u2013 Lorsqu\u2019on termine sa \u2018Amida","datePublished":"2016-02-17T18:00:22+00:00","dateModified":"2017-08-13T09:35:05+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/"},"wordCount":1046,"articleSection":["Chapitre 17 \u2013 La \u2018Amida"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/","url":"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/","name":"20 \u2013 Lorsqu\u2019on termine sa \u2018Amida - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-02-17T18:00:22+00:00","dateModified":"2017-08-13T09:35:05+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/02-17-20\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/02-17-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"20 \u2013 Lorsqu\u2019on termine sa \u2018Amida"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2082"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2082\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}