{"id":21,"date":"2000-03-01T00:07:29","date_gmt":"2000-02-29T22:07:29","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=21"},"modified":"2017-11-07T10:53:21","modified_gmt":"2017-11-07T08:53:21","slug":"03-01-07","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/","title":{"rendered":"07. L\u2019institution des trois pri\u00e8res quotidiennes"},"content":{"rendered":"<p>En plus des pri\u00e8res particuli\u00e8res qu\u2019ils disaient en temps de d\u00e9tresse, nos patriarches avaient l\u2019habitude de se choisir un temps fixe o\u00f9 ils adressaient leur pri\u00e8re \u00e0 Dieu (<em>Berakhot<\/em> 26b). Abraham notre p\u00e8re a initi\u00e9 la pri\u00e8re de l\u2019aube (Cha\u2019harit), car c\u2019est lui qui a commenc\u00e9 \u00e0 illuminer le monde par sa foi (<em>\u00e9mouna<\/em>)<sup><a href='#_te01ftn1_n' id='_te01ftnref1_n' class='aup1'>[n]<\/a><\/sup>\u00a0; il a ainsi fix\u00e9 sa pri\u00e8re au moment o\u00f9 le soleil commence \u00e0 briller. Isaac notre p\u00e8re a initi\u00e9 la pri\u00e8re de l\u2019apr\u00e8s-midi (Min\u2019ha). Ce qui distingue Isaac est qu\u2019il a continu\u00e9 de marcher dans la voie d\u2019Abraham son p\u00e8re. Il est parfois plus facile de frayer un chemin nouveau que de prolonger une d\u00e9marche. La force d\u2019Isaac est d\u2019avoir continu\u00e9 \u00e0 marcher sur le chemin de l\u2019<em>\u00e9mouna<\/em>. En regard de cela, vient la pri\u00e8re de l\u2019apr\u00e8s-midi, qui exprime la continuit\u00e9\u00a0: toute la journ\u00e9e est entra\u00een\u00e9e par la force de l\u2019<em>\u00e9mouna<\/em>. Jacob notre P\u00e8re a quant \u00e0 lui cr\u00e9\u00e9 la pri\u00e8re du soir (Arvit ou, selon la d\u00e9nomination ashk\u00e9naze, <em>Ma\u2019ariv<\/em>), car Jacob s\u2019est mesur\u00e9 \u00e0 des difficult\u00e9s et des complications nombreuses, et de toutes il est sorti renforc\u00e9\u00a0; c\u2019est pourquoi il a initi\u00e9 la pri\u00e8re nocturne\u00a0; car m\u00eame dans l\u2019obscurit\u00e9, lorsque la r\u00e9alit\u00e9 n\u2019\u00e9claire point, il est possible de se lier \u00e0 Dieu et, par cela, de d\u00e9voiler une lumi\u00e8re sup\u00e9rieure \u00e9ternelle.<\/p>\n<p>Apr\u00e8s que les p\u00e8res du monde eurent montr\u00e9 la voie par ces pri\u00e8res, des fervents et des justes continu\u00e8rent de marcher dans leurs voies et pri\u00e8rent trois fois par jour, matin, apr\u00e8s-midi et soir, comme l\u2019a exprim\u00e9 le Roi David :<\/p>\n<p>J\u2019invoquerai Dieu, et l\u2019Eternel me secourra. Soir, matin et \u00e0 midi, je parlerai et m\u2019\u00e9mouvrai, et Il entendra ma voix (Ps 55, 17-18).<\/p>\n<p>Comme prolongation de l\u2019usage des patriarches, les membres de la Grande Assembl\u00e9e ont institu\u00e9 les trois offices quotidiens\u00a0: Cha\u2019harit (office du matin), Min\u2019ha (office de l\u2019apr\u00e8s-midi) et Arvit (office du soir). Or ces offices sont aussi fix\u00e9s en r\u00e9f\u00e9rence aux sacrifices collectifs, dans la mesure o\u00f9 les pri\u00e8res traduisent la signification int\u00e9rieure des sacrifices. Et puisque les sacrifices quotidiens du matin et de l\u2019apr\u00e8s-midi \u00e9taient obligatoires, les offices correspondants de Cha\u2019harit et de Min\u2019ha le sont eux aussi. Nos ma\u00eetres ont en revanche institu\u00e9 l\u2019office d\u2019Arvit en r\u00e9f\u00e9rence \u00e0 la combustion des graisses et des membres des sacrifices de la journ\u00e9e \u00e9coul\u00e9e, graisses et membres que l\u2019on faisait monter sur l\u2019autel du Temple la nuit venue. Cependant, dans le cas o\u00f9 cette oblation nocturne n\u2019\u00e9tait pas r\u00e9alis\u00e9e, les sacrifices correspondants n\u2019\u00e9taient pas pour autant invalid\u00e9s. De fa\u00e7on similaire, l\u2019office d\u2019Arvit est facultatif. Toutefois, dans la suite des g\u00e9n\u00e9rations, les hommes isra\u00e9lites ont pris sur eux, en tant qu\u2019obligation, l\u2019usage de r\u00e9citer la pri\u00e8re d\u2019Arvit. Par ailleurs, les jours de Chabbat, de f\u00eate et de n\u00e9om\u00e9nie (Roch \u2018hodech), nous avons ordre d\u2019apporter un sacrifice additionnel (appel\u00e9 <em>Moussaf<\/em>,\u00a0 suppl\u00e9ment)\u00a0; nos ma\u00eetres ont donc institu\u00e9 parall\u00e8lement la pri\u00e8re de Moussaf (qui prolonge et ach\u00e8ve l\u2019office du matin de ces jours sanctifi\u00e9s). Toutefois, les femmes sont dispens\u00e9es de la pri\u00e8re de Moussaf (d\u2019apr\u00e8s la majorit\u00e9 des d\u00e9cisionnaires, comme nous le verrons au chap. 2 \u00a7 9).<\/p>\n<p>Puisque les offices de pri\u00e8re ont \u00e9t\u00e9 institu\u00e9s en r\u00e9f\u00e9rence aux sacrifices, les heures des offices ont \u00e9t\u00e9 fix\u00e9es d\u2019apr\u00e8s les heures o\u00f9 les sacrifices \u00e9taient offerts (comme il sera expliqu\u00e9 plus loin, chap. 8 \u00a7 1 et chap. 18 \u00a7 1). Au chapitre suivant, nous pr\u00e9ciserons celles des pri\u00e8res qui sont obligatoires pour les femmes, et celles qui sont facultatives.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref1_n' id='_te01ftn1_n'>[n]<\/a>. Nous traduisons par <em>foi<\/em> le mot <em>\u00e9mouna<\/em>, bien que ce mot h\u00e9bra\u00efque soit difficilement traduisible dans une autre langue. <em>E<\/em><em>mouna<\/em> sugg\u00e8re une id\u00e9e de confiance totale \u00e0 l\u2019\u00e9gard de son objet, et une facult\u00e9 de vivre avec lui en pleine ad\u00e9quation et en pleine harmonie.<\/li>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En plus des pri\u00e8res particuli\u00e8res qu\u2019ils disaient en temps de d\u00e9tresse, nos patriarches avaient l\u2019habitude de se choisir un temps fixe o\u00f9 ils adressaient leur pri\u00e8re \u00e0 Dieu (Berakhot 26b). Abraham notre p\u00e8re a initi\u00e9 la pri\u00e8re de l\u2019aube (Cha\u2019harit), car c\u2019est lui qui a commenc\u00e9 \u00e0 illuminer le monde par sa foi (\u00e9mouna)[n]\u00a0; il [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-21","post","type-post","status-publish","format-standard","hentry","category-03-01"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>07. L\u2019institution des trois pri\u00e8res quotidiennes - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"07. L\u2019institution des trois pri\u00e8res quotidiennes - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"En plus des pri\u00e8res particuli\u00e8res qu\u2019ils disaient en temps de d\u00e9tresse, nos patriarches avaient l\u2019habitude de se choisir un temps fixe o\u00f9 ils adressaient leur pri\u00e8re \u00e0 Dieu (Berakhot 26b). Abraham notre p\u00e8re a initi\u00e9 la pri\u00e8re de l\u2019aube (Cha\u2019harit), car c\u2019est lui qui a commenc\u00e9 \u00e0 illuminer le monde par sa foi (\u00e9mouna)[n]\u00a0; il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-02-29T22:07:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-07T08:53:21+00:00\" \/>\n<meta name=\"author\" content=\"\u05d9\u05e2\u05e7\u05d1 \u05d5\u05d9\u05e0\u05d1\u05e8\u05d2\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05d9\u05e2\u05e7\u05d1 \u05d5\u05d9\u05e0\u05d1\u05e8\u05d2\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-01-07\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-01-07\\\/\"},\"author\":{\"name\":\"\u05d9\u05e2\u05e7\u05d1 \u05d5\u05d9\u05e0\u05d1\u05e8\u05d2\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/75fdeb03a6306eebf1f8830958b8af0a\"},\"headline\":\"07. L\u2019institution des trois pri\u00e8res quotidiennes\",\"datePublished\":\"2000-02-29T22:07:29+00:00\",\"dateModified\":\"2017-11-07T08:53:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-01-07\\\/\"},\"wordCount\":735,\"articleSection\":[\"Chapitre 01 \u2013 Bases des lois de la pri\u00e8re\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-01-07\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-01-07\\\/\",\"name\":\"07. L\u2019institution des trois pri\u00e8res quotidiennes - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-02-29T22:07:29+00:00\",\"dateModified\":\"2017-11-07T08:53:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/75fdeb03a6306eebf1f8830958b8af0a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-01-07\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-01-07\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-01-07\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"07. L\u2019institution des trois pri\u00e8res quotidiennes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/75fdeb03a6306eebf1f8830958b8af0a\",\"name\":\"\u05d9\u05e2\u05e7\u05d1 \u05d5\u05d9\u05e0\u05d1\u05e8\u05d2\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1fb98ac78606c670f477ac97940d97d78a5ee38c22252ff9416f589fd64637c7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1fb98ac78606c670f477ac97940d97d78a5ee38c22252ff9416f589fd64637c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1fb98ac78606c670f477ac97940d97d78a5ee38c22252ff9416f589fd64637c7?s=96&d=mm&r=g\",\"caption\":\"\u05d9\u05e2\u05e7\u05d1 \u05d5\u05d9\u05e0\u05d1\u05e8\u05d2\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/pazzel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"07. L\u2019institution des trois pri\u00e8res quotidiennes - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/","og_locale":"fr_FR","og_type":"article","og_title":"07. L\u2019institution des trois pri\u00e8res quotidiennes - Pnin\u00e9 Halakha","og_description":"En plus des pri\u00e8res particuli\u00e8res qu\u2019ils disaient en temps de d\u00e9tresse, nos patriarches avaient l\u2019habitude de se choisir un temps fixe o\u00f9 ils adressaient leur pri\u00e8re \u00e0 Dieu (Berakhot 26b). Abraham notre p\u00e8re a initi\u00e9 la pri\u00e8re de l\u2019aube (Cha\u2019harit), car c\u2019est lui qui a commenc\u00e9 \u00e0 illuminer le monde par sa foi (\u00e9mouna)[n]\u00a0; il [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-02-29T22:07:29+00:00","article_modified_time":"2017-11-07T08:53:21+00:00","author":"\u05d9\u05e2\u05e7\u05d1 \u05d5\u05d9\u05e0\u05d1\u05e8\u05d2\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05d9\u05e2\u05e7\u05d1 \u05d5\u05d9\u05e0\u05d1\u05e8\u05d2\u05e8","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/"},"author":{"name":"\u05d9\u05e2\u05e7\u05d1 \u05d5\u05d9\u05e0\u05d1\u05e8\u05d2\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/75fdeb03a6306eebf1f8830958b8af0a"},"headline":"07. L\u2019institution des trois pri\u00e8res quotidiennes","datePublished":"2000-02-29T22:07:29+00:00","dateModified":"2017-11-07T08:53:21+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/"},"wordCount":735,"articleSection":["Chapitre 01 \u2013 Bases des lois de la pri\u00e8re"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/","name":"07. L\u2019institution des trois pri\u00e8res quotidiennes - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-02-29T22:07:29+00:00","dateModified":"2017-11-07T08:53:21+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/75fdeb03a6306eebf1f8830958b8af0a"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-01-07\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-01-07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"07. L\u2019institution des trois pri\u00e8res quotidiennes"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/75fdeb03a6306eebf1f8830958b8af0a","name":"\u05d9\u05e2\u05e7\u05d1 \u05d5\u05d9\u05e0\u05d1\u05e8\u05d2\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1fb98ac78606c670f477ac97940d97d78a5ee38c22252ff9416f589fd64637c7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1fb98ac78606c670f477ac97940d97d78a5ee38c22252ff9416f589fd64637c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1fb98ac78606c670f477ac97940d97d78a5ee38c22252ff9416f589fd64637c7?s=96&d=mm&r=g","caption":"\u05d9\u05e2\u05e7\u05d1 \u05d5\u05d9\u05e0\u05d1\u05e8\u05d2\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/pazzel\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/21\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=21"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=21"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}