{"id":2200,"date":"2016-02-19T00:02:44","date_gmt":"2016-02-18T22:02:44","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2200"},"modified":"2017-08-14T09:58:44","modified_gmt":"2017-08-14T06:58:44","slug":"02-19-02","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/","title":{"rendered":"02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0?"},"content":{"rendered":"<p>Trois conditions doivent \u00eatre rassembl\u00e9es pour que le particulier puisse se rendre quitte de son obligation par l\u2019\u00e9coute de la r\u00e9p\u00e9tition de l\u2019officiant\u00a0: <strong>1)<\/strong> Ne pas \u00eatre capable de prier soi-m\u00eame. Si l\u2019on sait prier, on s\u2019oblige \u00e0 le faire et \u00e0 demander mis\u00e9ricorde par soi-m\u00eame, et l\u2019on ne peut s\u2019acquitter par l\u2019\u00e9coute de l\u2019officiant. Toutefois, si l\u2019on ne sait prier qu\u2019en prenant appui sur un sidour (livre de pri\u00e8re), et que l\u2019on se trouve dans un endroit o\u00f9 il n\u2019y en a pas, on pourra, \u00e0 cette occasion, s\u2019acquitter de son obligation par l\u2019\u00e9coute de l\u2019officiant. <strong>2)<\/strong> Il faut encore que dix personnes soient pr\u00e9sentes. En effet, si les sages ont \u00e9tabli que les particuliers pouvaient s\u2019acquitter de leur obligation par l\u2019\u00e9coute de l\u2019officiant, ce n\u2019est que dans le cadre d\u2019un minyan. <strong>3)<\/strong> L\u2019auditeur doit comprendre les paroles de l\u2019officiant. Si l\u2019on ne comprend pas l\u2019h\u00e9breu, on ne peut s\u2019acquitter par la r\u00e9p\u00e9tition de l\u2019officiant.<\/p>\n<p>Comme nous venons de le voir, si l\u2019on sait prier, on ne peut s\u2019acquitter de son obligation par l\u2019\u00e9coute de l\u2019officiant. Toutefois, si l\u2019on a oubli\u00e9 d\u2019inclure dans sa pri\u00e8re un passage dont l\u2019omission est invalidante (tel que <em>Yaal\u00e9 v\u00e9yavo<\/em> un jour de Roch \u2018hodech ou de \u2018Hol hamoed, cas dans lesquels on n\u2019est pas quitte et o\u00f9 il faut en principe r\u00e9p\u00e9ter la \u2018Amida), on peut, si l\u2019on veut, s\u2019acquitter par l\u2019\u00e9coute de l\u2019officiant, dans la mesure o\u00f9 l\u2019on a d\u00e9j\u00e0 pri\u00e9 et demand\u00e9 mis\u00e9ricorde pour soi-m\u00eame (<em>Choul\u2019han \u2018Aroukh<\/em> 124, 10)<sup><a href='#_te01ftn19_1' id='_te01ftnref19_1' class='aup1'>[1]<\/a><\/sup>.<\/p>\n<p>Quand on a l\u2019intention de s\u2019acquitter de son obligation par l\u2019\u00e9coute de l\u2019officiant, on doit se tenir de la m\u00eame fa\u00e7on que lorsqu\u2019on prie par soi-m\u00eame, pieds joints\u00a0; \u00e0 la fin de la \u2018Amida, on recule de trois pas (<em>Choul\u2019han \u2018Aroukh<\/em> 124, 1). On r\u00e9pond <em>amen<\/em> aux b\u00e9n\u00e9dictions prononc\u00e9es par l\u2019officiant. De m\u00eame, on r\u00e9pond \u00e0 la <em>Q\u00e9doucha<\/em>. En revanche, on ne r\u00e9pond pas <em>Baroukh Hou ouvaroukh Ch\u00e9mo<\/em> (\u00ab\u00a0Qu\u2019Il soit b\u00e9ni et que Son nom soit b\u00e9ni\u00a0\u00bb). Arriv\u00e9 \u00e0 <em>Modim<\/em>, on \u00e9coute \u00e9galement l\u2019officiant, sans dire soi-m\u00eame le <em>Modim derabbanan<\/em> (cf. plus loin \u00a7 8) (<em>Choul\u2019han \u2018Aroukh<\/em> 124, 1, <em>Michna Beroura<\/em> 3). On prend soin de ne pas s\u2019interrompre par des paroles\u00a0; et m\u00eame si l\u2019on entend, dans la pi\u00e8ce d\u2019\u00e0 c\u00f4t\u00e9, un autre minyan o\u00f9 l\u2019on r\u00e9cite le Qaddich, on n\u2019y r\u00e9pond pas. L\u2019officiant doit, quant \u00e0 lui, avoir soin de r\u00e9citer toute la r\u00e9p\u00e9tition \u00e0 haute voix, car tel est bien le caract\u00e8re de la r\u00e9p\u00e9tition de l\u2019officiant que de devoir \u00eatre dite int\u00e9gralement \u00e0 haute voix. Certains officiants se trompent, et disent une partie de la b\u00e9n\u00e9diction <em>Modim<\/em> \u00e0 voix basse\u00a0: non seulement ils n\u2019accomplissent pas l\u2019obligation de r\u00e9p\u00e9ter la \u2018Amida dans le plein sens du terme, mais il est de plus \u00e0 craindre que, s\u2019il se trouve un particulier qui souhaite s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition, il ne puisse le faire, dans la mesure o\u00f9 il n\u2019entend pas l\u2019int\u00e9gralit\u00e9 de la pri\u00e8re prononc\u00e9e par l\u2019officiant (<em>Michna Beroura<\/em> 124, 41).<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref19_1' id='_te01ftn19_1'>[1]<\/a>. Toutefois, pour le <em>Michna Beroura<\/em> 124, 40, il vaut mieux r\u00e9p\u00e9ter soi-m\u00eame sa \u2018Amida, car de cette fa\u00e7on on se concentre davantage.<\/p>\n<p>En ce qui concerne la pri\u00e8re de <em>Tachloumin<\/em>, voir chap. 18 \u00a7 8, note 9\u00a0: pour le remplacement de la \u2018Amida de Cha\u2019harit, il est admis par la majorit\u00e9 des d\u00e9cisionnaires que l\u2019on ne peut s\u2019acquitter par la r\u00e9p\u00e9tition de l\u2019officiant\u00a0; pour le remplacement d\u2019Arvit, les auteurs divergent.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Trois conditions doivent \u00eatre rassembl\u00e9es pour que le particulier puisse se rendre quitte de son obligation par l\u2019\u00e9coute de la r\u00e9p\u00e9tition de l\u2019officiant\u00a0: 1) Ne pas \u00eatre capable de prier soi-m\u00eame. Si l\u2019on sait prier, on s\u2019oblige \u00e0 le faire et \u00e0 demander mis\u00e9ricorde par soi-m\u00eame, et l\u2019on ne peut s\u2019acquitter par l\u2019\u00e9coute de l\u2019officiant. [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[],"class_list":["post-2200","post","type-post","status-publish","format-standard","hentry","category-02-19"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0? - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0? - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Trois conditions doivent \u00eatre rassembl\u00e9es pour que le particulier puisse se rendre quitte de son obligation par l\u2019\u00e9coute de la r\u00e9p\u00e9tition de l\u2019officiant\u00a0: 1) Ne pas \u00eatre capable de prier soi-m\u00eame. Si l\u2019on sait prier, on s\u2019oblige \u00e0 le faire et \u00e0 demander mis\u00e9ricorde par soi-m\u00eame, et l\u2019on ne peut s\u2019acquitter par l\u2019\u00e9coute de l\u2019officiant. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-18T22:02:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-14T06:58:44+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-02\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-02\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0?\",\"datePublished\":\"2016-02-18T22:02:44+00:00\",\"dateModified\":\"2017-08-14T06:58:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-02\\\/\"},\"wordCount\":674,\"articleSection\":[\"Chapitre 19 \u2013 R\u00e9p\u00e9tition de l\u2019officiant (\u2018hazara)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-02\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-02\\\/\",\"name\":\"02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0? - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-02-18T22:02:44+00:00\",\"dateModified\":\"2017-08-14T06:58:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-02\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-02\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0? - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/","og_locale":"fr_FR","og_type":"article","og_title":"02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0? - Pnin\u00e9 Halakha","og_description":"Trois conditions doivent \u00eatre rassembl\u00e9es pour que le particulier puisse se rendre quitte de son obligation par l\u2019\u00e9coute de la r\u00e9p\u00e9tition de l\u2019officiant\u00a0: 1) Ne pas \u00eatre capable de prier soi-m\u00eame. Si l\u2019on sait prier, on s\u2019oblige \u00e0 le faire et \u00e0 demander mis\u00e9ricorde par soi-m\u00eame, et l\u2019on ne peut s\u2019acquitter par l\u2019\u00e9coute de l\u2019officiant. [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-02-18T22:02:44+00:00","article_modified_time":"2017-08-14T06:58:44+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0?","datePublished":"2016-02-18T22:02:44+00:00","dateModified":"2017-08-14T06:58:44+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/"},"wordCount":674,"articleSection":["Chapitre 19 \u2013 R\u00e9p\u00e9tition de l\u2019officiant (\u2018hazara)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/","url":"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/","name":"02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0? - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-02-18T22:02:44+00:00","dateModified":"2017-08-14T06:58:44+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/02-19-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"02 \u2013 Qui peut s\u2019acquitter par l\u2019\u00e9coute de la r\u00e9p\u00e9tition\u00a0?"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2200"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2200\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}