{"id":2204,"date":"2016-02-19T00:04:59","date_gmt":"2016-02-18T22:04:59","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2204"},"modified":"2017-08-14T10:00:42","modified_gmt":"2017-08-14T07:00:42","slug":"02-19-04","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/","title":{"rendered":"04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0?"},"content":{"rendered":"<p>Lorsque l\u2019officiant r\u00e9cite la r\u00e9p\u00e9tition, chacun, parmi l\u2019assembl\u00e9e, doit se taire et se concentrer, pour \u00e9couter les b\u00e9n\u00e9dictions et y r\u00e9pondre <em>amen<\/em>. Comme nous l\u2019avons vu (r\u00e8gles du minyan, chap. 2 \u00a7 7), certains d\u00e9cisionnaires pensent qu\u2019il est interdit \u00e0 l\u2019officiant de commencer la r\u00e9p\u00e9tition de la \u2018Amida avant que neuf personnes ne soient \u00e0 m\u00eame de r\u00e9pondre <em>amen<\/em> \u00e0 ses b\u00e9n\u00e9dictions. D\u2019autres pensent que, quand bien m\u00eame une partie des membres du minyan seraient encore en train de r\u00e9citer la \u2018Amida, et bien qu\u2019ils ne puissent en ce cas r\u00e9pondre <em>amen<\/em>, ils s\u2019adjoindraient n\u00e9anmoins au minyan.<\/p>\n<p>A priori, on a coutume d\u2019\u00eatre rigoureux, et de ne pas commencer la r\u00e9p\u00e9tition avant que neuf personnes ne soient \u00e0 m\u00eame de r\u00e9pondre. En cas de n\u00e9cessit\u00e9 imp\u00e9rieuse, quand certains membres du minyan sont press\u00e9s de terminer l\u2019office, et qu\u2019il semble que celui des fid\u00e8les qui s\u2019\u00e9tend longuement dans sa pri\u00e8re n\u2019est pas sur le point de terminer, on peut s\u2019appuyer sur l\u2019opinion de la majorit\u00e9 des d\u00e9cisionnaires, et commencer la r\u00e9p\u00e9tition alors que seuls huit fid\u00e8les ont termin\u00e9 leur \u2018Amida. Quand ce n\u2019est pas suffisant, parce que plusieurs fid\u00e8les prolongent leur pri\u00e8re, et que l\u2019heure presse grandement, on peut \u00eatre indulgent, et commencer la r\u00e9p\u00e9tition alors que seuls cinq fid\u00e8les ont termin\u00e9 leur \u2018Amida, si bien qu\u2019avec l\u2019officiant, ils constituent ensemble la majorit\u00e9 du minyan. Pour lever le doute, lorsqu\u2019on est contraint de commencer la r\u00e9p\u00e9tition alors que neuf fid\u00e8les ne sont pas pr\u00eats \u00e0 r\u00e9pondre, l\u2019officiant \u00e9mettra int\u00e9rieurement la condition suivante\u00a0: \u00ab\u00a0Dans le cas o\u00f9 la halakha serait conforme \u00e0 l\u2019opinion selon laquelle il faut que neuf fid\u00e8les r\u00e9pondent, que ma r\u00e9p\u00e9tition soit consid\u00e9r\u00e9e comme une pri\u00e8re additionnelle volontaire (<em>n\u00e9dava<\/em>).\u00a0\u00bb Puisqu\u2019on a le droit de dire une \u2018Amida additionnelle \u00e0 titre volontaire, les b\u00e9n\u00e9dictions qui seront dites ne le seront de toute fa\u00e7on pas en vain, et cela, de l\u2019avis de tous les d\u00e9cisionnaires.<\/p>\n<p>De m\u00eame, si l\u2019on est officiant dans un endroit o\u00f9 de nombreuses personnes ont l\u2019habitude de bavarder, au point qu\u2019il soit douteux d\u2019avoir neuf personnes qui r\u00e9pondent <em>amen<\/em> \u00e0 toutes les b\u00e9n\u00e9dictions, on \u00e9mettra int\u00e9rieurement, avant la pri\u00e8re, cette condition\u00a0: \u00ab\u00a0S\u2019il ne se trouve pas neuf personnes pour r\u00e9pondre <em>amen<\/em> aux b\u00e9n\u00e9dictions, et que la halakha soit conforme \u00e0 l\u2019avis selon lequel neuf personnes doivent obligatoirement r\u00e9pondre, que ma pri\u00e8re soit consid\u00e9r\u00e9e comme volontaire.\u00a0\u00bb<\/p>\n<p>Pour ne pas entrer dans ce type de doute, chacun de ceux qui entendent la r\u00e9p\u00e9tition de l\u2019officiant doit penser qu\u2019il ne se trouve pas neuf fid\u00e8les pour r\u00e9pondre\u00a0\u00e0 part lui : on dirigera donc sa pens\u00e9e vers les b\u00e9n\u00e9dictions de l\u2019officiant et l\u2019on r\u00e9pondra <em>amen<\/em> (<em>Choul\u2019han \u2018Aroukh<\/em> 124, 4)<sup><a href='#_te01ftn19_3' id='_te01ftnref19_3' class='aup1'>[3]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref19_3' id='_te01ftn19_3'>[3]<\/a>. Les A\u2019haronim sont partag\u00e9s sur la question de savoir s\u2019il faut obligatoirement neuf personnes pour r\u00e9pondre \u00e0 la r\u00e9p\u00e9tition. Cette controverse est expliqu\u00e9e par le <em>Choul\u2019han \u2018Aroukh<\/em>, <em>Ora\u2019h \u2018Ha\u00efm<\/em> 55, 6-8 et les commentateurs. Ce point est r\u00e9sum\u00e9 ici, chap. 2 \u00a7 7 (r\u00e8gles du minyan). A priori, on est rigoureux, conform\u00e9ment \u00e0 l\u2019opinion du <em>Choul\u2019han \u2018Aroukh Harav<\/em> et du <em>Ben Ich \u2018Ha\u00ef<\/em>. En cas d\u2019urgence, on peut \u00eatre indulgent, puisque l\u2019opinion de la majorit\u00e9 des d\u00e9cisionnaires est indulgente. C\u2019est ce qu\u2019\u00e9crivent le <em>Tsits Eli\u00e9zer <\/em>12, 19 et le <em>Yalqout Yossef<\/em> I p. 287-291. M\u00eame si l\u2019on admet d\u2019adjoindre <em>un<\/em> fid\u00e8le qui n\u2019a pas termin\u00e9 de r\u00e9citer sa \u2018Amida, les auteurs restent partag\u00e9s, comme l\u2019explique le <em>Michna Beroura<\/em> 55, 32\u00a0: peut-on aller jusqu\u2019\u00e0 quatre fid\u00e8les en train de dire la \u2018Amida, ou bien pas plus d\u2019un seul\u00a0? Le conseil consistant \u00e0 \u00e9mettre une condition est rapport\u00e9 par le <em>Michna Beroura<\/em> 124, 19.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque l\u2019officiant r\u00e9cite la r\u00e9p\u00e9tition, chacun, parmi l\u2019assembl\u00e9e, doit se taire et se concentrer, pour \u00e9couter les b\u00e9n\u00e9dictions et y r\u00e9pondre amen. Comme nous l\u2019avons vu (r\u00e8gles du minyan, chap. 2 \u00a7 7), certains d\u00e9cisionnaires pensent qu\u2019il est interdit \u00e0 l\u2019officiant de commencer la r\u00e9p\u00e9tition de la \u2018Amida avant que neuf personnes ne soient \u00e0 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[],"class_list":["post-2204","post","type-post","status-publish","format-standard","hentry","category-02-19"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0? - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0? - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Lorsque l\u2019officiant r\u00e9cite la r\u00e9p\u00e9tition, chacun, parmi l\u2019assembl\u00e9e, doit se taire et se concentrer, pour \u00e9couter les b\u00e9n\u00e9dictions et y r\u00e9pondre amen. Comme nous l\u2019avons vu (r\u00e8gles du minyan, chap. 2 \u00a7 7), certains d\u00e9cisionnaires pensent qu\u2019il est interdit \u00e0 l\u2019officiant de commencer la r\u00e9p\u00e9tition de la \u2018Amida avant que neuf personnes ne soient \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-18T22:04:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-14T07:00:42+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-04\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-04\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0?\",\"datePublished\":\"2016-02-18T22:04:59+00:00\",\"dateModified\":\"2017-08-14T07:00:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-04\\\/\"},\"wordCount\":718,\"articleSection\":[\"Chapitre 19 \u2013 R\u00e9p\u00e9tition de l\u2019officiant (\u2018hazara)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-04\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-04\\\/\",\"name\":\"04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0? - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-02-18T22:04:59+00:00\",\"dateModified\":\"2017-08-14T07:00:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-04\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-04\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/02-19-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0? - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/","og_locale":"fr_FR","og_type":"article","og_title":"04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0? - Pnin\u00e9 Halakha","og_description":"Lorsque l\u2019officiant r\u00e9cite la r\u00e9p\u00e9tition, chacun, parmi l\u2019assembl\u00e9e, doit se taire et se concentrer, pour \u00e9couter les b\u00e9n\u00e9dictions et y r\u00e9pondre amen. Comme nous l\u2019avons vu (r\u00e8gles du minyan, chap. 2 \u00a7 7), certains d\u00e9cisionnaires pensent qu\u2019il est interdit \u00e0 l\u2019officiant de commencer la r\u00e9p\u00e9tition de la \u2018Amida avant que neuf personnes ne soient \u00e0 [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-02-18T22:04:59+00:00","article_modified_time":"2017-08-14T07:00:42+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0?","datePublished":"2016-02-18T22:04:59+00:00","dateModified":"2017-08-14T07:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/"},"wordCount":718,"articleSection":["Chapitre 19 \u2013 R\u00e9p\u00e9tition de l\u2019officiant (\u2018hazara)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/","url":"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/","name":"04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0? - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-02-18T22:04:59+00:00","dateModified":"2017-08-14T07:00:42+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/02-19-04\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/02-19-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"04 \u2013 Est-il indispensable que neuf hommes r\u00e9pondent \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant\u00a0?"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2204"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2204\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}