{"id":2396,"date":"2016-09-02T00:04:42","date_gmt":"2016-09-01T21:04:42","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2396"},"modified":"2017-09-04T12:57:33","modified_gmt":"2017-09-04T09:57:33","slug":"15-02-04","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/","title":{"rendered":"04. Le texte des Seli\u2019hot"},"content":{"rendered":"<p>Puisque nos sages n\u2019ont pas institu\u00e9 de mani\u00e8re explicite l\u2019obligation de r\u00e9citer les Seli\u2019hot, celles-ci ne sont pas dot\u00e9es d\u2019un rituel nettement d\u00e9fini\u00a0: chaque communaut\u00e9 a ajout\u00e9, au cours des g\u00e9n\u00e9rations, ses propres supplications et po\u00e8mes liturgiques. Cependant, on trouve un cadre g\u00e9n\u00e9ral, qui vaut pour toutes les communaut\u00e9s, comme le rapporte le <em>S\u00e9der<\/em> de Rabbi Amram Gaon<sup><a href='#_te01ftn2_b' id='_te01ftnref2_b' class='aup1'>[b]<\/a><\/sup>\u00a0:<\/p>\n<p>On commence par la r\u00e9citation d\u2019<em>Achr\u00e9<\/em> (\u00ab\u00a0Heureux ceux qui sont assis dans ta Maison\u2026\u00a0\u00bb suivi du psaume 145, <em>T\u00e9hila le-David<\/em>, louange de David)\u00a0; il est en effet d\u2019usage de commencer toute pri\u00e8re par des louanges \u00e0 Dieu. Apr\u00e8s cela, on dit le Qaddich abr\u00e9g\u00e9, puis les textes commen\u00e7ant par <em>Lekha Hachem hatsedaqa, v\u00e9lanou bochet hapanim<\/em> (\u00ab\u00a0\u00c0 Toi, Eternel, le bon droit, et \u00e0 nous la t\u00eate basse\u00a0\u00bb, Daniel 9, 7)\u00a0et par <em>Chom\u00e9a\u2019 t\u00e9phila, \u2018ad\u00e9kha kol bassar yavo-ou<\/em> (\u00ab\u00a0\u00d4 Toi qui \u00e9coutes la pri\u00e8re, jusqu\u2019\u00e0 Toi\u00a0parvient toute chair \u00bb, Ps 65, 3), suivis par d\u2019autres versets de requ\u00eate et de supplication. On r\u00e9cite ensuite les treize attributs de mis\u00e9ricorde (<em>Cheloch-\u2018esr\u00e9 midot ra\u2019hamim<\/em>), la confession (<em>Vidou\u00ef<\/em>), et le texte <em>Achamnou mikol \u2018am<\/em> (\u00ab\u00a0Nous sommes plus coupables que tout autre peuple\u00a0\u00bb). Peu avant la conclusion, on dit la supplication <em>\u2018An\u00e9nou Avinou \u2018an\u00e9nou<\/em>\u2026 (\u00ab\u00a0R\u00e9ponds-nous, \u00f4 notre P\u00e8re, r\u00e9ponds-nous\u2026\u00a0\u00bb), ainsi que le texte <em>Hachem, \u2018ass\u00e9 lema\u2019an chem\u00e9kha\u2026<\/em> (\u00ab\u00a0Eternel, agis en faveur de ton nom\u2026\u00a0\u00bb). \u00c0 la fin des Seli\u2019hot, on r\u00e9cite la <em>N\u00e9filat apayim<\/em> et l\u2019on conclut par le <em>Qaddich titqabal<\/em>.<\/p>\n<p>En plus de ce rituel de base, Rabbi Amram Gaon \u00e9crit que, si l\u2019on veut, on peut ajouter des versets, des pri\u00e8res pour l\u2019obtention du pardon et des po\u00e8mes liturgiques, parmi ceux qu\u2019ont \u00e9crits les po\u00e8tes. C\u2019est ainsi que les communaut\u00e9s juives ont pris coutume d\u2019inclure dans les Seli\u2019hot de nombreux po\u00e8mes, entre lesquels on r\u00e9cite les treize attributs de mis\u00e9ricorde. Dans ce choix de po\u00e8mes, des diff\u00e9rences existent entre S\u00e9farades et Ashk\u00e9nazes. Autre diff\u00e9rence\u00a0: selon la coutume s\u00e9farade, on r\u00e9cite le m\u00eame rituel tous les jours, tandis que, selon la coutume ashk\u00e9naze, on ajoute au rituel de base des po\u00e8mes diff\u00e9rents chaque jour.<\/p>\n<p>Si les fid\u00e8les disposent de peu de temps, ils omettent une partie des po\u00e8mes liturgiques\u00a0: ils r\u00e9citent la partie essentielle des Seli\u2019hot, telle que nous l\u2019a transmise Rabbi Amram Gaon, et s\u2019efforcent d\u2019ajouter ceux des po\u00e8mes qui \u00e9veillent le plus la <em>t\u00e9chouva<\/em><sup><a href='#_te01ftn2_2' id='_te01ftnref2_2' class='aup1'>[2]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref2_b' id='_te01ftn2_b'>[b]<\/a>. L\u2019un des Gu\u00e9onim du neuvi\u00e8me si\u00e8cle, en Babylonie. Son <em>S\u00e9der <\/em>(litt. <em>ordre<\/em>) est l\u2019anc\u00eatre de notre <em>sidour<\/em>, rituel de pri\u00e8res.<\/p>\n<p><a href='#_te01ftnref2_2' id='_te01ftn2_2'>[2]<\/a>. Selon certains, il est interdit de r\u00e9citer des po\u00e8mes contenant des requ\u00eates adress\u00e9es aux diff\u00e9rents anges, car ce n\u2019est qu\u2019\u00e0 Dieu, b\u00e9ni soit-Il, qu\u2019il est permis d\u2019adresser sa pri\u00e8re (Ma\u00efmonide, Na\u2019hmanide). Aussi ne faut-il pas dire <em>Makhniss\u00e9 ra\u2019hamim, hakhnissou ra\u2019hamim lifn\u00e9 ba\u2019al hara\u2019hamim<\/em> (\u00ab\u00a0Vous qui accueillez la mis\u00e9ricorde, introduisez notre qu\u00eate de mis\u00e9ricorde aupr\u00e8s du Ma\u00eetre de mis\u00e9ricorde\u00a0\u00bb), texte que l\u2019on trouve dans le S\u00e9der de Rabbi Amram Gaon (et que les Ashk\u00e9nazes ont l\u2019usage de r\u00e9citer \u00e0 la fin des Seli\u2019hot). De m\u00eame, selon eux, on ne dit pas le po\u00e8me\u00a0<em>Midat hara\u2019hamim, \u2018al\u00e9nou hitgalgueli, v\u00e9lifn\u00e9 Qonekha te\u2019hinat\u00e9nou hapili, ouv\u2019ad \u2018amekha ra\u2019hamim chaali<\/em> (\u00ab\u00a0Attribut de mis\u00e9ricorde, \u00e9panche-toi sur nous\u00a0; devant ton Cr\u00e9ateur porte notre supplication, et pour ton peuple requiers la mis\u00e9ricorde\u00a0\u00bb).<\/p>\n<p>Mais la majorit\u00e9 des d\u00e9cisionnaires estiment qu\u2019il est permis de r\u00e9citer ces po\u00e8mes, qui furent r\u00e9dig\u00e9s par de grands et anciens ma\u00eetres, et qu\u2019Isra\u00ebl a pris l\u2019usage de dire, durant de nombreuses g\u00e9n\u00e9rations. En effet, tant que le fid\u00e8le sait que tout est dans la main du Saint b\u00e9ni soit-Il, il est permis de demander aux anges, cr\u00e9\u00e9s pour \u00e9lever les pri\u00e8res et pour rappeler nos m\u00e9rites devant Lui, de remplir leur mission (Rav Cherira Gaon, Rabbi El\u00e9azar de Worms, auteur du <em>Roq\u00e9a\u2019h<\/em>, <em>Chibol\u00e9 Hal\u00e9qet<\/em> 252, Mahari Bruna). Et tel est l\u2019usage de la majorit\u00e9 des communaut\u00e9s juives que de ne pas supprimer ces po\u00e8mes du sidour. D\u2019autres d\u00e9cisionnaires partagent l\u2019opinion des auteurs rigoureux, mais, pour ne pas annuler la r\u00e9citation de ces po\u00e8mes, que tant de communaut\u00e9s ont coutume de dire, ils modifient quelque peu le texte, de mani\u00e8re que la pri\u00e8re soit adress\u00e9e \u00e0 Dieu seul, \u00e0 qui l\u2019on demande d\u2019ordonner aux anges pr\u00e9pos\u00e9s \u00e0 la transmission des pri\u00e8res de lui pr\u00e9senter les n\u00f4tres (Maharal, <em>Netiv Ha\u2019avoda<\/em> 12\u00a0; tel \u00e9tait l\u2019usage du Rav Tsvi Yehouda Kook). Certains s\u2019\u00e9tendent dans les pri\u00e8res qui pr\u00e9c\u00e8dent ces po\u00e8mes, de sorte que, en pratique, il ne leur reste plus de temps pour les r\u00e9citer\u00a0; pour autant, ils n\u2019annulent pas la possibilit\u00e9 pour les fid\u00e8les de les dire (<em>\u2018Hatam Sofer, Ora\u2019h \u2018Ha\u00efm <\/em>166). Cf. <em>Mo\u2019adim Le-sim\u2019ha, Eloul-tichri<\/em>, p. 37-62.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Puisque nos sages n\u2019ont pas institu\u00e9 de mani\u00e8re explicite l\u2019obligation de r\u00e9citer les Seli\u2019hot, celles-ci ne sont pas dot\u00e9es d\u2019un rituel nettement d\u00e9fini\u00a0: chaque communaut\u00e9 a ajout\u00e9, au cours des g\u00e9n\u00e9rations, ses propres supplications et po\u00e8mes liturgiques. Cependant, on trouve un cadre g\u00e9n\u00e9ral, qui vaut pour toutes les communaut\u00e9s, comme le rapporte le S\u00e9der de [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[],"class_list":["post-2396","post","type-post","status-publish","format-standard","hentry","category-15-02"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>04. Le texte des Seli\u2019hot - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"04. Le texte des Seli\u2019hot - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Puisque nos sages n\u2019ont pas institu\u00e9 de mani\u00e8re explicite l\u2019obligation de r\u00e9citer les Seli\u2019hot, celles-ci ne sont pas dot\u00e9es d\u2019un rituel nettement d\u00e9fini\u00a0: chaque communaut\u00e9 a ajout\u00e9, au cours des g\u00e9n\u00e9rations, ses propres supplications et po\u00e8mes liturgiques. Cependant, on trouve un cadre g\u00e9n\u00e9ral, qui vaut pour toutes les communaut\u00e9s, comme le rapporte le S\u00e9der de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-01T21:04:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-04T09:57:33+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-04\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-04\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"04. Le texte des Seli\u2019hot\",\"datePublished\":\"2016-09-01T21:04:42+00:00\",\"dateModified\":\"2017-09-04T09:57:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-04\\\/\"},\"wordCount\":920,\"articleSection\":[\"Chapitre 02 - Les Seli\u2019hot et autres pri\u00e8res\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-04\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-04\\\/\",\"name\":\"04. Le texte des Seli\u2019hot - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-09-01T21:04:42+00:00\",\"dateModified\":\"2017-09-04T09:57:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-04\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-04\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"04. Le texte des Seli\u2019hot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"04. Le texte des Seli\u2019hot - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/","og_locale":"fr_FR","og_type":"article","og_title":"04. Le texte des Seli\u2019hot - Pnin\u00e9 Halakha","og_description":"Puisque nos sages n\u2019ont pas institu\u00e9 de mani\u00e8re explicite l\u2019obligation de r\u00e9citer les Seli\u2019hot, celles-ci ne sont pas dot\u00e9es d\u2019un rituel nettement d\u00e9fini\u00a0: chaque communaut\u00e9 a ajout\u00e9, au cours des g\u00e9n\u00e9rations, ses propres supplications et po\u00e8mes liturgiques. Cependant, on trouve un cadre g\u00e9n\u00e9ral, qui vaut pour toutes les communaut\u00e9s, comme le rapporte le S\u00e9der de [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-09-01T21:04:42+00:00","article_modified_time":"2017-09-04T09:57:33+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"04. Le texte des Seli\u2019hot","datePublished":"2016-09-01T21:04:42+00:00","dateModified":"2017-09-04T09:57:33+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/"},"wordCount":920,"articleSection":["Chapitre 02 - Les Seli\u2019hot et autres pri\u00e8res"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/","url":"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/","name":"04. Le texte des Seli\u2019hot - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-09-01T21:04:42+00:00","dateModified":"2017-09-04T09:57:33+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/15-02-04\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"04. Le texte des Seli\u2019hot"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2396"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2396\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}