{"id":2398,"date":"2016-09-02T00:05:46","date_gmt":"2016-09-01T21:05:46","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2398"},"modified":"2019-01-16T12:44:11","modified_gmt":"2019-01-16T10:44:11","slug":"15-02-05","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/","title":{"rendered":"05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation"},"content":{"rendered":"<p>\u00c0 l\u2019\u00e9poque des Gu\u00e9onim<sup><a id=\"_te01ftnref2_c\" class=\"aup1\" href=\"#_te01ftn2_c\">[c]<\/a><\/sup>, on avait coutume de r\u00e9citer les Seli\u2019hot durant les dix jours de p\u00e9nitence. Tel \u00e9tait l\u2019usage dans les deux grandes acad\u00e9mies talmudiques de Babylonie<sup><a id=\"_te01ftnref2_d\" class=\"aup1\" href=\"#_te01ftn2_d\">[d]<\/a><\/sup>\u00a0; et dans certaines contr\u00e9es, peu nombreuses, on avait \u00e9galement coutume de les r\u00e9citer durant tout le mois d\u2019\u00e9loul.<\/p>\n<p>\u00c0 la fin de la p\u00e9riode des Richonim<sup><a id=\"_te01ftnref2_e\" class=\"aup1\" href=\"#_te01ftn2_e\">[e]<\/a><\/sup>, la coutume consistant \u00e0 dire les Seli\u2019hot durant tout le mois d\u2019\u00e9loul et les dix jours de p\u00e9nitence avait \u00e9t\u00e9 adopt\u00e9e dans les communaut\u00e9s s\u00e9farades (<em>Choul\u2019han \u2018Aroukh<\/em> 581, 1). Mais le jour de Roch \u2018hodech \u00e9loul lui-m\u00eame, on ne r\u00e9cite pas de Seli\u2019hot (Rabbi Mena\u2019hem Azaria da Fano 79, <em>Kaf Ha\u2019ha\u00efm<\/em> 1). Plus on se rapproche de Roch hachana, plus nombreux sont ceux qui ont soin de se lever pour participer aux Seli\u2019hot\u00a0; en particulier, on est minutieux \u00e0 cet \u00e9gard pendant les dix jours de p\u00e9nitence (de Roch hachana \u00e0 Kipour).<\/p>\n<p>La coutume ashk\u00e9naze consiste \u00e0 commencer la r\u00e9citation des Seli\u2019hot \u00e0 l\u2019issue du Chabbat pr\u00e9c\u00e9dant Roch hachana, \u00e0 condition de pouvoir ainsi r\u00e9citer les Seli\u2019hot quatre jours au moins avant la f\u00eate. En d\u2019autres termes, si Roch hachana tombe le jeudi ou le Chabbat, on commence les Seli\u2019hot \u00e0 l\u2019issue du Chabbat pr\u00e9c\u00e9dant Roch hachana. Mais si Roch hachana tombe un lundi ou un mardi, on commence \u00e0 les r\u00e9citer \u00e0 l\u2019issue du Chabbat encore ant\u00e9rieur<sup><a id=\"_te01ftnref2_3\" class=\"aup1\" href=\"#_te01ftn2_3\">[3]<\/a><\/sup>.<\/p>\n<p>Bien que les Richonim n\u2019aient pas prescrit d\u2019obligation formelle de r\u00e9citer les Seli\u2019hot, telle est la coutume d\u2019Isra\u00ebl. Toutefois, celui \u00e0 qui il serait difficile de se lever assez t\u00f4t pour r\u00e9citer les Seli\u2019hot n\u2019y est pas oblig\u00e9 pendant le mois d\u2019\u00e9loul. Mais pendant les dix jours de p\u00e9nitence, il s\u2019efforcera d\u2019\u00eatre plus minutieux \u00e0 cet \u00e9gard, car ces jours sont davantage propices \u00e0 la <em>t\u00e9chouva<\/em> et \u00e0 l\u2019expiation (cf. <em>Roch Hachana<\/em> 18a, Ma\u00efmonide, <em>Hilkhot t\u00e9chouva<\/em> 2, 6).<\/p>\n<p>Si l\u2019on ne peut se coucher t\u00f4t, et que le fait de se lever pour les Seli\u2019hot soit de nature \u00e0 engendrer une fatigue telle que l\u2019on ne pourrait plus remplir ses obligations dans son travail, il sera pr\u00e9f\u00e9rable, m\u00eame durant les dix jours de p\u00e9nitence, de ne pas aller aux Seli\u2019hot. On s\u2019efforcera alors, au lieu de cela, de r\u00e9citer des psaumes, et, si l\u2019on veut, on pourra dire, dans le courant de la journ\u00e9e, les parties des Seli\u2019hot qu\u2019il est permis au particulier de r\u00e9citer (cf. ci-apr\u00e8s, \u00a7 7).<\/p>\n<p>Il est admis de recommander aux \u00e9rudits de la Torah eux-m\u00eames, qui ont l\u2019habitude d\u2019\u00e9tudier assidument, de consacrer le temps n\u00e9cessaire \u00e0 la r\u00e9citation des Seli\u2019hot (<em>Birk\u00e9 Yossef<\/em>, <em>Choul\u2019han \u2018Aroukh<\/em> 581, 1). Tel est l\u2019usage dans toutes les y\u00e9chivot que de r\u00e9citer les Seli\u2019hot, bien que le temps n\u00e9cessaire \u00e0 cela soit pris sur le temps de l\u2019\u00e9tude. Toutefois, celui \u00e0 qui un lever si pr\u00e9coce causerait une perte de temps d\u2019\u00e9tude sup\u00e9rieure \u00e0 la dur\u00e9e m\u00eame de la r\u00e9citation des Seli\u2019hot \u2013 parce que le changement de l\u2019emploi du temps habituel le conduirait ensuite \u00e0 manquer de concentration \u2013 fera mieux de ne pas y participer.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div><a id=\"_te01ftn2_c\" href=\"#_te01ftnref2_c\">[c]<\/a>. Du 6<sup>\u00e8me<\/sup> au 11<sup>\u00e8me<\/sup> si\u00e8cle.<a id=\"_te01ftn2_d\" href=\"#_te01ftnref2_d\">[d]<\/a>. Soura et Poumbedita.<\/p>\n<p><a id=\"_te01ftn2_e\" href=\"#_te01ftnref2_e\">[e]<\/a>. Du 11<sup>\u00e8me<\/sup> si\u00e8cle au 16<sup>\u00e8me<\/sup>.<\/p>\n<p><a id=\"_te01ftn2_3\" href=\"#_te01ftnref2_3\">[3]<\/a>. Si l\u2019on a soin de r\u00e9server quatre jours, c\u2019est parce que de nombreuses personnes ont l\u2019usage de je\u00fbner dix jours, au titre de la <em>t\u00e9chouva<\/em>, comme nous le verrons ci-apr\u00e8s, \u00a7 9. Or, pendant les dix jours de p\u00e9nitence, on ne peut je\u00fbner que six jours (puisque c\u2019est une mitsva que de manger lors des deux jours de Roch hachana, le <em>Chabbat Chouva<\/em> et la veille de Kipour)\u00a0; on a donc ajout\u00e9 quatre jours de je\u00fbne avant Roch hachana, et l\u2019on y r\u00e9citait les Seli\u2019hot. Et bien que, de nos jours, l\u2019usage courant ne soit plus de je\u00fbner dix jours, on perp\u00e9tue la coutume quant aux Seli\u2019hot elles-m\u00eames.<\/p>\n<p>De plus, l\u2019homme doit se \u00ab\u00a0sacrifier\u00a0\u00bb devant le Saint b\u00e9ni soit-Il [lui faire don de sa personne], \u00e0 Roch hachana\u00a0; or nous voyons que, en mati\u00e8re de sacrifices, il fallait pr\u00e9parer les animaux destin\u00e9s au sacrifice et v\u00e9rifier qu\u2019ils n\u2019\u00e9taient affect\u00e9s d\u2019aucun d\u00e9faut, cela quatre jours avant leur oblation, \u00e0 tout le moins. Et pour que les gens ne fassent aucune confusion, on a fix\u00e9 l\u2019issue de Chabbat comme premier jour de la r\u00e9citation des Seli\u2019hot (<em>Tour<\/em> et Rama 581, 1, <em>Michna Beroura<\/em> 6). Autre raison pour laquelle on fixe le commencement des Seli\u2019hot \u00e0 l\u2019issue de Chabbat\u00a0: afin de commencer sa supplication en \u00e9tant encore empreint de la saintet\u00e9 du Chabbat. En effet, le Chabbat, tout le monde a l\u2019habitude d\u2019\u00e9tudier, dans la joie et la d\u00e9lectation\u00a0; or la Pr\u00e9sence divine ne r\u00e9side qu\u2019au sein de la joie du commandement (<em>L\u00e9qet Yocher<\/em>).<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l\u2019\u00e9poque des Gu\u00e9onim[c], on avait coutume de r\u00e9citer les Seli\u2019hot durant les dix jours de p\u00e9nitence. Tel \u00e9tait l\u2019usage dans les deux grandes acad\u00e9mies talmudiques de Babylonie[d]\u00a0; et dans certaines contr\u00e9es, peu nombreuses, on avait \u00e9galement coutume de les r\u00e9citer durant tout le mois d\u2019\u00e9loul. \u00c0 la fin de la p\u00e9riode des Richonim[e], la [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[],"class_list":["post-2398","post","type-post","status-publish","format-standard","hentry","category-15-02"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l\u2019\u00e9poque des Gu\u00e9onim[c], on avait coutume de r\u00e9citer les Seli\u2019hot durant les dix jours de p\u00e9nitence. Tel \u00e9tait l\u2019usage dans les deux grandes acad\u00e9mies talmudiques de Babylonie[d]\u00a0; et dans certaines contr\u00e9es, peu nombreuses, on avait \u00e9galement coutume de les r\u00e9citer durant tout le mois d\u2019\u00e9loul. \u00c0 la fin de la p\u00e9riode des Richonim[e], la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-01T21:05:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-16T10:44:11+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-05\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-05\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation\",\"datePublished\":\"2016-09-01T21:05:46+00:00\",\"dateModified\":\"2019-01-16T10:44:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-05\\\/\"},\"wordCount\":883,\"articleSection\":[\"Chapitre 02 - Les Seli\u2019hot et autres pri\u00e8res\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-05\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-05\\\/\",\"name\":\"05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-09-01T21:05:46+00:00\",\"dateModified\":\"2019-01-16T10:44:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-05\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/","og_locale":"fr_FR","og_type":"article","og_title":"05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation - Pnin\u00e9 Halakha","og_description":"\u00c0 l\u2019\u00e9poque des Gu\u00e9onim[c], on avait coutume de r\u00e9citer les Seli\u2019hot durant les dix jours de p\u00e9nitence. Tel \u00e9tait l\u2019usage dans les deux grandes acad\u00e9mies talmudiques de Babylonie[d]\u00a0; et dans certaines contr\u00e9es, peu nombreuses, on avait \u00e9galement coutume de les r\u00e9citer durant tout le mois d\u2019\u00e9loul. \u00c0 la fin de la p\u00e9riode des Richonim[e], la [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-09-01T21:05:46+00:00","article_modified_time":"2019-01-16T10:44:11+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation","datePublished":"2016-09-01T21:05:46+00:00","dateModified":"2019-01-16T10:44:11+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/"},"wordCount":883,"articleSection":["Chapitre 02 - Les Seli\u2019hot et autres pri\u00e8res"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/","url":"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/","name":"05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-09-01T21:05:46+00:00","dateModified":"2019-01-16T10:44:11+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/15-02-05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"05. Jours o\u00f9 sont r\u00e9cit\u00e9es les Seli\u2019hot\u00a0; leur degr\u00e9 d\u2019obligation"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2398"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2398\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}