{"id":2412,"date":"2016-09-02T00:12:22","date_gmt":"2016-09-01T21:12:22","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2412"},"modified":"2017-09-04T13:06:06","modified_gmt":"2017-09-04T10:06:06","slug":"15-02-12","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/","title":{"rendered":"12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte"},"content":{"rendered":"<p>La halakha veut que la \u2018Amida se r\u00e9cite \u00e0 voix basse (cf. <em>La Pri\u00e8re d\u2019Isra\u00ebl <\/em>17, 7). Mais \u00e0 Roch hachana et \u00e0 Kipour, certains avaient l\u2019usage de r\u00e9citer la \u2018Amida \u00e0 voix haute, afin d\u2019\u00e9veiller la <em>kavana<\/em>. Et bien que, le reste de l\u2019ann\u00e9e, toute indulgence \u00e0 cet \u00e9gard soit interdite \u2013 cela, afin de ne pas perturber les autres fid\u00e8les \u2013, on ne craint pas, \u00e0 Roch hachana et \u00e0 Kipour, que les autres se trompent en leur pri\u00e8re, puisque chacun a son rituel en main (<em>Choul\u2019han \u2018Aroukh<\/em> 582, 9). Quoi qu\u2019il en soit, on n\u2019\u00e9l\u00e8vera pas la voix, afin de ne pas d\u00e9ranger les autres fid\u00e8les, et afin de ne pas ressembler aux proph\u00e8tes du Baal, qui criaient \u00e0 l\u2019adresse de leurs idoles (Rama, <em>Michna Beroura<\/em> 12).<\/p>\n<p>Mais il est pr\u00e9f\u00e9rable de r\u00e9citer la \u2018Amida en chuchotant, car l\u2019\u00e9l\u00e9vation sublime de cette pri\u00e8re justifie qu\u2019elle reste secr\u00e8te, inaccessible \u00e0 l\u2019oreille des autres fid\u00e8les (<em>Maguen Avraham, Ora\u2019h \u2018Ha\u00efm<\/em> 101, 4\u00a0; <em>Michna Beroura<\/em> 11). Or pr\u00e9cis\u00e9ment, aux jours redoutables, il convient d\u2019\u00eatre plus attentif encore \u00e0 cela. En un lieu o\u00f9 tout le monde ou presque prie silencieusement, comme c\u2019est l\u2019usage de nos jours, dans la majorit\u00e9 des communaut\u00e9s, il est interdit de dire la \u2018Amida \u00e0 haute voix. Et bien qu\u2019il ne soit pas \u00e0 craindre que les autres se trompent dans le texte du rituel, puisque chacun a son <em>ma\u2019hzor<\/em> devant soi, celui qui prie \u00e0 haute voix d\u00e9concentre les fid\u00e8les et porte atteinte \u00e0 leur <em>kavana<\/em>.<\/p>\n<p>Comme il est indiqu\u00e9 dans les rituels, on a coutume d\u2019ouvrir l\u2019arche sainte lors de certains passages de la pri\u00e8re\u00a0; \u00e0 ces instants, il est d\u2019usage que tout le monde se l\u00e8ve en l\u2019honneur de la Torah, qui est d\u00e9voil\u00e9e \u00e0 l\u2019assembl\u00e9e. Cependant, si l\u2019on s\u2019en tient \u00e0 la stricte obligation, il n\u2019est obligatoire de se lever que lorsqu\u2019on am\u00e8ne le rouleau de la Torah vers le pupitre de lecture, o\u00f9 qu\u2019on l\u2019en ram\u00e8ne vers l\u2019arche\u00a0; par contre, quand le rouleau se trouve \u00e0 sa place, dans l\u2019arche ou sur le pupitre de lecture, il n\u2019est pas obligatoire de se lever. Aussi, les personnes \u00e2g\u00e9es, faibles ou malades \u00e0 qui il est difficile de se tenir debout \u00e0 ces moments, sont autoris\u00e9es \u00e0 rester assises, m\u00eame au moment o\u00f9 l\u2019on ouvre l\u2019arche sainte. Ce n\u2019est que lorsqu\u2019on portera le rouleau de la Torah de l\u2019arche au pupitre ou du pupitre \u00e0 l\u2019arche que l\u2019on s\u2019efforcera de se lever<sup><a href='#_te01ftn2_6' id='_te01ftnref2_6' class='aup1'>[6]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref2_6' id='_te01ftn2_6'>[6]<\/a>. Selon le <em>Tour\u00e9 Zahav<\/em> sur <em>Yor\u00e9 D\u00e9\u2019a<\/em> 242, 13, quand le rouleau (<em>s\u00e9fer-Torah<\/em>) est pos\u00e9 dans l\u2019arche ou sur le pupitre de lecture, il n\u2019est pas n\u00e9cessaire d\u2019\u00eatre debout, puisque le rouleau se trouve dans un autre domaine. Qu\u2019appelle-t-on \u00ab\u00a0autre domaine\u00a0\u00bb (<em>rechout a\u2019h\u00e9ret<\/em>)\u00a0? C\u2019est un domaine semblable au <em>rechout haya\u2019hid<\/em> (domaine particulier) en mati\u00e8re de Chabbat\u00a0: un lieu dont la hauteur soit d\u2019au moins dix <em>t\u00e9fa\u2019him<\/em> (76 cm) et la largeur de quatre <em>t\u00e9fa\u2019him<\/em> (30, 4 cm). Selon le <em>Peri M\u00e9gadim, Ora\u2019h \u2018Ha\u00efm<\/em> 148, <em>Michbetsot Zahav<\/em> 3, m\u00eame quand l\u2019arche sainte ou le pupitre n\u2019atteignent pas ces dimensions, il n\u2019est pas obligatoire de se lever, m\u00eame quand on y voit le rouleau de la Tora, puisqu\u2019il s\u2019agit de son lieu, et que celui-ci est honorable. En pratique, il n\u2019est pas de pupitre, et presque pas d\u2019arche sainte, dont les dimensions soient inf\u00e9rieures \u00e0 dix <em>t\u00e9fa\u2019him <\/em>de hauteur et \u00e0 quatre <em>t\u00e9fa\u2019him<\/em> de largeur.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La halakha veut que la \u2018Amida se r\u00e9cite \u00e0 voix basse (cf. La Pri\u00e8re d\u2019Isra\u00ebl 17, 7). Mais \u00e0 Roch hachana et \u00e0 Kipour, certains avaient l\u2019usage de r\u00e9citer la \u2018Amida \u00e0 voix haute, afin d\u2019\u00e9veiller la kavana. Et bien que, le reste de l\u2019ann\u00e9e, toute indulgence \u00e0 cet \u00e9gard soit interdite \u2013 cela, afin [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139],"tags":[],"class_list":["post-2412","post","type-post","status-publish","format-standard","hentry","category-15-02"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"La halakha veut que la \u2018Amida se r\u00e9cite \u00e0 voix basse (cf. La Pri\u00e8re d\u2019Isra\u00ebl 17, 7). Mais \u00e0 Roch hachana et \u00e0 Kipour, certains avaient l\u2019usage de r\u00e9citer la \u2018Amida \u00e0 voix haute, afin d\u2019\u00e9veiller la kavana. Et bien que, le reste de l\u2019ann\u00e9e, toute indulgence \u00e0 cet \u00e9gard soit interdite \u2013 cela, afin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-01T21:12:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-04T10:06:06+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-12\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte\",\"datePublished\":\"2016-09-01T21:12:22+00:00\",\"dateModified\":\"2017-09-04T10:06:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-12\\\/\"},\"wordCount\":641,\"articleSection\":[\"Chapitre 02 - Les Seli\u2019hot et autres pri\u00e8res\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-12\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-12\\\/\",\"name\":\"12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2016-09-01T21:12:22+00:00\",\"dateModified\":\"2017-09-04T10:06:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-12\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-12\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/15-02-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/","og_locale":"fr_FR","og_type":"article","og_title":"12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte - Pnin\u00e9 Halakha","og_description":"La halakha veut que la \u2018Amida se r\u00e9cite \u00e0 voix basse (cf. La Pri\u00e8re d\u2019Isra\u00ebl 17, 7). Mais \u00e0 Roch hachana et \u00e0 Kipour, certains avaient l\u2019usage de r\u00e9citer la \u2018Amida \u00e0 voix haute, afin d\u2019\u00e9veiller la kavana. Et bien que, le reste de l\u2019ann\u00e9e, toute indulgence \u00e0 cet \u00e9gard soit interdite \u2013 cela, afin [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2016-09-01T21:12:22+00:00","article_modified_time":"2017-09-04T10:06:06+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte","datePublished":"2016-09-01T21:12:22+00:00","dateModified":"2017-09-04T10:06:06+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/"},"wordCount":641,"articleSection":["Chapitre 02 - Les Seli\u2019hot et autres pri\u00e8res"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/","url":"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/","name":"12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2016-09-01T21:12:22+00:00","dateModified":"2017-09-04T10:06:06+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/15-02-12\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/15-02-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"12. Prier \u00e0 haute voix\u00a0; \u00eatre debout au moment de l\u2019ouverture de l\u2019arche sainte"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2412"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2412\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}