{"id":2577,"date":"2000-03-10T00:05:07","date_gmt":"2000-03-09T22:05:07","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2577"},"modified":"2017-11-08T10:16:46","modified_gmt":"2017-11-08T08:16:46","slug":"03-10-05","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/","title":{"rendered":"05. Couvre-chef pour les hommes"},"content":{"rendered":"<p>Afin d\u2019examiner la question de savoir si les femmes doivent se couvrir la t\u00eate quand elles r\u00e9citent la pri\u00e8re ou des b\u00e9n\u00e9dictions, il faut d\u2019abord exposer la r\u00e8gle applicable aux hommes. Jadis, une partie des grands sages d\u2019Isra\u00ebl adopt\u00e8rent le pieux usage de ne point parcourir une distance de quatre <em>amot<\/em> (environ deux m\u00e8tres) t\u00eate nue. Ainsi, Rav Houna, fils de Rabbi Yehochoua, se f\u00e9licitait de ne pas marcher quatre <em>amot<\/em> sans couvre-chef (<em>Chabbat <\/em>118b) et disait\u00a0: \u00ab\u00a0La Pr\u00e9sence divine (<em>Chekhina<\/em>) n\u2019est-elle pas au-dessus de ma t\u00eate\u00a0? Comment marcherais-je t\u00eate nue\u00a0?\u00a0\u00bb (<em>Qidouchin<\/em> 31a). On raconte de m\u00eame, dans le Talmud (cf. <em>Chabbat <\/em>156b), que la m\u00e8re de Rav Na\u2019hman fils de Yits\u2019haq, apr\u00e8s avoir appris que, selon sa destin\u00e9e astrale, son fils risquait de devenir voleur, veilla grandement \u00e0 ce qu\u2019il se couvr\u00eet constamment la t\u00eate\u00a0; de cette fa\u00e7on, il grandit dans la Torah et les mitsvot. Un jour, alors que son couvre-chef tomba de sa t\u00eate, son mauvais penchant l\u2019attaqua, et il d\u00e9sira vivement grimper au sommet d\u2019un palmier pour voler des dattes. Il comprit alors l\u2019exigence de sa m\u00e8re. Au fil du temps, cet usage de pi\u00e9t\u00e9 fut adopt\u00e9 parmi tout le peuple juif, au point qu\u2019il devint une coutume obligatoire (<em>Choul\u2019han \u2018Aroukh<\/em>, <em>Ora\u2019h \u2018Ha\u00efm<\/em> 2, 6).<\/p>\n<p>Certains d\u00e9cisionnaires estiment que, quand on mentionne le nom divin, ou quand on r\u00e9cite des b\u00e9n\u00e9dictions, il est obligatoire de se couvrir la t\u00eate. D\u2019autres pensent qu\u2019il n\u2019y a pas d\u2019obligation sp\u00e9cifique pour les hommes de se couvrir la t\u00eate quand ils mentionnent le nom divin ou r\u00e9citent des b\u00e9n\u00e9dictions, mais que, en raison de la coutume mentionn\u00e9e ci-dessus, il faut se couvrir la t\u00eate toute la journ\u00e9e, <em>y compris<\/em> lorsque l\u2019on mentionne le nom divin. Le <em>Choul\u2019han \u2018Aroukh<\/em> tranche selon l\u2019opinion rigoureuse, selon laquelle se couvrir la t\u00eate quand on mentionne le nom divin et quand on r\u00e9cite des b\u00e9n\u00e9dictions est une obligation en tant que telle (<em>Ora\u2019h \u2018Ha\u00efm<\/em> 91, 3\u00a0; 206, 3)<sup><a href='#_te01ftn10_5' id='_te01ftnref10_5' class='aup1'>[5]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref10_5' id='_te01ftn10_5'>[5]<\/a>. Au trait\u00e9 <em>Sofrim <\/em>de la Michna (14, 15), nous apprenons que, selon la premi\u00e8re opinion tanna\u00eftique rapport\u00e9e, il est permis de mentionner le nom divin\u00a0t\u00eate nue ; selon d\u2019autres, c\u2019est interdit. Rabb\u00e9nou Yerou\u2019ham et le <em>Or Zaroua\u2019<\/em> II, 43 d\u00e9cident qu\u2019il est interdit de r\u00e9citer des b\u00e9n\u00e9dictions sans calotte (<em>kippa<\/em>), et c\u2019est en ce sens que le <em>Choul\u2019han \u2018Aroukh<\/em> statue<br \/>\n(91, 3 et 206, 3).<\/p>\n<p>Toutefois, le <em>Or Zaroua\u2019<\/em> rapporte que les rabbins de France, \u00e0 son \u00e9poque (13\u00e8me si\u00e8cle), avaient l\u2019usage de r\u00e9citer les b\u00e9n\u00e9dictions sans couvre-chef. L\u2019opinion de Ma\u00efmonide est que la pri\u00e8re requiert un couvre-chef, tandis que cela n\u2019est pas n\u00e9cessaire pour les b\u00e9n\u00e9dictions [courtes, telles que les b\u00e9n\u00e9dictions matinales et de jouissance]. Le <em>Peri \u2018Hadach<\/em> 91, 3 et le Gaon de Vilna 8, 6, eux aussi, \u00e9crivent que, si l\u2019on s\u2019en tient \u00e0 la stricte obligation, il n\u2019est pas n\u00e9cessaire de se couvrir la t\u00eate pendant les b\u00e9n\u00e9dictions\u00a0; en effet, la formulation m\u00eame des <em>Birkot hacha\u2019har<\/em>, telle qu\u2019expos\u00e9e par le trait\u00e9 <em>Berakhot<\/em> 60b, implique que toutes les b\u00e9n\u00e9dictions r\u00e9cit\u00e9es avant <em>\u2018Oter Isra\u00ebl<\/em> (\u00ab\u00a0qui couronne Isra\u00ebl de splendeur\u00a0\u00bb) se disent sans kippa. [En effet, \u00e0 l\u2019\u00e9poque talmudique, les <em>Birkot hacha\u2019har<\/em> ne se disaient pas d\u2019un seul bloc, en introduction \u00e0 l\u2019office, mais au fur et \u00e0 mesure que l\u2019objet de chacune se pr\u00e9sentait. Si bien que l\u2019on b\u00e9nissait Dieu \u00ab\u00a0qui couronne Isra\u00ebl de splendeur\u00a0\u00bb lorsque l\u2019on mettait sa \u00ab\u00a0couronne\u00a0\u00bb, c\u2019est-\u00e0-dire son couvre-chef. Cf. chap. 6 \u00a7 1.] C\u2019est aussi ce qu\u2019\u00e9crit le <em>Beit Yossef<\/em>, <em>Ora\u2019h \u2018Ha\u00efm<\/em> 46. C\u2019est encore l\u2019opinion du Roch, du <em>Mikhtam<\/em>, du Rachba et d\u2019autres Richonim, qui expliquent que les propos du trait\u00e9 <em>Berakhot<\/em> d\u00e9crivent l\u2019ordre pr\u00e9cis de r\u00e9citation des <em>Birkot hacha\u2019har<\/em>. Le Maharchal dans son responsum 72 \u00e9crit lui aussi que, si l\u2019on s\u2019en tient \u00e0 la stricte obligation, il est permis de mentionner le nom divin sans porter de kippa.<\/p>\n<p>Toutefois, s\u2019agissant des hommes, l\u2019usage est en pratique clairement \u00e9tabli\u00a0: il faut porter une kippa pour r\u00e9citer toute parole sainte, comme l\u2019a d\u00e9cid\u00e9 le <em>Choul\u2019han \u2018Aroukh<\/em>. De m\u00eame, l\u2019usage a \u00e9t\u00e9 adopt\u00e9 de ne pas marcher quatre <em>amot<\/em> sans couvre-chef (cf. \u00e9galement <em>La Pri\u00e8re d\u2019Isra\u00ebl<\/em> 5, note 3).<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Afin d\u2019examiner la question de savoir si les femmes doivent se couvrir la t\u00eate quand elles r\u00e9citent la pri\u00e8re ou des b\u00e9n\u00e9dictions, il faut d\u2019abord exposer la r\u00e8gle applicable aux hommes. Jadis, une partie des grands sages d\u2019Isra\u00ebl adopt\u00e8rent le pieux usage de ne point parcourir une distance de quatre amot (environ deux m\u00e8tres) t\u00eate [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2577","post","type-post","status-publish","format-standard","hentry","category-03-10"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>05. Couvre-chef pour les hommes - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"05. Couvre-chef pour les hommes - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Afin d\u2019examiner la question de savoir si les femmes doivent se couvrir la t\u00eate quand elles r\u00e9citent la pri\u00e8re ou des b\u00e9n\u00e9dictions, il faut d\u2019abord exposer la r\u00e8gle applicable aux hommes. Jadis, une partie des grands sages d\u2019Isra\u00ebl adopt\u00e8rent le pieux usage de ne point parcourir une distance de quatre amot (environ deux m\u00e8tres) t\u00eate [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-09T22:05:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-08T08:16:46+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-10-05\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-10-05\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"05. Couvre-chef pour les hommes\",\"datePublished\":\"2000-03-09T22:05:07+00:00\",\"dateModified\":\"2017-11-08T08:16:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-10-05\\\/\"},\"wordCount\":800,\"articleSection\":[\"Chapitre 10 \u2013 Pr\u00e9paration spirituelle et vestimentaire\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-10-05\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-10-05\\\/\",\"name\":\"05. Couvre-chef pour les hommes - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-09T22:05:07+00:00\",\"dateModified\":\"2017-11-08T08:16:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-10-05\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-10-05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-10-05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"05. Couvre-chef pour les hommes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"05. Couvre-chef pour les hommes - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/","og_locale":"fr_FR","og_type":"article","og_title":"05. Couvre-chef pour les hommes - Pnin\u00e9 Halakha","og_description":"Afin d\u2019examiner la question de savoir si les femmes doivent se couvrir la t\u00eate quand elles r\u00e9citent la pri\u00e8re ou des b\u00e9n\u00e9dictions, il faut d\u2019abord exposer la r\u00e8gle applicable aux hommes. Jadis, une partie des grands sages d\u2019Isra\u00ebl adopt\u00e8rent le pieux usage de ne point parcourir une distance de quatre amot (environ deux m\u00e8tres) t\u00eate [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-09T22:05:07+00:00","article_modified_time":"2017-11-08T08:16:46+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"05. Couvre-chef pour les hommes","datePublished":"2000-03-09T22:05:07+00:00","dateModified":"2017-11-08T08:16:46+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/"},"wordCount":800,"articleSection":["Chapitre 10 \u2013 Pr\u00e9paration spirituelle et vestimentaire"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/","name":"05. Couvre-chef pour les hommes - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-09T22:05:07+00:00","dateModified":"2017-11-08T08:16:46+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-10-05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-10-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"05. Couvre-chef pour les hommes"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2577"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2577\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}