{"id":2644,"date":"2000-03-13T00:05:20","date_gmt":"2000-03-12T22:05:20","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2644"},"modified":"2017-11-08T11:35:53","modified_gmt":"2017-11-08T09:35:53","slug":"03-13-05","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/","title":{"rendered":"05. Cas de \u00a0doute"},"content":{"rendered":"<p>Une femme qui a l\u2019habitude de r\u00e9citer chaque jour la \u2018Amida de Cha\u2019harit ou celle de Min\u2019ha, ou les deux, et qui, un certain jour, ne se souvient plus si elle a dit ou non la pri\u00e8re qu\u2019elle a l\u2019habitude de r\u00e9citer, devra, dans la mesure o\u00f9 le temps de r\u00e9citation de la pri\u00e8re consid\u00e9r\u00e9e n\u2019est pas expir\u00e9, redire la \u2018Amida en raison du doute. On formule alors int\u00e9rieurement la condition suivante\u00a0: dans le cas o\u00f9 j\u2019aurais d\u00e9j\u00e0 pri\u00e9, la pr\u00e9sente \u2018Amida constituerait une pri\u00e8re additionnelle volontaire, et dans le cas o\u00f9 je n\u2019aurais pas encore pri\u00e9, cette \u2018Amida aurait valeur de pri\u00e8re r\u00e9guli\u00e8re obligatoire. Dans un tel cas, il n\u2019est pas n\u00e9cessaire d\u2019ajouter de requ\u00eate personnelle, car le fait m\u00eame de sortir du doute constitue pour la fid\u00e8le un \u00e9l\u00e9ment de renouveau. Et bien que, de nos jours, la \u2018Amida additionnelle volontaire ne soit plus en usage, l\u2019usage reste actuel quand il s\u2019agit de sortir du doute. Si, apr\u00e8s avoir ainsi entam\u00e9 une \u2018Amida additionnelle, on se souvient que l\u2019on avait en r\u00e9alit\u00e9 d\u00e9j\u00e0 dit la \u2018Amida, on devra poursuivre sa pri\u00e8re additionnelle jusqu\u2019\u00e0 la fin. En effet, il avait \u00e9t\u00e9 pr\u00e9alablement stipul\u00e9 que, dans le cas o\u00f9 l\u2019on aurait d\u00e9j\u00e0 pri\u00e9, la pr\u00e9sente \u2018Amida aurait valeur de pri\u00e8re volontaire. Simplement, en ce cas, on ajoutera une demande personnelle, afin de manifester qu\u2019il s\u2019agit effectivement d\u2019une pri\u00e8re personnelle.<\/p>\n<p>Si, croyant n\u2019avoir pas encore pri\u00e9, on entame la \u2018Amida en pensant qu\u2019il s\u2019agit d\u2019une pri\u00e8re obligatoire, et que l\u2019on se souvienne soudain, au milieu de cette \u2018Amida, que l\u2019on avait en r\u00e9alit\u00e9 d\u00e9j\u00e0 pri\u00e9, on interrompt imm\u00e9diatement sa pri\u00e8re. Il est impossible de poursuivre cette pri\u00e8re en stipulant int\u00e9rieurement que la suite de celle-ci aura le caract\u00e8re de pri\u00e8re volontaire. En effet, de m\u00eame qu\u2019un sacrifice ne peut appartenir en partie \u00e0 la cat\u00e9gorie de sacrifice obligatoire et en partie \u00e0 celle de sacrifice volontaire, de m\u00eame une pri\u00e8re ne peut commencer en tant qu\u2019obligation et se terminer en tant que b\u00e9n\u00e9volat (<em>Choul\u2019han \u2018Aroukh<\/em> 107, 1).<\/p>\n<p>Quand l\u2019esprit vagabonde au milieu de sa pri\u00e8re, au point de ne plus savoir \u00e0 quelle b\u00e9n\u00e9diction l\u2019on se trouve \u2013 par exemple, quand on ne sait plus si l\u2019on en est \u00e0 la sixi\u00e8me b\u00e9n\u00e9diction ou \u00e0 la dixi\u00e8me \u2013 on doit reprendre sa r\u00e9citation \u00e0 la premi\u00e8re des b\u00e9n\u00e9dictions faisant l\u2019objet de l\u2019h\u00e9sitation\u00a0; dans l\u2019exemple cit\u00e9, on reprendra \u00e0 la sixi\u00e8me b\u00e9n\u00e9diction, et l\u2019on r\u00e9citera toute la suite, jusqu\u2019\u00e0 la fin (conform\u00e9ment \u00e0 l\u2019avis de la majorit\u00e9 des d\u00e9cisionnaires\u00a0; cf. <em>La Pri\u00e8re d\u2019Isra\u00ebl<\/em> 18, note 3).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une femme qui a l\u2019habitude de r\u00e9citer chaque jour la \u2018Amida de Cha\u2019harit ou celle de Min\u2019ha, ou les deux, et qui, un certain jour, ne se souvient plus si elle a dit ou non la pri\u00e8re qu\u2019elle a l\u2019habitude de r\u00e9citer, devra, dans la mesure o\u00f9 le temps de r\u00e9citation de la pri\u00e8re consid\u00e9r\u00e9e [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2644","post","type-post","status-publish","format-standard","hentry","category-03-13"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>05. Cas de \u00a0doute - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"05. Cas de \u00a0doute - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Une femme qui a l\u2019habitude de r\u00e9citer chaque jour la \u2018Amida de Cha\u2019harit ou celle de Min\u2019ha, ou les deux, et qui, un certain jour, ne se souvient plus si elle a dit ou non la pri\u00e8re qu\u2019elle a l\u2019habitude de r\u00e9citer, devra, dans la mesure o\u00f9 le temps de r\u00e9citation de la pri\u00e8re consid\u00e9r\u00e9e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-12T22:05:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-08T09:35:53+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-13-05\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-13-05\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"05. Cas de \u00a0doute\",\"datePublished\":\"2000-03-12T22:05:20+00:00\",\"dateModified\":\"2017-11-08T09:35:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-13-05\\\/\"},\"wordCount\":511,\"articleSection\":[\"Chapitre 13 \u2013 Erreurs et oublis dans la r\u00e9citation de la \u2018Amida\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-13-05\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-13-05\\\/\",\"name\":\"05. Cas de \u00a0doute - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-12T22:05:20+00:00\",\"dateModified\":\"2017-11-08T09:35:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-13-05\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-13-05\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-13-05\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"05. Cas de \u00a0doute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"05. Cas de \u00a0doute - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/","og_locale":"fr_FR","og_type":"article","og_title":"05. Cas de \u00a0doute - Pnin\u00e9 Halakha","og_description":"Une femme qui a l\u2019habitude de r\u00e9citer chaque jour la \u2018Amida de Cha\u2019harit ou celle de Min\u2019ha, ou les deux, et qui, un certain jour, ne se souvient plus si elle a dit ou non la pri\u00e8re qu\u2019elle a l\u2019habitude de r\u00e9citer, devra, dans la mesure o\u00f9 le temps de r\u00e9citation de la pri\u00e8re consid\u00e9r\u00e9e [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-12T22:05:20+00:00","article_modified_time":"2017-11-08T09:35:53+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"05. Cas de \u00a0doute","datePublished":"2000-03-12T22:05:20+00:00","dateModified":"2017-11-08T09:35:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/"},"wordCount":511,"articleSection":["Chapitre 13 \u2013 Erreurs et oublis dans la r\u00e9citation de la \u2018Amida"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/","name":"05. Cas de \u00a0doute - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-12T22:05:20+00:00","dateModified":"2017-11-08T09:35:53+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-13-05\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-13-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"05. Cas de \u00a0doute"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2644"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2644\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}