{"id":2750,"date":"2000-03-20T00:06:32","date_gmt":"2000-03-19T22:06:32","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2750"},"modified":"2017-11-09T10:31:32","modified_gmt":"2017-11-09T08:31:32","slug":"03-20-06","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/","title":{"rendered":"06. R\u00e9p\u00e9tition de l\u2019officiant"},"content":{"rendered":"<p>Les membres de la Grande Assembl\u00e9e (<em>anch\u00e9 Knesset Haguedola<\/em>) ont d\u00e9cr\u00e9t\u00e9 qu\u2019une fois la \u2018Amida r\u00e9cit\u00e9e par les fid\u00e8les, l\u2019officiant r\u00e9p\u00e9terait celle-ci \u00e0 voix haute, afin d\u2019acquitter de leur obligation ceux qui ne savent pas prier par eux-m\u00eames (<em>Roch Hachana<\/em> 34b). Mais pour l\u2019office d\u2019Arvit, ils n\u2019ont pas institu\u00e9 de r\u00e9p\u00e9tition car, dans son fondement, cet office est facultatif, aussi n\u2019est-il pas besoin d\u2019en rendre quitte ceux qui ne sont pas vers\u00e9s dans le rituel.<\/p>\n<p>Les sages ont d\u00e9cr\u00e9t\u00e9 que l\u2019officiant devait lui-m\u00eame prononcer pr\u00e9alablement la \u2018Amida \u00e0 voix basse, avec les autres membres du minyan, afin d\u2019en bien ordonner le texte dans sa bouche avant d\u2019entamer sa r\u00e9p\u00e9tition. Ils ont encore d\u00e9cr\u00e9t\u00e9 que ceux qui savent prier par eux-m\u00eames doivent, eux aussi, \u00e9couter la r\u00e9p\u00e9tition de l\u2019officiant et r\u00e9pondre <em>amen <\/em>aux b\u00e9n\u00e9dictions.<\/p>\n<p>Or, dans la mesure o\u00f9 ce sont les sages qui ont institu\u00e9 la r\u00e9p\u00e9tition de l\u2019officiant, il faut la r\u00e9citer, m\u00eame en un endroit o\u00f9 tous les fid\u00e8les savent prier par eux-m\u00eames. M\u00eame apr\u00e8s que l\u2019on eut autoris\u00e9 de porter \u00e0 l\u2019\u00e9crit la Torah orale, dont fait partie le texte de la pri\u00e8re, et que les livres de pri\u00e8re se furent r\u00e9pandus, au point que presque aucun minyan ne comportait de membre comptant sur la r\u00e9p\u00e9tition pour\u00a0 se rendre quitte, le d\u00e9cret des sages ne fut pas r\u00e9voqu\u00e9. Car le principe veut que, une fois que les sages ont pris une d\u00e9cision, celle-ci n\u2019est pas susceptible d\u2019\u00eatre modifi\u00e9e en raison des circonstances (<em>Choul\u2019han \u2018Aroukh<\/em> 124, 3 d\u2019apr\u00e8s un responsum de Ma\u00efmonide). De plus, les sages ont institu\u00e9, au sein de la r\u00e9p\u00e9tition, la <em>Q\u00e9doucha<\/em> et la b\u00e9n\u00e9diction sacerdotale\u00a0; or, si l\u2019on ne disait plus la r\u00e9p\u00e9tition de la \u2018Amida, ces deux c\u00e9r\u00e9monies sortiraient de l\u2019usage (<em>Tour<\/em>).<\/p>\n<p>Selon la Kabbale, il appara\u00eet qu\u2019en plus de sa signification premi\u00e8re \u2013 rendre quitte ceux qui ne sont pas vers\u00e9s dans le rituel \u2013, la r\u00e9p\u00e9tition poss\u00e8de une signification mystique profonde. D\u2019apr\u00e8s cela, l\u2019une et l\u2019autre des r\u00e9citations de la \u2018Amida sont n\u00e9cessaires \u2013 celle qui se dit \u00e0 voix basse et celle de l\u2019officiant \u2013, car par leur biais la pri\u00e8re agit davantage. Aussi, m\u00eame en un lieu o\u00f9 il n\u2019est pas n\u00e9cessaire d\u2019acquitter d\u2019\u00e9ventuels \u00ab\u00a0non-experts\u00a0\u00bb, il reste n\u00e9cessaire de r\u00e9citer la r\u00e9p\u00e9tition de la \u2018Amida, pour le motif profond que nous avons \u00e9voqu\u00e9. La valeur de la r\u00e9p\u00e9tition est m\u00eame consid\u00e9r\u00e9e comme plus \u00e9lev\u00e9e que celle de la \u2018Amida dite \u00e0 voix basse, en ce qu\u2019elle est une pri\u00e8re plus collective, et en ce que le public r\u00e9pond <em>amen<\/em> \u00e0 ses b\u00e9n\u00e9dictions. Aussi, bien que le contenu de la \u2018Amida soit profond et supr\u00eamement \u00e9lev\u00e9, et que, pour respecter son \u00e9l\u00e9vation, le particulier doive la r\u00e9citer \u00e0 voix basse, la r\u00e9p\u00e9tition, quant \u00e0 elle, se dit \u00e0 haute voix\u00a0: en raison de sa haute valeur, il n\u2019est pas \u00e0 craindre que les <em>\u00e9corces <\/em>impures<sup><a href='#_te01ftn20_i' id='_te01ftnref20_i' class='aup1'>[i]<\/a><\/sup> aient prise sur elle (cf. <em>Choul\u2019han \u2018Aroukh<\/em> 124, 7, <em>Kaf Ha\u2019ha\u00efm<\/em> 124, 2 et 16).<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref20_i' id='_te01ftn20_i'>[i]<\/a>. Ecorces (h\u00e9breu <em>qlipa<\/em>, plur. <em>qlipot<\/em>)\u00a0: d\u00e9signe, dans la mystique juive, les forces du mal, en ce qu\u2019elles voilent le bien.<\/li>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les membres de la Grande Assembl\u00e9e (anch\u00e9 Knesset Haguedola) ont d\u00e9cr\u00e9t\u00e9 qu\u2019une fois la \u2018Amida r\u00e9cit\u00e9e par les fid\u00e8les, l\u2019officiant r\u00e9p\u00e9terait celle-ci \u00e0 voix haute, afin d\u2019acquitter de leur obligation ceux qui ne savent pas prier par eux-m\u00eames (Roch Hachana 34b). Mais pour l\u2019office d\u2019Arvit, ils n\u2019ont pas institu\u00e9 de r\u00e9p\u00e9tition car, dans son fondement, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2750","post","type-post","status-publish","format-standard","hentry","category-03-20"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>06. R\u00e9p\u00e9tition de l\u2019officiant - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"06. R\u00e9p\u00e9tition de l\u2019officiant - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Les membres de la Grande Assembl\u00e9e (anch\u00e9 Knesset Haguedola) ont d\u00e9cr\u00e9t\u00e9 qu\u2019une fois la \u2018Amida r\u00e9cit\u00e9e par les fid\u00e8les, l\u2019officiant r\u00e9p\u00e9terait celle-ci \u00e0 voix haute, afin d\u2019acquitter de leur obligation ceux qui ne savent pas prier par eux-m\u00eames (Roch Hachana 34b). Mais pour l\u2019office d\u2019Arvit, ils n\u2019ont pas institu\u00e9 de r\u00e9p\u00e9tition car, dans son fondement, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-19T22:06:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T08:31:32+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-06\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-06\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"06. R\u00e9p\u00e9tition de l\u2019officiant\",\"datePublished\":\"2000-03-19T22:06:32+00:00\",\"dateModified\":\"2017-11-09T08:31:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-06\\\/\"},\"wordCount\":619,\"articleSection\":[\"Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-06\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-06\\\/\",\"name\":\"06. R\u00e9p\u00e9tition de l\u2019officiant - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-19T22:06:32+00:00\",\"dateModified\":\"2017-11-09T08:31:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-06\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-06\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-06\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"06. R\u00e9p\u00e9tition de l\u2019officiant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"06. R\u00e9p\u00e9tition de l\u2019officiant - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/","og_locale":"fr_FR","og_type":"article","og_title":"06. R\u00e9p\u00e9tition de l\u2019officiant - Pnin\u00e9 Halakha","og_description":"Les membres de la Grande Assembl\u00e9e (anch\u00e9 Knesset Haguedola) ont d\u00e9cr\u00e9t\u00e9 qu\u2019une fois la \u2018Amida r\u00e9cit\u00e9e par les fid\u00e8les, l\u2019officiant r\u00e9p\u00e9terait celle-ci \u00e0 voix haute, afin d\u2019acquitter de leur obligation ceux qui ne savent pas prier par eux-m\u00eames (Roch Hachana 34b). Mais pour l\u2019office d\u2019Arvit, ils n\u2019ont pas institu\u00e9 de r\u00e9p\u00e9tition car, dans son fondement, [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-19T22:06:32+00:00","article_modified_time":"2017-11-09T08:31:32+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"06. R\u00e9p\u00e9tition de l\u2019officiant","datePublished":"2000-03-19T22:06:32+00:00","dateModified":"2017-11-09T08:31:32+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/"},"wordCount":619,"articleSection":["Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/","name":"06. R\u00e9p\u00e9tition de l\u2019officiant - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-19T22:06:32+00:00","dateModified":"2017-11-09T08:31:32+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-20-06\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-06\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"06. R\u00e9p\u00e9tition de l\u2019officiant"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2750"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2750\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}