{"id":2752,"date":"2000-03-20T00:07:02","date_gmt":"2000-03-19T22:07:02","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2752"},"modified":"2017-11-09T10:33:06","modified_gmt":"2017-11-09T08:33:06","slug":"03-20-07","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/","title":{"rendered":"07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre <em>amen<\/em>"},"content":{"rendered":"<p>Trois conditions doivent \u00eatre rassembl\u00e9es pour que le particulier puisse se rendre quitte de son obligation par l\u2019\u00e9coute de la r\u00e9p\u00e9tition de l\u2019officiant\u00a0: <strong>1)<\/strong> Ne pas \u00eatre capable de r\u00e9citer soi-m\u00eame la \u2018Amida. Si l\u2019on sait r\u00e9citer cette pri\u00e8re, on s\u2019oblige \u00e0 le faire et \u00e0 demander mis\u00e9ricorde par soi-m\u00eame, et l\u2019on ne peut s\u2019acquitter par l\u2019\u00e9coute de l\u2019officiant. <strong>2)<\/strong> Il faut encore qu\u2019un minyan de dix hommes soit pr\u00e9sent. En effet, si les sages ont \u00e9tabli que les particuliers pouvaient s\u2019acquitter de leur obligation par l\u2019\u00e9coute de l\u2019officiant, ce n\u2019est que dans le cadre d\u2019un minyan. <strong>3)<\/strong> L\u2019auditeur doit comprendre les paroles de l\u2019officiant. Si l\u2019on ne comprend pas l\u2019h\u00e9breu, on ne peut s\u2019acquitter par cette r\u00e9p\u00e9tition.<\/p>\n<p>Les auditeurs, m\u00eame s\u2019ils ont pri\u00e9 par eux-m\u00eames, doivent avoir grand soin de r\u00e9pondre <em>amen <\/em>\u00e0 chaque b\u00e9n\u00e9diction r\u00e9cit\u00e9e par l\u2019officiant. Nos sages ont dit (<em>Berakhot<\/em> 53b)\u00a0: \u00ab\u00a0Celui qui r\u00e9pond <em>amen<\/em> est plus grand que celui qui prononce la b\u00e9n\u00e9diction.\u00a0\u00bb<\/p>\n<p>On r\u00e9pond <em>amen<\/em> en y mettant toute son attention. En disant <em>amen<\/em>, on pensera que ce que vient de dire l\u2019officiant est v\u00e9rit\u00e9<sup><a href='#_te01ftn20_j' id='_te01ftnref20_j' class='aup1'>[j]<\/a><\/sup>. Par exemple, quand on \u00e9coute la b\u00e9n\u00e9diction \u00ab\u00a0B\u00e9ni sois-Tu, Eternel, le Dieu saint\u00a0\u00bb (<em>Baroukh\u2026<\/em> <em>haE-l haqadoch<\/em>), on doit penser\u00a0: \u00ab\u00a0C\u2019est vrai qu\u2019Il est le Dieu saint \u00bb. Quand la b\u00e9n\u00e9diction comprend \u00e9galement une requ\u00eate, on pensera aussi\u00a0: \u00ab\u00a0Plaise \u00e0 Dieu que notre requ\u00eate soit agr\u00e9\u00e9e devant Lui.\u00a0\u00bb Par exemple dans la b\u00e9n\u00e9diction <em>\u2018Honen hada\u2019at<\/em> (\u00ab\u00a0\u2026 qui dispenses la sagesse\u00a0\u00bb), on orientera sa pens\u00e9e vers ces deux aspects\u00a0: 1) c\u2019est vrai que la sagesse vient de Dieu\u00a0; 2) plaise \u00e0 Dieu de nous gratifier de sagesse (<em>Choul\u2019han \u2018Aroukh<\/em> 124, 6\u00a0; <em>Michna Beroura<\/em> 25).<\/p>\n<p>C\u2019est ici le lieu d\u2019approfondir quelque peu les r\u00e8gles relatives au mot <em>amen<\/em>, qu\u2019il s\u2019agisse de r\u00e9pondre <em>amen<\/em> \u00e0 la r\u00e9p\u00e9tition de la \u2018Amida ou aux autres b\u00e9n\u00e9dictions. On r\u00e9pond <em>amen<\/em> d\u2019une voix agr\u00e9able, sans \u00e9lever la voix plus que ne le fait l\u2019officiant qui dit la b\u00e9n\u00e9diction (<em>Choul\u2019han \u2018Aroukh<\/em> 124, 12). Le mot <em>amen<\/em> ne doit pas \u00eatre trop court\u00a0: on le prolongera quelque peu, de telle fa\u00e7on qu\u2019il dure un temps \u00e9quivalent \u00e0 celui qu\u2019il faut pour dire les mots <em>E-l M\u00e9lekh N\u00e9\u00e9man<\/em> (\u00ab\u00a0Dieu, Roi fid\u00e8le\u00a0\u00bb)<sup><a href='#_te01ftn20_k' id='_te01ftnref20_k' class='aup1'>[k]<\/a><\/sup>. \u00c0 l\u2019inverse, on ne prolongera pas ce mot plus qu\u2019il ne faut.<\/p>\n<p>Il ne faut pas pr\u00e9cipiter le mot <em>amen<\/em>, en le disant avant que l\u2019officiant ne termine la b\u00e9n\u00e9diction. Il ne faut pas non plus escamoter le mot <em>amen<\/em>, en avalant l\u2019une de ses lettres ou en le bredouillant d\u2019une langue l\u00e2che et d\u2019une voix faible. On ne retardera pas non plus le mot <em>amen<\/em> en l\u2019\u00e9loignant de la fin de la b\u00e9n\u00e9diction, car cela s\u2019appellerait alors un <em>amen yetoma<\/em> (\u00ab\u00a0amen orphelin\u00a0\u00bb) (cf. <em>Berakhot<\/em> 47a\u00a0; <em>Choul\u2019han \u2018Aroukh<\/em> 124, 8).<\/p>\n<p>Le fait de r\u00e9pondre <em>amen<\/em> \u00e0 la suite des b\u00e9n\u00e9dictions est l\u2019expression du lien\u00a0 de l\u2019homme avec la foi en Dieu, b\u00e9ni soit-Il. Or puisque notre vie d\u00e9pend de Lui, un d\u00e9faut affectant la foi entra\u00eene une alt\u00e9ration de la vie m\u00eame. Ben \u2018Aza\u00ef dit en ce sens\u00a0: \u00ab\u00a0Si l\u2019on prononce un \u201c<em>amen<\/em> orphelin\u201d, on expose ses enfants \u00e0 devenir orphelins\u00a0; un <em>amen<\/em> pr\u00e9cipit\u00e9 \u2013 on expose sa vie \u00e0 \u00eatre abr\u00e9g\u00e9e\u00a0; un <em>amen<\/em> escamot\u00e9 \u2013 on expose sa vie \u00e0 \u00eatre coup\u00e9e. Mais si l\u2019on prolonge le mot <em>amen<\/em>, ses jours et ses ann\u00e9es se voient prolong\u00e9s\u00a0\u00bb (<em>Berakhot<\/em> 47a).<\/p>\n<p>Les plus grands ma\u00eetres parmi les Richonim avaient coutume de dire <em>Baroukh Hou ouvaroukh Ch\u00e9mo<\/em> (\u00ab\u00a0B\u00e9ni soit-Il et b\u00e9ni soit Son nom\u00a0\u00bb) apr\u00e8s la mention du nom divin prononc\u00e9 dans les b\u00e9n\u00e9dictions, et cet usage s\u2019est r\u00e9pandu parmi le peuple juif. Cependant, cette formule ne se dit que lorsqu\u2019il s\u2019agit de b\u00e9n\u00e9dictions par lesquelles l\u2019auditeur n\u2019a pas \u00e0 s\u2019acquitter de sa propre obligation\u00a0; par exemple, dans la r\u00e9p\u00e9tition de l\u2019officiant, pour un fid\u00e8le qui a lui-m\u00eame prononc\u00e9 la \u2018Amida \u00e0 voix basse. En revanche, pour des b\u00e9n\u00e9dictions par lesquelles l\u2019auditeur doit lui-m\u00eame, en r\u00e9pondant <em>amen<\/em>, s\u2019acquitter de son obligation, telles que celles du Qidouch ou de la sonnerie du chofar, on a l\u2019usage de ne pas r\u00e9pondre <em>Baroukh Hou ouvaroukh Ch\u00e9mo<\/em>, afin de ne pas interrompre la b\u00e9n\u00e9diction par une parole que les sages du Talmud n\u2019ont pas institu\u00e9e. A posteriori, si l\u2019on a r\u00e9pondu <em>Baroukh Hou ouvaroukh Ch\u00e9mo<\/em> apr\u00e8s une b\u00e9n\u00e9diction par laquelle on comptait s\u2019acquitter soi-m\u00eame, on est quitte, car par cette incise, on n\u2019a pas d\u00e9tourn\u00e9 son esprit de la b\u00e9n\u00e9diction (<em>Michna Beroura<\/em> 124, 21\u00a0; <em>Kaf Ha\u2019ha\u00efm<\/em> 26\u00a0; dans certaines communaut\u00e9s d\u2019Afrique du Nord, cependant, on a l\u2019usage de r\u00e9pondre <em>Baroukh Hou ouvaroukh Ch\u00e9mo<\/em>, m\u00eame dans celles des b\u00e9n\u00e9dictions par lesquelles on compte s\u2019acquitter soi-m\u00eame\u00a0; quant aux Y\u00e9m\u00e9nites, ils n\u2019ont pas du tout l\u2019usage de dire cette formule)<sup><a href='#_te01ftn20_l' id='_te01ftnref20_l' class='aup1'>[l]<\/a><\/sup>.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref20_j' id='_te01ftn20_j'>[j]<\/a>. Le mot <em>amen <\/em>(\u00ab\u00a0qu\u2019il en soit ainsi\u00a0\u00bb) est forg\u00e9 sur la racine \u05d0.\u05de.\u05df, qui traduit une id\u00e9e de force, de constance, de stabilit\u00e9. Dans sa premi\u00e8re acception, <em>amen<\/em> signifie\u00a0: v\u00e9rit\u00e9, droiture, loyaut\u00e9 (Even-Shoshan, <em>Hamilon h\u00e9\u2019hadach<\/em>).<\/li>\n<p><a href='#_te01ftnref20_k' id='_te01ftn20_k'>[k]<\/a>. Ces trois mots ont pour initiales les lettres <em>aleph<\/em>, <em>mem<\/em>, <em>noun<\/em>, qui forment ensemble le mot <em>amen<\/em>.<\/li>\n<p><a href='#_te01ftnref20_l' id='_te01ftn20_l'>[l]<\/a>. L\u2019auteur rapporte, dans <em>La Pri\u00e8re d\u2019Isra\u00ebl<\/em> 19, 3 note 2\u00a0: \u00ab\u00a0Selon le <em>\u2018Hay\u00e9 Adam<\/em> et le <em>Choul\u2019han \u2018Aroukh Harav<\/em> 124, 2, si l\u2019on a r\u00e9pondu <em>Baroukh Hou ouvaroukh Ch\u00e9mo<\/em>, on n\u2019est pas quitte\u00a0; c\u2019est aussi ce que pense le <em>Igrot Moch\u00e9<\/em>, <em>Ora\u2019h \u2018Ha\u00efm<\/em> II 98. En revanche, d\u2019apr\u00e8s le Rav Messaoud \u2018Ha\u00ef Raqa\u2019h (de Libye), on doit r\u00e9pondre <em>Baroukh Hou ouvaroukh Ch\u00e9mo<\/em>.\u00a0\u00bb C\u2019est aussi l\u2019avis du Rav Chalom Messas pour les communaut\u00e9s du Maroc et d\u2019Alg\u00e9rie. Cf. <em>Divr\u00e9 Chalom v\u00e9-Emet<\/em> du Rav Chelomo Tol\u00e9dano, p. 152, qui justifie longuement cet usage, citant entre autres sources le Roch, le <em>Tour<\/em>, le <em>Choul\u2019han \u2018Aroukh<\/em>, <em>Ora\u2019h \u2018Ha\u00efm<\/em> 124, 5, le <em>Qitsour Choul\u2019han \u2018Aroukh<\/em> du Rav Rapha\u00ebl Baroukh Tol\u00e9dano et le <em>Rav P\u00e9\u2019alim<\/em>, lequel signale que cet usage, mentionn\u00e9 dans les <em>Kavanot<\/em> de Rabbi Isaac Louria, est fond\u00e9 sur une source midrachique.<\/li>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Trois conditions doivent \u00eatre rassembl\u00e9es pour que le particulier puisse se rendre quitte de son obligation par l\u2019\u00e9coute de la r\u00e9p\u00e9tition de l\u2019officiant\u00a0: 1) Ne pas \u00eatre capable de r\u00e9citer soi-m\u00eame la \u2018Amida. Si l\u2019on sait r\u00e9citer cette pri\u00e8re, on s\u2019oblige \u00e0 le faire et \u00e0 demander mis\u00e9ricorde par soi-m\u00eame, et l\u2019on ne peut s\u2019acquitter [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2752","post","type-post","status-publish","format-standard","hentry","category-03-20"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre amen - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre amen - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"Trois conditions doivent \u00eatre rassembl\u00e9es pour que le particulier puisse se rendre quitte de son obligation par l\u2019\u00e9coute de la r\u00e9p\u00e9tition de l\u2019officiant\u00a0: 1) Ne pas \u00eatre capable de r\u00e9citer soi-m\u00eame la \u2018Amida. Si l\u2019on sait r\u00e9citer cette pri\u00e8re, on s\u2019oblige \u00e0 le faire et \u00e0 demander mis\u00e9ricorde par soi-m\u00eame, et l\u2019on ne peut s\u2019acquitter [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-19T22:07:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T08:33:06+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-07\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-07\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre amen\",\"datePublished\":\"2000-03-19T22:07:02+00:00\",\"dateModified\":\"2017-11-09T08:33:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-07\\\/\"},\"wordCount\":1161,\"articleSection\":[\"Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-07\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-07\\\/\",\"name\":\"07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre amen - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-19T22:07:02+00:00\",\"dateModified\":\"2017-11-09T08:33:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-07\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-07\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-07\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre amen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre amen - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/","og_locale":"fr_FR","og_type":"article","og_title":"07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre amen - Pnin\u00e9 Halakha","og_description":"Trois conditions doivent \u00eatre rassembl\u00e9es pour que le particulier puisse se rendre quitte de son obligation par l\u2019\u00e9coute de la r\u00e9p\u00e9tition de l\u2019officiant\u00a0: 1) Ne pas \u00eatre capable de r\u00e9citer soi-m\u00eame la \u2018Amida. Si l\u2019on sait r\u00e9citer cette pri\u00e8re, on s\u2019oblige \u00e0 le faire et \u00e0 demander mis\u00e9ricorde par soi-m\u00eame, et l\u2019on ne peut s\u2019acquitter [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-19T22:07:02+00:00","article_modified_time":"2017-11-09T08:33:06+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre amen","datePublished":"2000-03-19T22:07:02+00:00","dateModified":"2017-11-09T08:33:06+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/"},"wordCount":1161,"articleSection":["Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/","name":"07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre amen - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-19T22:07:02+00:00","dateModified":"2017-11-09T08:33:06+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-20-07\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"07. Quelques r\u00e8gles relatives \u00e0 la r\u00e9p\u00e9tition de l\u2019officiant et au fait de r\u00e9pondre amen"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2752"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2752\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}