{"id":2762,"date":"2000-03-20T00:12:42","date_gmt":"2000-03-19T22:12:42","guid":{"rendered":"https:\/\/ph.yhb.org.il\/fr\/?p=2762"},"modified":"2017-11-09T10:37:19","modified_gmt":"2017-11-09T08:37:19","slug":"03-20-12","status":"publish","type":"post","link":"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/","title":{"rendered":"12. Quelques r\u00e8gles relatives \u00e0 la <em>Birkat Cohanim<\/em>"},"content":{"rendered":"<p>La b\u00e9n\u00e9diction sacerdotale se dit en h\u00e9breu\u00a0; elle se r\u00e9cite \u00e0 voix haute\u00a0; les Cohanim doivent se tenir debout\u00a0; ils doivent \u00e9tendre leurs mains en direction du peuple. Si un Cohen ne peut appliquer quelqu\u2019une de ces quatre r\u00e8gles, il ne prendra pas part \u00e0 la <em>Birkat cohanim<\/em> (<em>Choul\u2019han \u2018Aroukh<\/em>, <em>Ora\u2019h \u2018Ha\u00efm<\/em> 128, 14\u00a0; <em>La Pri\u00e8re d\u2019Isra\u00ebl <\/em>20, 4).<\/p>\n<p>Avant de proc\u00e9der \u00e0 la b\u00e9n\u00e9diction, les Cohanim doivent se laver les mains. Une allusion \u00e0 cela se trouve dans la Bible, comme il est dit\u00a0: \u00ab\u00a0Elevez les mains en \u00e9tat de saintet\u00e9, et b\u00e9nissez l\u2019Eternel\u00a0\u00bb (Ps 134, 2). Un Cohen qui ne se serait pas lav\u00e9 les mains ne pourrait prendre part \u00e0 la b\u00e9n\u00e9diction sacerdotale (<em>Sota<\/em> 39a).<\/p>\n<p>Rabban Yo\u2019hanan ben Zaka\u00ef a d\u00e9cr\u00e9t\u00e9 que les Cohanim ne peuvent monter sur l\u2019estrade d\u2019o\u00f9 se r\u00e9cite la b\u00e9n\u00e9diction s\u2019ils portent des sandales ou des chaussures (<em>La Pri\u00e8re d\u2019Isra\u00ebl<\/em> 20, 8)<sup><a href='#_te01ftn20_n' id='_te01ftnref20_n' class='aup1'>[n]<\/a><\/sup>.<\/p>\n<p>La b\u00e9n\u00e9diction se fait suivant ce c\u00e9r\u00e9monial\u00a0: l\u2019officiant ou l\u2019administrateur de la synagogue (le <em>gaba\u00ef<\/em>) annonce\u00a0: \u00ab\u00a0Cohanim\u00a0!\u00a0\u00bb, comme il est dit\u00a0:\u00a0\u00ab\u00a0Tu leur <em>diras<\/em>\u00a0\u00bb (Nb 6, 23). Si un seul Cohen se pr\u00e9sente sur l\u2019estrade, on ne fait pas cette annonce, puisqu\u2019il est dit\u00a0: \u00ab\u00a0Tu <em>leur<\/em> diras\u00a0\u00bb, au pluriel, ce qui laisse entendre que c\u2019est seulement dans le cas o\u00f9 il y a deux Cohanim ou davantage que l\u2019on annonce \u00ab\u00a0Cohanim\u00a0!\u00a0\u00bb (<em>Choul\u2019han \u2018Aroukh<\/em> 128, 10). Les Cohanim ne disent pas non plus la b\u00e9n\u00e9diction sacerdotale de leur propre mouvement\u00a0: l\u2019officiant leur \u00e9nonce les versets mot \u00e0 mot, et les Cohanim r\u00e9p\u00e8tent apr\u00e8s lui. Quant aux fid\u00e8les, ils r\u00e9pondent <em>amen <\/em>\u00e0 la fin de chaque verset.<\/p>\n<div>\n<hr size=\"1\" \/>\n<div>\n<a href='#_te01ftnref20_n' id='_te01ftn20_n'>[n]<\/a>. L\u2019auteur donne diff\u00e9rentes raisons \u00e0 cette disposition, notamment l\u2019honneur d\u00fb \u00e0 l\u2019assembl\u00e9e, qui impose de ne pas porter, au moment de la b\u00e9n\u00e9diction, des chaussures qui ont peut-\u00eatre \u00e9t\u00e9 promen\u00e9es dans la boue\u00a0; de plus, le service des pr\u00eatres dans le Temple se faisait pieds nus, en raison de la saintet\u00e9 du lieu.<\/li>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La b\u00e9n\u00e9diction sacerdotale se dit en h\u00e9breu\u00a0; elle se r\u00e9cite \u00e0 voix haute\u00a0; les Cohanim doivent se tenir debout\u00a0; ils doivent \u00e9tendre leurs mains en direction du peuple. Si un Cohen ne peut appliquer quelqu\u2019une de ces quatre r\u00e8gles, il ne prendra pas part \u00e0 la Birkat cohanim (Choul\u2019han \u2018Aroukh, Ora\u2019h \u2018Ha\u00efm 128, 14\u00a0; La [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2762","post","type-post","status-publish","format-standard","hentry","category-03-20"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12. Quelques r\u00e8gles relatives \u00e0 la Birkat Cohanim - Pnin\u00e9 Halakha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12. Quelques r\u00e8gles relatives \u00e0 la Birkat Cohanim - Pnin\u00e9 Halakha\" \/>\n<meta property=\"og:description\" content=\"La b\u00e9n\u00e9diction sacerdotale se dit en h\u00e9breu\u00a0; elle se r\u00e9cite \u00e0 voix haute\u00a0; les Cohanim doivent se tenir debout\u00a0; ils doivent \u00e9tendre leurs mains en direction du peuple. Si un Cohen ne peut appliquer quelqu\u2019une de ces quatre r\u00e8gles, il ne prendra pas part \u00e0 la Birkat cohanim (Choul\u2019han \u2018Aroukh, Ora\u2019h \u2018Ha\u00efm 128, 14\u00a0; La [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Pnin\u00e9 Halakha\" \/>\n<meta property=\"article:published_time\" content=\"2000-03-19T22:12:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-09T08:37:19+00:00\" \/>\n<meta name=\"author\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-12\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-12\\\/\"},\"author\":{\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"headline\":\"12. Quelques r\u00e8gles relatives \u00e0 la Birkat Cohanim\",\"datePublished\":\"2000-03-19T22:12:42+00:00\",\"dateModified\":\"2017-11-09T08:37:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-12\\\/\"},\"wordCount\":366,\"articleSection\":[\"Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-12\\\/\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-12\\\/\",\"name\":\"12. Quelques r\u00e8gles relatives \u00e0 la Birkat Cohanim - Pnin\u00e9 Halakha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\"},\"datePublished\":\"2000-03-19T22:12:42+00:00\",\"dateModified\":\"2017-11-09T08:37:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-12\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-12\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/03-20-12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea\",\"item\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12. Quelques r\u00e8gles relatives \u00e0 la Birkat Cohanim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/\",\"name\":\"Pnin\u00e9 Halakha\",\"description\":\"Rav Eli\u00e9zer Melamed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/#\\\/schema\\\/person\\\/8822293bfa4f7cd35b44a3c311851b63\",\"name\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g\",\"caption\":\"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8\"},\"url\":\"https:\\\/\\\/ph.yhb.org.il\\\/fr\\\/author\\\/shlomit12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12. Quelques r\u00e8gles relatives \u00e0 la Birkat Cohanim - Pnin\u00e9 Halakha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/","og_locale":"fr_FR","og_type":"article","og_title":"12. Quelques r\u00e8gles relatives \u00e0 la Birkat Cohanim - Pnin\u00e9 Halakha","og_description":"La b\u00e9n\u00e9diction sacerdotale se dit en h\u00e9breu\u00a0; elle se r\u00e9cite \u00e0 voix haute\u00a0; les Cohanim doivent se tenir debout\u00a0; ils doivent \u00e9tendre leurs mains en direction du peuple. Si un Cohen ne peut appliquer quelqu\u2019une de ces quatre r\u00e8gles, il ne prendra pas part \u00e0 la Birkat cohanim (Choul\u2019han \u2018Aroukh, Ora\u2019h \u2018Ha\u00efm 128, 14\u00a0; La [&hellip;]","og_url":"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/","og_site_name":"Pnin\u00e9 Halakha","article_published_time":"2000-03-19T22:12:42+00:00","article_modified_time":"2017-11-09T08:37:19+00:00","author":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/#article","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/"},"author":{"name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"headline":"12. Quelques r\u00e8gles relatives \u00e0 la Birkat Cohanim","datePublished":"2000-03-19T22:12:42+00:00","dateModified":"2017-11-09T08:37:19+00:00","mainEntityOfPage":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/"},"wordCount":366,"articleSection":["Chapitre 20 \u2013 Quelques r\u00e8gles relatives \u00e0 la pri\u00e8re en minyan"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/","url":"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/","name":"12. Quelques r\u00e8gles relatives \u00e0 la Birkat Cohanim - Pnin\u00e9 Halakha","isPartOf":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#website"},"datePublished":"2000-03-19T22:12:42+00:00","dateModified":"2017-11-09T08:37:19+00:00","author":{"@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63"},"breadcrumb":{"@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ph.yhb.org.il\/fr\/03-20-12\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ph.yhb.org.il\/fr\/03-20-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u05d3\u05e3 \u05d4\u05d1\u05d9\u05ea","item":"https:\/\/ph.yhb.org.il\/fr\/"},{"@type":"ListItem","position":2,"name":"12. Quelques r\u00e8gles relatives \u00e0 la Birkat Cohanim"}]},{"@type":"WebSite","@id":"https:\/\/ph.yhb.org.il\/fr\/#website","url":"https:\/\/ph.yhb.org.il\/fr\/","name":"Pnin\u00e9 Halakha","description":"Rav Eli\u00e9zer Melamed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ph.yhb.org.il\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/ph.yhb.org.il\/fr\/#\/schema\/person\/8822293bfa4f7cd35b44a3c311851b63","name":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4839847e1f630d0e0f5d54879b51b427c551b51611b74d6558e54ff6e69ce498?s=96&d=mm&r=g","caption":"\u05e6\u05d5\u05d5\u05ea \u05d4\u05d0\u05ea\u05e8"},"url":"https:\/\/ph.yhb.org.il\/fr\/author\/shlomit12\/"}]}},"_links":{"self":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/comments?post=2762"}],"version-history":[{"count":0,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/posts\/2762\/revisions"}],"wp:attachment":[{"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/media?parent=2762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/categories?post=2762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ph.yhb.org.il\/fr\/wp-json\/wp\/v2\/tags?post=2762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}